{"id":58567,"date":"2024-07-31T21:27:33","date_gmt":"2024-08-01T00:27:33","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/31\/faixas-de-onibus-em-avenidas-deixam-de-ser-exclusivas-em-ribeirao-preto-nesta-quinta-feira\/"},"modified":"2024-07-31T21:27:33","modified_gmt":"2024-08-01T00:27:33","slug":"faixas-de-onibus-em-avenidas-deixam-de-ser-exclusivas-em-ribeirao-preto-nesta-quinta-feira","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/31\/faixas-de-onibus-em-avenidas-deixam-de-ser-exclusivas-em-ribeirao-preto-nesta-quinta-feira\/","title":{"rendered":"Faixas de \u00f4nibus em avenidas deixam de ser exclusivas em Ribeir\u00e3o Preto nesta quinta-feira"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><strong>Come\u00e7a a valer<\/strong>, a partir desta<strong> quinta-feira<\/strong> (1), a <strong>altera\u00e7\u00e3o em 11 faixas<\/strong>, que seriam exclusivas de \u00f4nibus e, agora, <strong>passam a ser liberadas para todos os ve\u00edculos<\/strong>, com <strong>prefer\u00eancia ao transporte p\u00fablico coletivo<\/strong>.<\/mark><\/span><\/p>\n<p>As <strong>modifica\u00e7\u00f5es<\/strong> ser\u00e3o em <strong>principais avenidas<\/strong> como <strong>Saudade, Dom Pedro I, Presidente Vargas e Brasil<\/strong>.<\/p>\n<p>Em comunicado, a\u00a0<strong>RP Mobi, empresa que gerencia o tr\u00e2nsito e o transporte na cidade,\u00a0<\/strong>informou que a <strong>medida <\/strong>foi tomada ap\u00f3s <strong>estudos t\u00e9cnicos<\/strong> para <strong>adequa\u00e7\u00e3o da nova rede do transporte coletivo urbano<\/strong> de Ribeir\u00e3o Preto.<\/p>\n<p>Ainda, segundo a empresa, a <strong><span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">faixa preferencial de \u00f4nibus permite a circula\u00e7\u00e3o de condutores de ve\u00edculos convencionais, como carros, motocicletas, entre outros. Mas neste caso os mesmos devem dar a prefer\u00eancia para a circula\u00e7\u00e3o dos \u00f4nibus urbano<\/mark><\/span><\/strong>.<\/p>\n<p>Confira as <strong>11 avenidas que deixam de ter faixas exclusivas para \u00f4nibus<\/strong>:<\/p>\n<ul>\n<li>avenida Brasil<\/li>\n<li>avenida Saudade<\/li>\n<li>avenida Presidente Vargas<\/li>\n<li>avenida Jos\u00e9 Ces\u00e1rio Monteiro da Silva<\/li>\n<li>avenida Braz Olaia Acosta<\/li>\n<li>avenida F\u00e1bio Barreto<\/li>\n<li>rua Silveira Martins<\/li>\n<li>avenida Marechal Costa e Silva<\/li>\n<li>avenida Capit\u00e3o Salom\u00e3o<\/li>\n<li>avenida Dom Pedro I<\/li>\n<li>avenida Luiz Galv\u00e3o C\u00e9sar<\/li>\n<\/ul>\n<p>SAIBA MAIS <\/p>\n<p>Policial Militar que matou mulher na zona Sul de Ribeir\u00e3o Preto vai a j\u00fari popular<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong>\u00a0acidade on<\/strong>\u00a0no<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Que horas vai passar \u2018Alma G\u00eamea\u2019 hoje?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/faixas-de-onibus-em-avenidas-deixam-de-ser-exclusivas-em-ribeirao-preto-nesta-quinta-feira\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Come\u00e7a a valer, a partir desta quinta-feira (1), a altera\u00e7\u00e3o em 11 faixas, que seriam exclusivas de \u00f4nibus e, agora, passam a ser liberadas para todos os ve\u00edculos, com prefer\u00eancia ao transporte p\u00fablico coletivo. As modifica\u00e7\u00f5es ser\u00e3o em principais avenidas como Saudade, Dom Pedro I, Presidente Vargas e Brasil. Em comunicado, a\u00a0RP Mobi, empresa &#8230; <a title=\"Faixas de \u00f4nibus em avenidas deixam de ser exclusivas em Ribeir\u00e3o Preto nesta quinta-feira\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/31\/faixas-de-onibus-em-avenidas-deixam-de-ser-exclusivas-em-ribeirao-preto-nesta-quinta-feira\/\" aria-label=\"Read more about Faixas de \u00f4nibus em avenidas deixam de ser exclusivas em Ribeir\u00e3o Preto nesta quinta-feira\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":58568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-58567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor.jpg?fit=1200%2C673&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor.jpg?fit=1200%2C673&ssl=1",1200,673,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor.jpg?fit=300%2C168&ssl=1",300,168,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor.jpg?fit=768%2C431&ssl=1",768,431,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor.jpg?fit=1024%2C574&ssl=1",1024,574,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor.jpg?fit=1200%2C673&ssl=1",1200,673,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor.jpg?fit=1200%2C673&ssl=1",1200,673,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Come\u00e7a a valer, a partir desta quinta-feira (1), a altera\u00e7\u00e3o em 11 faixas, que seriam exclusivas de \u00f4nibus e, agora, passam a ser liberadas para todos os ve\u00edculos, com prefer\u00eancia ao transporte p\u00fablico coletivo. As modifica\u00e7\u00f5es ser\u00e3o em principais avenidas como Saudade, Dom Pedro I, Presidente Vargas e Brasil. Em comunicado, a\u00a0RP Mobi, empresa&hellip;","jetpack-related-posts":[{"id":58616,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/01\/entenda-por-que-algumas-faixas-de-onibus-em-ribeirao-preto-continuam-exclusivas\/","url_meta":{"origin":58567,"position":0},"title":"Entenda por que algumas faixas de \u00f4nibus em Ribeir\u00e3o Preto continuam exclusivas","author":"ismaelcolosi.com.br","date":"1 de August de 2024","format":false,"excerpt":"[ad_1] A partir desta quinta-feira (1), 11 avenidas de Ribeir\u00e3o Preto que tinham faixas exclusivas de \u00f4nibus passam a ser preferenciais. Contudo, em outros cinco locais (veja abaixo), a altera\u00e7\u00e3o n\u00e3o \u00e9 v\u00e1lida, portanto, permanecem sendo permitida somente a passagem de ve\u00edculos do transporte p\u00fablico coletivo. Segundo o diretor de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19_2024-08-01_13-45-36_jpg_2024-08-01_13-45-36.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19_2024-08-01_13-45-36_jpg_2024-08-01_13-45-36.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19_2024-08-01_13-45-36_jpg_2024-08-01_13-45-36.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19_2024-08-01_13-45-36_jpg_2024-08-01_13-45-36.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19_2024-08-01_13-45-36_jpg_2024-08-01_13-45-36.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55676,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/04\/faixas-exclusivas-de-onibus-passam-a-ser-preferenciais-em-11-avenidas-de-ribeirao-preto-veja-quais\/","url_meta":{"origin":58567,"position":1},"title":"Faixas exclusivas de \u00f4nibus passam a ser preferenciais em 11 avenidas de Ribeir\u00e3o Preto; Veja quais","author":"ismaelcolosi.com.br","date":"4 de July de 2024","format":false,"excerpt":"[ad_1] A RP Mobi anunciou nesta quinta-feira (4) que 11 faixas exclusivas de \u00f4nibus ser\u00e3o modificadas como faixas preferenciais a partir do dia 1\u00ba de agosto. Entre as avenidas afetadas, est\u00e3o a Saudade, Dom Pedro I, Presidente Vargas e Brasil. Em comunicado publicado nas redes sociais, a RP Mobi informou\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus_2024-07-04_19-03-39_jpeg_2024-07-04_19-03-39.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus_2024-07-04_19-03-39_jpeg_2024-07-04_19-03-39.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus_2024-07-04_19-03-39_jpeg_2024-07-04_19-03-39.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus_2024-07-04_19-03-39_jpeg_2024-07-04_19-03-39.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus_2024-07-04_19-03-39_jpeg_2024-07-04_19-03-39.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58155,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/28\/avenidas-de-ribeirao-preto-deixam-de-ter-faixas-exclusivas-de-onibus-nesta-semana-veja-quais\/","url_meta":{"origin":58567,"position":2},"title":"Avenidas de Ribeir\u00e3o Preto deixam de ter faixas exclusivas de \u00f4nibus nesta semana; Veja quais","author":"ismaelcolosi.com.br","date":"28 de July de 2024","format":false,"excerpt":"[ad_1] A partir da pr\u00f3xima quinta-feira (1\u00ba de agosto), 11 faixas exclusivas de \u00f4nibus ser\u00e3o modificadas como faixas preferenciais. Entre as avenidas afetadas, est\u00e3o a Saudade, Dom Pedro I, Presidente Vargas e Brasil. Em comunicado, a RP Mobi informou que a medida foi tomada ap\u00f3s estudos t\u00e9cnicos para adequa\u00e7\u00e3o da\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus-insta_2024-07-07_15-57-49_jpg_2024-07-07_15-57-49.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus-insta_2024-07-07_15-57-49_jpg_2024-07-07_15-57-49.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus-insta_2024-07-07_15-57-49_jpg_2024-07-07_15-57-49.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus-insta_2024-07-07_15-57-49_jpg_2024-07-07_15-57-49.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/corredor-de-onibus-insta_2024-07-07_15-57-49_jpg_2024-07-07_15-57-49.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":68053,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/rp-mobi-muda-regra-para-utilizacao-da-faixa-exclusiva-de-onibus-em-ribeirao\/","url_meta":{"origin":58567,"position":3},"title":"RP Mobi muda regra para utiliza\u00e7\u00e3o da faixa exclusiva de \u00f4nibus em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"26 de September de 2024","format":false,"excerpt":"[ad_1] A RP Mobi mudou a regra para utiliza\u00e7\u00e3o da faixa exclusiva de \u00f4nibus em Ribeir\u00e3o Preto. A informa\u00e7\u00e3o foi publicada no Di\u00e1rio Oficial do Munic\u00edpio desta quinta-feira (26). Conforme a publica\u00e7\u00e3o, a partir de agora tamb\u00e9m est\u00e1 permitida a circula\u00e7\u00e3o de t\u00e1xis no local. Veja o comunicado: Art. 1\u00ba.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/img.g1-30-_2024-09-26_22-21-52.webp.webp?fit=984%2C616&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/img.g1-30-_2024-09-26_22-21-52.webp.webp?fit=984%2C616&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/img.g1-30-_2024-09-26_22-21-52.webp.webp?fit=984%2C616&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/img.g1-30-_2024-09-26_22-21-52.webp.webp?fit=984%2C616&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":74566,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/01\/rp-mobi-inicia-fiscalizacao-nos-novos-corredores-de-onibus-em-ribeirao-preto\/","url_meta":{"origin":58567,"position":4},"title":"RP Mobi Inicia Fiscaliza\u00e7\u00e3o nos Novos Corredores de \u00d4nibus em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"1 de November de 2024","format":false,"excerpt":"[ad_1] O programa RP Mobi, respons\u00e1vel por implementar melhorias na mobilidade urbana de Ribeir\u00e3o Preto, iniciou uma nova etapa de fiscaliza\u00e7\u00e3o nos rec\u00e9m-inaugurados corredores de \u00f4nibus. O objetivo \u00e9 assegurar que as vias exclusivas para o transporte coletivo sejam respeitadas, promovendo maior agilidade e seguran\u00e7a para os usu\u00e1rios e condutores\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3_fiscalizacao_corredores_central_-_foto_fernando_gonzaga_6.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3_fiscalizacao_corredores_central_-_foto_fernando_gonzaga_6.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3_fiscalizacao_corredores_central_-_foto_fernando_gonzaga_6.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3_fiscalizacao_corredores_central_-_foto_fernando_gonzaga_6.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3_fiscalizacao_corredores_central_-_foto_fernando_gonzaga_6.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71775,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/17\/corredor-de-onibus-central-e-inaugurado-em-ribeirao-veja-quando-comeca-a-fiscalizacao\/","url_meta":{"origin":58567,"position":5},"title":"Corredor de \u00f4nibus central \u00e9 inaugurado em Ribeir\u00e3o; Veja quando come\u00e7a a fiscaliza\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"17 de October de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto inaugurou nesta quinta-feira (17), os corredores de \u00f4nibus da regi\u00e3o central do munic\u00edpio. A fiscaliza\u00e7\u00e3o, no entanto, come\u00e7a no dia 1\u00ba de novembro de 2024, de acordo com a RP Mobi. Com sete quil\u00f4metros de extens\u00e3o, o corredor de \u00f4nibus central passa por diversas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-15.21.41-2_2024-10-17_21-55-15_jpeg_2024-10-17_21-55-16-e1729202136692.webp.webp?fit=1200%2C792&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-15.21.41-2_2024-10-17_21-55-15_jpeg_2024-10-17_21-55-16-e1729202136692.webp.webp?fit=1200%2C792&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-15.21.41-2_2024-10-17_21-55-15_jpeg_2024-10-17_21-55-16-e1729202136692.webp.webp?fit=1200%2C792&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-15.21.41-2_2024-10-17_21-55-15_jpeg_2024-10-17_21-55-16-e1729202136692.webp.webp?fit=1200%2C792&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-15.21.41-2_2024-10-17_21-55-15_jpeg_2024-10-17_21-55-16-e1729202136692.webp.webp?fit=1200%2C792&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-feD","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=58567"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/58568"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=58567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=58567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=58567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}