{"id":57713,"date":"2024-07-24T06:27:29","date_gmt":"2024-07-24T09:27:29","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/24\/especialista-em-ia-quer-mais-mulheres-na-area\/"},"modified":"2024-07-24T06:27:29","modified_gmt":"2024-07-24T09:27:29","slug":"especialista-em-ia-quer-mais-mulheres-na-area","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/24\/especialista-em-ia-quer-mais-mulheres-na-area\/","title":{"rendered":"Especialista em IA quer mais mulheres na \u00e1rea"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div id=\"attachment_623954\" class=\"wp-caption alignnone style=\" max-width:=\"\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-623954 size-full\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-768x512.jpg?resize=678%2C452&#038;ssl=1\" http:=\"\" alt=\"Heloisy Rodrigues, especialista em intelig\u00eancia artificial\" width=\"678\" height=\"452\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-768x512.jpg\"\/><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-623954 size-full\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-768x512.jpg?resize=678%2C452&#038;ssl=1\" alt=\"Heloisy Rodrigues, especialista em intelig\u00eancia artificial\" width=\"678\" height=\"452\"\/><\/p>\n<p class=\"wp-caption-text\">Heloisy Rodrigues tamb\u00e9m est\u00e1 \u00e0 frente da Macau, startup de solu\u00e7\u00f5es de intelig\u00eancia artificial para o mercado de call center<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<\/div>\n<div class=\"accessibility\">\n<p>Acessibilidade<\/p>\n<p>\n<button onclick=\"alterFont1()\" id=\"btn1\" class=\"btn\">L<\/button><br \/>\n<button onclick=\"alterFont2()\" id=\"btn2\" class=\"btn\" style=\"font-family: Merriweather\">L<\/button><br \/>\n<button onclick=\"alterFontSmallerSize()\" id=\"btn3\" class=\"btn\">A-<\/button><br \/>\n<button onclick=\"alterFontBiggerSize()\" id=\"btn4\" class=\"btn\">A+<\/button><\/p>\n<p><button onclick=\"alterBackground()\" id=\"btn6\" class=\"btn\">\u25d0<\/button><\/p>\n<\/div>\n<p>Depois de ler manchetes e relat\u00f3rios que descreviam os profissionais e empregos do futuro, <strong>Heloisy Rodrigues, 24 anos,<\/strong> decidiu se matricular na primeira turma do curso de <strong>gradua\u00e7\u00e3o em intelig\u00eancia artificial<\/strong> da UFG (Universidade Federal de Goi\u00e1s), o \u00fanico do pa\u00eds.<\/p>\n<p>No in\u00edcio, eram 4 mulheres em uma turma de 40 pessoas. Ao final, ela foi a \u00fanica entre os 15 formandos. Mas j\u00e1 observa um aumento da participa\u00e7\u00e3o feminina: hoje, as turmas t\u00eam, em m\u00e9dia, 25% de mulheres. \u201cTenho uma responsabilidade muito grande de inspirar e encorajar outras mulheres a ver que \u00e9 poss\u00edvel seguir esse caminho e ocupar espa\u00e7os que elas nunca nem imaginaram\u201d, diz Heloisy, que foi convidada para ser <strong>embaixadora da Dove<\/strong> e trabalhar para reeducar algoritmos e incentivar a entrada de mais mulheres na \u00e1rea.<\/p>\n<h2>Leia tamb\u00e9m<\/h2>\n<p>Heloisy recebeu uma avalanche de mensagens de mulheres parabenizando pela forma\u00e7\u00e3o e buscando entender mais sobre o curso. \u201cPodem ir sem medo. A IA tem um mercado muito grande e, se voc\u00ea tem o m\u00ednimo de interesse, vale a pena pesquisar sobre\u201d, afirma.\u00a0De acordo com o F\u00f3rum Econ\u00f4mico Mundial,<strong> espera-se que a IA crie 69 milh\u00f5es de novos empregos nos pr\u00f3ximos 5 anos,<\/strong> tornando-se um dos setores com crescimento mais acelerado. \u201cA cria\u00e7\u00e3o do ChatGPT contribuiu para o hype. A partir disso, as pessoas come\u00e7aram a se interessar mais pela IA.\u201d<\/p>\n<p>Hoje, Heloisy est\u00e1 \u00e0 frente da <strong>Macau<\/strong>, um spin-off da empresa Datam\u00e9trica, A startup fundada por ela desenvolve solu\u00e7\u00f5es de IA voltadas para o mercado de call center.<\/p>\n<h2>Por que precisamos de mais mulheres por tr\u00e1s da IA<\/h2>\n<p>A <strong>representatividade<\/strong> importa \u2013 e muito \u2013 para que mais meninas e mulheres enxerguem as c<strong>arreiras em STEM<\/strong> (sigla em ingl\u00eas para ci\u00eancia, tecnologia, engenharia e matem\u00e1tica) como uma possibilidade. \u201cDesde cedo, os meninos s\u00e3o incentivados a brincar no computador e quando chega a hora de escolher a profiss\u00e3o, tem mais interesse nessas \u00e1reas.\u201d<\/p>\n<p>E se a tecnologia e os algoritmos s\u00e3o constru\u00eddos apenas por homens, n\u00e3o levam em conta as perspectivas femininas. \u201cPrecisamos de profissionais mulheres na \u00e1rea para termos representa\u00e7\u00f5es diferentes e acabarmos com os vieses presentes nos algoritmos.\u201d<\/p>\n<p>Especialistas estimam que <strong>at\u00e9 2026, 90% do conte\u00fado online poder\u00e1 ser gerado por intelig\u00eancia artificial<\/strong>, segundo relat\u00f3rio da Europol. E as mulheres j\u00e1 est\u00e3o sendo impactadas por deepfakes, influenciadoras virtuais, misses criadas com IA e o refor\u00e7o de padr\u00f5es de beleza inating\u00edveis.<\/p>\n<p>Quase 87% das mulheres adultas e 88% das jovens j\u00e1 foram expostas a <strong>conte\u00fados t\u00f3xicos de beleza online<\/strong>, segundo pesquisa da Dove com 33 mil entrevistadas, sendo 1.001 no Brasil. No pa\u00eds, os n\u00fameros chegam a 95% e 92%, respectivamente.<\/p>\n<p>O impacto vai al\u00e9m: 1 em cada 3 mulheres (no Brasil, 1 em cada 2) se sente <strong>pressionada a alterar sua apar\u00eancia<\/strong> por conta do que v\u00ea nas redes, mesmo sabendo que pode estar diante de imagens manipuladas. \u201cA gente sempre sofre, e o mais preocupante \u00e9 o impacto nas novas gera\u00e7\u00f5es\u201d, diz a especialista em IA e embaixadora da Dove. A campanha da marca pela Beleza Real tem 20 anos, e foi atualizada para combater os impactos da intelig\u00eancia artificial. A empresa tamb\u00e9m se comprometeu a n\u00e3o utilizar tecnologia para criar ou distorcer imagens de mulheres.<\/p>\n<p>Reeducar os algoritmos de IA envolve mais diversidade entre os profissionais, mas tamb\u00e9m conscientiza\u00e7\u00e3o dos usu\u00e1rios da internet. \u201cEssa preocupa\u00e7\u00e3o precisa partir da sociedade como um todo. As pessoas tamb\u00e9m conseguem mudar os algoritmos de IA postando imagens mais reais nas suas pr\u00f3prias redes\u201d, diz Heloisy. Isso porque as ferramentas s\u00e3o treinadas com base nas informa\u00e7\u00f5es que j\u00e1 est\u00e3o dispon\u00edveis na internet.<\/p>\n<h2>O que \u00e9 a forma\u00e7\u00e3o em intelig\u00eancia artificial<\/h2>\n<p>A especialista em intelig\u00eancia artificial j\u00e1 tinha afinidade com exatas desde o ensino m\u00e9dio, mas cursou um semestre de odontologia antes de se matricular na gradua\u00e7\u00e3o em IA. Ela conta que o curso da UFG foi criado pelos professores da universidade, que viam a necessidade de formar profissionais que est\u00e3o sendo demandados pelo mercado. Antes, s\u00f3 havia cursos de p\u00f3s-gradua\u00e7\u00e3o em IA.<\/p>\n<p>O curso, com dura\u00e7\u00e3o de quatro anos, \u00e9 baseado em um trip\u00e9: matem\u00e1tica, programa\u00e7\u00e3o e computa\u00e7\u00e3o e empreendedorismo. \u201c\u00c9 a mentalidade empreendedora que faz com que a gente pegue as ferramentas de IA e construa solu\u00e7\u00f5es para resolver dores de pessoas e empresas.\u201d<\/p>\n<ul>\n<li>\n<h4>Siga a <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u\" target=\"_blank\" rel=\"noopener\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias sobre neg\u00f3cios, carreira, tecnologia e estilo de vida<\/h4>\n<\/li>\n<\/ul>\n<p>A forma\u00e7\u00e3o \u00e9 bastante pr\u00e1tica e, por meio do Centro de Excel\u00eancia em IA da universidade, fomentado pelo governo, os alunos participam de projetos de pesquisa e desenvolvimento envolvendo tecnologias de IA para grandes empresas, como iFood e Globo. \u201cConstru\u00edmos essa bagagem no decorrer da faculdade e essa troca com o mercado e outros pesquisadores mais seniores.\u201d<\/p>\n<p>A IA pode e j\u00e1 est\u00e1 sendo usada em diversos campos. \u201cA intelig\u00eancia artificial vem para ajudar na produtividade, mas tamb\u00e9m est\u00e1 sendo utilizada na \u00e1rea da sa\u00fade, por exemplo, para detec\u00e7\u00e3o de c\u00e2ncer de mama e outras doen\u00e7as.\u201d<\/p>\n<h2>Escolhas do editor<\/h2>\n<\/div>\n<p><script type=\"rocketlazyloadscript\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/forbes-mulher\/2024\/07\/especialista-inteligencia-artificial-quer-reeducar-algoritmos-contra-padroes-de-beleza-toxicos\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Heloisy Rodrigues tamb\u00e9m est\u00e1 \u00e0 frente da Macau, startup de solu\u00e7\u00f5es de intelig\u00eancia artificial para o mercado de call center Acessibilidade L L A- A+ \u25d0 Depois de ler manchetes e relat\u00f3rios que descreviam os profissionais e empregos do futuro, Heloisy Rodrigues, 24 anos, decidiu se matricular na primeira turma do curso de gradua\u00e7\u00e3o &#8230; <a title=\"Especialista em IA quer mais mulheres na \u00e1rea\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/24\/especialista-em-ia-quer-mais-mulheres-na-area\/\" aria-label=\"Read more about Especialista em IA quer mais mulheres na \u00e1rea\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":57714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-57713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-1024x683.jpg?fit=1024%2C683&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-1024x683.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-1024x683.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-1024x683.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mulher-heloisy-rodrigues-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Heloisy Rodrigues tamb\u00e9m est\u00e1 \u00e0 frente da Macau, startup de solu\u00e7\u00f5es de intelig\u00eancia artificial para o mercado de call center Acessibilidade L L A- A+ \u25d0 Depois de ler manchetes e relat\u00f3rios que descreviam os profissionais e empregos do futuro, Heloisy Rodrigues, 24 anos, decidiu se matricular na primeira turma do curso de gradua\u00e7\u00e3o&hellip;","jetpack-related-posts":[{"id":74915,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/03\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-17\/","url_meta":{"origin":57713,"position":0},"title":"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"3 de November de 2024","format":false,"excerpt":"Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo Microset Tecnologia Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo V\u00eddeos","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71983,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/18\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-16\/","url_meta":{"origin":57713,"position":1},"title":"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"18 de October de 2024","format":false,"excerpt":"Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo Microset Tecnologia Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo V\u00eddeos","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729282097_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729282097_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729282097_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729282097_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729282097_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":76947,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/19\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-18\/","url_meta":{"origin":57713,"position":2},"title":"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"19 de November de 2024","format":false,"excerpt":"Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo Auxiliar Administrativo Ribeir\u00e3o Preto - SPEfetivo Auxiliar T\u00e9cnico de RedesRibeir\u00e3o Preto - SPEfetivo Microset Tecnologia Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo V\u00eddeos","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":82676,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/02\/07\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-23\/","url_meta":{"origin":57713,"position":3},"title":"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"7 de February de 2025","format":false,"excerpt":"Assistente de Service Desk l Ribeir\u00e3o Preto - SPEfetivo Auxiliar T\u00e9cnico de Redes Ribeir\u00e3o Preto - SPEfetivo Gerente de Neg\u00f3cios - Campinas e regi\u00e3o Ribeir\u00e3o Preto - SPPessoa jur\u00eddica Microset Tecnologia Assistente de Service Desk l Ribeir\u00e3o Preto - SPEfetivo V\u00eddeos","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51227,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/24\/conselho-da-petrobras-aprova-magda-chambriard-como-ceo\/","url_meta":{"origin":57713,"position":4},"title":"Conselho da Petrobras aprova Magda Chambriard como CEO","author":"ismaelcolosi.com.br","date":"24 de May de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 A Petrobras informou que seu conselho de administra\u00e7\u00e3o aprovou nesta sexta-feira (24) Magda Chambriard como nova presidente-executiva e conselheira da companhia. Segundo fato relevante, Chambriard tomou posse em ambos os cargos nesta sexta-feira e passou a integrar o conselho imediatamente, n\u00e3o sendo\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":76394,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/12\/vivara-anuncia-novo-ceo\/","url_meta":{"origin":57713,"position":5},"title":"Vivara Anuncia Novo CEO","author":"ismaelcolosi.com.br","date":"12 de November de 2024","format":false,"excerpt":"[ad_1] Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r A Vivara informou que seu conselho de administra\u00e7\u00e3o elegeu o atual diretor de opera\u00e7\u00f5es, Icaro Borrello, para o cargo de presidente-executivo da companhia, em reuni\u00e3o realizada nesta ter\u00e7a-feira (11), conforme comunicado ao mercado. A decis\u00e3o segue-se \u00e0 ren\u00fancia do CEO\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-f0R","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/57713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=57713"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/57713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/57714"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=57713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=57713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=57713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}