{"id":57388,"date":"2024-07-20T13:37:39","date_gmt":"2024-07-20T16:37:39","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/20\/atleta-da-regiao-de-ribeirao-vence-ultimo-desafio-antes-dos-jogos-olimpicos-de-paris\/"},"modified":"2024-07-20T13:37:39","modified_gmt":"2024-07-20T16:37:39","slug":"atleta-da-regiao-de-ribeirao-vence-ultimo-desafio-antes-dos-jogos-olimpicos-de-paris","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/20\/atleta-da-regiao-de-ribeirao-vence-ultimo-desafio-antes-dos-jogos-olimpicos-de-paris\/","title":{"rendered":"Atleta da regi\u00e3o de Ribeir\u00e3o vence \u00faltimo desafio antes dos Jogos Ol\u00edmpicos de Paris"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O corredor <strong>Alison dos Santos<\/strong>, o Piu, venceu a prova dos 400 metros com barreiras, neste s\u00e1bado (20), na etapa de <strong>Londres<\/strong> da <strong>Diamond League<\/strong> \u2013 veja o v\u00eddeo abaixo. \u00a0<mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">Esse \u00e9 o \u00faltimo compromisso de Piu antes dos<strong> Jogos Ol\u00edmpicos de Paris.<\/strong><\/mark><\/p>\n<p>O atleta, que \u00e9 natural de<strong> S\u00e3o Joaquim da Barra<\/strong>, na regi\u00e3o de <strong>Ribeir\u00e3o Preto<\/strong>, cruzou em primeiro lugar com o tempo de 47s18 \u00e0 frente de <strong>Roshawn Clarke<\/strong>, da Jamaica, segundo colocado com 47s63 e de <strong>Ismail Doudai Abakar<\/strong>, do Catar, com 47s72.<\/p>\n<h4 class=\"wp-block-heading\"><strong>VEJA O V\u00cdDEO<\/strong><\/h4>\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/C9pZfZtuhDY\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"\/>\n<p>Alison, o Piu, n\u00e3o teve grandes dificuldades para obter a quinta vit\u00f3ria em seis etapas disputadas. O brasileiro liderou a prova a partir dos 200 metros e n\u00e3o precisou for\u00e7ar muito o ritmo para fechar em primeiro lugar.<\/p>\n<p>Por causa dos Jogos Ol\u00edmpicos, a pr\u00f3xima etapa da Diamond League est\u00e1 prevista apenas para 22 de agosto, em Lausanne, na Su\u00ed\u00e7a.<\/p>\n<p>Esta foi a \u00faltima competi\u00e7\u00e3o antes de Paris-2024, competi\u00e7\u00e3o na qual Alison ter\u00e1 como principais competidores o noruegu\u00eas Karsten Warholm e o americano Rai Benjamin, que n\u00e3o estiveram em Londres.<\/p>\n<p>Os tr\u00eas se enfrentaram no dia 12, em M\u00f4naco, e Benjamin venceu a prova, com Warholm em segundo e Alison em terceiro. Ali\u00e1s, na Olimp\u00edada de T\u00f3quio, o ouro ficou com o noruegu\u00eas, a prata com o americano e o bronze com o brasileiro.<\/p>\n<p>SAIBA MAIS<br \/>Saerp alerta para falta d\u2019\u00e1gua em sete bairros de Ribeir\u00e3o Preto; Veja os locais<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong> acidade on<\/strong> no<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Instagram <\/a>e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do<strong> acidade on <\/strong>no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Neymar ter\u00e1 quarto filho?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/esportes\/atleta-da-regiao-de-ribeirao-vence-ultimo-desafio-antes-dos-jogos-olimpicos-de-paris\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O corredor Alison dos Santos, o Piu, venceu a prova dos 400 metros com barreiras, neste s\u00e1bado (20), na etapa de Londres da Diamond League \u2013 veja o v\u00eddeo abaixo. \u00a0Esse \u00e9 o \u00faltimo compromisso de Piu antes dos Jogos Ol\u00edmpicos de Paris. O atleta, que \u00e9 natural de S\u00e3o Joaquim da Barra, na &#8230; <a title=\"Atleta da regi\u00e3o de Ribeir\u00e3o vence \u00faltimo desafio antes dos Jogos Ol\u00edmpicos de Paris\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/20\/atleta-da-regiao-de-ribeirao-vence-ultimo-desafio-antes-dos-jogos-olimpicos-de-paris\/\" aria-label=\"Leia mais sobre Atleta da regi\u00e3o de Ribeir\u00e3o vence \u00faltimo desafio antes dos Jogos Ol\u00edmpicos de Paris\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":55899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-57388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1216%2C839&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1216%2C839&ssl=1",1216,839,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=300%2C207&ssl=1",300,207,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=768%2C530&ssl=1",768,530,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1024%2C707&ssl=1",1024,707,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1216%2C839&ssl=1",1216,839,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1216%2C839&ssl=1",1216,839,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O corredor Alison dos Santos, o Piu, venceu a prova dos 400 metros com barreiras, neste s\u00e1bado (20), na etapa de Londres da Diamond League \u2013 veja o v\u00eddeo abaixo. \u00a0Esse \u00e9 o \u00faltimo compromisso de Piu antes dos Jogos Ol\u00edmpicos de Paris. O atleta, que \u00e9 natural de S\u00e3o Joaquim da Barra, na&hellip;","jetpack-related-posts":[{"id":55898,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/07\/atleta-da-regiao-de-ribeirao-preto-vence-em-paris-e-segue-invicto-em-2024\/","url_meta":{"origin":57388,"position":0},"title":"Atleta da regi\u00e3o de Ribeir\u00e3o Preto vence em Paris e segue invicto em 2024","author":"ismaelcolosi.com.br","date":"7 de Julho de 2024","format":false,"excerpt":"[ad_1] O corredor Alison dos Santos, o Piu, que \u00e9 de S\u00e3o Joaquim da Barra, na regi\u00e3o de Ribeir\u00e3o Preto, conquistou mais uma vit\u00f3ria na Diamond League, neste domingo (7). O atleta est\u00e1 invicto na temporada. Na disputa dos 400 metros com barreiras, em Paris, na Fran\u00e7a, Alison dos Santos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1200%2C828&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1200%2C828&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1200%2C828&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1200%2C828&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/alison-dos-santos_2024-07-07_16-55-12_jpg_2024-07-07_16-55-13.webp.webp?fit=1200%2C828&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51763,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/30\/atleta-da-regiao-de-ribeirao-preto-faz-melhor-tempo-do-ano-em-prova-de-atletismo\/","url_meta":{"origin":57388,"position":1},"title":"Atleta da regi\u00e3o de Ribeir\u00e3o Preto faz melhor tempo do ano em prova de atletismo","author":"ismaelcolosi.com.br","date":"30 de Maio de 2024","format":false,"excerpt":"[ad_1] O atleta Alison dos Santos, conhecido como Piu, que \u00e9 de S\u00e3o Joaquim da Barra, na regi\u00e3o de Ribeir\u00e3o Preto, venceu os 400 metros com barreiras da etapa Oslo da Diamond League de atletismo, que aconteceu na Noruega. A disputa contra o noruegu\u00eas Karsten Warholm, que era favorito, aconteceu\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-70_2024-05-30_21-28-54_jpg_2024-05-30_21-28-54.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-70_2024-05-30_21-28-54_jpg_2024-05-30_21-28-54.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-70_2024-05-30_21-28-54_jpg_2024-05-30_21-28-54.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-70_2024-05-30_21-28-54_jpg_2024-05-30_21-28-54.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-70_2024-05-30_21-28-54_jpg_2024-05-30_21-28-54.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59463,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/08\/conheca-alison-dos-santos-o-piu-atleta-que-disputa-final-olimpica-em-paris\/","url_meta":{"origin":57388,"position":2},"title":"Conhe\u00e7a Alison dos Santos, o Piu, atleta que disputa final ol\u00edmpica em Paris","author":"ismaelcolosi.com.br","date":"8 de Agosto de 2024","format":false,"excerpt":"[ad_1] Nesta sexta-feira (9), o atleta Alison dos Santos, o Piu, disputa a final dos 400 metros com barreiras, nos Jogos Ol\u00edmpicos de Paris 2024. O corredor, que \u00e9 nascido em S\u00e3o Joaquim da Barra, na regi\u00e3o de Ribeir\u00e3o Preto, \u00e9 um dos cotados ao p\u00f3dio na prova, que acontece\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45332,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/atleta-da-regiao-de-ribeirao-preto-sonha-com-a-medalha-de-ouro-nos-jogos-de-paris-2024\/","url_meta":{"origin":57388,"position":3},"title":"Atleta da regi\u00e3o de Ribeir\u00e3o Preto sonha com a medalha de ouro nos Jogos de Paris 2024","author":"ismaelcolosi.com.br","date":"3 de Abril de 2024","format":false,"excerpt":"[ad_1] O atleta Alisson dos Santos, o Piu, de S\u00e3o Joaquim da Barra, na regi\u00e3o de Ribeir\u00e3o Preto, sonha com a medalha de ouro nos Jogos Ol\u00edmpicos de Paris 2024. Em T\u00f3quio 2020, ele foi bronze na prova dos 400 metros com barreiras. Piu \u00e9 o terceiro melhor atleta do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/5dd3c926-f759-44b3-852f-8bc8a2a45920.jpeg?fit=760%2C507&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/5dd3c926-f759-44b3-852f-8bc8a2a45920.jpeg?fit=760%2C507&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/5dd3c926-f759-44b3-852f-8bc8a2a45920.jpeg?fit=760%2C507&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/5dd3c926-f759-44b3-852f-8bc8a2a45920.jpeg?fit=760%2C507&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":59593,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/09\/alison-dos-santos-e-bronze-nos-400-metros-com-barreiras-nas-olimpiadas-de-paris\/","url_meta":{"origin":57388,"position":4},"title":"Alison dos Santos \u00e9 bronze nos 400 metros com barreiras nas Olimp\u00edadas de Paris","author":"ismaelcolosi.com.br","date":"9 de Agosto de 2024","format":false,"excerpt":"[ad_1] Alison dos Santos, o Piu, ficou em terceiro lugar e garantiu medalha de bronze na final dos 400 metros com barreiras, nos Jogos Ol\u00edmpicos de Paris 2024, nesta sexta-feira (9). O atleta \u00e9 nascido em S\u00e3o Joaquim da Barra, na regi\u00e3o de Ribeir\u00e3o Preto e era um dos favoritos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alison-dos-santos-piu_2024-08-08_19-02-19_jpg_2024-08-08_19-02-19.webp.webp?fit=1080%2C717&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16781,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/16\/atleta-da-regiao-de-ribeirao-e-um-dos-vencedores-do-premio-brasil-olimpico\/","url_meta":{"origin":57388,"position":5},"title":"Atleta da regi\u00e3o de Ribeir\u00e3o \u00e9 um dos vencedores do Pr\u00eamio Brasil Ol\u00edmpico","author":"ismaelcolosi.com.br","date":"16 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O corredor Alison dos Santos, o Piu, que \u00e9 natural de S\u00e3o Joaquim da Barra, na regi\u00e3o de Ribeir\u00e3o Preto, foi o vencedor do Pr\u00eamio Retorno do Ano, do Pr\u00eamio Brasil Ol\u00edmpico 2023, realizado na \u00faltima sexta-feira (15), no Rio de Janeiro. O medalhista de bronze nos Jogos Ol\u00edmpicos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/alison-dos-santos.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/alison-dos-santos.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/alison-dos-santos.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/alison-dos-santos.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/alison-dos-santos.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-eVC","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/57388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=57388"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/57388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/55899"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=57388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=57388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=57388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}