{"id":56310,"date":"2024-07-10T21:51:49","date_gmt":"2024-07-11T00:51:49","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/10\/apostadores-do-interior-de-sp-sao-premiados-na-mega-sena-veja-os-numeros\/"},"modified":"2024-07-10T21:51:49","modified_gmt":"2024-07-11T00:51:49","slug":"apostadores-do-interior-de-sp-sao-premiados-na-mega-sena-veja-os-numeros","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/10\/apostadores-do-interior-de-sp-sao-premiados-na-mega-sena-veja-os-numeros\/","title":{"rendered":"Apostadores do interior de SP s\u00e3o premiados na Mega-Sena; Veja os n\u00fameros"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>O sorteio do concurso 2.747 da<strong> Mega-Sena<\/strong>, realizado na noite desta quarta-feira (10), no Espa\u00e7o da Sorte, em <strong>S\u00e3o Paulo<\/strong>, premiou <strong>11 apostadores do interior de S\u00e3o Paulo<\/strong>, entre eles, moradores de <strong>Ribeir\u00e3o Preto<\/strong> e <strong>Barretos<\/strong>.<\/p>\n<p><strong>Nenhuma aposta acertou as seis dezenas<\/strong>, portanto, o pr\u00eamio principal acumulou em <strong>R$ 15 milh\u00f5es<\/strong>. <strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Os n\u00fameros sorteados foram: 14 \u2013 17 \u2013 24 \u2013 28 \u2013 36 \u2013 45.<\/mark><\/strong><\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>Cada aposta premiada acertou <strong>cinco n\u00fameros<\/strong> e vai receber <strong>R$ 22.625,51<\/strong>. De acordo com as informa\u00e7\u00f5es da <strong>Caixa Econ\u00f4mica Federal<\/strong>, os outros apostadores premiados s\u00e3o dos munic\u00edpios de:<\/p>\n<h3 class=\"wp-block-heading\"><strong>Pr\u00f3ximo sorteio<\/strong><\/h3>\n<p>O pr\u00f3ximo sorteio da <strong>Mega-Sena <\/strong>acontece no s\u00e1bado (13), \u00e0s 20h. A <strong>aposta simples<\/strong> custa <strong>R$ 5<\/strong> e pode ser realizada atrav\u00e9s das casas lot\u00e9ricas credenciadas ou pelo app \u2018Loterias Caixa\u2019.<\/p>\n<p><iframe title=\"Loterias CAIXA | 10\/07\/2024\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/0YOKhKCTcX4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Companhia a\u00e9rea de Ribeir\u00e3o Preto anuncia novas bases em Chapec\u00f3 e no Rio de Janeiro<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Sandra vai perder beb\u00ea em \u2018Renascer\u2019?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/economia\/apostadores-do-interior-de-sp-sao-premiados-na-mega-sena-veja-os-numeros\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O sorteio do concurso 2.747 da Mega-Sena, realizado na noite desta quarta-feira (10), no Espa\u00e7o da Sorte, em S\u00e3o Paulo, premiou 11 apostadores do interior de S\u00e3o Paulo, entre eles, moradores de Ribeir\u00e3o Preto e Barretos. Nenhuma aposta acertou as seis dezenas, portanto, o pr\u00eamio principal acumulou em R$ 15 milh\u00f5es. Os n\u00fameros sorteados &#8230; <a title=\"Apostadores do interior de SP s\u00e3o premiados na Mega-Sena; Veja os n\u00fameros\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/10\/apostadores-do-interior-de-sp-sao-premiados-na-mega-sena-veja-os-numeros\/\" aria-label=\"Read more about Apostadores do interior de SP s\u00e3o premiados na Mega-Sena; Veja os n\u00fameros\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":3624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-56310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1170%2C700&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1170%2C700&ssl=1",1170,700,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=300%2C179&ssl=1",300,179,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=768%2C459&ssl=1",768,459,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1024%2C613&ssl=1",1024,613,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1170%2C700&ssl=1",1170,700,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1170%2C700&ssl=1",1170,700,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O sorteio do concurso 2.747 da Mega-Sena, realizado na noite desta quarta-feira (10), no Espa\u00e7o da Sorte, em S\u00e3o Paulo, premiou 11 apostadores do interior de S\u00e3o Paulo, entre eles, moradores de Ribeir\u00e3o Preto e Barretos. Nenhuma aposta acertou as seis dezenas, portanto, o pr\u00eamio principal acumulou em R$ 15 milh\u00f5es. Os n\u00fameros sorteados&hellip;","jetpack-related-posts":[{"id":58928,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/04\/apostadores-do-interior-de-sp-sao-premiados-na-mega-sena\/","url_meta":{"origin":56310,"position":0},"title":"Apostadores do interior de SP s\u00e3o premiados na Mega-Sena","author":"ismaelcolosi.com.br","date":"4 de August de 2024","format":false,"excerpt":"[ad_1] O sorteio do concurso 2.757 da Mega-Sena, realizado na noite deste s\u00e1bado (3), no Espa\u00e7o da Sorte, em S\u00e3o Paulo, premiou cinco apostas do interior de S\u00e3o Paulo com pouco mais de R$ 71 mil. Ningu\u00e9m acertou todas as dezenas sorteadas e o pr\u00eamio ficou acumulado em R$ 12\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/megasena_1024x576_12112020081600.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/megasena_1024x576_12112020081600.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/megasena_1024x576_12112020081600.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/megasena_1024x576_12112020081600.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":59687,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/11\/apostadores-do-interior-de-sp-sao-premiados-na-mega-sena-veja-os-numeros-2\/","url_meta":{"origin":56310,"position":1},"title":"Apostadores do interior de SP s\u00e3o premiados na Mega-Sena; Veja os n\u00fameros","author":"ismaelcolosi.com.br","date":"11 de August de 2024","format":false,"excerpt":"[ad_1] Cinco apostadores do interior de S\u00e3o Paulo faturaram na quina da Mega-Sena e v\u00e3o receber pouco mais de R$ 58 mil. O sorteio foi realizado na noite deste s\u00e1bado (10), no Espa\u00e7o de Sorte, em S\u00e3o Paulo. Ningu\u00e9m acertou as seis dezenas do concurso 2.760 e o pr\u00eamio principal\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/20230622_182751.webp.webp?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":67688,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/24\/apostadores-do-interior-de-sp-faturam-na-mega-sena-veja-os-numeros-sorteados\/","url_meta":{"origin":56310,"position":2},"title":"Apostadores do interior de SP faturam na Mega-Sena; Veja os n\u00fameros sorteados","author":"ismaelcolosi.com.br","date":"24 de September de 2024","format":false,"excerpt":"[ad_1] Tr\u00eas apostadores do interior de S\u00e3o Paulo acertaram cinco n\u00fameros no concurso 2.778 da Mega-Sena, realizado na noite desta ter\u00e7a-feira (24), e v\u00e3o receber pouco mais de R$ 89 mil. Entre os premiados est\u00e1 uma aposta de Ribeir\u00e3o Preto \u2013 veja abaixo. Em contrapartida, ningu\u00e9m acertou as seis dezenas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/megasena_acumulou_1024x576_15032020092615.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/megasena_acumulou_1024x576_15032020092615.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/megasena_acumulou_1024x576_15032020092615.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/megasena_acumulou_1024x576_15032020092615.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":56679,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/14\/apostadores-do-interior-de-sp-sao-premiados-em-sorteio-da-mega-sena-confira-os-numeros\/","url_meta":{"origin":56310,"position":3},"title":"Apostadores do interior de SP s\u00e3o premiados em sorteio da Mega-Sena; Confira os n\u00fameros","author":"ismaelcolosi.com.br","date":"14 de July de 2024","format":false,"excerpt":"[ad_1] O sorteio da Mega-Sena, na noite de s\u00e1bado (13), premiou apostadores do interior de S\u00e3o Paulo com os acertos de cinco e quatro n\u00fameros. Ningu\u00e9m acertou o pr\u00eamio principal com as seis dezenas sorteadas (veja abaixo) e o pr\u00eamio para o pr\u00f3ximo sorteio, no dia 16 de julho, deve\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Capturar_2024-07-14_13-25-27_jpg_2024-07-14_13-25-27.webp.webp?fit=1141%2C646&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Capturar_2024-07-14_13-25-27_jpg_2024-07-14_13-25-27.webp.webp?fit=1141%2C646&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Capturar_2024-07-14_13-25-27_jpg_2024-07-14_13-25-27.webp.webp?fit=1141%2C646&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Capturar_2024-07-14_13-25-27_jpg_2024-07-14_13-25-27.webp.webp?fit=1141%2C646&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Capturar_2024-07-14_13-25-27_jpg_2024-07-14_13-25-27.webp.webp?fit=1141%2C646&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":72171,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/20\/apostadores-do-interior-de-sp-sao-premiados-na-mega-sena-veja-numeros-3\/","url_meta":{"origin":56310,"position":4},"title":"Apostadores do interior de SP s\u00e3o premiados na Mega-Sena; Veja n\u00fameros","author":"ismaelcolosi.com.br","date":"20 de October de 2024","format":false,"excerpt":"[ad_1] Apostadores do interior de S\u00e3o Paulo acertaram cinco dezenas no concurso 2787 da Mega-Sena e ganharam R$ 48,7 mil cada um no sorteio deste s\u00e1bado (19), realizado pela Caixa Econ\u00f4mica Federal. O pr\u00eamio principal, por\u00e9m, n\u00e3o teve ganhador e est\u00e1 estimado em R$ 51 milh\u00f5es. Os n\u00fameros sorteados s\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/AnyConv.com__20230622_182547-scaled.webp.webp?fit=1200%2C751&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/AnyConv.com__20230622_182547-scaled.webp.webp?fit=1200%2C751&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/AnyConv.com__20230622_182547-scaled.webp.webp?fit=1200%2C751&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/AnyConv.com__20230622_182547-scaled.webp.webp?fit=1200%2C751&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/AnyConv.com__20230622_182547-scaled.webp.webp?fit=1200%2C751&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":56977,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/16\/apostadores-do-interior-de-sp-levam-premio-na-mega-sena-veja-os-numeros\/","url_meta":{"origin":56310,"position":5},"title":"Apostadores do interior de SP levam pr\u00eamio na Mega-Sena; Veja os n\u00fameros","author":"ismaelcolosi.com.br","date":"16 de July de 2024","format":false,"excerpt":"[ad_1] Uma aposta de Ribeir\u00e3o Preto acertou cinco n\u00fameros do concurso 2.749 da Mega-Sena e faturou mais de R$ 58 mil, na noite desta ter\u00e7a-feira (16). O sorteio foi realizado no Espa\u00e7o da Sorte, em S\u00e3o Paulo. Nenhum apostador acertou todas as dezenas e o pr\u00eamio principal acumulou em R$\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mega_sena_1024x576_24112020155229.jpg?fit=1024%2C575&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mega_sena_1024x576_24112020155229.jpg?fit=1024%2C575&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mega_sena_1024x576_24112020155229.jpg?fit=1024%2C575&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/mega_sena_1024x576_24112020155229.jpg?fit=1024%2C575&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-eEe","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=56310"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/3624"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=56310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=56310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=56310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}