{"id":54372,"date":"2024-06-24T19:54:28","date_gmt":"2024-06-24T22:54:28","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/24\/show-com-integrantes-do-legiao-urbana-em-ribeirao-preto-tem-ingresso-solidario\/"},"modified":"2024-06-24T19:54:28","modified_gmt":"2024-06-24T22:54:28","slug":"show-com-integrantes-do-legiao-urbana-em-ribeirao-preto-tem-ingresso-solidario","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/24\/show-com-integrantes-do-legiao-urbana-em-ribeirao-preto-tem-ingresso-solidario\/","title":{"rendered":"Show com integrantes do Legi\u00e3o Urbana em Ribeir\u00e3o Preto tem ingresso solid\u00e1rio"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>O <strong>show \u201cAs V Esta\u00e7\u00f5es com Legi\u00e3o Urbana\u201d<\/strong>, que acontece em <strong>Ribeir\u00e3o Preto<\/strong>, no dia <strong>5 de julho<\/strong> est\u00e1 com <strong>lote de ingressos solid\u00e1rios<\/strong>. <\/p>\n<p>Os <span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><strong>interessados ter\u00e3o 50% de desconto no valor do ingresso<\/strong> mediante a <strong>doa\u00e7\u00e3o de dois quilos de aveia ou dois litros de \u00f3leo de soja<\/strong><\/mark><\/span>. O<strong> lote solid\u00e1rio<\/strong> \u00e9 v\u00e1lido para o <strong>setor pista \u201cSer\u00e1\u201d e \u201cTempo Perdido\u201d<\/strong>.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>Todos os <span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><strong>produtos arrecadados<\/strong> ser\u00e3o <strong>doados \u00e0 Casa do Vov\u00f4<\/strong>, institui\u00e7\u00e3o que abriga <strong>idosos na cidade<\/strong><\/mark><\/span>.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Confira os valores com desconto:<\/strong><\/h2>\n<ul>\n<li>Pista Ser\u00e1 \u2013 R$ 150 (meia-entrada)<\/li>\n<li>Pista Tempo Perdido \u2013 R$ 125 (meia-entrada)<\/li>\n<\/ul>\n<p>* Para adquirir estes ingressos, a <strong>troca acontecer\u00e1 somente nas bilheterias do Multiplan Hall<\/strong>.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Sobre o show<\/strong><\/h2>\n<p>O <strong>grupo Legi\u00e3o Urbana<\/strong>, atualmente, \u00e9 formado por <strong>Dado Villa Lobos<\/strong> e <strong>Marcelo Bonf\u00e1<\/strong>, ambos da forma\u00e7\u00e3o original, <strong>Andr\u00e9 Frateschi<\/strong>, <strong>Mauro Berman<\/strong>, <strong>Lucas Vasconcelos<\/strong> e <strong>Pedro Augusto<\/strong>.<\/p>\n<p>Durante a <strong>apresenta\u00e7\u00e3o musical<\/strong>, o p\u00fablico ir\u00e1 <strong>relembrar m\u00fasicas <\/strong>que fizeram <strong>sucesso<\/strong> e<strong> foram tocadas pela \u00faltima vez h\u00e1 25 anos, quando a banda chegou ao fim<\/strong>.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n<p><strong>As V Esta\u00e7\u00f5es com Legi\u00e3o Urbana<\/strong><br \/>DATA: 05 de julho<br \/>Local: Multiplan Hall, no Ribeir\u00e3oShopping<br \/>Funcionamento da bilheteria: 14h \u00e0s 22h<br \/>Abertura para o p\u00fablico: 19h30<\/p>\n<p>SAIBA MAIS <\/p>\n<p>Saiba quem \u00e9 a enfermeira do interior de SP que desapareceu por uma semana<\/p>\n<p><strong>FIQUE ON<\/strong><\/p>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Qual a diferen\u00e7a entre tornado e furac\u00e3o?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/show-com-integrantes-legiao-urbana-em-ribeirao-preto-tem-ingresso-solidario\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O show \u201cAs V Esta\u00e7\u00f5es com Legi\u00e3o Urbana\u201d, que acontece em Ribeir\u00e3o Preto, no dia 5 de julho est\u00e1 com lote de ingressos solid\u00e1rios. Os interessados ter\u00e3o 50% de desconto no valor do ingresso mediante a doa\u00e7\u00e3o de dois quilos de aveia ou dois litros de \u00f3leo de soja. O lote solid\u00e1rio \u00e9 v\u00e1lido &#8230; <a title=\"Show com integrantes do Legi\u00e3o Urbana em Ribeir\u00e3o Preto tem ingresso solid\u00e1rio\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/24\/show-com-integrantes-do-legiao-urbana-em-ribeirao-preto-tem-ingresso-solidario\/\" aria-label=\"Read more about Show com integrantes do Legi\u00e3o Urbana em Ribeir\u00e3o Preto tem ingresso solid\u00e1rio\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":54373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-54372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-11_2024-06-24_22-37-31.webp.webp?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-11_2024-06-24_22-37-31.webp.webp?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-11_2024-06-24_22-37-31.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-11_2024-06-24_22-37-31.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-11_2024-06-24_22-37-31.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-11_2024-06-24_22-37-31.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-11_2024-06-24_22-37-31.webp.webp?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-11_2024-06-24_22-37-31.webp.webp?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O show \u201cAs V Esta\u00e7\u00f5es com Legi\u00e3o Urbana\u201d, que acontece em Ribeir\u00e3o Preto, no dia 5 de julho est\u00e1 com lote de ingressos solid\u00e1rios. Os interessados ter\u00e3o 50% de desconto no valor do ingresso mediante a doa\u00e7\u00e3o de dois quilos de aveia ou dois litros de \u00f3leo de soja. O lote solid\u00e1rio \u00e9 v\u00e1lido&hellip;","jetpack-related-posts":[{"id":48964,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/show-do-titas-em-ribeirao-preto-tem-ingresso-solidario-para-ajudar-vitimas-das-chuvas-no-rs\/","url_meta":{"origin":54372,"position":0},"title":"Show do Tit\u00e3s em Ribeir\u00e3o Preto tem ingresso solid\u00e1rio para ajudar v\u00edtimas das chuvas no RS","author":"ismaelcolosi.com.br","date":"7 de May de 2024","format":false,"excerpt":"[ad_1] Em solidariedade \u00e0s v\u00edtimas das chuvas no Rio Grande do Sul, foi lan\u00e7ado nesta ter\u00e7a-feira (7), um lote solid\u00e1rio de ingressos para o show \u201cTit\u00e3s Microfonado\u201d, que acontece em Ribeir\u00e3o Preto. A apresenta\u00e7\u00e3o musical da banda de rock ser\u00e1 no s\u00e1bado (11), no Multiplan Hall, espa\u00e7o que fica dentro\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Titas-2024-credito-para-Dantas-Jr-Fotografia-68_2024-05-07_21-14-59_jpg_2024-05-07_21-15-00.webp.webp?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Titas-2024-credito-para-Dantas-Jr-Fotografia-68_2024-05-07_21-14-59_jpg_2024-05-07_21-15-00.webp.webp?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Titas-2024-credito-para-Dantas-Jr-Fotografia-68_2024-05-07_21-14-59_jpg_2024-05-07_21-15-00.webp.webp?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Titas-2024-credito-para-Dantas-Jr-Fotografia-68_2024-05-07_21-14-59_jpg_2024-05-07_21-15-00.webp.webp?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Titas-2024-credito-para-Dantas-Jr-Fotografia-68_2024-05-07_21-14-59_jpg_2024-05-07_21-15-00.webp.webp?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42549,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/15\/veja-quanto-custa-o-ingresso-para-o-show-do-dire-straits-legacy-em-ribeirao-preto\/","url_meta":{"origin":54372,"position":1},"title":"Veja quanto custa o ingresso para o show do Dire Straits Legacy em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"15 de March de 2024","format":false,"excerpt":"[ad_1] Os ingressos para o show da banda brit\u00e2nica Dire Straits Legacy em Ribeir\u00e3o Preto est\u00e3o sendo vendidos desde o dia 10 de mar\u00e7o. Para os f\u00e3s que queiram garantir presen\u00e7a no evento, os valores dos ingressos variam entre R$ 150 a R$ 2.800. A apresenta\u00e7\u00e3o internacional acontece na cidade\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710509090_DSL-Band-Credit-RON-ELKAM-USA-TODAY-NETWORK-scaled.jpg?fit=1200%2C688&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710509090_DSL-Band-Credit-RON-ELKAM-USA-TODAY-NETWORK-scaled.jpg?fit=1200%2C688&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710509090_DSL-Band-Credit-RON-ELKAM-USA-TODAY-NETWORK-scaled.jpg?fit=1200%2C688&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710509090_DSL-Band-Credit-RON-ELKAM-USA-TODAY-NETWORK-scaled.jpg?fit=1200%2C688&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710509090_DSL-Band-Credit-RON-ELKAM-USA-TODAY-NETWORK-scaled.jpg?fit=1200%2C688&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":54454,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/25\/show-da-joss-stone-e-confirmado-em-ribeirao-preto-veja-quando\/","url_meta":{"origin":54372,"position":2},"title":"Show da Joss Stone \u00e9 confirmado em Ribeir\u00e3o Preto; Veja quando","author":"ismaelcolosi.com.br","date":"25 de June de 2024","format":false,"excerpt":"[ad_1] A cantora brit\u00e2nica Joss Stone vai se apresentar em Ribeir\u00e3o Preto no dia 21 de setembro, com o show da turn\u00ea Ellipsis Tour. A apresenta\u00e7\u00e3o ser\u00e1 realizada no Alcans Hall, antigo Quinta Linda. A venda dos ingressos come\u00e7a nesta quarta-feira (26), a partir das 10h, pelo site da Ticket\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-91_2024-06-22_00-08-25_png_2024-06-22_00-08-25.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-91_2024-06-22_00-08-25_png_2024-06-22_00-08-25.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-91_2024-06-22_00-08-25_png_2024-06-22_00-08-25.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-91_2024-06-22_00-08-25_png_2024-06-22_00-08-25.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-91_2024-06-22_00-08-25_png_2024-06-22_00-08-25.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40710,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/05\/joao-rock-divulga-line-up-com-lulu-santos-marina-sena-duda-beat-e-samuel-rosa-confira\/","url_meta":{"origin":54372,"position":3},"title":"Jo\u00e3o Rock divulga line-up com Lulu Santos, Marina Sena, Duda Beat e Samuel Rosa; Confira","author":"ismaelcolosi.com.br","date":"5 de March de 2024","format":false,"excerpt":"[ad_1] O Jo\u00e3o Rock anunciou nesta ter\u00e7a-feira (5) o line-up do festival de 2024 que conta com artistas como Emicida e Pitty, Lulu Santos, Marina Sena, Duda Beat, Ney Matogrosso, Maria Gad\u00fa, Samuel Rosa, Djavan, entre outros \u2013 veja a lista completa abaixo. O Jo\u00e3o Rock 2024 acontece no dia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__joao-rock.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__joao-rock.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__joao-rock.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__joao-rock.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__joao-rock.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3049,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/17\/drift-legiao-urbana-e-guilherme-de-sa-saiba-o-que-acontece-no-fim-de-semana-em-ribeirao\/","url_meta":{"origin":54372,"position":4},"title":"Drift, Legi\u00e3o Urbana e Guilherme de S\u00e1: Saiba o que acontece no fim de semana em Ribeir\u00e3o\u00a0","author":"ismaelcolosi.com.br","date":"17 de November de 2023","format":false,"excerpt":"[ad_1] O fim de semana em Ribeir\u00e3o Preto conta com diversas apresenta\u00e7\u00f5es de m\u00fasica, espet\u00e1culos nos teatros e atividades gratuitas. \u00a0 H\u00e1 a final do Campeonato Brasileiro de Drift, show com integrantes da Legi\u00e3o Urbana, tributo \u00e0 Rita Lee, Guilherme de S\u00e1, festival de hip hop, entre outros. CHORINHO NA\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/Pilotos-de-drift-em-acao-durante-a-temporada-em-2022-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/Pilotos-de-drift-em-acao-durante-a-temporada-em-2022-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/Pilotos-de-drift-em-acao-durante-a-temporada-em-2022-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/Pilotos-de-drift-em-acao-durante-a-temporada-em-2022-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":49854,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/13\/doce-maravilha-2024-ingresso-solidario-tera-parte-de-sua-verba-a-instituicoes-do-rio-grande-do-sul\/","url_meta":{"origin":54372,"position":5},"title":"Doce Maravilha 2024 &#8211; Ingresso solid\u00e1rio ter\u00e1 parte de sua verba a institui\u00e7\u00f5es do Rio Grande do Sul","author":"ismaelcolosi.com.br","date":"13 de May de 2024","format":false,"excerpt":"[ad_1] Ingresso solid\u00e1rio ter\u00e1 parte de sua\u00a0verba destinada a institui\u00e7\u00f5es do Rio Grande do Sul O festival Doce Maravilha, que acontece dias 25 e 26 de maio no Jockey Club, no Rio de Janeiro, apresenta os hor\u00e1rios dos shows. Mais de 40 artistas est\u00e3o confirmados nos dois palcos do evento,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/samuel-rosa.jpg?fit=1200%2C551&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/samuel-rosa.jpg?fit=1200%2C551&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/samuel-rosa.jpg?fit=1200%2C551&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/samuel-rosa.jpg?fit=1200%2C551&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/samuel-rosa.jpg?fit=1200%2C551&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-e8Y","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54372"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/54373"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}