{"id":54170,"date":"2024-06-21T23:47:38","date_gmt":"2024-06-22T02:47:38","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/21\/usp-inscricoes-abertas-para-concurso-com-salario-de-r-15-mil\/"},"modified":"2024-06-21T23:47:38","modified_gmt":"2024-06-22T02:47:38","slug":"usp-inscricoes-abertas-para-concurso-com-salario-de-r-15-mil","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/21\/usp-inscricoes-abertas-para-concurso-com-salario-de-r-15-mil\/","title":{"rendered":"USP: inscri\u00e7\u00f5es abertas para concurso com sal\u00e1rio de R$ 15 mil"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>A Universidade de S\u00e3o Paulo (USP), por meio do Instituto de Ci\u00eancias Matem\u00e1ticas e Computa\u00e7\u00e3o, anunciou a abertura de inscri\u00e7\u00f5es para um concurso p\u00fablico. Este concurso visa preencher uma vaga para o cargo de professor doutor, especializado em geometria e topologia.<\/p>\n<p>Os profissionais contratados para esta posi\u00e7\u00e3o receber\u00e3o uma remunera\u00e7\u00e3o mensal de R$ 15.498,97. Os interessados devem se inscrever exclusivamente pela internet. O per\u00edodo de inscri\u00e7\u00f5es inicia-se \u00e0s 8h30 do dia 1\u00ba de julho e termina \u00e0s 16h30 do dia 29 de agosto, considerando o hor\u00e1rio de Bras\u00edlia \u2013 DF. As inscri\u00e7\u00f5es podem ser realizadas diretamente no site oficial da USP.<\/p>\n<p>Para a classifica\u00e7\u00e3o dos candidatos, o processo seletivo inclui tr\u00eas etapas: uma prova escrita, um julgamento de memorial e uma prova did\u00e1tica. Estas etapas foram desenvolvidas para avaliar a capacidade acad\u00eamica e a experi\u00eancia dos candidatos na \u00e1rea de geometria e topologia.<\/p>\n<p>Informa\u00e7\u00f5es adicionais e detalhes sobre o processo seletivo, incluindo os crit\u00e9rios de avalia\u00e7\u00e3o e o conte\u00fado program\u00e1tico, podem ser obtidos no edital completo dispon\u00edvel no site da USP. Esta \u00e9 uma excelente oportunidade para profissionais qualificados ingressarem em uma das mais prestigiadas universidades do pa\u00eds e contribu\u00edrem para o avan\u00e7o do conhecimento em suas \u00e1reas de especializa\u00e7\u00e3o.<\/p>\n<p>Para se inscrever: <strong><a href=\"http:\/\/diariooficial.imprensaoficial.com.br\/nav_v6\/index.asp?c=34946&amp;e=20240620&amp;p=1\" target=\"_blank\" rel=\"noopener\">[Clique aqui]<\/a><\/strong><\/p>\n<h2>Veduca &#8211; Cursos online gratuitos de professores USP e outras institui\u00e7\u00f5es renomadas\u00a0<\/h2>\n<p>O Veduca \u00e9 um site que j\u00e1 ultrapassou mais de 4 milh\u00f5es de alunos e oferece cursos online gratuitos com professores da USP e profissionais de mercado. S\u00e3o cursos que far\u00e3o a diferen\u00e7a na sua carreira, pois combinam conceitos fundamentais dos mais diferentes assuntos com exemplos pr\u00e1ticos e depoimentos.<\/p>\n<ol>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/ingles\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Ingl\u00eas: <\/strong><\/a>compreende os conceitos essenciais do ingl\u00eas, voc\u00ea ir\u00e1 aprender sobre o verbo to be, dias da semana, n\u00fameros, continentes, pa\u00edses, nacionalidades, vocabul\u00e1rio, frases, adjetivos, sentimentos, imperativo e at\u00e9 sobre empregos.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/fundamentos-de-administracao\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Fundamentos da Administra\u00e7\u00e3o:<\/strong><\/a>\u00a0voc\u00ea ir\u00e1 aprender conceitos e metodologias para colocar na pr\u00e1tica o melhor da fun\u00e7\u00e3o administrativa, planejamento, organiza\u00e7\u00e3o, dire\u00e7\u00e3o e controle, casos de sucesso no Brasil, no mundo e muito mais.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/gestao-de-projetos\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Gest\u00e3o de Projetos:<\/strong><\/a>\u00a0nesse curso, voc\u00ea aprender\u00e1 gest\u00e3o de stakeholders. Como administrar o escopo de um projeto. M\u00e9todos de an\u00e1lise de um projeto. Como fazer um planejamento excelente.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/engenharia-economica\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Engenharia Econ\u00f4mica:<\/strong><\/a>\u00a0voc\u00ea ir\u00e1 aprender sobre juros.Taxa de mercado. Dinheiro no tempo. Sistema de amortiza\u00e7\u00e3o de financiamento. Payback e VPL. Taxa interna de retorno.Op\u00e7\u00f5es e fechamento. Estimativa do custo de capital. Modelando um projeto de gera\u00e7\u00e3o de energia e\u00f3lica.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/gestao-da-inovacao\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Gest\u00e3o da Inova\u00e7\u00e3o:<\/strong><\/a>\u00a0voc\u00ea aprender\u00e1 sobre o\u00a0que \u00e9 inova\u00e7\u00e3o, princ\u00edpios da criatividade, financiamento de ideias, lean startup, gerenciamento de incertezas.<\/li>\n<p>&#13;<\/p>\n<li><strong><a href=\"https:\/\/veduca.org\/courses\/desenvolvimento-de-produtos-e-servicos\/?ref=artigo\" target=\"_blank\" rel=\"noopener\">Desenvolvimento de Produtos e Servi\u00e7os:<\/a>\u00a0<\/strong>A cria\u00e7\u00e3o de um novo produto ou servi\u00e7o requer estrat\u00e9gia, organiza\u00e7\u00e3o e planejamento. Saiba neste curso quais as etapas, atividades e m\u00e9todos para desenvolver novos produtos e servi\u00e7os desde a sua concep\u00e7\u00e3o at\u00e9 o primeiro contato com o cliente.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/eletromagnetismo\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Eletromagnetismo:<\/strong><\/a>\u00a0O curso online gratuito compreende os conceitos b\u00e1sicos de eletromagnetismo, o conceito de cargas e de como elas interagem entre si, o movimento de carga denominado corrente el\u00e9trica, as leis b\u00e1sicas da corrente el\u00e9trica, o circuito onde elas percorrem e o conceito de magnetismo. O objetivo do curso \u00e9 mostrar a conex\u00e3o entre a eletricidade e o magnetismo em uma unifica\u00e7\u00e3o atrav\u00e9s das equa\u00e7\u00f5es de Maxwell.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/fisica-basica\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>F\u00edsica B\u00e1sica:<\/strong><\/a>\u00a0O curso online de F\u00edsica B\u00e1sica, ministrado pelo professor doutor Vanderlei Salvador Bagnato, traz um estudo te\u00f3rico e pr\u00e1tico sobre o movimento, as leis de Newton, energia, a evolu\u00e7\u00e3o no tempo e seus deslocamentos sob a a\u00e7\u00e3o de for\u00e7as e seus efeitos subsequentes sobre seu ambiente. O curso traz uma vis\u00e3o aprofundada e precisa, com descri\u00e7\u00e3o das fun\u00e7\u00f5es matem\u00e1ticas da f\u00edsica, seu prop\u00f3sito e aplica\u00e7\u00e3o, com exemplos trazidos do mundo real.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/gestao-ambiental\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Gest\u00e3o Ambiental:<\/strong><\/a>\u00a0Conhec\u0327a os fundamentos que orientam a implementac\u0327a\u0303o de poli\u0301ticas de meio ambiente e sistemas de gesta\u0303o ambiental no contexto da gesta\u0303o da sustentabilidade empresarial. Entenda como acontecem as relac\u0327o\u0303es entre as esferas pu\u0301blica e privada da gesta\u0303o ambiental no Brasil.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/medicina-do-sono\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Medicina do Sono:<\/strong><\/a>\u00a0O curso online gratuito trata de diversos aspectos relacionado ao sono. Com uma vis\u00e3o cient\u00edfica e psicol\u00f3gica, o curso aborda os principais transtornos do sono, com enfoque pr\u00e1tico para os interessados na \u00e1rea da medicina do sono. O curso \u00e9 voltado para estudantes de medicina, fisioterapia, enfermagem e toda \u00e1rea de ci\u00eancias biol\u00f3gicas, al\u00e9m das pessoas que se interessam em entender os transtornos do sono, fen\u00f4meno que afeta mais de 33% da popula\u00e7\u00e3o.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/ecoinovacao\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Ecoinova\u00e7\u00e3o:<\/strong><\/a>\u00a0Neste curso voc\u00ea ver\u00e1 conte\u00fados relacionados a sustentabilidade e gest\u00e3o ambiental, ser\u00e1 abordado alguns conceitos e aplica\u00e7\u00f5es para a \u00e1rea de engenharia e inova\u00e7\u00e3o. Entre os assuntos discutidos est\u00e3o as \u201cpegadas ecol\u00f3gicas\u201d, gest\u00e3o e avalia\u00e7\u00e3o do ciclo de vida e novas tecnologias em energia.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/coronavirus\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Coronav\u00edrus:<\/strong><\/a>\u00a0Este curso, produzido pela Faculdade de Medicina de Ribeir\u00e3o Preto USP e disponibilizado gratuitamente pelo Veduca, tem como objetivo informar toda a SOCIEDADE sobre a pandemia do coronav\u00edrus (SARS-CoV-2). O Brasil est\u00e1 reduzindo suas atividades e todos devemos saber o PORQU\u00ca que essas medidas s\u00e3o necess\u00e1rias e COMO podemos contribuir para minimizar a dissemina\u00e7\u00e3o da doen\u00e7a no pa\u00eds. S\u00e3o quatro m\u00f3dulos curtos e bem simples. Esperamos que este curso ajude voc\u00ea a entender melhor o que est\u00e1 acontecendo, sendo uma fonte segura e confi\u00e1vel de informa\u00e7\u00e3o sobre o coronav\u00edrus para seus amigos, familiares e contatos.<\/li>\n<p>&#13;<\/p>\n<li><strong><a href=\"https:\/\/veduca.org\/courses\/ecologia-industrial\/?ref=artigo\" target=\"_blank\" rel=\"noopener\">Ecologia Industrial<\/a>:<\/strong>\u00a0Neste curso apresentamos a defini\u00e7\u00e3o do conceito de P+L (Produ\u00e7\u00e3o Mais Limpa) e o roteiro para a sua aplica\u00e7\u00e3o e seus indicadores de desempenho numa empresa. Ao final do curso voc\u00ea ter\u00e1 uma vis\u00e3o n\u00e3o apenas da Ecologia Industrial, mas de alternativas para desenvolver processos produtivos mais limpos.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/metodologia-cientifica\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Metodologia Cient\u00edfica:<\/strong><\/a>\u00a0Metodologia cient\u00edfica \u00e9 um conjunto de t\u00e9cnicas e processos empregados para a pesquisa e a formula\u00e7\u00e3o de uma produ\u00e7\u00e3o cient\u00edfica. Aprenda a elaborar um trabalho de conclus\u00e3o de curso (TCC), e saiba como selecionar um tema, definir objetivos, identificar e descrever um problema, fundamentar sua argumenta\u00e7\u00e3o com base em trabalhos de outros autores, coletar e analisar dados e como apresentar resultados e conclus\u00f5es de forma concisa e clara.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/probabilidade-e-estatistica\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Probabilidade e Estat\u00edstica:<\/strong><\/a>\u00a0Neste curso online gratuito voc\u00ea ver\u00e1 como o c\u00e1lculo de probabilidade \u00e9 uma importante ferramenta estat\u00edstica e como trata de situa\u00e7\u00f5es que n\u00e3o s\u00e3o totalmente previs\u00edveis. Esse conhecimento \u00e9 fundamental para interpretar resultados obtidos pelos m\u00e9todos estat\u00edsticos e pode ser aplicado de diversas formas no dia a dia.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/planejamento-estrategico\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>Planejamento Estrat\u00e9gico:<\/strong><\/a>\u00a0voc\u00ea ir\u00e1 aprender conceitos e ferramentas da estrat\u00e9gia empresarial para utiliz\u00e1-los em suas organiza\u00e7\u00f5es, construindo um planejamento estrat\u00e9gico de neg\u00f3cio adequado a din\u00e2mica do mercado em que se encontram e um acompanhamento alinhado com as ferramentas de gest\u00e3o mais utilizadas.<\/li>\n<p>&#13;<\/p>\n<li><a href=\"https:\/\/veduca.org\/courses\/lgbtqia-conceitos-e-historias\/?ref=artigo\" target=\"_blank\" rel=\"noopener\"><strong>LGBTQIA+ Conceitos e Hist\u00f3rias:<\/strong><\/a>\u00a0O curso oferece uma vis\u00e3o geral sobre quest\u00f5es que envolvem a sexualidade humana e a identidade de g\u00eanero. S\u00e3o apresentados conceitos e informa\u00e7\u00f5es sobre quatro caracter\u00edsticas \u2013 Sexo Biol\u00f3gico, Identidade de G\u00eanero, Express\u00e3o de G\u00eanero e Orienta\u00e7\u00e3o Afetivo-sexual \u2013 e tamb\u00e9m sobre o significado da sigla LGBT+. As hist\u00f3rias de vida s\u00e3o um convite para que voc\u00ea amplie seu olhar de mundo. Esses v\u00eddeos contam com a participa\u00e7\u00e3o de colaboradores do Veduca, da Serasa e tamb\u00e9m de convidados e convidadas que compartilham suas experi\u00eancias e vis\u00f5es.<\/li>\n<p>&#13;\n<\/ol>\n<h2>Inscri\u00e7\u00e3o Cursos Online Gratuitos Veduca<\/h2>\n<p>Para se inscrever nos cursos da Veduca:\u00a0<span style=\"color: #008080;\"><strong><a style=\"color: #008080;\" href=\"https:\/\/veduca.org\/?ref=artigo\" target=\"_blank\" rel=\"noopener noreferrer\">[Acesse aqui]<\/a><\/strong><\/span><\/p>\n<p><!-- CONTENT END 1 --><\/p>\n<p><!-- #comments --><\/p>\n<\/div>\n<p><script>\n                    (function(d, s, id) {\n                        var js, fjs = d.getElementsByTagName(s)[0];\n                        if (d.getElementById(id)) return;\n                        js = d.createElement(s);\n                        js.id = id;\n                        js.src = \"\/\/connect.facebook.net\/pt_PT\/sdk.js#xfbml=1&version=v2.5\";\n                        fjs.parentNode.insertBefore(js, fjs);\n                    }(document, 'script', 'facebook-jssdk'));\n                <\/script><script type=\"text\/javascript\">\n\t    (function(d){\n\t        var js, id = 'facebook-jssdk', ref = d.getElementsByTagName('script')[0];\n\t        if (d.getElementById(id)) {return;}\n\t        js = d.createElement('script'); js.id = id; js.async = true;\n\t        js.src = \"https:\/\/connect.facebook.net\/en_US\/all.js\";\n\t        ref.parentNode.insertBefore(js, ref);\n\t    }(document));\n\t    window.fbAsyncInit = function() {\n\t      \t\tFB.init({\n\t            \tappId: facebook_app_ID,\n\t            \tstatus: true,\n\t            \tcookie: true,\n\t            \txfbml: true\n\t        \t});  \n\t    };\n\t\tfunction login() {\n\t\t\tFB.login(function(response) {\n\t\t\t\tFB.api('\/me', { locale: 'en_US', fields: 'name, email' },\n\t\t\t\t\tfunction(response2) {\n\t\t\t\t\t\tif (typeof response2.error == 'undefined') {\n\t\t\t\t\t\t\tjQuery(document).ready(function($){'use strict';\n      \t\t\t\t\t\/\/console.log(response2);\n\t\t\t\t\t\t\t\t$.ajax({\n\t\t\t\t\t\t\t        type: 'POST',\n\t\t\t\t\t\t\t        dataType: 'json',\n\t\t\t\t\t\t\t        url: ajax_object.ajaxurl,\n\t\t\t\t\t\t\t        data: { \n\t\t\t\t\t\t\t            'action': 'ajaxfacebooklogin', \/\/calls wp_ajax_nopriv_ajaxlogin\n\t\t\t\t\t\t\t            'id_token': response.authResponse.accessToken,\n\t\t\t\t\t\t\t            'useremail': response2.email,\n\t\t\t\t\t\t\t            'username': response2.name,\n\t\t\t\t\t\t\t            'security': $( 'form#login #security2').val() },\n\t\t\t\t\t\t\t        success: function(data){\n\t\t\t\t\t\t\t            \/\/$('form#login div.login-error').text(data.message);\n\t\t\t\t\t\t\t            if (data.loggedin == true){\n      \t\t\t\t\t\t\t\t\t\t\t\t$('form#login div.login-error').removeClass('alert-danger').addClass('alert-success');\n      \t\t\t\t\t\t\t\t\t\t\t\t$('form#login div.login-error').text(data.message);\n\t\t\t\t\t\t\t                document.location.href = ajax_object.redirecturl;\n\t\t\t\t\t\t\t            }else{\n      \t\t\t\t\t\t\t\t\t\t\t\t$('form#login div.login-error').removeClass('alert-success').addClass('alert-danger');\n      \t\t\t\t\t\t\t\t\t\t\t\t$('form#login div.login-error').text(data.message);\n      \t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t            if($('.login-error').text() == ''){\n\t\t\t\t\t\t\t                $('form#login div.login-error').hide();\n\t\t\t\t\t\t\t            }else{\n\t\t\t\t\t\t\t                $('form#login div.login-error').show();\n\t\t\t\t\t\t\t            }\n\t\t\t\t\t\t\t        }\n\t\t\t\t\t\t\t    });\n\t\t\t\t\t\t    });\n\t\t\t\t\t\t\t\/\/ console.log('FB Login Working!');\n\t\t\t\t\t\t\t\/\/ console.log(response2);\n\t\t\t\t\t\t}else{\n\t\t\t\t\t\t\t\/\/ console.log('FB Login Error!');\n\t\t\t\t\t\t\t\/\/ console.log(response);\n\t\t\t\t\t\t}\n\t\t\t\t\t}\n\t\t\t\t);\n\t\t\t}, {scope: 'public_profile,user_friends,email'});    \n\t\t}\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/veduca.org\/usp-inscricoes-abertas-para-concurso-com-salario-de-r-15-mil\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Universidade de S\u00e3o Paulo (USP), por meio do Instituto de Ci\u00eancias Matem\u00e1ticas e Computa\u00e7\u00e3o, anunciou a abertura de inscri\u00e7\u00f5es para um concurso p\u00fablico. Este concurso visa preencher uma vaga para o cargo de professor doutor, especializado em geometria e topologia. Os profissionais contratados para esta posi\u00e7\u00e3o receber\u00e3o uma remunera\u00e7\u00e3o mensal de R$ 15.498,97. &#8230; <a title=\"USP: inscri\u00e7\u00f5es abertas para concurso com sal\u00e1rio de R$ 15 mil\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/21\/usp-inscricoes-abertas-para-concurso-com-salario-de-r-15-mil\/\" aria-label=\"Read more about USP: inscri\u00e7\u00f5es abertas para concurso com sal\u00e1rio de R$ 15 mil\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":54171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3598],"tags":[],"class_list":["post-54170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empregos-classificados-vagas-trabalho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/usp-concurso-15-mil.webp.webp?fit=1220%2C674&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/usp-concurso-15-mil.webp.webp?fit=1220%2C674&ssl=1",1220,674,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/usp-concurso-15-mil.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/usp-concurso-15-mil.webp.webp?fit=300%2C166&ssl=1",300,166,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/usp-concurso-15-mil.webp.webp?fit=768%2C424&ssl=1",768,424,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/usp-concurso-15-mil.webp.webp?fit=1024%2C566&ssl=1",1024,566,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/usp-concurso-15-mil.webp.webp?fit=1220%2C674&ssl=1",1220,674,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/usp-concurso-15-mil.webp.webp?fit=1220%2C674&ssl=1",1220,674,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Universidade de S\u00e3o Paulo (USP), por meio do Instituto de Ci\u00eancias Matem\u00e1ticas e Computa\u00e7\u00e3o, anunciou a abertura de inscri\u00e7\u00f5es para um concurso p\u00fablico. Este concurso visa preencher uma vaga para o cargo de professor doutor, especializado em geometria e topologia. Os profissionais contratados para esta posi\u00e7\u00e3o receber\u00e3o uma remunera\u00e7\u00e3o mensal de R$ 15.498,97.&hellip;","jetpack-related-posts":[{"id":41817,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/abertas-inscricoes-para-concurso-publico-da-usp-veja-as-vagas\/","url_meta":{"origin":54170,"position":0},"title":"Abertas inscri\u00e7\u00f5es para concurso p\u00fablico da USP; veja as vagas","author":"ismaelcolosi.com.br","date":"11 de March de 2024","format":false,"excerpt":"[ad_1] As inscri\u00e7\u00f5es para os concursos p\u00fablicos da USP (Universidade de S\u00e3o Paulo) abriram ao meio-dia desta segunda-feira (11). As oportunidades para os diversos segmentos (veja abaixo) s\u00e3o para os campi da universidade na capital e no interior de S\u00e3o Paulo, incluindo Ribeir\u00e3o Preto e S\u00e3o Carlos. Ao todo, s\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/3-4.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/3-4.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/3-4.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/3-4.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/3-4.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41474,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/08\/veja-como-fazer-a-inscricao-no-concurso-publico-da-usp-ha-vagas-em-ribeirao\/","url_meta":{"origin":54170,"position":1},"title":"Veja como fazer a inscri\u00e7\u00e3o no concurso p\u00fablico da USP; H\u00e1 vagas em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"8 de March de 2024","format":false,"excerpt":"[ad_1] As inscri\u00e7\u00f5es para o concurso p\u00fablico da USP (Universidade de S\u00e3o Paulo) com 49 vagas de n\u00edvel superior come\u00e7am na pr\u00f3xima segunda-feira (11) e seguem at\u00e9 o dia 11 de abril. H\u00e1 vagas para o campus de Ribeir\u00e3o Preto. Os sal\u00e1rios para as fun\u00e7\u00f5es variam entre R$ 5,4 mil\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/CAMPUS-DA-USP-DE-RIBEIRAO-PRETO-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/CAMPUS-DA-USP-DE-RIBEIRAO-PRETO-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/CAMPUS-DA-USP-DE-RIBEIRAO-PRETO-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/CAMPUS-DA-USP-DE-RIBEIRAO-PRETO-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":61335,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/21\/usp-ribeirao-preto-abre-concurso-publico-com-salarios-de-r-15-mil-saiba-como-participar\/","url_meta":{"origin":54170,"position":2},"title":"USP Ribeir\u00e3o Preto abre concurso p\u00fablico com sal\u00e1rios de R$ 15 mil; Saiba como participar","author":"ismaelcolosi.com.br","date":"21 de August de 2024","format":false,"excerpt":"[ad_1] A\u00a0USP (Universidade de S\u00e3o Paulo), por meio da Faculdade de Medicina de Ribeir\u00e3o Preto, anunciou nesta quarta-feira a realiza\u00e7\u00e3o de um novo concurso p\u00fablico destinado \u00e0 contrata\u00e7\u00e3o de Professor Doutor, a fim de atuar nos seguintes departamentos: Puericultura e Pediatria, Gen\u00e9tica e Cirurgia e Anatomia. O sal\u00e1rio \u00e9 de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/USPRibeiroPretoabreconcursopblicocomsalriosdeR14mil_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/USPRibeiroPretoabreconcursopblicocomsalriosdeR14mil_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/USPRibeiroPretoabreconcursopblicocomsalriosdeR14mil_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/USPRibeiroPretoabreconcursopblicocomsalriosdeR14mil_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/USPRibeiroPretoabreconcursopblicocomsalriosdeR14mil_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":64557,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/08\/inscricoes-para-concurso-do-hc-ribeirao-com-salarios-de-ate-r-56-mil-terminam-nesta-segunda-feira\/","url_meta":{"origin":54170,"position":3},"title":"Inscri\u00e7\u00f5es para concurso do HC Ribeir\u00e3o com sal\u00e1rios de at\u00e9 R$ 5,6 mil terminam nesta segunda-feira","author":"ismaelcolosi.com.br","date":"8 de September de 2024","format":false,"excerpt":"[ad_1] As inscri\u00e7\u00f5es para o concursos p\u00fablico de n\u00edvel superior do Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto (HC-RP) terminam nesta segunda-feira (9). Os sal\u00e1rios variam de R$ 2,7 mil a R$ 5,6 mil. As oportunidades s\u00e3o para os cargos de m\u00e9dico ortopedista e traumatologia, terapeuta ocupacional e fisioterapeuta. As jornadas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-10_20-51-42_jpg_2024-05-10_20-51-42.webp.webp?fit=830%2C371&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-10_20-51-42_jpg_2024-05-10_20-51-42.webp.webp?fit=830%2C371&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-10_20-51-42_jpg_2024-05-10_20-51-42.webp.webp?fit=830%2C371&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-10_20-51-42_jpg_2024-05-10_20-51-42.webp.webp?fit=830%2C371&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31666,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/23\/cursinho-pre-vestibular-da-usp-ribeirao-esta-com-inscricoes-abertas-saiba-como-participar\/","url_meta":{"origin":54170,"position":4},"title":"Cursinho pr\u00e9-vestibular da USP Ribeir\u00e3o est\u00e1 com inscri\u00e7\u00f5es abertas; Saiba como participar","author":"ismaelcolosi.com.br","date":"23 de January de 2024","format":false,"excerpt":"[ad_1] Est\u00e3o abertas as inscri\u00e7\u00f5es para o cursinho popular da Faculdade de Ci\u00eancias Farmac\u00eauticas de Ribeir\u00e3o Preto (FCFRP) da USP (Universidade de S\u00e3o Paulo). As aulas s\u00e3o oferecidas de maneira extensiva e completamente gratuita. Podem participar da sele\u00e7\u00e3o estudantes que conclu\u00edram o ensino m\u00e9dio ou ainda est\u00e3o cursando, desde que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/escrevendo_aluno_1200x675_30062022170131.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/escrevendo_aluno_1200x675_30062022170131.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/escrevendo_aluno_1200x675_30062022170131.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/escrevendo_aluno_1200x675_30062022170131.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/escrevendo_aluno_1200x675_30062022170131.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59526,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/09\/usp-ribeirao-preto-tem-concurso-publico-com-salarios-de-r-15-mil-2\/","url_meta":{"origin":54170,"position":5},"title":"USP Ribeir\u00e3o Preto tem concurso p\u00fablico com sal\u00e1rios de R$ 15 mil","author":"ismaelcolosi.com.br","date":"9 de August de 2024","format":false,"excerpt":"[ad_1] A FEA-RP (Faculdade de Economia, Administra\u00e7\u00e3o e Contabilidade de Ribeir\u00e3o Preto) da USP (Universidade de S\u00e3o Paulo) est\u00e1 com as inscri\u00e7\u00f5es abertas para o concurso p\u00fablico de professor doutor. Os sal\u00e1rios para o cargo s\u00e3o de R$ 15.498,97. O profissional vai atuar na \u00e1rea de teoria econ\u00f4mica no departamento\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/fea-usp-ribeirao-preto.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/fea-usp-ribeirao-preto.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/fea-usp-ribeirao-preto.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/fea-usp-ribeirao-preto.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/fea-usp-ribeirao-preto.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-e5I","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54170"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/54171"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}