{"id":53719,"date":"2024-06-19T07:17:30","date_gmt":"2024-06-19T10:17:30","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/19\/aniversario-de-ribeirao-preto-entenda-a-importancia-do-agronegocio-para-a-cidade\/"},"modified":"2024-06-19T07:17:30","modified_gmt":"2024-06-19T10:17:30","slug":"aniversario-de-ribeirao-preto-entenda-a-importancia-do-agronegocio-para-a-cidade","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/19\/aniversario-de-ribeirao-preto-entenda-a-importancia-do-agronegocio-para-a-cidade\/","title":{"rendered":"Anivers\u00e1rio de Ribeir\u00e3o Preto: Entenda a import\u00e2ncia do agroneg\u00f3cio para a cidade"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Reconhecida como <strong>a<\/strong><span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><strong> \u201cCapital Brasileira do Agroneg\u00f3cio\u201d h\u00e1 20 anos<\/strong>, <strong>Ribeir\u00e3o Preto<\/strong><\/mark><\/span> tem <strong>papel fundamental para o setor no \u00e2mbito nacional<\/strong>, tornando-se <strong>um dos polos mais importantes<\/strong> de <strong>agroind\u00fastria<\/strong> do Pa\u00eds devido a <strong>produtividade<\/strong> e <strong>inova\u00e7\u00e3o<\/strong>.<\/p>\n<p>Com a popula\u00e7\u00e3o de <strong>698.642 habitantes<\/strong> e uma \u00e1rea territorial de 650.916 km\u00b2, de acordo com o \u00faltimo Censo do IBGE, a regi\u00e3o<span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">, que inicialmente <strong>tinha como principal atividade agr\u00edcola a produ\u00e7\u00e3o de caf\u00e9<\/strong>, atualmente tem a <strong>cana-de-a\u00e7\u00facar<\/strong> como <strong>predominante<\/strong> em planta\u00e7\u00f5es, sendo o <strong>principal produto agr\u00edcola regional<\/strong>.<\/mark><\/span><\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<h4 class=\"wp-block-heading\"><strong>Veja a import\u00e2ncia em n\u00fameros<\/strong><\/h4>\n<p>Segundo \u00faltimos<strong> dados<\/strong> divulgados pela<strong> Secretaria de Agricultura e Abastecimento de S\u00e3o Paulo<\/strong>, <strong>Ribeir\u00e3o Preto possui uma produ\u00e7\u00e3o agr\u00edcola de cana-de-a\u00e7\u00facar avaliada em R$ 4,9 bilh\u00f5es<\/strong>. Em 2022, foram produzidos 25 milh\u00f5es de toneladas de cana para a ind\u00fastria, em uma<strong> \u00e1rea de 336 mil hectares<\/strong>.<\/p>\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/11_2024-06-14_19-56-22_jpg_2024-06-14_19-56-23-1024x576.webp?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-84569\" srcset=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/11_2024-06-14_19-56-22_jpg_2024-06-14_19-56-23-1024x576.webp 1024w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/11_2024-06-14_19-56-22_jpg_2024-06-14_19-56-23-300x169.webp 300w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/11_2024-06-14_19-56-22_jpg_2024-06-14_19-56-23-768x432.webp 768w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/11_2024-06-14_19-56-22_jpg_2024-06-14_19-56-23-1536x864.webp 1536w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/11_2024-06-14_19-56-22_jpg_2024-06-14_19-56-23-696x392.webp 696w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/11_2024-06-14_19-56-22_jpg_2024-06-14_19-56-23-1068x601.webp 1068w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/11_2024-06-14_19-56-22_jpg_2024-06-14_19-56-23.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"\/><figcaption class=\"wp-element-caption\">Foto: Acervo EP<\/figcaption><\/figure>\n<p>Contudo, <strong>n\u00e3o \u00e9 s\u00f3 cana-de-a\u00e7\u00facar que a regi\u00e3o produz<\/strong>. Pelo VBP (Valor Bruto de Produ\u00e7\u00e3o), a <strong>lista<\/strong> segue com a <strong>produ\u00e7\u00e3o de carne bovina<\/strong> (R$ 469,2 milh\u00f5es) e <strong>caf\u00e9<\/strong> beneficiado (R$ 466,7 milh\u00f5es).<\/p>\n<p>Dados do IEA (Instituto de Economia Agr\u00edcola), mostram que <strong><span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Ribeir\u00e3o Preto est\u00e1 em 12\u00ba lugar no ranking pelo valor da produ\u00e7\u00e3o agr\u00edcola total do estado, com R$ 7,5 bilh\u00f5es<\/mark><\/span><\/strong>.<\/p>\n<p>Pela Funda\u00e7\u00e3o <strong>Seade<\/strong>, a <strong>regi\u00e3o administrativa de Ribeir\u00e3o Preto<\/strong> corresponde a <strong>2,6% do PIB do estado<\/strong>. Em <strong>2023<\/strong>, o <strong>indicador da cidade<\/strong> foi de R$ <strong>82 milh\u00f5es<\/strong>, j\u00e1 o do Estado de S\u00e3o Paulo, R$ 3,2 trilh\u00f5es. A <strong>agropecu\u00e1ria<\/strong>, no ano passado, representou <strong>2% do estado<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Gera\u00e7\u00e3o de emprego<\/strong><\/h4>\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/WhatsApp-Image-2024-06-17-at-15.41.43_2024-06-17_18-42-39_jpeg_2024-06-17_18-42-39-1024x576.webp?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-84782\" srcset=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/WhatsApp-Image-2024-06-17-at-15.41.43_2024-06-17_18-42-39_jpeg_2024-06-17_18-42-39-1024x576.webp 1024w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/WhatsApp-Image-2024-06-17-at-15.41.43_2024-06-17_18-42-39_jpeg_2024-06-17_18-42-39-300x169.webp 300w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/WhatsApp-Image-2024-06-17-at-15.41.43_2024-06-17_18-42-39_jpeg_2024-06-17_18-42-39-768x432.webp 768w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/WhatsApp-Image-2024-06-17-at-15.41.43_2024-06-17_18-42-39_jpeg_2024-06-17_18-42-39-696x392.webp 696w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/WhatsApp-Image-2024-06-17-at-15.41.43_2024-06-17_18-42-39_jpeg_2024-06-17_18-42-39-1068x601.webp 1068w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/WhatsApp-Image-2024-06-17-at-15.41.43_2024-06-17_18-42-39_jpeg_2024-06-17_18-42-39.webp 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"\/><figcaption class=\"wp-element-caption\">Foto: Acervo EP<\/figcaption><\/figure>\n<p>Tendo a <strong>cana-de-a\u00e7\u00facar<\/strong> como <strong>principal atividade agr\u00edcola<\/strong>, <span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><strong>Ribeir\u00e3o Preto<\/strong> pode ser <strong>considerada<\/strong> tamb\u00e9m a <strong>maior regi\u00e3o do mundo em concentra\u00e7\u00e3o por hectare de cana, a\u00e7\u00facar e etanol produzidos<\/strong><\/mark><\/span>. <\/p>\n<p>Ao todo, <strong>na regi\u00e3o s\u00e3o 30 usinas instaladas<\/strong>. Com isso, <strong><span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">80 mil empregos diretos s\u00e3o gerados por ano<\/mark><\/span><\/strong>, segundo dados da Unica (Uni\u00e3o da Ind\u00fastria de Cana-de-A\u00e7\u00facar e Bioenergia).<\/p>\n<h4 class=\"wp-block-heading\"><strong>Maior feria agr\u00edcola da Am\u00e9rica Latina<\/strong><\/h4>\n<p>A <strong>Agrishow<\/strong>, maior <strong>feira de agroneg\u00f3cio da Am\u00e9rica Latina<\/strong>, acontece em <strong>Ribeir\u00e3o Preto<\/strong> h\u00e1 <strong>mais de duas d\u00e9cadas<\/strong>. Este ano, o <strong>evento<\/strong> recebeu <strong>mais de 195 mil pessoas<\/strong> e gerou R$ 13,608 bilh\u00f5es em inten\u00e7\u00f5es de neg\u00f3cios em m\u00e1quinas e implementos agr\u00edcolas.<\/p>\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" width=\"659\" height=\"431\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/Capturar_2024-06-14_19-57-39_png_2024-06-14_19-57-39.webp?resize=659%2C431&#038;ssl=1\" alt=\"\" class=\"wp-image-84570\" srcset=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/Capturar_2024-06-14_19-57-39_png_2024-06-14_19-57-39.webp 659w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/Capturar_2024-06-14_19-57-39_png_2024-06-14_19-57-39-300x196.webp 300w\" sizes=\"auto, (max-width: 659px) 100vw, 659px\"\/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o Agrishow<\/figcaption><\/figure>\n<p>Al\u00e9m do valor em neg\u00f3cios, a<strong> Agrishow gerou cerca de 7 mil empregos diretos e indiretos<\/strong> na cidade e <strong>movimentou<\/strong> durante os dias da feira, <strong>cerca de R$ 500 milh\u00f5es<\/strong> na <strong>economia local<\/strong> e regional.<\/p>\n<p>O <strong>presidente da Agrishow<\/strong> e 1\u00ba vice-presidente do conselho de administra\u00e7\u00e3o da <strong>Abimaq<\/strong>, <strong>Jo\u00e3o Marchesan<\/strong>, destaca que Ribeir\u00e3o est\u00e1 estrategicamente localizada \u201cno cora\u00e7\u00e3o de uma das regi\u00f5es agr\u00edcolas mais produtivas do Brasil\u201d, um dos motivos que foi escolhida para sediar a Agrishow. Al\u00e9m disso, fala da import\u00e2ncia do setor para a cidade.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p class=\"has-text-align-left\">\u201cO agroneg\u00f3cio \u00e9 fundamental para a economia de Ribeir\u00e3o Preto e da regi\u00e3o. Este setor n\u00e3o apenas contribui significativamente para o PIB local, mas tamb\u00e9m \u00e9 respons\u00e1vel pela gera\u00e7\u00e3o de milhares de empregos diretos e indiretos. A cidade \u00e9 um importante polo de desenvolvimento e inova\u00e7\u00e3o tecnol\u00f3gica no campo agr\u00edcola, com v\u00e1rias empresas, centros de pesquisa e universidades dedicadas \u00e0 melhoria das pr\u00e1ticas agr\u00edcolas e ao desenvolvimento de novas tecnologias, consolidando Ribeir\u00e3o Preto como um centro de excel\u00eancia no agroneg\u00f3cio\u201d.<\/p>\n<p><cite>Jo\u00e3o Marchesan \u2013 presidente da Agrishow<\/cite><\/p><\/blockquote>\n<h4 class=\"wp-block-heading\"><strong>Inova\u00e7\u00e3o<\/strong><\/h4>\n<p>Outro <strong>destaque <\/strong>que o <strong>agroneg\u00f3cio proporciona a cidade<\/strong> \u00e9 a <strong>inova\u00e7\u00e3o e a concentra\u00e7\u00e3o<\/strong> de empresas consolidadas no pa\u00eds e no mundo, al\u00e9m de um polo de startups, o <strong>Supera Parque<\/strong>.<\/p>\n<p><strong>Ribeir\u00e3o Preto <\/strong>possui <strong>44 startups Agritechs<\/strong>, ou seja, que utilizam <strong>tecnologia de ponta <\/strong>para o desenvolvimento de<strong> produtos e servi\u00e7os na agricultura<\/strong>.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p class=\"has-text-align-left\">\u201cEssa concentra\u00e7\u00e3o de empresas e talentos fomenta um ambiente prop\u00edcio ao desenvolvimento econ\u00f4mico e \u00e0 inova\u00e7\u00e3o, criando um ambiente \u00fanico que beneficia todo o setor agr\u00edcola que n\u00e3o se v\u00ea em mais nenhum lugar do Brasil. Ribeir\u00e3o Preto continua a ser um centro de excel\u00eancia no agroneg\u00f3cio, onde tradi\u00e7\u00e3o e inova\u00e7\u00e3o caminham lado a lado, gerando desenvolvimento, emprego e progresso para nossa cidade e regi\u00e3o.\u201d<\/p>\n<p><cite><em>Wilson<\/em>\u00a0Fran\u00e7a Prado \u2013 secret\u00e1rio municipal de Inova\u00e7\u00e3o e Desenvolvimento <\/cite><\/p><\/blockquote>\n<h4 class=\"wp-block-heading\"><strong>Por que Capital Brasileira do Agroneg\u00f3cio?<\/strong><\/h4>\n<p>Em <strong>maio de 2004<\/strong>, <strong>Ribeir\u00e3o Preto<\/strong> que at\u00e9 ent\u00e3o <strong>era conhecida<\/strong> como a<strong> \u201cCapital do Caf\u00e9\u201d<\/strong>, recebeu o <strong><span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">t\u00edtulo de \u201cCapital Brasileira do Agroneg\u00f3cio\u201d<\/mark><\/span><\/strong>, em reconhecimento pela diversificada <strong>atividade agroindustrial <\/strong>da cidade.<\/p>\n<p>O t\u00edtulo em reconhecimento foi iniciativa da<strong> Abag-RP<\/strong> (Associa\u00e7\u00e3o Brasileira de Agribusiness de Ribeir\u00e3o Preto), <strong>Acirp<\/strong> (Associa\u00e7\u00e3o Comercial e Industrial de Ribeir\u00e3o Preto), <strong>Pensa-USP<\/strong> e <strong>Prefeitura de Ribeir\u00e3o<\/strong>.<\/p>\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/CENTRO-RIBEIRAO-PRETO-DRONE-Foto-Guilherme-Sircili-3_2024-06-14_20-03-55_jpg_2024-06-14_20-03-58-1024x768.webp?resize=1024%2C768&#038;ssl=1\" alt=\"\" class=\"wp-image-84571\" srcset=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/CENTRO-RIBEIRAO-PRETO-DRONE-Foto-Guilherme-Sircili-3_2024-06-14_20-03-55_jpg_2024-06-14_20-03-58-1024x768.webp 1024w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/CENTRO-RIBEIRAO-PRETO-DRONE-Foto-Guilherme-Sircili-3_2024-06-14_20-03-55_jpg_2024-06-14_20-03-58-300x225.webp 300w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/CENTRO-RIBEIRAO-PRETO-DRONE-Foto-Guilherme-Sircili-3_2024-06-14_20-03-55_jpg_2024-06-14_20-03-58-768x576.webp 768w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/CENTRO-RIBEIRAO-PRETO-DRONE-Foto-Guilherme-Sircili-3_2024-06-14_20-03-55_jpg_2024-06-14_20-03-58-1536x1152.webp 1536w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/CENTRO-RIBEIRAO-PRETO-DRONE-Foto-Guilherme-Sircili-3_2024-06-14_20-03-55_jpg_2024-06-14_20-03-58-2048x1536.webp 2048w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/CENTRO-RIBEIRAO-PRETO-DRONE-Foto-Guilherme-Sircili-3_2024-06-14_20-03-55_jpg_2024-06-14_20-03-58-696x522.webp 696w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/CENTRO-RIBEIRAO-PRETO-DRONE-Foto-Guilherme-Sircili-3_2024-06-14_20-03-55_jpg_2024-06-14_20-03-58-1068x801.webp 1068w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/06\/CENTRO-RIBEIRAO-PRETO-DRONE-Foto-Guilherme-Sircili-3_2024-06-14_20-03-55_jpg_2024-06-14_20-03-58-1920x1440.webp 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"\/><figcaption class=\"wp-element-caption\">Imagem da regi\u00e3o central de Ribeir\u00e3o Preto (Foto: Guilherme Sircili\/CCS)<\/figcaption><\/figure>\n<p>SAIBA MAIS<br \/>Confira as festa juninas de Ribeir\u00e3o Preto e regi\u00e3o no site do Rota do Arrai\u00e1<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Como Juliano Floss ficou famoso?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/aniversario-de-ribeirao-preto-entenda-a-importancia-do-agronegocio-para-a-cidade\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Reconhecida como a \u201cCapital Brasileira do Agroneg\u00f3cio\u201d h\u00e1 20 anos, Ribeir\u00e3o Preto tem papel fundamental para o setor no \u00e2mbito nacional, tornando-se um dos polos mais importantes de agroind\u00fastria do Pa\u00eds devido a produtividade e inova\u00e7\u00e3o. Com a popula\u00e7\u00e3o de 698.642 habitantes e uma \u00e1rea territorial de 650.916 km\u00b2, de acordo com o \u00faltimo &#8230; <a title=\"Anivers\u00e1rio de Ribeir\u00e3o Preto: Entenda a import\u00e2ncia do agroneg\u00f3cio para a cidade\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/19\/aniversario-de-ribeirao-preto-entenda-a-importancia-do-agronegocio-para-a-cidade\/\" aria-label=\"Read more about Anivers\u00e1rio de Ribeir\u00e3o Preto: Entenda a import\u00e2ncia do agroneg\u00f3cio para a cidade\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":53720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-53719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1920%2C1080&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1920%2C1080&ssl=1",1920,1080,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1536%2C864&ssl=1",1536,864,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1920%2C1080&ssl=1",1920,1080,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Reconhecida como a \u201cCapital Brasileira do Agroneg\u00f3cio\u201d h\u00e1 20 anos, Ribeir\u00e3o Preto tem papel fundamental para o setor no \u00e2mbito nacional, tornando-se um dos polos mais importantes de agroind\u00fastria do Pa\u00eds devido a produtividade e inova\u00e7\u00e3o. Com a popula\u00e7\u00e3o de 698.642 habitantes e uma \u00e1rea territorial de 650.916 km\u00b2, de acordo com o \u00faltimo&hellip;","jetpack-related-posts":[{"id":3191,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/10\/18\/ribeirao-preto-sedia-iv-congresso-de-direito-aplicado-ao-agronegocio\/","url_meta":{"origin":53719,"position":0},"title":"Ribeir\u00e3o Preto sedia IV Congresso de Direito aplicado ao Agroneg\u00f3cio","author":"ismaelcolosi.com.br","date":"18 de October de 2023","format":false,"excerpt":"[ad_1] 171 Em um contexto de constante transforma\u00e7\u00e3o e desafios, o Direito aplicado ao Agroneg\u00f3cio exige profissionais cada vez mais preparados e atualizados. O IV Congresso de Direito aplicado ao Agroneg\u00f3cio tem como objetivo discutir agendas importantes do setor e garantir ambiente de seguran\u00e7a jur\u00eddica \u00e0 produ\u00e7\u00e3o agropecu\u00e1ria. O evento\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/congresso_oab_direito_agronegocio_-_foto_fernando_gonzaga_1.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/congresso_oab_direito_agronegocio_-_foto_fernando_gonzaga_1.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/congresso_oab_direito_agronegocio_-_foto_fernando_gonzaga_1.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/congresso_oab_direito_agronegocio_-_foto_fernando_gonzaga_1.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/congresso_oab_direito_agronegocio_-_foto_fernando_gonzaga_1.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42462,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/14\/ribeirao-preto-e-regiao-tem-mais-de-400-vagas-de-emprego-abertas\/","url_meta":{"origin":53719,"position":1},"title":"Ribeir\u00e3o Preto e regi\u00e3o t\u00eam mais de 400 vagas de emprego abertas","author":"ismaelcolosi.com.br","date":"14 de March de 2024","format":false,"excerpt":"[ad_1] Mais de 415 vagas de empregos em Ribeir\u00e3o Preto, Franca e regi\u00e3o est\u00e3o sendo divulgadas por uma empresa de tecnologia em gest\u00e3o de pessoas para pequenas e m\u00e9dias empresas. As oportunidades s\u00e3o para diversos segmentos e em \u00e1reas distintas como administrativa, agroneg\u00f3cio, comercial, compras, educa\u00e7\u00e3o, engenharia, financeiro, jur\u00eddico, marketing,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao.jpg?fit=1200%2C606&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao.jpg?fit=1200%2C606&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao.jpg?fit=1200%2C606&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao.jpg?fit=1200%2C606&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao.jpg?fit=1200%2C606&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42474,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/14\/ribeirao-preto-e-regiao-tem-mais-de-400-vagas-de-emprego-abertas-2\/","url_meta":{"origin":53719,"position":2},"title":"Ribeir\u00e3o Preto e regi\u00e3o t\u00eam mais de 400 vagas de emprego abertas","author":"ismaelcolosi.com.br","date":"14 de March de 2024","format":false,"excerpt":"[ad_1] Mais de 415 vagas de empregos em Ribeir\u00e3o Preto, Franca e regi\u00e3o est\u00e3o sendo divulgadas por uma empresa de tecnologia em gest\u00e3o de pessoas para pequenas e m\u00e9dias empresas. As oportunidades s\u00e3o para diversos segmentos e em \u00e1reas distintas como administrativa, agroneg\u00f3cio, comercial, compras, educa\u00e7\u00e3o, engenharia, financeiro, jur\u00eddico, marketing,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-53.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-53.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-53.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-53.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-53.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":49371,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/10\/advogada-e-abordada-no-transito-e-tem-carro-roubado-em-estrada-na-regiao-de-ribeirao\/","url_meta":{"origin":53719,"position":3},"title":"Advogada \u00e9 abordada no tr\u00e2nsito e tem carro roubado em estrada na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"10 de May de 2024","format":false,"excerpt":"[ad_1] Uma advogada de 40 anos foi abordada por dois assaltantes em pleno tr\u00e2nsito e teve o carro e o celular roubados na tarde desta quinta-feira (9), na estrada velha entre Ribeir\u00e3o Preto e Jardin\u00f3polis. Segundo a v\u00edtima disse no boletim de ocorr\u00eancia (BO), os criminosos entraram na frente de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/policia_qru_1024x576_25052021184749.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/policia_qru_1024x576_25052021184749.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/policia_qru_1024x576_25052021184749.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/policia_qru_1024x576_25052021184749.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":70143,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/09\/banco-abc-brasil-promove-evento-de-agronegocio-em-ribeirao-preto\/","url_meta":{"origin":53719,"position":4},"title":"Banco ABC Brasil promove evento de agroneg\u00f3cio em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"9 de October de 2024","format":false,"excerpt":"[ad_1] \u201cEm Ribeir\u00e3o Preto, o agroneg\u00f3cio \u00e9 t\u00e3o estruturado que estamos em uma vin\u00edcola com a temperatura batendo os 38 graus\u201d, comentou o especialista em agroneg\u00f3cio Carlos Cogo, durante a palestra que realizou na quarta-feira, dia 02\/10, sobre os cen\u00e1rios, desafios e oportunidades do agro brasileiro. Consultor do segmento h\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/capa_2024-10-09_20-25-34_jpg_2024-10-09_20-25-37-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/capa_2024-10-09_20-25-34_jpg_2024-10-09_20-25-37-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/capa_2024-10-09_20-25-34_jpg_2024-10-09_20-25-37-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/capa_2024-10-09_20-25-34_jpg_2024-10-09_20-25-37-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/capa_2024-10-09_20-25-34_jpg_2024-10-09_20-25-37-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":49387,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/10\/homem-e-suspeito-de-furtar-carro-da-namorada-e-emprestar-veiculo-em-ribeirao-preto\/","url_meta":{"origin":53719,"position":5},"title":"Homem \u00e9 suspeito de furtar carro da namorada e emprestar ve\u00edculo em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"10 de May de 2024","format":false,"excerpt":"[ad_1] Um homem \u00e9 suspeito de furtar o carro da namorada na noite desta quinta-feira (9), em Ribeir\u00e3o Preto. Segundo o boletim de ocorr\u00eancia (BO), a v\u00edtima disse que o homem saiu da casa dela com o carro \u2013 um Fiat Uno vermelho \u2013 sem o seu consentimento. O endere\u00e7o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/FURTO-CARRO_2024-05-10_14-31-05_jpg_2024-05-10_14-31-05.webp.webp?fit=1200%2C848&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/FURTO-CARRO_2024-05-10_14-31-05_jpg_2024-05-10_14-31-05.webp.webp?fit=1200%2C848&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/FURTO-CARRO_2024-05-10_14-31-05_jpg_2024-05-10_14-31-05.webp.webp?fit=1200%2C848&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/FURTO-CARRO_2024-05-10_14-31-05_jpg_2024-05-10_14-31-05.webp.webp?fit=1200%2C848&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/FURTO-CARRO_2024-05-10_14-31-05_jpg_2024-05-10_14-31-05.webp.webp?fit=1200%2C848&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-dYr","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=53719"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/53720"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=53719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=53719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=53719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}