{"id":53717,"date":"2024-06-19T06:50:45","date_gmt":"2024-06-19T09:50:45","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/19\/desistiu-da-mudanca-de-emprego-saiba-como-agir\/"},"modified":"2024-06-19T06:50:45","modified_gmt":"2024-06-19T09:50:45","slug":"desistiu-da-mudanca-de-emprego-saiba-como-agir","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/19\/desistiu-da-mudanca-de-emprego-saiba-como-agir\/","title":{"rendered":"Desistiu da mudan\u00e7a de emprego? Saiba como agir"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O caso do atacante Dudu, do Palmeiras, chamou a aten\u00e7\u00e3o da web ap\u00f3s o jogador anunciar que ficaria no time paulista apesar das negocia\u00e7\u00f5es com o Cruzeiro. O acontecimento trouxe \u00e0 tona uma quest\u00e3o relevante no mundo corporativo: <strong>como agir quando desistimos de mudar de emprego? <\/strong>Afinal, no mercado de trabalho, transi\u00e7\u00f5es s\u00e3o decis\u00f5es importantes que envolvem complexidades e riscos.<\/p>\n<div class=\"accessibility\">\n<p>Acessibilidade<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>\n<button onclick=\"alterFont1()\" id=\"btn1\" class=\"btn\">L<\/button><br \/>\n<button onclick=\"alterFont2()\" id=\"btn2\" class=\"btn\" style=\"font-family: Merriweather\">L<\/button><br \/>\n<button onclick=\"alterFontSmallerSize()\" id=\"btn3\" class=\"btn\">A-<\/button><br \/>\n<button onclick=\"alterFontBiggerSize()\" id=\"btn4\" class=\"btn\">A+<\/button><\/p>\n<p><button onclick=\"alterBackground()\" id=\"btn6\" class=\"btn\">\u25d0<\/button><\/p>\n<\/div>\n<div id=\"attachment_617535\" class=\"wp-caption alignnone style=\" max-width:=\"\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-617535 size-full\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-768x512.jpg?resize=678%2C452&#038;ssl=1\" http:=\"\" alt=\"Mulher em um ambiente corporativo segurando uma caixa com pertences pessoais. Imagem: Getty Images\" width=\"678\" height=\"452\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-768x512.jpg\"\/><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-617535 size-full\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-768x512.jpg?resize=678%2C452&#038;ssl=1\" alt=\"Mulher em um ambiente corporativo segurando uma caixa com pertences pessoais. Imagem: Getty Images\" width=\"678\" height=\"452\"\/><\/p>\n<p>Getty Images<\/p>\n<p class=\"wp-caption-text\">Saiba como mitigar riscos e manter a integridade profissional ap\u00f3s desistir da mudan\u00e7a de emprego<\/p>\n<\/div>\n<p>Por isso, desistir de uma nova oportunidade depois de j\u00e1 ter avisado o chefe pode gerar incertezas para ambas as partes. <strong>Entenda como lidar com esse tipo de situa\u00e7\u00e3o:<\/strong><\/p>\n<h2><strong>A import\u00e2ncia da transpar\u00eancia<\/strong><\/h2>\n<p>Segundo <strong>Andr\u00e9a Krug<\/strong>, especialista em carreira que j\u00e1 atuou em empresas como AMBEV e Claro, <strong>a chave para gerenciar a desist\u00eancia \u00e9 agir com m\u00e1xima transpar\u00eancia e profissionalismo<\/strong>. Nesses casos, explicar o motivo da mudan\u00e7a sem maldizer as pessoas envolvidas \u00e9 crucial. \u201c\u00c9 importante que todos percebam o cuidado em n\u00e3o expor nem o atual, nem o futuro empregador.\u201d<\/p>\n<p>Para informar a empresa, <strong>\u00e9 necess\u00e1rio se atentar \u00e0 ordem de comunica\u00e7\u00e3o<\/strong>. Primeiramente, fale com o superior imediato e, em seguida, com a \u00e1rea de Recursos Humanos atual, para verificar se h\u00e1 possibilidade de revers\u00e3o da decis\u00e3o. Depois, \u00e9 preciso avisar o l\u00edder e o RH respons\u00e1veis pelo processo de admiss\u00e3o.<\/p>\n<h2>Riscos e repercuss\u00f5es<\/h2>\n<p>No entanto, desistir de uma mudan\u00e7a de emprego pode trazer v\u00e1rios riscos para o profissional. <strong>Fernando Mantovani,<\/strong> diretor-geral da Robert Half para a Am\u00e9rica do Sul, aponta que <strong>o principal rev\u00e9s \u00e9 a perda de confian\u00e7a<\/strong>. \u201cA nova companhia pode ver a desist\u00eancia como falta de comprometimento, e a empresa atual pode questionar a lealdade do colaborador.\u201d<\/p>\n<p>Krug observa que a falta de maturidade tamb\u00e9m pode ser percebida na a\u00e7\u00e3o: \u201cPode parecer imaturo e impulsivo n\u00e3o explorar todas as vari\u00e1veis necess\u00e1rias para uma decis\u00e3o t\u00e3o importante.\u201d<\/p>\n<p><strong>Leia tamb\u00e9m:<\/strong><\/p>\n<h2>Como pesar a balan\u00e7a<\/h2>\n<p>V\u00e1rios fatores podem levar um profissional a hesitar na troca de emprego. Sentimentos de lealdade, medo do desconhecido e incertezas sobre a adapta\u00e7\u00e3o \u00e0 nova cultura organizacional s\u00e3o comuns. <strong>A escolha, por\u00e9m, deve ser baseada em uma vis\u00e3o de carreira a longo prazo<\/strong>.<\/p>\n<ul>\n<li>\n<h3>Siga a <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u\" target=\"_blank\" rel=\"noopener\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias sobre neg\u00f3cios, carreira, tecnologia e estilo de vida<\/h3>\n<\/li>\n<\/ul>\n<p>Para evitar o arrependimento, os especialistas destacam a necessidade de uma avalia\u00e7\u00e3o criteriosa e um alinhamento entre os objetivos de carreira e pessoais. \u201cConsidere os pr\u00f3s e contras, a cultura organizacional, perspectivas de crescimento e estabilidade\u201d, recomenda Mantovani.<\/p>\n<\/div>\n<p><script type=\"rocketlazyloadscript\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2024\/06\/desistiu-de-mudar-de-emprego-na-ultima-hora-saiba-como-agir\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O caso do atacante Dudu, do Palmeiras, chamou a aten\u00e7\u00e3o da web ap\u00f3s o jogador anunciar que ficaria no time paulista apesar das negocia\u00e7\u00f5es com o Cruzeiro. O acontecimento trouxe \u00e0 tona uma quest\u00e3o relevante no mundo corporativo: como agir quando desistimos de mudar de emprego? Afinal, no mercado de trabalho, transi\u00e7\u00f5es s\u00e3o decis\u00f5es &#8230; <a title=\"Desistiu da mudan\u00e7a de emprego? Saiba como agir\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/19\/desistiu-da-mudanca-de-emprego-saiba-como-agir\/\" aria-label=\"Read more about Desistiu da mudan\u00e7a de emprego? Saiba como agir\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":53718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-53717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=1024%2C683&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O caso do atacante Dudu, do Palmeiras, chamou a aten\u00e7\u00e3o da web ap\u00f3s o jogador anunciar que ficaria no time paulista apesar das negocia\u00e7\u00f5es com o Cruzeiro. O acontecimento trouxe \u00e0 tona uma quest\u00e3o relevante no mundo corporativo: como agir quando desistimos de mudar de emprego? Afinal, no mercado de trabalho, transi\u00e7\u00f5es s\u00e3o decis\u00f5es&hellip;","jetpack-related-posts":[{"id":58842,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/02\/agir-confirma-ismar-menezes-como-candidato-a-prefeitura-de-ribeirao-preto\/","url_meta":{"origin":53717,"position":0},"title":"Agir confirma Ismar Menezes como candidato \u00e0 Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"2 de August de 2024","format":false,"excerpt":"[ad_1] O Agir oficializou o nome do Juiz Federal do Trabalho aposentado Ismar Menezes como candidato \u00e0 Prefeitura de Ribeir\u00e3o Preto, durante conven\u00e7\u00e3o partid\u00e1ria, realizada na noite desta sexta-feira (2), no bairro Vila Tib\u00e9rio. Milena Bressan (Agir) foi anunciada como candidata ao cargo de vice-prefeita. O Agir traz como plataforma\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-02-at-21.17.10_2024-08-03_00-18-43_jpeg_2024-08-03_00-18-43.webp.webp?fit=1200%2C669&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-02-at-21.17.10_2024-08-03_00-18-43_jpeg_2024-08-03_00-18-43.webp.webp?fit=1200%2C669&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-02-at-21.17.10_2024-08-03_00-18-43_jpeg_2024-08-03_00-18-43.webp.webp?fit=1200%2C669&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-02-at-21.17.10_2024-08-03_00-18-43_jpeg_2024-08-03_00-18-43.webp.webp?fit=1200%2C669&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-02-at-21.17.10_2024-08-03_00-18-43_jpeg_2024-08-03_00-18-43.webp.webp?fit=1200%2C669&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48781,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/06\/ribeirao-preto-tem-mutirao-de-emprego-com-mais-de-300-vagas-saiba-mais\/","url_meta":{"origin":53717,"position":1},"title":"Ribeir\u00e3o Preto tem mutir\u00e3o de emprego com mais de 300 vagas; Saiba mais","author":"ismaelcolosi.com.br","date":"6 de May de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto realiza nesta quarta-feira (8) um \u201cMutir\u00e3o de Emprego\u201d com mais de 300 vagas. A a\u00e7\u00e3o ser\u00e1 no Terminal Rodovi\u00e1rio, que fica na avenida Jer\u00f4nimo Gon\u00e7alves, 640, das 9h \u00e0s 12h. Os interessados em concorrer a uma das vagas, que v\u00e3o desde est\u00e1gios at\u00e9 recoloca\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/closeup-de-candidato-a-emprego-dando-seu-curriculo-durante-a-entrevista-de-emprego-no-escritorio-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/closeup-de-candidato-a-emprego-dando-seu-curriculo-durante-a-entrevista-de-emprego-no-escritorio-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/closeup-de-candidato-a-emprego-dando-seu-curriculo-durante-a-entrevista-de-emprego-no-escritorio-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/closeup-de-candidato-a-emprego-dando-seu-curriculo-durante-a-entrevista-de-emprego-no-escritorio-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/closeup-de-candidato-a-emprego-dando-seu-curriculo-durante-a-entrevista-de-emprego-no-escritorio-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":84973,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/04\/29\/contratacao-imediata-vagas-de-vigilante-com-turno-flexivel-em-ribeirao-preto-va-dia-30-04\/","url_meta":{"origin":53717,"position":2},"title":"\ud83d\udea8 CONTRATA\u00c7\u00c3O IMEDIATA! Vagas de Vigilante com Turno Flex\u00edvel em Ribeir\u00e3o Preto \u2013 V\u00e1 dia 30\/04","author":"ismaelcolosi.com.br","date":"29 de April de 2025","format":false,"excerpt":"O vigilante \u00e9 o profissional respons\u00e1vel por garantir a seguran\u00e7a de pessoas, espa\u00e7os e patrim\u00f4nios. Sua fun\u00e7\u00e3o principal \u00e9 prevenir situa\u00e7\u00f5es de risco, controlar acessos, monitorar movimenta\u00e7\u00f5es e agir com rapidez em casos de emerg\u00eancia. Al\u00e9m da presen\u00e7a f\u00edsica nos locais, o vigilante tamb\u00e9m realiza rondas peri\u00f3dicas, observa comportamentos suspeitos,\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/portrait-male-security-guard-with-radio-station-camera-screens-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/portrait-male-security-guard-with-radio-station-camera-screens-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/portrait-male-security-guard-with-radio-station-camera-screens-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/portrait-male-security-guard-with-radio-station-camera-screens-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/portrait-male-security-guard-with-radio-station-camera-screens-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":84432,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/04\/09\/alerta-de-vaga-95-das-pessoas-nao-sabem-desta-chance-no-savegnago-salario-va-em-ribeirao-preto-sp-exclusivo-para-quem-agir-hoje\/","url_meta":{"origin":53717,"position":3},"title":"\u26a0\ufe0f ALERTA DE VAGA: 95% das Pessoas N\u00e3o Sabem DESTAS Chances no Savegnago! (Sal\u00e1rio + VA em Ribeir\u00e3o Preto-SP \u2013 Exclusivo para Quem Agir HOJE!","author":"ismaelcolosi.com.br","date":"9 de April de 2025","format":false,"excerpt":"O\u00a0Savegnago Novo Shopping, uma das redes de varejo mais reconhecidas do pa\u00eds, est\u00e1 com vagas abertas para diversos setores, oferecendo oportunidades para quem busca ingressar ou se recolocar no mercado de trabalho. As posi\u00e7\u00f5es dispon\u00edveis incluem fun\u00e7\u00f5es como\u00a0Repositor,\u00a0A\u00e7ougueiro,\u00a0Auxiliar de Cozinha,\u00a0Promotor de Cart\u00e3o, entre outras, com processos seletivos \u00e1geis e acesso\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/savegnago-credito-site-oficial_widelg.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/savegnago-credito-site-oficial_widelg.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/savegnago-credito-site-oficial_widelg.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/savegnago-credito-site-oficial_widelg.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/savegnago-credito-site-oficial_widelg.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":81351,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/01\/10\/clique-aqui-e-veja-a-entrevista-para-vaga-de-vigia-para-hoje-dia-10-as-14h-oportunidade-para-homem-e-para-mulher\/","url_meta":{"origin":53717,"position":4},"title":"Clique aqui e veja a entrevista para vaga de Vigia para hoje, dia 10; oportunidade para homem e para mulher","author":"ismaelcolosi.com.br","date":"10 de January de 2025","format":false,"excerpt":"O que \u00e9 e o que faz um vigia? 1. Quem \u00e9 o vigia? O vigia \u00e9 um profissional fundamental para garantir a seguran\u00e7a de um local, seja ele p\u00fablico ou privado. Sua principal responsabilidade \u00e9 zelar pela integridade do ambiente, prevenindo situa\u00e7\u00f5es de risco e assegurando que tudo esteja\u2026","rel":"","context":"In &quot;Entrevistas agendadas para hoje em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Entrevistas agendadas para hoje em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/entrevistas-agendadas-para-hoje-em-ribeirao-preto-sp\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/guarda-municipal-itaquaquecetuba-divulgacao-pmitaquaquecetuba_widelg.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/guarda-municipal-itaquaquecetuba-divulgacao-pmitaquaquecetuba_widelg.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/guarda-municipal-itaquaquecetuba-divulgacao-pmitaquaquecetuba_widelg.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/guarda-municipal-itaquaquecetuba-divulgacao-pmitaquaquecetuba_widelg.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/guarda-municipal-itaquaquecetuba-divulgacao-pmitaquaquecetuba_widelg.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51388,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/27\/5-prompts-do-chatgpt-para-ter-uma-mentalidade-de-vencedor\/","url_meta":{"origin":53717,"position":5},"title":"5 prompts do ChatGPT para ter uma mentalidade de vencedor","author":"ismaelcolosi.com.br","date":"27 de May de 2024","format":false,"excerpt":"[ad_1] N\u00e3o desista, n\u00e3o importa o que aconte\u00e7a Acessibilidade L L A- A+ \u25d0 O sucesso \u00e9 inevit\u00e1vel. Se voc\u00ea continuar, vai conseguir. Como? Com paci\u00eancia e determina\u00e7\u00e3o para conhecer novas pessoas, ser curioso, tomar boas decis\u00f5es, aparecer e fazer um bom trabalho. Siga a Forbes no WhatsApp e receba\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/5-Prompts-do-ChatGPT-Para-Ter-Uma-Mentalidade-de-Vencedor-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/5-Prompts-do-ChatGPT-Para-Ter-Uma-Mentalidade-de-Vencedor-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/5-Prompts-do-ChatGPT-Para-Ter-Uma-Mentalidade-de-Vencedor-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/5-Prompts-do-ChatGPT-Para-Ter-Uma-Mentalidade-de-Vencedor-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-dYp","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=53717"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/53717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/53718"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=53717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=53717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=53717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}