{"id":52754,"date":"2024-06-10T14:31:03","date_gmt":"2024-06-10T17:31:03","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/10\/ufologo-passeador-de-caes-e-instrutores-de-yoga-ministerio-do-trabalho-inclui-19-novas-ocupacoes-em-classificacao-oficial-veja-lista\/"},"modified":"2024-06-10T14:31:03","modified_gmt":"2024-06-10T17:31:03","slug":"ufologo-passeador-de-caes-e-instrutores-de-yoga-ministerio-do-trabalho-inclui-19-novas-ocupacoes-em-classificacao-oficial-veja-lista","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/10\/ufologo-passeador-de-caes-e-instrutores-de-yoga-ministerio-do-trabalho-inclui-19-novas-ocupacoes-em-classificacao-oficial-veja-lista\/","title":{"rendered":"Uf\u00f3logo, passeador de c\u00e3es e instrutores de yoga: Minist\u00e9rio do Trabalho inclui 19 novas ocupa\u00e7\u00f5es em classifica\u00e7\u00e3o oficial; veja lista"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<div class=\"content-infos\">\n<div class=\"texts\">\n<p class=\"author tooltip-comp\"> Da reda\u00e7\u00e3o com Ag\u00eancias<span class=\"icon-i\">i<\/span><span class=\"tooltiptext\"> <span class=\"author\"><span>Da reda\u00e7\u00e3o com Ag\u00eancias<\/span> <\/span><span class=\"desc\"\/> <\/span><\/p>\n<p>10\/06\/2024 &#8211; 14:05<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<\/div>\n<div id=\"share-modal\" class=\"share-modal\"> <button class=\"box-close btn-share\"> <img decoding=\"async\" src=\"https:\/\/istoedinheiro.com.br\/wp-content\/themes\/dinheiro-wp-theme\/assets\/img\/svg\/closeIcon.svg?x46096\" alt=\"Close icon\" class=\"close-btn lazy\"\/> <\/button><\/div>\n<\/p><\/div>\n<p>O Minist\u00e9rio do Trabalho em Emprego (MTE) anunciou nesta segunda-feira (10) que a <a href=\"http:\/\/pdet.mte.gov.br\/guia-brasileiro-de-ocupacoes\" target=\"_blank\" rel=\"noopener\">Classifica\u00e7\u00e3o Brasileira de Ocupa\u00e7\u00f5es (CBO)<\/a> ganhou 19 novas atividades e atualizou outras 424. Agora, trabalhos como facilitador de biodan\u00e7a, uf\u00f3logo, passeador de c\u00e3es, instrutor de yoga e brinquedista est\u00e3o entre as atividades que passam a compor o cat\u00e1logo oficial de ocupa\u00e7\u00f5es (veja lista completa abaixo).<\/p>\n<p>De acordo com o Minist\u00e9rio, atualmente s\u00e3o 2.741 ocupa\u00e7\u00f5es listadas na CBO. A atualiza\u00e7\u00e3o da lista com novas inser\u00e7\u00f5es s\u00e3o feitas de forma peri\u00f3dica. Para isso, \u00e9 necess\u00e1rio que entidades e associa\u00e7\u00f5es de trabalhadores fa\u00e7am a solicita\u00e7\u00e3o ao MTE, que forma um grupo para avalia\u00e7\u00e3o do requerimento, explica o minist\u00e9rio.<\/p>\n<p>Nessa an\u00e1lise, a subsecret\u00e1ria de Estat\u00edsticas e Estudos do Trabalho do MTE, Paula Montagner, diz que se avalia a necessidade de inserir novas ocupa\u00e7\u00f5es ou de ampliar a lista de atividades das que j\u00e1 existem. \u201cProcuramos estar o mais pr\u00f3ximo das mudan\u00e7as do mundo do mercado, retratando a sua realidade, pois esses dados s\u00e3o usados por trabalhadores, empregadores, profissionais de RH na hora da tomada de decis\u00f5es\u201d, afirma.<\/p>\n<p>Segundo o MTE, o CBO foi criado para incrementar a realidade do mercado de trabalho no Brasil. Ela \u00e9 uma plataforma online p\u00fablica que tem na sua base de dados informa\u00e7\u00f5es da Classifica\u00e7\u00e3o de Ocupa\u00e7\u00f5es, do Cadastro Geral de Empregados e Desempregados (Caged), da Rela\u00e7\u00e3o Anual de Informa\u00e7\u00f5es Sociais (Rais) e do Sistema Nacional de Emprego (Sine).<\/p>\n<p>A ideia \u00e9 que o documento sirva de refer\u00eancia para trabalhadores, estudantes, empregadores e pesquisadores. H\u00e1 informa\u00e7\u00f5es sobre a m\u00e9dia salarial, habilidades, conhecimentos e requisitos de cada uma das ocupa\u00e7\u00f5es.<\/p>\n<p>As informa\u00e7\u00f5es da CBO alimentam as bases estat\u00edsticas referente ao mercado de trabalho, al\u00e9m de servir de subs\u00eddios para a formula\u00e7\u00e3o de pol\u00edticas p\u00fablicas de emprego, diz o MTE, e que a finalidade da classifica\u00e7\u00e3o \u00e9 dar visibilidade a uma ocupa\u00e7\u00e3o, diferentemente de profiss\u00e3o, que necessita ser regulamentada por meio de lei, passando por aprecia\u00e7\u00e3o do Congresso Nacional e san\u00e7\u00e3o do Presidente da Rep\u00fablica.<\/p>\n<p>\u00a0<\/p>\n<h3>Confira as novas ocupa\u00e7\u00f5es:<\/h3>\n<ol>\n<li>Analista de sucesso do cliente<\/li>\n<li>Analista de experi\u00eancia do cliente<\/li>\n<li>Ergonomista (respons\u00e1vel por tornar o ambiente trabalho mais eficiente e seguro)<\/li>\n<li>Bi\u00f3logo em meio ambiente e diversidade<\/li>\n<li>Bi\u00f3logo em sa\u00fade<\/li>\n<li>Facilitador de biodan\u00e7a<\/li>\n<li>Terapeuta Reiki<\/li>\n<li>Instrutor de Yoga<\/li>\n<li>Instrutor de medita\u00e7\u00e3o<\/li>\n<li>Facilitador de grupos de movimento (bioenerg\u00e9tica)<\/li>\n<li>Brinquedista<\/li>\n<li>Lactarista (respons\u00e1vel por preparar e cuidar da nutri\u00e7\u00e3o dos beb\u00eas em creches e hospitais)<\/li>\n<li>Hidrojatista (respons\u00e1vel por operar equipamentos de hidrojateamento, que utilizam \u00e1gua sob alta press\u00e3o)<\/li>\n<li>Confeccionador de Perucas<\/li>\n<li>Uf\u00f3logo<\/li>\n<li>Monitor de animais dom\u00e9sticos<\/li>\n<li>Condutor de c\u00e3es dom\u00e9sticos (passeador)<\/li>\n<li>Instrutor de mobilidade com c\u00e3es-guia (respons\u00e1vel pela intera\u00e7\u00e3o entre a pessoa com defici\u00eancia visual e o animal)<\/li>\n<li>Condutor escolar (terrestre)<\/li>\n<\/ol>\n<div id=\"share-modal\" class=\"share-modal\"> <button class=\"box-close btn-share\"> <img decoding=\"async\" src=\"https:\/\/istoedinheiro.com.br\/wp-content\/themes\/dinheiro-wp-theme\/assets\/img\/svg\/closeIcon.svg?x46096\" alt=\"Close icon\" class=\"close-btn lazy\"\/> <\/button><\/div>\n<\/p><\/div>\n<p><script>!function(f,b,e,v,n,t,s){if(f.fbq)return;n=f.fbq=function(){n.callMethod?n.callMethod.apply(n,arguments):n.queue.push(arguments)};if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';n.queue=[];t=b.createElement(e);t.async=!0;t.src=v;s=b.getElementsByTagName(e)[0];s.parentNode.insertBefore(t,s)}(window,document,'script','<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/istoedinheiro.com.br\/ufologo-passeador-de-caes-e-instrutores-de-yoga-ministerio-do-trabalho-inclui-19-novas-ocupacoes-em-classificacao-oficial-veja-lista\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Da reda\u00e7\u00e3o com Ag\u00eanciasi Da reda\u00e7\u00e3o com Ag\u00eancias 10\/06\/2024 &#8211; 14:05 O Minist\u00e9rio do Trabalho em Emprego (MTE) anunciou nesta segunda-feira (10) que a Classifica\u00e7\u00e3o Brasileira de Ocupa\u00e7\u00f5es (CBO) ganhou 19 novas atividades e atualizou outras 424. Agora, trabalhos como facilitador de biodan\u00e7a, uf\u00f3logo, passeador de c\u00e3es, instrutor de yoga e brinquedista est\u00e3o entre &#8230; <a title=\"Uf\u00f3logo, passeador de c\u00e3es e instrutores de yoga: Minist\u00e9rio do Trabalho inclui 19 novas ocupa\u00e7\u00f5es em classifica\u00e7\u00e3o oficial; veja lista\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/10\/ufologo-passeador-de-caes-e-instrutores-de-yoga-ministerio-do-trabalho-inclui-19-novas-ocupacoes-em-classificacao-oficial-veja-lista\/\" aria-label=\"Read more about Uf\u00f3logo, passeador de c\u00e3es e instrutores de yoga: Minist\u00e9rio do Trabalho inclui 19 novas ocupa\u00e7\u00f5es em classifica\u00e7\u00e3o oficial; veja lista\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":52755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3598],"tags":[],"class_list":["post-52754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empregos-classificados-vagas-trabalho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/aula-de-yoga.jpg?fit=750%2C500&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/aula-de-yoga.jpg?fit=750%2C500&ssl=1",750,500,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/aula-de-yoga.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/aula-de-yoga.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/aula-de-yoga.jpg?fit=750%2C500&ssl=1",750,500,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/aula-de-yoga.jpg?fit=750%2C500&ssl=1",750,500,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/aula-de-yoga.jpg?fit=750%2C500&ssl=1",750,500,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/aula-de-yoga.jpg?fit=750%2C500&ssl=1",750,500,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Da reda\u00e7\u00e3o com Ag\u00eanciasi Da reda\u00e7\u00e3o com Ag\u00eancias 10\/06\/2024 &#8211; 14:05 O Minist\u00e9rio do Trabalho em Emprego (MTE) anunciou nesta segunda-feira (10) que a Classifica\u00e7\u00e3o Brasileira de Ocupa\u00e7\u00f5es (CBO) ganhou 19 novas atividades e atualizou outras 424. Agora, trabalhos como facilitador de biodan\u00e7a, uf\u00f3logo, passeador de c\u00e3es, instrutor de yoga e brinquedista est\u00e3o entre&hellip;","jetpack-related-posts":[{"id":14270,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/nova-lista-de-doencas-do-trabalho-inclui-burnout\/","url_meta":{"origin":52754,"position":0},"title":"Nova lista de doen\u00e7as do trabalho inclui burnout","author":"ismaelcolosi.com.br","date":"11 de December de 2023","format":false,"excerpt":"[ad_1] Getty ImagesA atualiza\u00e7\u00e3o da lista de doen\u00e7as do trabalho leva em conta todas as ocupa\u00e7\u00f5es e vale para trabalhadores formais e informais O Minist\u00e9rio da Sa\u00fade anunciou na quarta-feira (29) a atualiza\u00e7\u00e3o da lista de doen\u00e7as relacionadas ao trabalho. Portaria j\u00e1 foi publicada incluindo 165 novas patologias, apontadas como\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/carreira-burnout-saude-mental-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/carreira-burnout-saude-mental-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/carreira-burnout-saude-mental-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/carreira-burnout-saude-mental-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":17046,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/17\/mei-tem-novas-atividades-autorizadas-veja-agora-mesmo\/","url_meta":{"origin":52754,"position":1},"title":"MEI tem novas atividades autorizadas? Veja agora mesmo","author":"ismaelcolosi.com.br","date":"17 de December de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: Istock\/FG TradeMudan\u00e7as na transi\u00e7\u00e3o de MEI para microempresa chegam em breve Antes de iniciar o processo de formaliza\u00e7\u00e3o como Micro Empreendedor Individual (MEI) em 2024, \u00e9 crucial verificar se sua atividade profissional est\u00e1 na lista de atividades autorizadas. Algumas profiss\u00f5es e servi\u00e7os podem n\u00e3o se enquadrar nas regras,\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702824913_istock-1463712307.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702824913_istock-1463712307.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702824913_istock-1463712307.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702824913_istock-1463712307.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702824913_istock-1463712307.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45253,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/o-que-e-a-insalubridade-e-periculosidade-no-trabalho\/","url_meta":{"origin":52754,"position":2},"title":"O que \u00e9 a insalubridade e periculosidade no trabalho?","author":"ismaelcolosi.com.br","date":"3 de April de 2024","format":false,"excerpt":"[ad_1] A insalubridade e periculosidade no trabalho s\u00e3o classifica\u00e7\u00f5es de ocupa\u00e7\u00f5es de risco, consideradas atividades especiais pelo Minist\u00e9rio do Trabalho e Emprego. A partir de uma per\u00edcia t\u00e9cnica,\u00a0\u00e9 acrescido um valor no sal\u00e1rio do funcion\u00e1rio exposto a agentes prejudiciais \u00e0 sua sa\u00fade\u00a0ou com possibilidade de fatalidade. No post de hoje,\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/insalubridade-e-periculosidade-no-trabalho.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/insalubridade-e-periculosidade-no-trabalho.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/insalubridade-e-periculosidade-no-trabalho.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/insalubridade-e-periculosidade-no-trabalho.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/insalubridade-e-periculosidade-no-trabalho.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":81149,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/01\/08\/confira-as-10-funcoes-que-mais-contrataram-e-mais-demitiram-em-ribeirao-preto-sp-no-ano-de-2024\/","url_meta":{"origin":52754,"position":3},"title":"Confira as 10 fun\u00e7\u00f5es que mais contrataram e mais demitiram em Ribeir\u00e3o Preto-SP no ano de 2024","author":"ismaelcolosi.com.br","date":"8 de January de 2025","format":false,"excerpt":"Confira as 10 fun\u00e7\u00f5es que mais contrataram e mais demitiram em Ribeir\u00e3o Preto-SP no ano de 2024 Ribeir\u00e3o Preto gerou de janeiro a novembro de 2024, o total 9.363 novos empregos formais, ou seja, com registro registro em carteira;\u00a0 sendo 46% (4.270) no setor de Servi\u00e7os, 34% (3.177) no Com\u00e9rcio,\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/10-funcoes-que-mais-demitiram-nos-11-meses-de-2024-em-Ribeirao-Preto.png?fit=629%2C550&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/10-funcoes-que-mais-demitiram-nos-11-meses-de-2024-em-Ribeirao-Preto.png?fit=629%2C550&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/10-funcoes-que-mais-demitiram-nos-11-meses-de-2024-em-Ribeirao-Preto.png?fit=629%2C550&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":82567,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/02\/04\/enem-dos-concursos-resultados-do-cnu-serao-divulgados-hoje-veja-como-acessar\/","url_meta":{"origin":52754,"position":4},"title":"\u2018Enem dos concursos\u2019: Resultados do CNU ser\u00e3o divulgados hoje; veja como acessar","author":"ismaelcolosi.com.br","date":"4 de February de 2025","format":false,"excerpt":"[ad_1] Da reda\u00e7\u00e3o com Ag\u00eancia Brasili Da reda\u00e7\u00e3o com Ag\u00eancia Brasil 04\/02\/2025 - 8:02 O resultado final para os candidatos que concorreram aos cargos de n\u00edvel intermedi\u00e1rio (Bloco 8) do Concurso P\u00fablico Nacional Unificado (CPNU) estar\u00e1 dispon\u00edvel a partir das 10h desta ter\u00e7a-feira, 4, na \u00c1rea do candidato da p\u00e1gina\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/prova-1.jpg?fit=1200%2C751&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/prova-1.jpg?fit=1200%2C751&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/prova-1.jpg?fit=1200%2C751&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/prova-1.jpg?fit=1200%2C751&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/prova-1.jpg?fit=1200%2C751&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":38821,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/empregos-ligados-a-matematica-tem-vagas-mais-qualificadas-em-periodos-de-crise\/","url_meta":{"origin":52754,"position":5},"title":"Empregos ligados \u00e0 matem\u00e1tica t\u00eam vagas mais qualificadas em per\u00edodos de crise","author":"ismaelcolosi.com.br","date":"21 de February de 2024","format":false,"excerpt":"[ad_1] Da reda\u00e7\u00e3o com Ag\u00eancia Brasili Da reda\u00e7\u00e3o com Ag\u00eancia Brasil 20\/02\/2024 - 10:14 A qualidade dos empregos ligados \u00e0 matem\u00e1tica \u00e9 muito maior em termos de resili\u00eancia \u00e0s situa\u00e7\u00f5es de crise do que a de outras ocupa\u00e7\u00f5es n\u00e3o vinculadas a essa disciplina revela uma pesquisa divulgada na a segunda-feira\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/closeup-de-economista-usando-calculadora-ao-passar-por-contas-e-impostos-no-escritorio-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/closeup-de-economista-usando-calculadora-ao-passar-por-contas-e-impostos-no-escritorio-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/closeup-de-economista-usando-calculadora-ao-passar-por-contas-e-impostos-no-escritorio-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/closeup-de-economista-usando-calculadora-ao-passar-por-contas-e-impostos-no-escritorio-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-dIS","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52754"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/52755"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}