{"id":52593,"date":"2024-06-07T19:55:00","date_gmt":"2024-06-07T22:55:00","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/07\/bruna-louise-traz-novo-show-para-ribeirao-preto-veja-quando\/"},"modified":"2024-06-07T19:55:00","modified_gmt":"2024-06-07T22:55:00","slug":"bruna-louise-traz-novo-show-para-ribeirao-preto-veja-quando","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/07\/bruna-louise-traz-novo-show-para-ribeirao-preto-veja-quando\/","title":{"rendered":"Bruna Louise traz novo show para Ribeir\u00e3o Preto; Veja quando"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>A humorista <strong>Bruna Louise<\/strong>, um dos principais destaques da <strong>com\u00e9dia stand-up<\/strong> no <strong>Brasil<\/strong>, se apresenta em <strong>Ribeir\u00e3o Preto<\/strong>, no dia 29 de junho, \u00e0s 17h30 e \u00e0s 20h, no <strong>Theatro Pero II<\/strong>.<\/p>\n<p>Os ingressos para apresenta\u00e7\u00e3o ainda est\u00e3o <strong>dispon\u00edveis <\/strong>e podem ser adquiridos de <strong>forma on-line (<a href=\"https:\/\/ingressodigital.com\/\/evento\/12197,11251\/Bruna_Louise__Ela_T_Correndo_Atrs\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>)<\/strong> ou na bilheteria do theatro (<a href=\"https:\/\/www.theatropedro2.com.br\/comprar-ingresso.php\" target=\"_blank\" rel=\"noreferrer noopener\">consulte os hor\u00e1rios<\/a>).<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>Seu novo show, \u201c<strong>Ela T\u00e1 Correndo Atr\u00e1s<\/strong>\u201c, promete fazer a plateia gargalhar, mas tamb\u00e9m empoderar e combater os preconceitos, julgamentos e escolhas que tentam fazer por ela.<\/p>\n<figure class=\"wp-block-pullquote\">\n<blockquote>\n<p>Chegou a vez da mulher tamb\u00e9m falar o que pensa e com muito humor, por que n\u00e3o? Eu trago minha perspectiva sobre o mundo, tiro sarro dos meus pr\u00f3prios problemas e acho que essa \u00e9 uma maneira de quebrar alguns comportamentos dentro da com\u00e9dia e, talvez, normalizar alguns tabus por a\u00ed<\/p>\n<p><cite>diz a comediante<\/cite><\/p><\/blockquote>\n<\/figure>\n<h2 class=\"wp-block-heading\"><strong>Setores<\/strong><\/h2>\n<ul>\n<li>Plateia e Frisa: (t\u00e9rreo em frente ao palco): R$ 120 inteira | R$ 60 meia-entrada\u00a0<\/li>\n<\/ul>\n<ul>\n<li>Balc\u00e3o Nobre (1\u00ba andar): R$ 100 inteira | R$ 50 meia-entrada<\/li>\n<\/ul>\n<ul>\n<li>Balc\u00e3o Simples (2\u00ba andar): R$ 80 inteira | R$ 40 meia-entrada<\/li>\n<\/ul>\n<p>Apenas os setores balc\u00e3o nobre e balc\u00e3o simples est\u00e3o dispon\u00edveis para a apresenta\u00e7\u00e3o das 20h. Vale ressaltar que, os ingressos podem sofrer altera\u00e7\u00f5es de valores.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Servi\u00e7o<\/strong><\/h3>\n<p><em>Bruna Louise \u2013 Ela T\u00e1 Correndo Atr\u00e1s<\/em><\/p>\n<p>Data: 29 de junho de 2024<\/p>\n<p>Hor\u00e1rio: \u00e0s 20h<\/p>\n<p>Local: Theatro Pedro II \u2013 rua \u00c1lvares Cabral, 370 \u2013 Centro<\/p>\n<p>Classifica\u00e7\u00e3o: 16 anos<\/p>\n<p>Ingressos: a partir de R$ 40 \u2013 clique aqui<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Tudo o que voc\u00ea precisa saber sobre o Jo\u00e3o Rock; Festival \u00e9 neste s\u00e1bado<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Jo\u00e3o Rock ter\u00e1 transmiss\u00e3o ao vivo do Tudo EP; veja como assistir<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/bruna-louise-traz-novo-show-para-ribeirao-preto-veja-quando\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A humorista Bruna Louise, um dos principais destaques da com\u00e9dia stand-up no Brasil, se apresenta em Ribeir\u00e3o Preto, no dia 29 de junho, \u00e0s 17h30 e \u00e0s 20h, no Theatro Pero II. Os ingressos para apresenta\u00e7\u00e3o ainda est\u00e3o dispon\u00edveis e podem ser adquiridos de forma on-line (clique aqui) ou na bilheteria do theatro (consulte &#8230; <a title=\"Bruna Louise traz novo show para Ribeir\u00e3o Preto; Veja quando\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/07\/bruna-louise-traz-novo-show-para-ribeirao-preto-veja-quando\/\" aria-label=\"Read more about Bruna Louise traz novo show para Ribeir\u00e3o Preto; Veja quando\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":52594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-52593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/384780018_18390396589051206_3173563243841154185_n_2024-06-07_22-35-48_jpg_2024-06-07_22-35-48.webp.webp?fit=1440%2C963&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/384780018_18390396589051206_3173563243841154185_n_2024-06-07_22-35-48_jpg_2024-06-07_22-35-48.webp.webp?fit=1440%2C963&ssl=1",1440,963,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/384780018_18390396589051206_3173563243841154185_n_2024-06-07_22-35-48_jpg_2024-06-07_22-35-48.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/384780018_18390396589051206_3173563243841154185_n_2024-06-07_22-35-48_jpg_2024-06-07_22-35-48.webp.webp?fit=300%2C201&ssl=1",300,201,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/384780018_18390396589051206_3173563243841154185_n_2024-06-07_22-35-48_jpg_2024-06-07_22-35-48.webp.webp?fit=768%2C514&ssl=1",768,514,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/384780018_18390396589051206_3173563243841154185_n_2024-06-07_22-35-48_jpg_2024-06-07_22-35-48.webp.webp?fit=1024%2C685&ssl=1",1024,685,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/384780018_18390396589051206_3173563243841154185_n_2024-06-07_22-35-48_jpg_2024-06-07_22-35-48.webp.webp?fit=1440%2C963&ssl=1",1440,963,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/384780018_18390396589051206_3173563243841154185_n_2024-06-07_22-35-48_jpg_2024-06-07_22-35-48.webp.webp?fit=1440%2C963&ssl=1",1440,963,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A humorista Bruna Louise, um dos principais destaques da com\u00e9dia stand-up no Brasil, se apresenta em Ribeir\u00e3o Preto, no dia 29 de junho, \u00e0s 17h30 e \u00e0s 20h, no Theatro Pero II. Os ingressos para apresenta\u00e7\u00e3o ainda est\u00e3o dispon\u00edveis e podem ser adquiridos de forma on-line (clique aqui) ou na bilheteria do theatro (consulte&hellip;","jetpack-related-posts":[{"id":46042,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/09\/veja-12-shows-de-comedia-confirmados-no-theatro-pedro-ii-em-ribeirao-preto\/","url_meta":{"origin":52593,"position":0},"title":"Veja 12 shows de com\u00e9dia confirmados no Theatro Pedro II em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"9 de April de 2024","format":false,"excerpt":"[ad_1] O Theatro Pedro II, em Ribeir\u00e3o Preto, conta com 12 shows de com\u00e9dia confirmados at\u00e9 o m\u00eas de setembro. Entre os nomes que v\u00e3o passar pelo palco, est\u00e3o Afonso Padilha, Thiago Ventura, Bruna Louise, Os Melhores do Mundo e Os Barbixas de Humor. Confira as atra\u00e7\u00f5es: Abril \u00a0 Tiago\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/26862-banner-uhuu-thiago-ventura.png?fit=1180%2C420&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/26862-banner-uhuu-thiago-ventura.png?fit=1180%2C420&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/26862-banner-uhuu-thiago-ventura.png?fit=1180%2C420&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/26862-banner-uhuu-thiago-ventura.png?fit=1180%2C420&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/26862-banner-uhuu-thiago-ventura.png?fit=1180%2C420&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":54892,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/28\/clarice-falcao-e-whindersson-nunes-confira-o-que-fazer-em-ribeirao-este-fim-de-semana\/","url_meta":{"origin":52593,"position":1},"title":"Clarice Falc\u00e3o e Whindersson Nunes: Confira o que fazer em Ribeir\u00e3o este fim de semana","author":"ismaelcolosi.com.br","date":"28 de June de 2024","format":false,"excerpt":"[ad_1] Este fim de semana, Ribeir\u00e3o Preto conta com uma agenda cultural diversificada para todas as idades e gostos. Entre os destaques est\u00e3o: o show da turn\u00ea \u201cTRUQUE\u201c, da cantora Clarice Falc\u00e3o, e o retorno de Whindersson Nunes aos palcos com stand-up. Confira o que fazer em Ribeir\u00e3o Preto este\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23_2024-06-28_12-45-37_jpg_2024-06-28_12-45-37.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23_2024-06-28_12-45-37_jpg_2024-06-28_12-45-37.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23_2024-06-28_12-45-37_jpg_2024-06-28_12-45-37.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23_2024-06-28_12-45-37_jpg_2024-06-28_12-45-37.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23_2024-06-28_12-45-37_jpg_2024-06-28_12-45-37.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35261,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/05\/thiago-ventura-se-apresenta-em-ribeirao-preto-veja-quando\/","url_meta":{"origin":52593,"position":2},"title":"Thiago Ventura se apresenta em Ribeir\u00e3o Preto; Veja quando","author":"ismaelcolosi.com.br","date":"5 de February de 2024","format":false,"excerpt":"[ad_1] O comediante Thiago Ventura anunciou em suas redes sociais, que trar\u00e1 para Ribeir\u00e3o Preto, o seu 7\u00ba espet\u00e1culo solo, o \u2018Novo Show\u2019. A apresenta\u00e7\u00e3o acontece no Theatro Pedro II, no Centro do munic\u00edpio, no dia 4 de maio, \u00e0s 21h. Os ingressos j\u00e1 est\u00e3o dispon\u00edveis. Somando mais de 21\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37124,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/14\/renato-albani-se-apresenta-em-ribeirao-preto-veja-como-comprar-ingressos\/","url_meta":{"origin":52593,"position":3},"title":"Renato Albani se apresenta em Ribeir\u00e3o Preto; Veja como comprar ingressos","author":"ismaelcolosi.com.br","date":"14 de February de 2024","format":false,"excerpt":"[ad_1] O humorista Renato Albani se apresenta em Ribeir\u00e3o Preto em mar\u00e7o com o \u201cNovo Show\u201d no Theatro Pedro II, no dia 15 de mar\u00e7o, \u00e0s 19h e \u00e0s 21h. Ingressos ainda est\u00e3o dispon\u00edveis. Renato j\u00e1 esteve em Ribeir\u00e3o Preto para apresentar o show \u201cAssim Caminha a Humanidade\u201d. Agora, ele\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-10.jpg?fit=645%2C423&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-10.jpg?fit=645%2C423&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-10.jpg?fit=645%2C423&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":60747,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/18\/novo-parque-de-ribeirao-preto-ganha-nome-e-deve-ser-aberto-no-proximo-mes\/","url_meta":{"origin":52593,"position":4},"title":"Novo parque de Ribeir\u00e3o Preto ganha nome e deve ser aberto no pr\u00f3ximo m\u00eas","author":"ismaelcolosi.com.br","date":"18 de August de 2024","format":false,"excerpt":"[ad_1] O prefeito de Ribeir\u00e3o Preto, Duarte Nogueira (PSDB), publicou decreto que denomina de Parque Primavera Vera L\u00facia de Amorim Biagi a \u00e1rea que ficou conhecida como \u201cPico da Unaerp\u201d, no bairro Ribeir\u00e2nia, na zona Leste da cidade. Segundo a prefeitura, nas pr\u00f3ximas semanas ser\u00e3o instaladas placas de comunica\u00e7\u00e3o visual\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/parque-primavera_2024-08-17_21-32-49_jpg_2024-08-17_21-32-49.webp.webp?fit=1200%2C686&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/parque-primavera_2024-08-17_21-32-49_jpg_2024-08-17_21-32-49.webp.webp?fit=1200%2C686&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/parque-primavera_2024-08-17_21-32-49_jpg_2024-08-17_21-32-49.webp.webp?fit=1200%2C686&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/parque-primavera_2024-08-17_21-32-49_jpg_2024-08-17_21-32-49.webp.webp?fit=1200%2C686&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/parque-primavera_2024-08-17_21-32-49_jpg_2024-08-17_21-32-49.webp.webp?fit=1200%2C686&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58508,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/31\/o-que-e-slam-competicao-de-poesia-agita-a-feira-do-livro-de-ribeirao-preto\/","url_meta":{"origin":52593,"position":5},"title":"O que \u00e9 Slam? Competi\u00e7\u00e3o de poesia agita a Feira do Livro de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"31 de July de 2024","format":false,"excerpt":"[ad_1] A 23\u00aa edi\u00e7\u00e3o da Feira Internacional do Livro de Ribeir\u00e3o Preto traz atividades que prometem agitar o p\u00fablico: as competi\u00e7\u00f5es de poesia Slam. Mas voc\u00ea sabe o que \u00e9 Slam? O acidade on explica essa forma expressiva de poesia que est\u00e1 conquistando o mundo. A hist\u00f3ria O Slam \u00e9\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-31_15-52-32_jpg_2024-07-31_15-52-33.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-31_15-52-32_jpg_2024-07-31_15-52-33.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-31_15-52-32_jpg_2024-07-31_15-52-33.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-31_15-52-32_jpg_2024-07-31_15-52-33.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-31_15-52-32_jpg_2024-07-31_15-52-33.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-dGh","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52593"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/52594"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}