{"id":51740,"date":"2024-05-30T13:40:24","date_gmt":"2024-05-30T16:40:24","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/30\/catedral-de-ribeirao-preto-tem-missa-com-tapetes-de-corpus-christi-veja-o-horario\/"},"modified":"2024-05-30T13:40:24","modified_gmt":"2024-05-30T16:40:24","slug":"catedral-de-ribeirao-preto-tem-missa-com-tapetes-de-corpus-christi-veja-o-horario","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/30\/catedral-de-ribeirao-preto-tem-missa-com-tapetes-de-corpus-christi-veja-o-horario\/","title":{"rendered":"Catedral de Ribeir\u00e3o Preto tem missa com tapetes de Corpus Christi; Veja o hor\u00e1rio"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<p><strong>A Catedral Metropolitana de S\u00e3o Sebasti\u00e3o ter\u00e1 missa de Corpus Christi seguida de prociss\u00e3o nesta quinta-feira (30), \u00e0s 18h30, em Ribeir\u00e3o Preto.<\/strong> Esta ser\u00e1 a \u00faltima das tr\u00eas celebra\u00e7\u00f5es programadas neste dia. As outras foram realizadas \u00e0s 7h30 e 12h.<\/p>\n<p>Segundo a <strong>Catedral<\/strong>, a <strong>prociss\u00e3o <\/strong>percorrer\u00e1 <strong>ruas <\/strong>do <strong>Centro <\/strong>da cidade, por onde foram confeccionados os <strong>tapetes tradicionais <\/strong>para a data religiosa.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<h2 class=\"wp-block-heading\"><strong>O que \u00e9 Corpus Christi?<\/strong><\/h2>\n<p>O <strong>Corpus Christi<\/strong> exalta o <strong>sacramento <\/strong>do <strong>Corpo e Sangue de Cristo<\/strong>. <\/p>\n<p>\u00c9 o \u00fanico dia do ano em que o <strong>Sant\u00edssimo <\/strong>sai&nbsp;em prociss\u00e3o&nbsp;pelas ruas das cidades.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/C7mHxspudbI\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\"background:#FFF;border:0;border-radius:3px;margin: 1px;max-width:540px;min-width:326px;padding:0;width:99.375%;width:-webkit-calc(100% - 2px);width:calc(100% - 2px)\">\n<div style=\"padding:16px\"> <a href=\"https:\/\/www.instagram.com\/reel\/C7mHxspudbI\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\"background:#FFFFFF;line-height:0;padding:0 0;text-align:center;text-decoration:none;width:100%\" target=\"_blank\" rel=\"noopener\"> <\/p>\n<div style=\"flex-direction: row;align-items: center\">\n<div style=\"background-color: #F4F4F4;border-radius: 50%;flex-grow: 0;height: 40px;margin-right: 14px;width: 40px\"><\/div>\n<div style=\"flex-direction: column;flex-grow: 1;justify-content: center\">\n<div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 100px\"><\/div>\n<div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;width: 60px\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0\"><\/div>\n<div style=\"height:50px;margin:0 auto 12px;width:50px\"><\/div>\n<div style=\"padding-top: 8px\">\n<div style=\"color:#3897f0;font-family:Arial,sans-serif;font-size:14px;font-style:normal;font-weight:550;line-height:18px\">Ver essa foto no Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0\"><\/div>\n<div style=\"flex-direction: row;margin-bottom: 14px;align-items: center\">\n<div>\n<div style=\"background-color: #F4F4F4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div>\n<div style=\"background-color: #F4F4F4;height: 12.5px;width: 12.5px;flex-grow: 0;margin-right: 14px;margin-left: 2px\"><\/div>\n<div style=\"background-color: #F4F4F4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px\">\n<div style=\"background-color: #F4F4F4;border-radius: 50%;flex-grow: 0;height: 20px;width: 20px\"><\/div>\n<div style=\"width: 0;height: 0;border-top: 2px solid transparent;border-left: 6px solid #f4f4f4;border-bottom: 2px solid transparent\"><\/div>\n<\/div>\n<div style=\"margin-left: auto\">\n<div style=\"width: 0px;border-top: 8px solid #F4F4F4;border-right: 8px solid transparent\"><\/div>\n<div style=\"background-color: #F4F4F4;flex-grow: 0;height: 12px;width: 16px\"><\/div>\n<div style=\"width: 0;height: 0;border-top: 8px solid #F4F4F4;border-left: 8px solid transparent\"><\/div>\n<\/div>\n<\/div>\n<div style=\"flex-direction: column;flex-grow: 1;justify-content: center;margin-bottom: 24px\">\n<div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 224px\"><\/div>\n<div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;width: 144px\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\"color:#c9c8cd;font-family:Arial,sans-serif;font-size:14px;line-height:17px;margin-bottom:0;margin-top:8px;overflow:hidden;padding:8px 0 7px;text-align:center\"><a href=\"https:\/\/www.instagram.com\/reel\/C7mHxspudbI\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\"color:#c9c8cd;font-family:Arial,sans-serif;font-size:14px;font-style:normal;font-weight:normal;line-height:17px;text-decoration:none\" target=\"_blank\" rel=\"noopener\">Uma publica\u00e7\u00e3o compartilhada por acidade on Ribeir\u00e3o (@acidadeonribeirao)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p>SAIBA MAIS<\/p>\n<p>Confira as estreias nos cinemas de Ribeir\u00e3o no feriado; Assista aos trailers dos filmes<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do&nbsp;<strong>acidade on&nbsp;<\/strong>no&nbsp;<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>&nbsp;e no&nbsp;<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta&nbsp;<a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Saidinha dos presos est\u00e1 proibida?<\/p>\n<p>O post Catedral de Ribeir\u00e3o Preto tem missa com tapetes de Corpus Christi; Veja o hor\u00e1rio apareceu primeiro em ACidade ON Ribeir\u00e3o Preto.<\/p>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/catedral-de-ribeirao-preto-tem-missa-com-tapetes-de-corpus-christi-veja-o-horario\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Catedral Metropolitana de S\u00e3o Sebasti\u00e3o ter\u00e1 missa de Corpus Christi seguida de prociss\u00e3o nesta quinta-feira (30), \u00e0s 18h30, em Ribeir\u00e3o Preto. Esta ser\u00e1 a \u00faltima das tr\u00eas celebra\u00e7\u00f5es programadas neste dia. As outras foram realizadas \u00e0s 7h30 e 12h. Segundo a Catedral, a prociss\u00e3o percorrer\u00e1 ruas do Centro da cidade, por onde foram &#8230; <a title=\"Catedral de Ribeir\u00e3o Preto tem missa com tapetes de Corpus Christi; Veja o hor\u00e1rio\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/30\/catedral-de-ribeirao-preto-tem-missa-com-tapetes-de-corpus-christi-veja-o-horario\/\" aria-label=\"Read more about Catedral de Ribeir\u00e3o Preto tem missa com tapetes de Corpus Christi; Veja o hor\u00e1rio\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":51741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-51740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-10.25.16-1_2024-05-30_16-01-31_jpeg_2024-05-30_16-01-33-scaled.webp.webp?fit=2560%2C1440&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-10.25.16-1_2024-05-30_16-01-31_jpeg_2024-05-30_16-01-33-scaled.webp.webp?fit=2560%2C1440&ssl=1",2560,1440,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-10.25.16-1_2024-05-30_16-01-31_jpeg_2024-05-30_16-01-33-scaled.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-10.25.16-1_2024-05-30_16-01-31_jpeg_2024-05-30_16-01-33-scaled.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-10.25.16-1_2024-05-30_16-01-31_jpeg_2024-05-30_16-01-33-scaled.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-10.25.16-1_2024-05-30_16-01-31_jpeg_2024-05-30_16-01-33-scaled.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-10.25.16-1_2024-05-30_16-01-31_jpeg_2024-05-30_16-01-33-scaled.webp.webp?fit=1536%2C864&ssl=1",1536,864,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-10.25.16-1_2024-05-30_16-01-31_jpeg_2024-05-30_16-01-33-scaled.webp.webp?fit=2048%2C1152&ssl=1",2048,1152,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Catedral Metropolitana de S\u00e3o Sebasti\u00e3o ter\u00e1 missa de Corpus Christi seguida de prociss\u00e3o nesta quinta-feira (30), \u00e0s 18h30, em Ribeir\u00e3o Preto. Esta ser\u00e1 a \u00faltima das tr\u00eas celebra\u00e7\u00f5es programadas neste dia. As outras foram realizadas \u00e0s 7h30 e 12h. Segundo a Catedral, a prociss\u00e3o percorrer\u00e1 ruas do Centro da cidade, por onde foram&hellip;","jetpack-related-posts":[{"id":51696,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/29\/tapetes-de-serragem-sao-destaque-em-celebracao-de-corpus-christi-em-paroquia-de-ribeirao\/","url_meta":{"origin":51740,"position":0},"title":"Tapetes de serragem s\u00e3o destaque em celebra\u00e7\u00e3o de Corpus Christi em Par\u00f3quia de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"29 de May de 2024","format":false,"excerpt":"[ad_1] Igrejas de Ribeir\u00e3o Preto realizam a celebra\u00e7\u00e3o de Corpus Christi nesta quinta-feira (30) e, al\u00e9m de missas e prociss\u00f5es, algumas par\u00f3quias tamb\u00e9m realizam a montagem dos tradicionais tapetes de serragem. Esse \u00e9 o caso da Par\u00f3quia Nossa Senhora de Lourdes, localizada na rua Major Ricardo Guimar\u00e3es, 603, no Parque\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-29-at-19.13.01_2024-05-29_23-49-28_jpeg_2024-05-29_23-49-30-scaled.webp.webp?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-29-at-19.13.01_2024-05-29_23-49-28_jpeg_2024-05-29_23-49-30-scaled.webp.webp?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-29-at-19.13.01_2024-05-29_23-49-28_jpeg_2024-05-29_23-49-30-scaled.webp.webp?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-29-at-19.13.01_2024-05-29_23-49-28_jpeg_2024-05-29_23-49-30-scaled.webp.webp?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":51742,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/30\/novo-trecho-da-avenida-nove-de-julho-em-ribeirao-preto-sera-interditado-por-60-dias\/","url_meta":{"origin":51740,"position":1},"title":"Novo trecho da avenida Nove de Julho em Ribeir\u00e3o Preto ser\u00e1 interditado por 60 dias","author":"ismaelcolosi.com.br","date":"30 de May de 2024","format":false,"excerpt":"[ad_1] Um novo trecho da avenida Nove de Julho ser\u00e1 interditado por 60 dias, a partir desta sexta-feira (31). O bloqueio ser\u00e1 na pista bairro-Centro, da rua Cerqueira C\u00e9sar at\u00e9 a rua Comandante Marcondes Salgado. Os acessos neste trecho ser\u00e3o liberados somente para os moradores e comerciantes da regi\u00e3o. A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-66_2024-05-30_16-47-36_jpg_2024-05-30_16-47-37.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-66_2024-05-30_16-47-36_jpg_2024-05-30_16-47-37.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-66_2024-05-30_16-47-36_jpg_2024-05-30_16-47-37.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-66_2024-05-30_16-47-36_jpg_2024-05-30_16-47-37.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-66_2024-05-30_16-47-36_jpg_2024-05-30_16-47-37.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44172,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/26\/semana-santa-confira-a-programacao-das-missas-em-igrejas-de-ribeirao-preto\/","url_meta":{"origin":51740,"position":2},"title":"Semana Santa: Confira a programa\u00e7\u00e3o das missas em igrejas de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"26 de March de 2024","format":false,"excerpt":"[ad_1] Igrejas cat\u00f3licas de Ribeir\u00e3o Preto divulgaram a programa\u00e7\u00e3o para a Semana Santa. As celebra\u00e7\u00f5es marcam a trajet\u00f3ria de Jesus Cristo at\u00e9 a crucifica\u00e7\u00e3o e a ressurrei\u00e7\u00e3o. Confira as datas e hor\u00e1rios em sete igrejas de Ribeir\u00e3o: 1. Catedral Metropolitana de S\u00e3o Sebasti\u00e3o Quinta-feira (28) Ceia do Senhor (Lava-p\u00e9s) \u2013\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51360,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/27\/corpus-christi-entenda-se-e-feriado-ou-ponto-facultativo-em-ribeirao-preto\/","url_meta":{"origin":51740,"position":3},"title":"Corpus Christi: Entenda se \u00e9 feriado ou ponto facultativo em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"27 de May de 2024","format":false,"excerpt":"[ad_1] O Dia de Corpus Christi, na pr\u00f3xima quinta-feira (30), comemora a institui\u00e7\u00e3o da eucaristia, um sacramento cat\u00f3lico. \u00c9 celebrado sempre 60 dias ap\u00f3s a P\u00e1scoa. Mas, afinal: \u00e9 feriado ou n\u00e3o? Pelo Governo Federal, a data \u00e9 considera ponto facultativo, por\u00e9m, cada munic\u00edpio tem a liberdade de considerar a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-27_12-36-20_jpg_2024-05-27_12-36-20.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-27_12-36-20_jpg_2024-05-27_12-36-20.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-27_12-36-20_jpg_2024-05-27_12-36-20.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-27_12-36-20_jpg_2024-05-27_12-36-20.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-27_12-36-20_jpg_2024-05-27_12-36-20.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44610,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/28\/confira-as-ruas-e-avenidas-de-ribeirao-interditadas-para-atividades-religiosas\/","url_meta":{"origin":51740,"position":4},"title":"Confira as ruas e avenidas de Ribeir\u00e3o interditadas para atividades religiosas","author":"ismaelcolosi.com.br","date":"28 de March de 2024","format":false,"excerpt":"[ad_1] Durante o feriado de Sexta-feira Santa, oito pontos de vias p\u00fablicas ser\u00e3o interditados em Ribeir\u00e3o Preto por conta das atividades religiosas que ocorrem na cidade (veja abaixo). Os bloqueios tempor\u00e1rios v\u00e3o ocorrer em diversos bairros e ser\u00e3o monitorados por agentes de tr\u00e2nsito da RP Mobi, empresa que gerencia o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-5-2.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-5-2.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-5-2.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-5-2.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-5-2.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51849,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/31\/gcm-recupera-caminhonete-furtada-no-feriado-de-corpus-christi-em-ribeirao-preto\/","url_meta":{"origin":51740,"position":5},"title":"GCM recupera caminhonete furtada no feriado de Corpus Christi em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"31 de May de 2024","format":false,"excerpt":"[ad_1] A Guarda Civil Metropolitana (GCM) de Ribeir\u00e3o Preto localizou nesta sexta-feira (31), uma caminhonete Toyota Hilux furtada na zona Sul da cidade. Segundo as informa\u00e7\u00f5es, o ve\u00edculo pertence a um m\u00e9dico ortopedista da cidade e foi furtado nesta quinta-feira (30), feriado de Corpus Christi, enquanto o homem estava jantando\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-05-31_19-39-01_png_2024-05-31_19-39-02.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-05-31_19-39-01_png_2024-05-31_19-39-02.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-05-31_19-39-01_png_2024-05-31_19-39-02.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-05-31_19-39-01_png_2024-05-31_19-39-02.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-05-31_19-39-01_png_2024-05-31_19-39-02.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-dsw","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=51740"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/51741"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=51740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=51740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=51740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}