{"id":51581,"date":"2024-05-28T21:11:23","date_gmt":"2024-05-29T00:11:23","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/gusttavo-lima-se-apresenta-na-regiao-de-ribeirao-preto-ingressos-estao-disponiveis\/"},"modified":"2024-05-28T21:11:23","modified_gmt":"2024-05-29T00:11:23","slug":"gusttavo-lima-se-apresenta-na-regiao-de-ribeirao-preto-ingressos-estao-disponiveis","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/gusttavo-lima-se-apresenta-na-regiao-de-ribeirao-preto-ingressos-estao-disponiveis\/","title":{"rendered":"Gusttavo Lima se apresenta na regi\u00e3o de Ribeir\u00e3o Preto; Ingressos est\u00e3o dispon\u00edveis"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Os ingressos para o show do cantor <strong>Gusttavo Lima<\/strong> em <strong>Pontal<\/strong>, cidade a aproximadamente 38 quil\u00f4metros de <strong>Ribeir\u00e3o Preto<\/strong>, ainda est\u00e3o dispon\u00edveis.<\/p>\n<p>A apresenta\u00e7\u00e3o acontece no dia<strong> 06 de junho<\/strong>, a partir das 21h, durante o <strong>Pontal Rodeo Music<\/strong>. O evento segue at\u00e9 o dia 8 de junho e ter\u00e1 <strong>pista solid\u00e1ria<\/strong> nesta data.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>Os ingressos para o show do <strong>Gusttavo Lima<\/strong> est\u00e3o dispon\u00edveis e podem ser adquiridos de forma on-line. <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Os valores variam entre<strong> R$ 90<\/strong> e <strong>R$ 370<\/strong> \u2013 veja abaixo.<\/mark><\/p>\n<p>Na programa\u00e7\u00e3o da festa tamb\u00e9m est\u00e3o o <strong>DJ Pedro Sampaio<\/strong>, o cantor <strong>L\u00e9o Santana<\/strong> e as duplas <strong>Jo\u00e3o Bosco &amp; Vin\u00edcius<\/strong> e <strong>Clayton &amp; Rom\u00e1rio<\/strong>.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Confira os valores e a programa\u00e7\u00e3o dos shows<\/strong><\/h2>\n<ul>\n<li><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Dia 06 de junho \u2013 Gusttavo Lima<\/mark><\/strong><\/li>\n<\/ul>\n<p>\u2013 Pista | R$ 90 + taxas<\/p>\n<p>\u2013 \u00c1rea Vip | R$ 200,00 + taxas<\/p>\n<p>\u2013 Camarote individual | R$ 370 + taxas<\/p>\n<ul>\n<li><strong>Dia 07 de junho \u2013 Pedro Sampaio e Jo\u00e3o Bosco &amp; Vin\u00edcius<\/strong><\/li>\n<\/ul>\n<p>\u2013 Pista | R$ 70 + taxas<\/p>\n<p>\u2013 \u00c1rea Vip | R$ 150,00 + taxas<\/p>\n<p>\u2013 Camarote individual | R$ 200 + taxas<\/p>\n<ul>\n<li><strong>Dia 08 de junho \u2013 L\u00e9o Santana e Clayton &amp; Rom\u00e1rio<\/strong><\/li>\n<\/ul>\n<p>\u2013 \u00c1rea Vip | R$ 160,00 + taxas<\/p>\n<p>\u2013 Camarote individual | R$ 250 + taxas<\/p>\n<p>Os ingressos est\u00e3o dispon\u00edveis atrav\u00e9s do link disponibilizado no perfil oficial do evento no <em>Instagram <\/em>(<a href=\"https:\/\/www.instagram.com\/pontalrodeomusic\/\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>). Os valores podem ser alterados sem aviso pr\u00e9vio.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Pista solid\u00e1ria<\/strong><\/h3>\n<p>De acordo com a organiza\u00e7\u00e3o do evento, os ingressos para o <strong>setor pista<\/strong> do dia 8 de junho ser\u00e3o solid\u00e1rios. Os interessados dever\u00e3o trocar <strong>1 kg de alimento n\u00e3o perec\u00edvel<\/strong>. <a href=\"https:\/\/www.instagram.com\/p\/C7gpB_8OxCw\/?utm_source=ig_web_copy_link&amp;igsh=MzRlODBiNWFlZA==\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui e confira os pontos para troca.<\/a><\/p>\n<h4 class=\"wp-block-heading\"><strong>Servi\u00e7o<\/strong><\/h4>\n<p><em>Pontal Rodeo Music<\/em><\/p>\n<p>Quando: de 06 a 08 de junho<\/p>\n<p>Onde: Parque Permanente de Exposi\u00e7\u00f5es Isaura Moro Ferrante \u2013 rua Felipe Jos\u00e9 Martins, 1200, Amadeu Carnesseca \u2013 Pontal<\/p>\n<p>Para mais informa\u00e7\u00f5es, acessa p\u00e1gina oficial do evento (<a href=\"https:\/\/www.instagram.com\/pontalrodeomusic\/\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>)<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Rede de cinemas com salas em Ribeir\u00e3o faz promo\u00e7\u00e3o de ingressos a R$ 12<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Por que Ana Maria Braga foi acusada de transfobia?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/gusttavo-lima-se-apresenta-na-regiao-de-ribeirao-preto-ingressos-estao-disponiveis\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Os ingressos para o show do cantor Gusttavo Lima em Pontal, cidade a aproximadamente 38 quil\u00f4metros de Ribeir\u00e3o Preto, ainda est\u00e3o dispon\u00edveis. A apresenta\u00e7\u00e3o acontece no dia 06 de junho, a partir das 21h, durante o Pontal Rodeo Music. O evento segue at\u00e9 o dia 8 de junho e ter\u00e1 pista solid\u00e1ria nesta data. &#8230; <a title=\"Gusttavo Lima se apresenta na regi\u00e3o de Ribeir\u00e3o Preto; Ingressos est\u00e3o dispon\u00edveis\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/gusttavo-lima-se-apresenta-na-regiao-de-ribeirao-preto-ingressos-estao-disponiveis\/\" aria-label=\"Read more about Gusttavo Lima se apresenta na regi\u00e3o de Ribeir\u00e3o Preto; Ingressos est\u00e3o dispon\u00edveis\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":47785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-51581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=900%2C692&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=900%2C692&ssl=1",900,692,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=300%2C231&ssl=1",300,231,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=768%2C591&ssl=1",768,591,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=900%2C692&ssl=1",900,692,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=900%2C692&ssl=1",900,692,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=900%2C692&ssl=1",900,692,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Os ingressos para o show do cantor Gusttavo Lima em Pontal, cidade a aproximadamente 38 quil\u00f4metros de Ribeir\u00e3o Preto, ainda est\u00e3o dispon\u00edveis. A apresenta\u00e7\u00e3o acontece no dia 06 de junho, a partir das 21h, durante o Pontal Rodeo Music. O evento segue at\u00e9 o dia 8 de junho e ter\u00e1 pista solid\u00e1ria nesta data.&hellip;","jetpack-related-posts":[{"id":49441,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/10\/gusttavo-lima-faz-show-na-regiao-de-ribeirao-preto-veja-como-comprar-ingressos\/","url_meta":{"origin":51581,"position":0},"title":"Gusttavo Lima faz show na regi\u00e3o de Ribeir\u00e3o Preto; Veja como comprar ingressos","author":"ismaelcolosi.com.br","date":"10 de May de 2024","format":false,"excerpt":"[ad_1] O cantor Gusttavo Lima se apresenta em Pontal, cidade a cerca de 38 quil\u00f4metros de Ribeir\u00e3o Preto, no dia 06 de junho, a partir das 21h. A apresenta\u00e7\u00e3o faz parte do Pontal Rodeo Music, que acontece entre os dias 06 e 08 de junho, no Parque Permanente de Exposi\u00e7\u00f5es\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52032,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/03\/rodeio-na-regiao-de-ribeirao-preto-tem-shows-de-gusttavo-lima-e-leo-santana\/","url_meta":{"origin":51581,"position":1},"title":"Rodeio na regi\u00e3o de Ribeir\u00e3o Preto tem shows de Gusttavo Lima e L\u00e9o Santana","author":"ismaelcolosi.com.br","date":"3 de June de 2024","format":false,"excerpt":"[ad_1] Os cantores Gusttavo Lima e L\u00e9o Santana fazem shows em Pontal, na regi\u00e3o de Ribeir\u00e3o Preto, durante o \u201cPontal Rodeo Music\u201d. O evento, que acontece entre os dias 6 e 8 de junho, ser\u00e1 no Parque Permanente de Exposi\u00e7\u00f5es Isaura Moro Ferrante. Al\u00e9m de Gusttavo Lima e L\u00e9o Santana,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35443,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/06\/ribeirao-rodeo-music-divulga-programacao-com-ana-castela-alok-e-gusttavo-lima\/","url_meta":{"origin":51581,"position":2},"title":"Ribeir\u00e3o Rodeo Music divulga programa\u00e7\u00e3o com Ana Castela, Alok e Gusttavo Lima","author":"ismaelcolosi.com.br","date":"6 de February de 2024","format":false,"excerpt":"[ad_1] A programa\u00e7\u00e3o do Ribeir\u00e3o Rodeo Music 2024 foi anunciada nesta ter\u00e7a-feira (6). S\u00e3o 16 shows com nomes do sertanejo entre os dias 20, 26, 27 e 30 de abril, no Parque Permanente de Exposi\u00e7\u00f5es de Ribeir\u00e3o Preto. Entre as atra\u00e7\u00f5es est\u00e3o Ana Castela, Gusttavo Lima, Jorge e Mateus e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ana-castela-1024x683.jpeg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ana-castela-1024x683.jpeg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ana-castela-1024x683.jpeg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ana-castela-1024x683.jpeg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":35494,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/06\/ivete-sangalo-abre-venda-de-ingressos-para-show-em-ribeirao-veja-os-valores\/","url_meta":{"origin":51581,"position":3},"title":"Ivete Sangalo abre venda de ingressos para show em Ribeir\u00e3o; Veja os valores","author":"ismaelcolosi.com.br","date":"6 de February de 2024","format":false,"excerpt":"[ad_1] A venda de ingressos para o show da cantora Ivete Sangalo em Ribeir\u00e3o Preto come\u00e7ou nesta ter\u00e7a-feira (6). As entradas para apresenta\u00e7\u00e3o, que acontece na Arena Nicnet\/Est\u00e1dio Santa Cruz, custam entre R$ 150 e R$ 3 mil. O show est\u00e1 marcado para o dia 7 de dezembro. S\u00e3o oito\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ivete-sangalo-1.jpg?fit=1200%2C699&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ivete-sangalo-1.jpg?fit=1200%2C699&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ivete-sangalo-1.jpg?fit=1200%2C699&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ivete-sangalo-1.jpg?fit=1200%2C699&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ivete-sangalo-1.jpg?fit=1200%2C699&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":38827,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/veja-os-valores-dos-ingressos-para-o-ribeirao-rodeo-music\/","url_meta":{"origin":51581,"position":4},"title":"Veja os valores dos ingressos para o Ribeir\u00e3o Rodeo Music","author":"ismaelcolosi.com.br","date":"21 de February de 2024","format":false,"excerpt":"[ad_1] Faltando dois meses para o Ribeir\u00e3o Rodeo Music, que acontece de 20 a 30 de abril, as vendas de ingressos para o evento j\u00e1 est\u00e3o acontecendo de forma on-line e, desde ter\u00e7a-feira (20), come\u00e7ou tamb\u00e9m nas lojas Oscar Cal\u00e7ados do Novo Shopping e no Centro de Ribeir\u00e3o Preto (veja\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":38844,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/veja-os-valores-dos-ingressos-para-o-ribeirao-rodeo-music-2\/","url_meta":{"origin":51581,"position":5},"title":"Veja os valores dos ingressos para o Ribeir\u00e3o Rodeo Music","author":"ismaelcolosi.com.br","date":"21 de February de 2024","format":false,"excerpt":"[ad_1] Faltando dois meses para o Ribeir\u00e3o Rodeo Music, que acontece de 20 a 30 de abril, as vendas de ingressos para o evento j\u00e1 est\u00e3o acontecendo de forma on-line e, desde ter\u00e7a-feira (20), come\u00e7ou tamb\u00e9m nas lojas Oscar Cal\u00e7ados do Novo Shopping e no Centro de Ribeir\u00e3o Preto (veja\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-dpX","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=51581"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/47785"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=51581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=51581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=51581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}