{"id":51506,"date":"2024-05-28T14:19:00","date_gmt":"2024-05-28T17:19:00","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/policia-prende-homem-condenado-a-30-anos-por-matar-a-namorada-na-regiao-de-ribeirao\/"},"modified":"2024-05-28T14:19:00","modified_gmt":"2024-05-28T17:19:00","slug":"policia-prende-homem-condenado-a-30-anos-por-matar-a-namorada-na-regiao-de-ribeirao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/policia-prende-homem-condenado-a-30-anos-por-matar-a-namorada-na-regiao-de-ribeirao\/","title":{"rendered":"Pol\u00edcia prende homem condenado a 30 anos por matar a namorada na regi\u00e3o de Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>A Pol\u00edcia Civil de Sert\u00e3ozinho prendeu nesta ter\u00e7a-feira (28) Junio Cezar Roza Giorgetti, condenado a 30 anos de pris\u00e3o pelo assassinato da namorada em Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto.<\/strong> <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">O crime ocorreu em 2013, quando a v\u00edtima, Vanessa Nobre Martins, tinha 19 anos.<\/mark><\/p>\n<p>Segundo a pol\u00edcia, <strong>Junio<\/strong>, que est\u00e1 com <strong>33 anos<\/strong> de <strong>idade<\/strong>, foi <strong>capturado <\/strong>quando sa\u00eda de sua <strong>resid\u00eancia<\/strong>, em <strong>Sert\u00e3ozinho<\/strong>. Havia um <strong>mandado de pris\u00e3o<\/strong> contra ele.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>O <strong>j\u00fari popular<\/strong> ocorreu em <strong>2023<\/strong>. O <strong>acusado <\/strong>chegou a ser preso, por\u00e9m havia conseguido habeas corpus para recorrer em <strong>liberdade <\/strong>at\u00e9 que a <strong>senten\u00e7a <\/strong>tornou-se <strong>definitiva <\/strong>com o <strong>\u201ctr\u00e2nsito em julgado\u201d<\/strong>, sem mais possibilidade de recurso.<\/p>\n<h2 class=\"wp-block-heading\"><strong>O crime<\/strong><\/h2>\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><strong>Vanessa Nobre Martins<\/strong> foi encontrada <strong>morta <\/strong>em um <strong>c\u00f3rrego <\/strong>no bairro na <strong>Cohab III<\/strong>, em <strong>Sert\u00e3ozinho<\/strong>, dez dias ap\u00f3s ser considerada desaparecida por sua fam\u00edlia.<\/mark><\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">No dia em que o corpo foi localizado, o acusado chegou a desmaiar no local.<\/mark><\/p>\n<p><strong>Familiares <\/strong>da <strong>v\u00edtima <\/strong>apontaram \u00e0 \u00e9poca que o <strong>casal brigava <\/strong>constantemente por conta de <strong>ci\u00fames<\/strong>.<\/p>\n<p><strong>Junio <\/strong>dever\u00e1 ser encaminhado \u00e0 <strong>Cadeia P\u00fablica de Prad\u00f3polis<\/strong>.<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Interior de SP amanhece com ce\u00fa nublado nesta ter\u00e7a; Veja previs\u00e3o do tempo<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Pode privatizar praia? Entenda nova PEC<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/policia-prende-homem-condenado-a-30-anos-por-matar-a-namorada-na-regiao-de-ribeirao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Pol\u00edcia Civil de Sert\u00e3ozinho prendeu nesta ter\u00e7a-feira (28) Junio Cezar Roza Giorgetti, condenado a 30 anos de pris\u00e3o pelo assassinato da namorada em Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto. O crime ocorreu em 2013, quando a v\u00edtima, Vanessa Nobre Martins, tinha 19 anos. Segundo a pol\u00edcia, Junio, que est\u00e1 com 33 anos de &#8230; <a title=\"Pol\u00edcia prende homem condenado a 30 anos por matar a namorada na regi\u00e3o de Ribeir\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/policia-prende-homem-condenado-a-30-anos-por-matar-a-namorada-na-regiao-de-ribeirao\/\" aria-label=\"Read more about Pol\u00edcia prende homem condenado a 30 anos por matar a namorada na regi\u00e3o de Ribeir\u00e3o\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":51507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-51506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-08.40.33_2024-05-28_11-40-46_jpeg_2024-05-28_11-40-46.webp.webp?fit=1920%2C1080&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-08.40.33_2024-05-28_11-40-46_jpeg_2024-05-28_11-40-46.webp.webp?fit=1920%2C1080&ssl=1",1920,1080,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-08.40.33_2024-05-28_11-40-46_jpeg_2024-05-28_11-40-46.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-08.40.33_2024-05-28_11-40-46_jpeg_2024-05-28_11-40-46.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-08.40.33_2024-05-28_11-40-46_jpeg_2024-05-28_11-40-46.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-08.40.33_2024-05-28_11-40-46_jpeg_2024-05-28_11-40-46.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-08.40.33_2024-05-28_11-40-46_jpeg_2024-05-28_11-40-46.webp.webp?fit=1536%2C864&ssl=1",1536,864,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-08.40.33_2024-05-28_11-40-46_jpeg_2024-05-28_11-40-46.webp.webp?fit=1920%2C1080&ssl=1",1920,1080,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Pol\u00edcia Civil de Sert\u00e3ozinho prendeu nesta ter\u00e7a-feira (28) Junio Cezar Roza Giorgetti, condenado a 30 anos de pris\u00e3o pelo assassinato da namorada em Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto. O crime ocorreu em 2013, quando a v\u00edtima, Vanessa Nobre Martins, tinha 19 anos. Segundo a pol\u00edcia, Junio, que est\u00e1 com 33 anos de&hellip;","jetpack-related-posts":[{"id":50587,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/17\/preso-homem-foragido-ha-dois-anos-apos-matar-namorada-em-ribeirao-preto\/","url_meta":{"origin":51506,"position":0},"title":"Preso homem foragido h\u00e1 dois anos ap\u00f3s matar namorada em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"17 de May de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia de Minas Gerais prendeu o homem acusado de matar a namorada com uma facada no pesco\u00e7o, em outubro de 2022, no Centro de Ribeir\u00e3o Preto. A pris\u00e3o de Gabriel Francisco Barbosa, ocorreu no dia 7 de maio em Uberl\u00e2ndia. O homem estava foragido h\u00e1 dois anos, desde\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-05-17_15-59-23.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-05-17_15-59-23.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-05-17_15-59-23.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-05-17_15-59-23.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-05-17_15-59-23.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28769,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/16\/acusado-de-matar-idoso-de-82-anos-e-condenado\/","url_meta":{"origin":51506,"position":1},"title":"Acusado de matar idoso de 82 anos \u00e9 condenado","author":"ismaelcolosi.com.br","date":"16 de January de 2024","format":false,"excerpt":"[ad_1] J\u00fari entendeu que houve homic\u00eddio privilegiado, isto \u00e9, quando o autor teria agido por fortes emo\u00e7\u00f5es ou provoca\u00e7\u00e3o da v\u00edtima 16 de janeiro de 2024 | 16:15 0Por: Adalberto LuqueMarcelo Lopes de Farias, de 68 anos, foi condenado, nesta segunda-feira (15), pelo homic\u00eddio de Hugo Rayol, de 82 anos.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-16-jan-2024-juri-idoso-foto-x-tudo-arquivo-scaled.jpg?fit=861%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-16-jan-2024-juri-idoso-foto-x-tudo-arquivo-scaled.jpg?fit=861%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-16-jan-2024-juri-idoso-foto-x-tudo-arquivo-scaled.jpg?fit=861%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-16-jan-2024-juri-idoso-foto-x-tudo-arquivo-scaled.jpg?fit=861%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":27313,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/utm_sourcerssutm_mediumrssutm_campaignavo-condenado-a-mais-de-30-anos-de-cadeia-por-abusar-das-netas-em-rp-e-preso-pelo-baep-em-sertaozinho\/","url_meta":{"origin":51506,"position":2},"title":"Av\u00f4 condenado a mais de 30 anos de CADEIA por abusar das netas em RP \u00e9 preso pelo BAEP em Sert\u00e3ozinho \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"11 de January de 2024","format":false,"excerpt":"[ad_1] Um homem condenado a mais de 30 anos de CADEIA por abusar sexualmente das pr\u00f3prias netas foi preso pela equipe do 11\u00ba BAEP (Batalh\u00e3o de A\u00e7\u00f5es Especiais de Pol\u00edcia) na tarde desta quinta-feira (11\/1), na cidade de Sert\u00e3ozinho.\u00a0 Segundo apurado com EXCLUSIVIDADE pelo X TUDO RIBEIR\u00c3O, durante o patrulhamento\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-11-at-22.47.04.jpeg?fit=1200%2C1122&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-11-at-22.47.04.jpeg?fit=1200%2C1122&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-11-at-22.47.04.jpeg?fit=1200%2C1122&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-11-at-22.47.04.jpeg?fit=1200%2C1122&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-11-at-22.47.04.jpeg?fit=1200%2C1122&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28500,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/16\/aposentado-e-condenado-a-8-anos-de-prisao-por-matar-vizinho-a-tiros-em-ribeirao-preto\/","url_meta":{"origin":51506,"position":3},"title":"Aposentado \u00e9 condenado a 8 anos de pris\u00e3o por matar vizinho a tiros em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"16 de January de 2024","format":false,"excerpt":"[ad_1] O aposentado Marcelo Lopes de Faria, de 66 anos, acusado de matar a tiros o vizinho, Hugo Rayol, de 82 anos, em Ribeir\u00e3o Preto, no ano de 2022, foi condenado a 8 anos e 10 meses de reclus\u00e3o em regime semiaberto. O acusado foi levado a J\u00fari Popular nesta\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33629,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/30\/utm_sourcerssutm_mediumrssutm_campaignlixo-condenado-a-8-anos-por-abusar-de-uma-crianca-de-6-anos-em-2019-e-preso-trabalhando-na-av-do-cafe-em-rp\/","url_meta":{"origin":51506,"position":4},"title":"LIXO condenado a 8 anos por abusar de uma crian\u00e7a de 6 anos em 2019 \u00e9 preso trabalhando na Av. do Caf\u00e9 em RP \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"30 de January de 2024","format":false,"excerpt":"[ad_1] Um LIXO da SOCIEDADE procurado pela Justi\u00e7a condenado a 8 anos de CADEIA pelo crime de ESTUPRO DE VULNER\u00c1VEL no ano de 2019, foi preso pela PM (Pol\u00edcia Militar) enquanto trabalhava em uma empresa situada na Vila Am\u00e9lia, zona Oeste de Ribeir\u00e3o Preto.\u00a0 Segundo informa\u00e7\u00f5es da PM, durante o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706620903_cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706620903_cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706620903_cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706620903_cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706620903_cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":61690,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/22\/dentista-que-matou-auditor-fiscal-na-regiao-de-ribeirao-preto-e-condenado-a-14-anos-de-prisao\/","url_meta":{"origin":51506,"position":5},"title":"Dentista que matou auditor fiscal na regi\u00e3o de Ribeir\u00e3o Preto \u00e9 condenado a 14 anos de pris\u00e3o","author":"ismaelcolosi.com.br","date":"22 de August de 2024","format":false,"excerpt":"[ad_1] O dentista Samir Moussa foi condenado a 14 anos de pris\u00e3o em regime fechado pela morte de Adriano Willian de Oliveira, de 52 anos. O caso aconteceu em 2022, no munic\u00edpio de Franca, regi\u00e3o de Ribeir\u00e3o Preto. O Tribunal do J\u00fari foi realizado nesta quinta-feira (22), no F\u00f3rum de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/dentista_1200x675_15032022155939.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/dentista_1200x675_15032022155939.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/dentista_1200x675_15032022155939.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/dentista_1200x675_15032022155939.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/dentista_1200x675_15032022155939.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-doK","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=51506"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/51507"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=51506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=51506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=51506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}