{"id":51479,"date":"2024-05-28T13:06:12","date_gmt":"2024-05-28T16:06:12","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/obra-emergencial-no-centro-de-ribeirao-preto-pode-provocar-falta-dagua-veja-onde\/"},"modified":"2024-05-28T13:06:12","modified_gmt":"2024-05-28T16:06:12","slug":"obra-emergencial-no-centro-de-ribeirao-preto-pode-provocar-falta-dagua-veja-onde","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/obra-emergencial-no-centro-de-ribeirao-preto-pode-provocar-falta-dagua-veja-onde\/","title":{"rendered":"Obra emergencial no Centro de Ribeir\u00e3o Preto pode provocar falta d\u2019\u00e1gua; Veja onde"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>A <strong>Saerp (<\/strong><a href=\"https:\/\/www.ribeiraopreto.sp.gov.br\/portal\/saerp\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto<\/strong><\/a><strong>) informou que pode faltar \u00e1gua na regi\u00e3o Central de Ribeir\u00e3o Preto, <\/strong>nesta<strong>\u00a0ter\u00e7a-feira (28)<\/strong>. O alerta aos consumidores \u00e9 de que a falta de abastecimento, <strong>por conta de uma obra emergencial<\/strong>, ocorra <strong>at\u00e9 \u00e0s 17h<\/strong>.   <\/p>\n<p>Os bairros que podem ser afetados s\u00e3o o <strong>Centro, Vila Seixas<\/strong> e <strong>regi\u00f5es pr\u00f3ximas<\/strong>. <\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>Ap\u00f3s a finaliza\u00e7\u00e3o da obra, o sistema ser\u00e1 religado e o abastecimento voltar\u00e1 de forma gradativa. <\/p>\n<p>Caso o seu bairro apresente falhas no abastecimento, entre em contato com a\u00a0<strong>Saerp<\/strong>\u00a0pelo telefone 0800 115 0115 ou procure por um posto de atendimento (<a href=\"https:\/\/www.ribeiraopreto.sp.gov.br\/portal\/saerp\/postos-de-atendimento\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>). <\/p>\n<p>SAIBA MAIS<br \/>Rede de cinemas com salas em Ribeir\u00e3o faz promo\u00e7\u00e3o de ingressos a R$ 12<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta <a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Qual \u00e9 o caso do \u201cLinha Direta\u201d desta semana?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/obra-emergencial-no-centro-de-ribeirao-preto-pode-provocar-falta-dagua-veja-onde\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que pode faltar \u00e1gua na regi\u00e3o Central de Ribeir\u00e3o Preto, nesta\u00a0ter\u00e7a-feira (28). O alerta aos consumidores \u00e9 de que a falta de abastecimento, por conta de uma obra emergencial, ocorra at\u00e9 \u00e0s 17h. Os bairros que podem ser afetados s\u00e3o o Centro, Vila &#8230; <a title=\"Obra emergencial no Centro de Ribeir\u00e3o Preto pode provocar falta d\u2019\u00e1gua; Veja onde\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/obra-emergencial-no-centro-de-ribeirao-preto-pode-provocar-falta-dagua-veja-onde\/\" aria-label=\"Read more about Obra emergencial no Centro de Ribeir\u00e3o Preto pode provocar falta d\u2019\u00e1gua; Veja onde\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":51480,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-51479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716912372_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716912372_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1",1200,900,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716912372_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716912372_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=300%2C225&ssl=1",300,225,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716912372_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=768%2C576&ssl=1",768,576,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716912372_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1024%2C768&ssl=1",1024,768,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716912372_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1",1200,900,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716912372_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1",1200,900,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que pode faltar \u00e1gua na regi\u00e3o Central de Ribeir\u00e3o Preto, nesta\u00a0ter\u00e7a-feira (28). O alerta aos consumidores \u00e9 de que a falta de abastecimento, por conta de uma obra emergencial, ocorra at\u00e9 \u00e0s 17h. Os bairros que podem ser afetados s\u00e3o o Centro, Vila&hellip;","jetpack-related-posts":[{"id":58539,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/31\/saerp-alerta-para-falta-dagua-em-5-bairros-de-ribeirao-preto-ate-amanha\/","url_meta":{"origin":51479,"position":0},"title":"Saerp alerta para falta d\u2019\u00e1gua em 5 bairros de Ribeir\u00e3o Preto at\u00e9 amanh\u00e3","author":"ismaelcolosi.com.br","date":"31 de July de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) alerta para falta d\u2019\u00e1gua em cinco bairros de Ribeir\u00e3o Preto at\u00e9 quinta-feira (1\u00ba de agosto), no per\u00edodo da manh\u00e3. Segundo a pasta, a falha no abastecimento pode ser ocasionada por conta da substitui\u00e7\u00e3o emergencial de uma bomba submersa no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4050,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/20\/saerp-alerta-para-falta-dagua-em-bairros-da-zona-sul-de-ribeirao-preto-2\/","url_meta":{"origin":51479,"position":1},"title":"Saerp alerta para falta d\u2019\u00e1gua em bairros da zona Sul de Ribeir\u00e3o\u00a0Preto","author":"ismaelcolosi.com.br","date":"20 de November de 2023","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou, nesta segunda-feira (20), que alguns bairros da zona Sul do munic\u00edpio podem sofrer com a falta d\u00b4\u00e1gua. De acordo com o \u00f3rg\u00e3o, uma bomba do po\u00e7o Canad\u00e1 apresentou falhas eletromec\u00e2nicas, por isso est\u00e1 sendo realizada a substitui\u00e7\u00e3o emergencial\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/water-tap-7055543_1280-1.jpg?fit=1200%2C884&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/water-tap-7055543_1280-1.jpg?fit=1200%2C884&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/water-tap-7055543_1280-1.jpg?fit=1200%2C884&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/water-tap-7055543_1280-1.jpg?fit=1200%2C884&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/water-tap-7055543_1280-1.jpg?fit=1200%2C884&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":64409,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/07\/saerp-alerta-para-falta-dagua-em-ribeirao-preto-veja-os-bairros-afetados-2\/","url_meta":{"origin":51479,"position":2},"title":"Saerp alerta para falta d\u2019\u00e1gua em Ribeir\u00e3o Preto; Veja os bairros afetados","author":"ismaelcolosi.com.br","date":"7 de September de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) publicou um alerta para falta d\u2019\u00e1gua em Ribeir\u00e3o Preto neste s\u00e1bado (7). O aviso \u00e9 v\u00e1lido para as zonas Oeste, Sul e Leste da cidade. Segundo a secretaria, o problema \u00e9 motivado por um reparo emergencial no sistema de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-08-19_12-12-48_jpg_2024-08-19_12-12-48.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-08-19_12-12-48_jpg_2024-08-19_12-12-48.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-08-19_12-12-48_jpg_2024-08-19_12-12-48.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-08-19_12-12-48_jpg_2024-08-19_12-12-48.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-08-19_12-12-48_jpg_2024-08-19_12-12-48.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":65471,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/12\/saerp-alerta-para-falta-dagua-em-ribeirao-saiba-os-bairros-afetados\/","url_meta":{"origin":51479,"position":3},"title":"Saerp alerta para falta d\u2019\u00e1gua em Ribeir\u00e3o; Saiba os bairros afetados","author":"ismaelcolosi.com.br","date":"12 de September de 2024","format":false,"excerpt":"[ad_1] A\u00a0Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto)\u00a0publicou um alerta para\u00a0falta d\u2019\u00e1gua\u00a0em\u00a0Ribeir\u00e3o Preto\u00a0nesta quinta-feira (12). O aviso \u00e9 v\u00e1lido para a zona Leste e Centro. Um reparo emergencial na rua Nabuco de Ara\u00fajo pode gerar intermit\u00eancia nos bairros Vila Virg\u00ednia, Jardim Piratininga, Parque Ribeir\u00e3o e imedia\u00e7\u00f5es. No Centro,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/falta-agua_2024-09-12_14-24-37_jpg_2024-09-12_14-24-37.webp.webp?fit=1068%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/falta-agua_2024-09-12_14-24-37_jpg_2024-09-12_14-24-37.webp.webp?fit=1068%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/falta-agua_2024-09-12_14-24-37_jpg_2024-09-12_14-24-37.webp.webp?fit=1068%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/falta-agua_2024-09-12_14-24-37_jpg_2024-09-12_14-24-37.webp.webp?fit=1068%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/falta-agua_2024-09-12_14-24-37_jpg_2024-09-12_14-24-37.webp.webp?fit=1068%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":60081,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/14\/saerp-alerta-para-falta-dagua-em-oito-bairros-de-ribeirao-preto-veja-os-locais\/","url_meta":{"origin":51479,"position":4},"title":"Saerp alerta para falta d\u2019\u00e1gua em oito bairros de Ribeir\u00e3o Preto; Veja os locais","author":"ismaelcolosi.com.br","date":"14 de August de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) publicou dois alertas de falta d\u2019\u00e1gua em oito bairros de Ribeir\u00e3o Preto, nesta quarta-feira (14). Equipes realizam servi\u00e7os de manuten\u00e7\u00e3o e reparo emergencial nas regi\u00f5es Leste e Sul. Na zona Leste Segundo a secretaria, equipes realizam o reparo emergencial\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":62770,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/29\/saerp-alerta-para-falta-dagua-em-6-bairros-de-ribeirao-preto-confira\/","url_meta":{"origin":51479,"position":5},"title":"Saerp alerta para falta d&#8217;\u00e1gua em 6 bairros de Ribeir\u00e3o Preto; Confira","author":"ismaelcolosi.com.br","date":"29 de August de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) alerta para o risco de falta d\u2019\u00e1gua nesta quinta-feira (29) em seis bairros das zonas Norte e Oeste de Ribeir\u00e3o Preto. Segundo a Pasta, uma equipe atua na substitui\u00e7\u00e3o emergencial da bomba submersa do po\u00e7o Vila Tib\u00e9rio, o que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-de-agua-3-1-1.jpg?fit=1200%2C673&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-de-agua-3-1-1.jpg?fit=1200%2C673&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-de-agua-3-1-1.jpg?fit=1200%2C673&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-de-agua-3-1-1.jpg?fit=1200%2C673&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-de-agua-3-1-1.jpg?fit=1200%2C673&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-doj","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=51479"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/51480"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=51479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=51479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=51479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}