{"id":51123,"date":"2024-05-23T11:44:22","date_gmt":"2024-05-23T14:44:22","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/23\/psicologa-tem-arma-apontada-para-cabeca-em-assalto-na-zona-sul-de-ribeirao-preto\/"},"modified":"2024-05-23T11:44:22","modified_gmt":"2024-05-23T14:44:22","slug":"psicologa-tem-arma-apontada-para-cabeca-em-assalto-na-zona-sul-de-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/23\/psicologa-tem-arma-apontada-para-cabeca-em-assalto-na-zona-sul-de-ribeirao-preto\/","title":{"rendered":"Psic\u00f3loga tem arma apontada para cabe\u00e7a em assalto na zona Sul de Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>Uma psic\u00f3loga de 26 anos foi assaltada no in\u00edcio da noite desta quarta-feira (22) e, na a\u00e7\u00e3o, o criminoso apontou uma arma para a cabe\u00e7a da v\u00edtima, no Alto da Boa Vista, zona Sul de Ribeir\u00e3o Preto.<\/strong><\/p>\n<p>Segundo o <strong>boletim de ocorr\u00eancia (BO)<\/strong>, o <strong>crime <\/strong>ocorreu na <strong>avenida Dr. Jo\u00e3o Palma Gui\u00e3o<\/strong>, pr\u00f3ximo \u00e0 <strong>rotat\u00f3ria da avenida Independ\u00eancia<\/strong>, quando a <strong>psic\u00f3loga caminhava <\/strong>em dire\u00e7\u00e3o a um <strong>ponto de \u00f4nibus<\/strong>.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<h2 class=\"wp-block-heading\"><strong>Sob mira de arma<\/strong><\/h2>\n<p>A <strong>v\u00edtima <\/strong>relatou \u00e0 <strong>pol\u00edcia <\/strong>que o <strong>criminoso <\/strong>saiu de um <strong>carro<\/strong>, mas que n\u00e3o se recorda das caracter\u00edsticas do ve\u00edculo, quando <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">apontou a arma para a cabe\u00e7a dela e ordenou para que n\u00e3o gritasse, que deixasse os pertences e fosse embora correndo em seguida.<\/mark><\/p>\n<p>A <strong>v\u00edtima <\/strong>disse que ficou <strong>assustada <\/strong>e <strong>obedeceu <\/strong>\u00e0s <strong>ordens <\/strong>do <strong>assaltante<\/strong>. Foram <strong>roubados <\/strong>um <strong>celular<\/strong>, duas <strong>bolsas<\/strong>, um <strong>documento pessoal <\/strong>e um <strong>cart\u00e3o banc\u00e1rio<\/strong>.<\/p>\n<p>O caso foi registrado na <strong>CPJ (Central de Pol\u00edcia Judici\u00e1ria) Permanente<\/strong> como <strong>roubo a transeunte<\/strong> para <strong>investiga\u00e7\u00e3o <\/strong>da <strong>Pol\u00edcia Civil<\/strong>. <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">Nenhum suspeito foi preso.<\/mark><\/p>\n<p>SAIBA MAIS<\/p>\n<p>Primeira onda de frio do ano derruba as temperaturas a partir de s\u00e1bado no estado de SP<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Como vai ser castra\u00e7\u00e3o qu\u00edmica volunt\u00e1ria no Brasil?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/psicologa-tem-arma-apontada-para-cabeca-em-assalto-na-zona-sul-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Uma psic\u00f3loga de 26 anos foi assaltada no in\u00edcio da noite desta quarta-feira (22) e, na a\u00e7\u00e3o, o criminoso apontou uma arma para a cabe\u00e7a da v\u00edtima, no Alto da Boa Vista, zona Sul de Ribeir\u00e3o Preto. Segundo o boletim de ocorr\u00eancia (BO), o crime ocorreu na avenida Dr. Jo\u00e3o Palma Gui\u00e3o, pr\u00f3ximo \u00e0 &#8230; <a title=\"Psic\u00f3loga tem arma apontada para cabe\u00e7a em assalto na zona Sul de Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/23\/psicologa-tem-arma-apontada-para-cabeca-em-assalto-na-zona-sul-de-ribeirao-preto\/\" aria-label=\"Read more about Psic\u00f3loga tem arma apontada para cabe\u00e7a em assalto na zona Sul de Ribeir\u00e3o Preto\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":39917,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-51123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/whatsapp_image_2022-08-14_at_12_10_03.jpe","uagb_featured_image_src":{"full":["https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/whatsapp_image_2022-08-14_at_12_10_03.jpe",1280,853,false],"thumbnail":["https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/whatsapp_image_2022-08-14_at_12_10_03-150x150.jpe",150,150,true],"medium":["https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/whatsapp_image_2022-08-14_at_12_10_03-300x200.jpe",300,200,true],"medium_large":["https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/whatsapp_image_2022-08-14_at_12_10_03-768x512.jpe",768,512,true],"large":["https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/whatsapp_image_2022-08-14_at_12_10_03-1024x682.jpe",1024,682,true],"1536x1536":["https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/whatsapp_image_2022-08-14_at_12_10_03.jpe",1280,853,false],"2048x2048":["https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/whatsapp_image_2022-08-14_at_12_10_03.jpe",1280,853,false]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Uma psic\u00f3loga de 26 anos foi assaltada no in\u00edcio da noite desta quarta-feira (22) e, na a\u00e7\u00e3o, o criminoso apontou uma arma para a cabe\u00e7a da v\u00edtima, no Alto da Boa Vista, zona Sul de Ribeir\u00e3o Preto. Segundo o boletim de ocorr\u00eancia (BO), o crime ocorreu na avenida Dr. Jo\u00e3o Palma Gui\u00e3o, pr\u00f3ximo \u00e0&hellip;","jetpack-related-posts":[{"id":45453,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/04\/motorista-em-carro-de-luxo-e-abordada-por-criminoso-na-zona-sul-de-ribeirao\/","url_meta":{"origin":51123,"position":0},"title":"Motorista em carro de luxo \u00e9 abordada por criminoso na zona Sul de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"4 de April de 2024","format":false,"excerpt":"[ad_1] Uma nutricionista de 43 anos, que dirigia um carro de luxo, foi abordado por um criminoso no acesso da avenida Adelmo Perdizza, pr\u00f3ximo ao Anel Vi\u00e1rio Sul, na zona Sul de Ribeir\u00e3o Preto. O caso aconteceu na tarde da \u00faltima quarta-feira (3). De acordo com o B.O. (boletim de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__adelmo-perdizza-1.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__adelmo-perdizza-1.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__adelmo-perdizza-1.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__adelmo-perdizza-1.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__adelmo-perdizza-1.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":56588,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/12\/entregador-de-lanches-fica-sob-mira-de-arma-e-tem-moto-roubada-em-ribeirao-preto\/","url_meta":{"origin":51123,"position":1},"title":"Entregador de lanches fica sob mira de arma e tem moto roubada em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"12 de July de 2024","format":false,"excerpt":"[ad_1] Um entregador de lanches teve a moto roubada durante o trabalho na noite desta quinta-feira (11), no Jardim Jos\u00e9 Sampaio Junior, zona Norte de Ribeir\u00e3o Preto. Segundo ao boletim de ocorr\u00eancia (BO), a v\u00edtima, de 22 anos, estacionou sua moto Honda CG Titan 160 vermelha na frente da casa\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1720814722_sao_carlos_500x320_03082019163914.jpg?fit=500%2C322&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":64216,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/06\/trio-tenta-assaltar-policial-e-um-acaba-morto-em-ribeirao-preto\/","url_meta":{"origin":51123,"position":2},"title":"Trio tenta assaltar policial e um acaba morto em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"6 de September de 2024","format":false,"excerpt":"[ad_1] Um policial militar reagiu a uma tentativa de assalto e matou um suspeito na noite desta quinta-feira (5), no Parque dos Servidores, zona Leste de Ribeir\u00e3o Preto. Segundo o boletim de ocorr\u00eancia (BO), o policial afrmou que fazia caminhada pela rotat\u00f3ria das avenidas Jos\u00e9 Ant\u00f4nio Ferrarezi e Marco Ant\u00f4nio\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/sirene_giroflex_1024x576_11032021085153.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/sirene_giroflex_1024x576_11032021085153.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/sirene_giroflex_1024x576_11032021085153.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/sirene_giroflex_1024x576_11032021085153.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":56931,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/16\/em-5-dias-ribeirao-preto-registra-3o-caso-de-sequestro-relampago-na-zona-sul\/","url_meta":{"origin":51123,"position":3},"title":"Em 5 dias, Ribeir\u00e3o Preto registra 3\u00ba caso de sequestro-rel\u00e2mpago na zona Sul","author":"ismaelcolosi.com.br","date":"16 de July de 2024","format":false,"excerpt":"[ad_1] Mais uma v\u00edtima sofreu sequestro-rel\u00e2mpago na zona Sul de Ribeir\u00e3o Preto. O caso mais recente, ocorrido na noite desta segunda-feira (15), \u00e9 o terceiro semelhante na cidade \u2013 o primeiro foi no Jardim Iraj\u00e1 e o segundo, no Jardim Bot\u00e2nico \u2013 em um per\u00edodo de cinco dias. Segundo o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1721147903_sirene_giroflex_1024x576_11032021085153.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1721147903_sirene_giroflex_1024x576_11032021085153.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1721147903_sirene_giroflex_1024x576_11032021085153.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1721147903_sirene_giroflex_1024x576_11032021085153.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":56807,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/15\/assaltante-invade-casa-de-policial-militar-e-rouba-arma-em-ribeirao-preto\/","url_meta":{"origin":51123,"position":4},"title":"Assaltante invade casa de policial militar e rouba arma em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"15 de July de 2024","format":false,"excerpt":"[ad_1] Um policial militar foi rendido por um assaltante em casa e teve uma arma de fogo de uso pessoal roubada na madrugada de s\u00e1bado (13), no Jardim Recreio, zona Oeste de Ribeir\u00e3o Preto. A v\u00edtima, de 45 anos, disse no boletim de ocorr\u00eancia (BO) que dormia na companhia da\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1721066051_cpj_policia_1024x576_21012021082231.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1721066051_cpj_policia_1024x576_21012021082231.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1721066051_cpj_policia_1024x576_21012021082231.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1721066051_cpj_policia_1024x576_21012021082231.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41982,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/12\/empresario-e-preso-apos-denuncia-de-disparos-na-zona-sul-de-ribeirao-preto\/","url_meta":{"origin":51123,"position":5},"title":"Empres\u00e1rio \u00e9 preso ap\u00f3s den\u00fancia de disparos na zona Sul de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"12 de March de 2024","format":false,"excerpt":"[ad_1] Um empres\u00e1rio de 31 anos foi preso ap\u00f3s uma den\u00fancia de supostos disparos com arma de fogo em frente ao um bar na avenida Independ\u00eancia, na zona Sul de Ribeir\u00e3o Preto. O caso aconteceu na madrugada da \u00faltima segunda-feira (11). De acordo com o B.O. (boletim de ocorr\u00eancia), a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710257645_WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710257645_WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710257645_WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710257645_WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-diz","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=51123"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/39917"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=51123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=51123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=51123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}