{"id":50146,"date":"2024-05-14T22:18:27","date_gmt":"2024-05-15T01:18:27","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/14\/petrobras-diz-que-presidente-pediu-para-deixar-empresa\/"},"modified":"2024-05-14T22:18:27","modified_gmt":"2024-05-15T01:18:27","slug":"petrobras-diz-que-presidente-pediu-para-deixar-empresa","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/14\/petrobras-diz-que-presidente-pediu-para-deixar-empresa\/","title":{"rendered":"Petrobras diz que presidente pediu para deixar empresa"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div id=\"attachment_516993\" class=\"wp-caption alignnone style=\" max-width:=\"\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-516993 size-full\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2023\/01\/Jean_Paul_Prates-CEO-Petrobras-768x512.jpg?resize=678%2C452&#038;ssl=1\" http:=\"\" alt=\"Foto: REUTERS\/Adriano Machado\" width=\"678\" height=\"452\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2023\/01\/Jean_Paul_Prates-CEO-Petrobras-768x512.jpg\"\/><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-516993 size-full\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2023\/01\/Jean_Paul_Prates-CEO-Petrobras-768x512.jpg?resize=678%2C452&#038;ssl=1\" alt=\"Foto: REUTERS\/Adriano Machado\" width=\"678\" height=\"452\"\/><\/p>\n<p>Foto: REUTERS\/Adriano Machado<\/p>\n<p class=\"wp-caption-text\">Jean Paul Prates deve ser substitu\u00eddo por Magda Chambriard na presid\u00eancia da Petrobras<\/p>\n<\/div>\n<p>A Petrobras informou em fato relevante que recebeu nesta ter\u00e7a-feira (14) de seu presidente-executivo, Jean Paul Prates, solicita\u00e7\u00e3o para que o conselho de administra\u00e7\u00e3o da estatal se re\u00fana para apreciar o encerramento antecipado de seu mandato como CEO.<\/p>\n<p>Segundo o comunicado da companhia, Prates informou que, se aprovado o encerramento do mandato, ele pretende posteriormente apresentar sua ren\u00fancia ao cargo de membro do conselho de administra\u00e7\u00e3o da Petrobras.<\/p>\n<ul>\n<li>\n<h4>Siga a <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u&gt;\" target=\"_blank\" rel=\"noopener\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias sobre neg\u00f3cios, carreira, tecnologia e estilo de vida<\/h4>\n<\/li>\n<\/ul>\n<p>Mais cedo, o jornal O Globo noticiou que o presidente Luiz In\u00e1cio Lula da Silva nomearia Magda Chambriard, ex-diretora-geral da Ag\u00eancia Nacional do Petr\u00f3leo, G\u00e1s Natural e Biocombust\u00edveis (ANP), como nova presidente-executiva da Petrobras.<\/p>\n<p>A Petrobras n\u00e3o tinha informa\u00e7\u00f5es sobre quem substituiria Prates na Petrobras. Tamb\u00e9m n\u00e3o tinha de imediato informa\u00e7\u00f5es sobre quando aconteceria a reuni\u00e3o do conselho.<\/p>\n<p>Os recibos de a\u00e7\u00f5es da Petrobras negociados em Nova York (ADRs), ca\u00edram mais de 6% nas negocia\u00e7\u00f5es p\u00f3s-mercado, diante das not\u00edcias da sa\u00edda de Prates do comando da empresa.<\/p>\n<p>As not\u00edcias vieram ap\u00f3s o presidente da Petrobras ter ficado amea\u00e7ado de demiss\u00e3o em algumas oportunidades, na mais recente delas depois de um embate p\u00fablico com o ministro de Minas e Energia, Alexandre Silveira, sobre os dividendos extraordin\u00e1rios, cuja proposta de pagamento referendada em assembleia de acionistas acabou ficando como o sugerido pela diretoria comandada por Prates.<\/p>\n<p>Prates tamb\u00e9m sofreu cr\u00edticas e press\u00f5es p\u00fablicas para que a Petrobras investisse mais em g\u00e1s natural e acelerasse investimentos de interesse do governo, como o setor de fertilizantes e ind\u00fastria naval.<\/p>\n<\/div>\n<p><script type=\"rocketlazyloadscript\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/forbes-money\/2024\/05\/petrobras-diz-que-presidente-executivo-pediu-para-deixar-empresa\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Foto: REUTERS\/Adriano Machado Jean Paul Prates deve ser substitu\u00eddo por Magda Chambriard na presid\u00eancia da Petrobras A Petrobras informou em fato relevante que recebeu nesta ter\u00e7a-feira (14) de seu presidente-executivo, Jean Paul Prates, solicita\u00e7\u00e3o para que o conselho de administra\u00e7\u00e3o da estatal se re\u00fana para apreciar o encerramento antecipado de seu mandato como CEO. &#8230; <a title=\"Petrobras diz que presidente pediu para deixar empresa\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/14\/petrobras-diz-que-presidente-pediu-para-deixar-empresa\/\" aria-label=\"Leia mais sobre Petrobras diz que presidente pediu para deixar empresa\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":50147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-50146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Jean_Paul_Prates-CEO-Petrobras-1024x683.jpg?fit=1024%2C683&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Jean_Paul_Prates-CEO-Petrobras-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Jean_Paul_Prates-CEO-Petrobras-1024x683.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Jean_Paul_Prates-CEO-Petrobras-1024x683.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Jean_Paul_Prates-CEO-Petrobras-1024x683.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Jean_Paul_Prates-CEO-Petrobras-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Jean_Paul_Prates-CEO-Petrobras-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Jean_Paul_Prates-CEO-Petrobras-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Foto: REUTERS\/Adriano Machado Jean Paul Prates deve ser substitu\u00eddo por Magda Chambriard na presid\u00eancia da Petrobras A Petrobras informou em fato relevante que recebeu nesta ter\u00e7a-feira (14) de seu presidente-executivo, Jean Paul Prates, solicita\u00e7\u00e3o para que o conselho de administra\u00e7\u00e3o da estatal se re\u00fana para apreciar o encerramento antecipado de seu mandato como CEO.&hellip;","jetpack-related-posts":[{"id":47553,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/26\/presidente-do-conselho-da-petrobras-e-reeleito\/","url_meta":{"origin":50146,"position":0},"title":"Presidente do conselho da Petrobras \u00e9 reeleito","author":"ismaelcolosi.com.br","date":"26 de Abril de 2024","format":false,"excerpt":"[ad_1] Foto: Paulo Whitaker\/ReutersLogotipo da Petrobras, em escrit\u00f3rio da empresa em S\u00e3o Paulo A assembleia de acionistas da\u00a0Petrobras\u00a0reelegeu na quinta-feira (25) Pietro Mendes como presidente do conselho de administra\u00e7\u00e3o da empresa, aliado do ministro de Minas e Energia, Alexandre Silveira, que vem travando embates com o CEO da companhia, Jean\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1714139989_Money-empresas-brasileiras-09Jun23-GettyImages-3-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1714139989_Money-empresas-brasileiras-09Jun23-GettyImages-3-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1714139989_Money-empresas-brasileiras-09Jun23-GettyImages-3-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1714139989_Money-empresas-brasileiras-09Jun23-GettyImages-3-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":46525,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/12\/justica-suspende-presidente-do-conselho-da-petrobras\/","url_meta":{"origin":50146,"position":1},"title":"Justi\u00e7a suspende presidente do conselho da Petrobras","author":"ismaelcolosi.com.br","date":"12 de Abril de 2024","format":false,"excerpt":"[ad_1] Getty ImagesNa segunda-feira (8), a Justi\u00e7a de S\u00e3o Paulo j\u00e1 havia suspendido um outro membro do conselho da\u00a0Petrobras, S\u00e9rgio Machado Rezende Um juiz federal de S\u00e3o Paulo suspendeu do cargo o presidente do Conselho de Administra\u00e7\u00e3o da\u00a0Petrobras, Pietro Sampaio Mendes, por conflito de interesse, segundo decis\u00e3o de quinta-feira (11).\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Money-empresas-brasileiras-09Jun23-GettyImages-3-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Money-empresas-brasileiras-09Jun23-GettyImages-3-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Money-empresas-brasileiras-09Jun23-GettyImages-3-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Money-empresas-brasileiras-09Jun23-GettyImages-3-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":50605,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/17\/petrobras-aprova-saida-de-prates-e-nomeia-clarice-coppetti-como-ceo-interina\/","url_meta":{"origin":50146,"position":2},"title":"Petrobras aprova sa\u00edda de Prates e nomeia Clarice Coppetti como CEO interina","author":"ismaelcolosi.com.br","date":"17 de Maio de 2024","format":false,"excerpt":"[ad_1] Sergio Moraes\/ReutersAs a\u00e7\u00f5es da Petrobras (PETR4) chegaram a recuar 8% na abertura dos neg\u00f3cios nesta quarta-feira (15), representando uma perda de R$ 46,7 bilh\u00f5es Acessibilidade L L A- A+ \u25d0 O conselho de administra\u00e7\u00e3o da Petrobras nomeou nesta quarta-feira (15) Clarice Coppetti como presidente interina da companhia ap\u00f3s aprovar\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/money-petrobras-08mar22-Sergio-Moraes-reuters-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/money-petrobras-08mar22-Sergio-Moraes-reuters-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/money-petrobras-08mar22-Sergio-Moraes-reuters-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/money-petrobras-08mar22-Sergio-Moraes-reuters-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":25773,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/08\/petrobras-abre-investigacao-administrativa-de-venda-de-refinaria\/","url_meta":{"origin":50146,"position":3},"title":"Petrobras abre investiga\u00e7\u00e3o administrativa de venda de refinaria \u2013 Folha de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"8 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Petrobras abriu investiga\u00e7\u00e3o administrativa para avaliar a venda da Refinaria Landulpho Alves, em novembro de 2021, informou nesta sexta-feira (5) o presidente da estatal, Jean Paul Prates. Ele reagiu \u00e0 divulga\u00e7\u00e3o de um relat\u00f3rio da Controladoria-Geral da Uni\u00e3o (CGU) que\u00a0apontou privatiza\u00e7\u00e3o com baixo pre\u00e7o. \u201cA respeito das not\u00edcias\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":24902,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/05\/prates-anuncia-916-vagas-na-petrobras-com-provas-em-todas-as-capitais\/","url_meta":{"origin":50146,"position":4},"title":"Prates anuncia 916 vagas na Petrobras com provas em todas as capitais","author":"ismaelcolosi.com.br","date":"5 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Da reda\u00e7\u00e3oi Da reda\u00e7\u00e3o 05\/01\/2024 - 13:07 O concurso p\u00fablico da Petrobras que prev\u00ea 916 vagas para n\u00edvel t\u00e9cnico, al\u00e9m da forma\u00e7\u00e3o de cadastro de reserva, acaba de receber uma atualiza\u00e7\u00e3o nas inscri\u00e7\u00f5es. Segundo an\u00fancio do presidente da estatal, Jean Paul Prates, a companhia dobrou o n\u00famero de cidades\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/petrobras-e1704469064823.jpg?fit=700%2C419&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/petrobras-e1704469064823.jpg?fit=700%2C419&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/petrobras-e1704469064823.jpg?fit=700%2C419&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/petrobras-e1704469064823.jpg?fit=700%2C419&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":52982,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/12\/petrobras-provavelmente-tera-mudancas-em-diretoria-ate-a-proxima-semana-diz-ceo\/","url_meta":{"origin":50146,"position":5},"title":"Petrobras provavelmente ter\u00e1 mudan\u00e7as em diretoria at\u00e9 a pr\u00f3xima semana, diz CEO","author":"ismaelcolosi.com.br","date":"12 de Junho de 2024","format":false,"excerpt":"[ad_1] A Petrobras provavelmente ter\u00e1 mudan\u00e7as em sua diretoria executiva at\u00e9 a pr\u00f3xima semana, afirmou a CEO da petroleira, Magda Chambriard, ao participar de um evento nesta quarta-feira com a presen\u00e7a do presidente Luiz In\u00e1cio Lula da Silva no Rio de janeiro. Acessibilidade L L A- A+ \u25d0 Siga a\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/2024-06-12T162627Z_1_LYNXMPEK5B0QA_RTROPTP_4_PETROBRAS-CEO-1024x664.jpg?fit=1024%2C664&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/2024-06-12T162627Z_1_LYNXMPEK5B0QA_RTROPTP_4_PETROBRAS-CEO-1024x664.jpg?fit=1024%2C664&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/2024-06-12T162627Z_1_LYNXMPEK5B0QA_RTROPTP_4_PETROBRAS-CEO-1024x664.jpg?fit=1024%2C664&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/2024-06-12T162627Z_1_LYNXMPEK5B0QA_RTROPTP_4_PETROBRAS-CEO-1024x664.jpg?fit=1024%2C664&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-d2O","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=50146"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/50147"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=50146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=50146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=50146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}