{"id":50105,"date":"2024-05-14T18:25:38","date_gmt":"2024-05-14T21:25:38","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/14\/onca-parda-e-encontrada-morta-em-rodovia-na-regiao-de-ribeirao-preto\/"},"modified":"2024-05-14T18:25:38","modified_gmt":"2024-05-14T21:25:38","slug":"onca-parda-e-encontrada-morta-em-rodovia-na-regiao-de-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/14\/onca-parda-e-encontrada-morta-em-rodovia-na-regiao-de-ribeirao-preto\/","title":{"rendered":"On\u00e7a-parda \u00e9 encontrada morta em rodovia na regi\u00e3o de Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Uma<strong> on\u00e7a-parda<\/strong> foi encontrada <strong>morta<\/strong> na manh\u00e3 desta <strong>ter\u00e7a-feira<\/strong> (14), no quil\u00f4metro <strong>382 da rodovia Armando de Salles Oliveira<\/strong>, em <strong>Bebedouro<\/strong>, na regi\u00e3o de<strong> Ribeir\u00e3o Preto<\/strong>.<\/p>\n<p>Segundo <strong>a Entrevias<\/strong>, concession\u00e1ria que administra o trecho, o <strong>animal foi visto pelas c\u00e2meras de monitoramento<\/strong> e, quando a equipe chegou ao local, <strong>j\u00e1 estava morto<\/strong>, por\u00e9m <strong>n\u00e3o apresentava sinais de atropelamento<\/strong>.<\/p>\n<p>A <strong>on\u00e7a-parda<\/strong> foi <strong>recolhida pela concession\u00e1ria<\/strong> e <strong>levada ao Bosque Municipal de Ribeir\u00e3o Preto<\/strong>, onde o animal <strong>fica \u00e0 disposi\u00e7\u00e3o dos profissionais para pesquisa e estudos<\/strong>.<\/p>\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-4_2024-05-14_20-33-09_jpg_2024-05-14_20-33-09-1024x576.webp?resize=872%2C490&#038;ssl=1\" alt=\"\" class=\"wp-image-81385\" width=\"872\" height=\"490\" srcset=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-4_2024-05-14_20-33-09_jpg_2024-05-14_20-33-09-1024x576.webp 1024w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-4_2024-05-14_20-33-09_jpg_2024-05-14_20-33-09-300x169.webp 300w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-4_2024-05-14_20-33-09_jpg_2024-05-14_20-33-09-768x432.webp 768w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-4_2024-05-14_20-33-09_jpg_2024-05-14_20-33-09-696x392.webp 696w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-4_2024-05-14_20-33-09_jpg_2024-05-14_20-33-09-1068x601.webp 1068w, https:\/\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-4_2024-05-14_20-33-09_jpg_2024-05-14_20-33-09.webp 1200w\" sizes=\"(max-width: 872px) 100vw, 872px\"\/><\/figure>\n<p>SAIBA MAIS <\/p>\n<p>Unidade de sa\u00fade inaugurada no Centro de Ribeir\u00e3o atende pacientes de antigo PS Central<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do<strong>\u00a0acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/CdrZ6xrf7quD44Vw3WlPuZ\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>Qual barragem pode desmoronar no RS?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/onca-parda-e-encontrada-morta-em-rodovia-na-regiao-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Uma on\u00e7a-parda foi encontrada morta na manh\u00e3 desta ter\u00e7a-feira (14), no quil\u00f4metro 382 da rodovia Armando de Salles Oliveira, em Bebedouro, na regi\u00e3o de Ribeir\u00e3o Preto. Segundo a Entrevias, concession\u00e1ria que administra o trecho, o animal foi visto pelas c\u00e2meras de monitoramento e, quando a equipe chegou ao local, j\u00e1 estava morto, por\u00e9m n\u00e3o &#8230; <a title=\"On\u00e7a-parda \u00e9 encontrada morta em rodovia na regi\u00e3o de Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/14\/onca-parda-e-encontrada-morta-em-rodovia-na-regiao-de-ribeirao-preto\/\" aria-label=\"Leia mais sobre On\u00e7a-parda \u00e9 encontrada morta em rodovia na regi\u00e3o de Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":50106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-50105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-14_20-34-12_jpg_2024-05-14_20-34-12.webp.webp?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-14_20-34-12_jpg_2024-05-14_20-34-12.webp.webp?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-14_20-34-12_jpg_2024-05-14_20-34-12.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-14_20-34-12_jpg_2024-05-14_20-34-12.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-14_20-34-12_jpg_2024-05-14_20-34-12.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-14_20-34-12_jpg_2024-05-14_20-34-12.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-14_20-34-12_jpg_2024-05-14_20-34-12.webp.webp?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-05-14_20-34-12_jpg_2024-05-14_20-34-12.webp.webp?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Uma on\u00e7a-parda foi encontrada morta na manh\u00e3 desta ter\u00e7a-feira (14), no quil\u00f4metro 382 da rodovia Armando de Salles Oliveira, em Bebedouro, na regi\u00e3o de Ribeir\u00e3o Preto. Segundo a Entrevias, concession\u00e1ria que administra o trecho, o animal foi visto pelas c\u00e2meras de monitoramento e, quando a equipe chegou ao local, j\u00e1 estava morto, por\u00e9m n\u00e3o&hellip;","jetpack-related-posts":[{"id":67951,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/homem-encontrado-morto-no-rio-pardo-e-identificado-em-ribeirao-preto\/","url_meta":{"origin":50105,"position":0},"title":"Homem encontrado morto no rio Pardo \u00e9 identificado em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"26 de Setembro de 2024","format":false,"excerpt":"[ad_1] Um homem de 60 anos que foi encontrado morto no rio Pardo, no \u00faltimo dia 6 de setembro, foi identificado. Segundo o boletim de ocorr\u00eancia (BO), Divino Francisco Pereira foi achado por pescadores quando j\u00e1 estava sem vida, nas proximidades de uma linha f\u00e9rrea, em \u00e1rea entre a rodovia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727360782_cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727360782_cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727360782_cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727360782_cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":45451,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/04\/concessionaria-busca-por-donos-de-animais-perdidos-em-rodovias-da-regiao-de-ribeirao\/","url_meta":{"origin":50105,"position":1},"title":"Concession\u00e1ria busca por donos de animais perdidos em rodovias da regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"4 de Abril de 2024","format":false,"excerpt":"[ad_1] A Entrevias faz buscas por donos de 90 animais que foram resgatados feridos nas rodovias no interior de S\u00e3o Paulo, como nas regi\u00f5es de Ribeir\u00e3o Preto e Mar\u00edlia. Os animais s\u00e3o mantidos sobre os cuidados da concession\u00e1ria. Um cat\u00e1logo foi criado com o mapeamento do local onde cada animal\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":54871,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/28\/acidente-provoca-interdicao-e-congestionamento-na-anhanguera-em-ribeirao\/","url_meta":{"origin":50105,"position":2},"title":"Acidente provoca interdi\u00e7\u00e3o e congestionamento na Anhanguera em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"28 de Junho de 2024","format":false,"excerpt":"[ad_1] Um acidente na manh\u00e3 desta sexta-feira (28) provocou a interdi\u00e7\u00e3o e congestionamento, de ao menos um quil\u00f4metro, no quil\u00f4metro 313 da rodovia Anhanguera (SP-330) em Ribeir\u00e3o Preto. A pista interditada \u00e9 no sentido norte. Segundo a Arteris Via Paulista, concession\u00e1ria que administra o trecho, o fluxo de ve\u00edculos est\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33529,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/29\/cachorro-e-resgatado-apos-ser-amarrado-e-abandonado-em-rodovia-na-regiao-de-ribeirao-veja-o-video\/","url_meta":{"origin":50105,"position":3},"title":"Cachorro \u00e9 resgatado ap\u00f3s ser amarrado e abandonado em rodovia na regi\u00e3o de Ribeir\u00e3o; Veja o v\u00eddeo","author":"ismaelcolosi.com.br","date":"29 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Um cachorro foi resgatado na rodovia Anhanguera (SP-330), pr\u00f3ximo ao quil\u00f4metro 244, na regi\u00e3o de Ribeir\u00e3o Preto, na manh\u00e3 desta segunda-feira (29), ap\u00f3s ser amarrado e abandonado na defensa met\u00e1lica do local. Um condutor foi quem teria visto o animal amarrado e acionado a Arteris ViaPaulista para efetuar o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51720,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/30\/onibus-com-66-pessoas-tomba-e-deixa-1-morto-e-feridos-na-rodovia-anhanguera\/","url_meta":{"origin":50105,"position":4},"title":"\u00d4nibus com 66 pessoas tomba e deixa 1 morto e feridos na rodovia Anhanguera \u00a0","author":"ismaelcolosi.com.br","date":"30 de Maio de 2024","format":false,"excerpt":"[ad_1] Um \u00f4nibus com 66 pessoas tombou na madrugada desta quinta-feira (30) e deixou um morto e ao menos quatro feridos, entre os quais um em estado grave, no km 301 da rodovia Anhanguera, entre Cravinhos e Ribeir\u00e3o Preto. O ve\u00edculo havia sa\u00eddo de Suzano (SP) e seguia com destino\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-07.00.42_2024-05-30_10-22-40_jpeg_2024-05-30_10-22-41-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-07.00.42_2024-05-30_10-22-40_jpeg_2024-05-30_10-22-41-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-07.00.42_2024-05-30_10-22-40_jpeg_2024-05-30_10-22-41-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-07.00.42_2024-05-30_10-22-40_jpeg_2024-05-30_10-22-41-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-07.00.42_2024-05-30_10-22-40_jpeg_2024-05-30_10-22-41-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44088,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/25\/cachorro-esta-preso-ha-dez-dias-em-bueiro-de-ribeirao-preto-veja-video\/","url_meta":{"origin":50105,"position":5},"title":"Cachorro est\u00e1 preso h\u00e1 dez dias em bueiro de Ribeir\u00e3o Preto; Veja v\u00eddeo","author":"ismaelcolosi.com.br","date":"25 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Um cachorro foi encontrado dentro de um bueiro pr\u00f3ximo a uma sa\u00edda do km 315 da rodovia Anhanguera (SP-330), sentido sul, em Ribeir\u00e3o Preto. De acordo com Maur\u00edcio Garcia, presidente da ONG (Organiza\u00e7\u00e3o n\u00e3o governamental) Patinhas de Rua, o animal est\u00e1 pelo local h\u00e1 dez dias. Cada dia vai\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-d29","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=50105"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/50106"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=50105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=50105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=50105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}