{"id":4944,"date":"2023-11-22T15:10:58","date_gmt":"2023-11-22T18:10:58","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/22\/pais-fazem-a-vontade-do-filho-de-6-anos-e-garoto-perde-a-vida-diante-deles\/"},"modified":"2023-11-22T15:10:58","modified_gmt":"2023-11-22T18:10:58","slug":"pais-fazem-a-vontade-do-filho-de-6-anos-e-garoto-perde-a-vida-diante-deles","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/22\/pais-fazem-a-vontade-do-filho-de-6-anos-e-garoto-perde-a-vida-diante-deles\/","title":{"rendered":"Pais fazem a vontade do filho de 6 anos e garoto perde a vida diante deles"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>Uma trag\u00e9dia se abateu sobre uma fam\u00edlia que est\u00e1 vivendo a mais profunda dor por causa da morte prematura de um garotinho de 6 anos. O caso ganhou uma enorme repercuss\u00e3o ap\u00f3s se tornar destaque nos principais portais de not\u00edcias do Brasil.<\/p>\n<p>De acordo com as primeiras informa\u00e7\u00f5es repassadas pelos agentes de seguran\u00e7a que foram acionados para atender a ocorr\u00eancia, o caso aconteceu na zona rural do munic\u00edpio de Carlinda, localizado a cerca de 760 km, da cidade de Cuiab\u00e1, capital do estado do Mato Grosso.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>A v\u00edtima de 6 anos, perdeu a vida na tarde do \u00faltimo domingo (19), segundo as informa\u00e7\u00f5es da Pol\u00edcia Civil do Mato Grosso, os pais do garotinho tinham passado boa parte do dia colhendo castanhas.<\/p>\n<p>Quando a fam\u00edlia se preparava para deixar o local, o menino teria pedido aos pais para seguir na carroceria da caminhonete para que pudesse observar os porcos do mato durante o trajeto de volta para a casa.<\/p>\n<p>Os pais concederam ao filho a possibilidade de seguir viagem na carroceria do autom\u00f3vel sem jamais imaginar a trag\u00e9dia que estava prestes a acontecer. O menino foi socorrido e seus pais o levaram de imediato para uma Unidade de Pronto Atendimento (UPA), entretanto, a v\u00edtima deu entrada na \u00e1rea hospitalar j\u00e1 sem vida.<\/p>\n<p>Para a pol\u00edcia os pais da crian\u00e7a relataram que o menino teria se desequilibrado e despencado da carroceria no ch\u00e3o quando o ve\u00edculo estava em movimento. O caso segue sob investiga\u00e7\u00e3o. N\u00e3o h\u00e1 informa\u00e7\u00f5es sobre o vel\u00f3rio e sepultamento do garoto, a fam\u00edlia est\u00e1 devastada.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/tragedia-em-familia-pais-fazem-vontade-filho-6-anos-garoto-perde-vida-diante-deles\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Uma trag\u00e9dia se abateu sobre uma fam\u00edlia que est\u00e1 vivendo a mais profunda dor por causa da morte prematura de um garotinho de 6 anos. O caso ganhou uma enorme repercuss\u00e3o ap\u00f3s se tornar destaque nos principais portais de not\u00edcias do Brasil. De acordo com as primeiras informa\u00e7\u00f5es repassadas pelos agentes de seguran\u00e7a que &#8230; <a title=\"Pais fazem a vontade do filho de 6 anos e garoto perde a vida diante deles\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/22\/pais-fazem-a-vontade-do-filho-de-6-anos-e-garoto-perde-a-vida-diante-deles\/\" aria-label=\"Read more about Pais fazem a vontade do filho de 6 anos e garoto perde a vida diante deles\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":4945,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655e41c8a68c57974.jpg?fit=1200%2C628&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655e41c8a68c57974.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655e41c8a68c57974.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655e41c8a68c57974.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655e41c8a68c57974.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655e41c8a68c57974.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655e41c8a68c57974.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655e41c8a68c57974.jpg?fit=1200%2C628&ssl=1",1200,628,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Uma trag\u00e9dia se abateu sobre uma fam\u00edlia que est\u00e1 vivendo a mais profunda dor por causa da morte prematura de um garotinho de 6 anos. O caso ganhou uma enorme repercuss\u00e3o ap\u00f3s se tornar destaque nos principais portais de not\u00edcias do Brasil. De acordo com as primeiras informa\u00e7\u00f5es repassadas pelos agentes de seguran\u00e7a que&hellip;","jetpack-related-posts":[{"id":29320,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/18\/garotinho-de-3-anos-se-escondeu-dentro-de-guarda-roupa-enquanto-pai-tirava-a-vida-de-sua-mae-de-forma-cruel\/","url_meta":{"origin":4944,"position":0},"title":"Garotinho de 3 anos se escondeu dentro de guarda-roupa enquanto pai tirava a vida de sua m\u00e3e de forma cruel","author":"ismaelcolosi.com.br","date":"18 de January de 2024","format":false,"excerpt":"[ad_1] Uma crian\u00e7a de tr\u00eas anos estava presente em sua resid\u00eancia e se escondeu dentro do guarda-roupas enquanto seu pai cometia o assassinato de sua m\u00e3e, nesta quarta-feira (17). O crime de feminic\u00eddio teve lugar no Recanto das Emas, no Distrito Federal.Ant\u00f4nia Maria da Silva, de 39 anos, completaria 40\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a89d5c925d36201.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a89d5c925d36201.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a89d5c925d36201.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a89d5c925d36201.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a89d5c925d36201.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":25889,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/08\/buscas-por-garoto-de-11-anos-que-estava-desaparecido-tem-desfecho-tragico\/","url_meta":{"origin":4944,"position":1},"title":"Buscas por garoto de 11 anos que estava desaparecido t\u00eam desfecho tr\u00e1gico","author":"ismaelcolosi.com.br","date":"8 de January de 2024","format":false,"excerpt":"[ad_1] Uma fam\u00edlia est\u00e1 vivendo a dor do luto pela perda de um ente querido. As buscas por um garoto de apenas 11 anos de idade apresentaram um desfecho tr\u00e1gico. Neste \u00faltimo domingo (7), uma crian\u00e7a de 11 anos faleceu durante um banho de rio na cidade de Ituporanga, localizada\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c504831c021377.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c504831c021377.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c504831c021377.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c504831c021377.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c504831c021377.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":26903,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/buscas-por-bebe-de-1-ano-terminam-de-maneira-tragica-detalhes-sao-expostos-pelas-autoridades\/","url_meta":{"origin":4944,"position":2},"title":"Buscas por beb\u00ea de 1 ano terminam de maneira tr\u00e1gica; detalhes s\u00e3o expostos pelas autoridades","author":"ismaelcolosi.com.br","date":"11 de January de 2024","format":false,"excerpt":"[ad_1] As buscas por um garotinho de apenas um ano e seis meses terminaram de maneira tr\u00e1gica nesta quarta-feira (10). Infelizmente, uma fam\u00edlia est\u00e1 vivendo a dor luto pela perda de um ente querido que partiu de maneira precoce, gerando uma enorme como\u00e7\u00e3o na comunidade local.Os socorristas do Corpo de\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f6061605332302.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f6061605332302.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f6061605332302.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f6061605332302.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f6061605332302.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":29509,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/18\/quem-e-o-menino-de-2-anos-que-perdeu-a-vida-por-fome-trancado-em-casa-ao-lado-do-corpo-do-pai\/","url_meta":{"origin":4944,"position":3},"title":"Quem \u00e9 o menino de 2 anos que perdeu a vida por fome trancado em casa ao lado do corpo do pai","author":"ismaelcolosi.com.br","date":"18 de January de 2024","format":false,"excerpt":"[ad_1] Uma crian\u00e7a de 2 anos faleceu por desnutri\u00e7\u00e3o ap\u00f3s seu pai sofrer um ataque card\u00edaco. O tr\u00e1gico incidente ocorreu no Reino Unido, as autoridades registraram o caso no \u00faltimo dia 9 de janeiro.A crian\u00e7a foi identificada como Bronson Battersby ela foi descoberta sem vida ao lado do corpo de\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a967c0cff416089.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a967c0cff416089.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a967c0cff416089.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a967c0cff416089.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a967c0cff416089.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":24221,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/03\/meu-medo-e-nao-encontrar-minha-filha-viva-desabafa-pai-de-adolescente-que-esta-desaparecida-em-sp\/","url_meta":{"origin":4944,"position":4},"title":"&#8220;Meu medo \u00e9 n\u00e3o encontrar minha filha viva&#8221;, desabafa pai de adolescente que est\u00e1 desaparecida em SP","author":"ismaelcolosi.com.br","date":"3 de January de 2024","format":false,"excerpt":"[ad_1] Na regi\u00e3o de Itapevi, no interior de S\u00e3o Paulo, uma jovem de apenas 17 anos de idade desapareceu e todo o caso est\u00e1 gerando muita preocupa\u00e7\u00e3o e mist\u00e9rios. A jovem, que saiu de casa dizendo que iria comprar maquiagem, n\u00e3o foi mais vista desde ent\u00e3o.Imagens capturadas por uma c\u00e2mera\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6595d80939aef8975.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6595d80939aef8975.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6595d80939aef8975.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6595d80939aef8975.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6595d80939aef8975.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":9429,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/02\/quem-sao-as-5-pessoas-da-mesma-familia-perdem-a-vida-em-acidente-tragico-quando-seguiam-para-velorio-do-avo\/","url_meta":{"origin":4944,"position":5},"title":"Quem s\u00e3o as 5 pessoas da mesma fam\u00edlia perdem a vida em acidente tr\u00e1gico quando seguiam para vel\u00f3rio do av\u00f4","author":"ismaelcolosi.com.br","date":"2 de December de 2023","format":false,"excerpt":"[ad_1] Uma fam\u00edlia est\u00e1 mergulhada na dor do sofrimento da perda de entes queridos em um terr\u00edvel acidente quando seguiam para o vel\u00f3rio e o sepultamento do av\u00f4.Cinco membros de uma mesma fam\u00edlia perderam a vida depois que o ve\u00edculo em que estavam se envolveu em uma colis\u00e3o frontal com\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ab06e48a769873.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ab06e48a769873.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ab06e48a769873.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ab06e48a769873.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ab06e48a769873.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-1hK","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4944"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/4945"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}