{"id":49188,"date":"2024-05-09T09:44:43","date_gmt":"2024-05-09T12:44:43","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/09\/carreta-com-doacoes-de-ribeirao-preto-para-o-rio-grande-do-sul-tomba-no-caminho\/"},"modified":"2024-05-09T09:44:43","modified_gmt":"2024-05-09T12:44:43","slug":"carreta-com-doacoes-de-ribeirao-preto-para-o-rio-grande-do-sul-tomba-no-caminho","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/09\/carreta-com-doacoes-de-ribeirao-preto-para-o-rio-grande-do-sul-tomba-no-caminho\/","title":{"rendered":"Carreta com doa\u00e7\u00f5es de Ribeir\u00e3o Preto para o Rio Grande do Sul tomba no caminho"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Na <strong>noite<\/strong> desta <strong>quarta-feira (8)<\/strong>, uma <strong>carreta<\/strong> dos <strong>Correios <\/strong>com <strong>doa\u00e7\u00f5es de Ribeir\u00e3o Preto<\/strong> para as <strong>v\u00edtimas <\/strong>das chuvas no<strong> Rio Grande do Sul tombou<\/strong> e<strong> parte da carga caiu<\/strong> na <strong>Rodovia dos Bandeirantes (SP-348)<\/strong>, na altura de <strong>Santa B\u00e1rbara d\u2019Oeste<\/strong>.<\/p>\n<p>Segundo a concession\u00e1ria que administra a rodovia, a <strong>AutoBAn<\/strong>, houve uma v\u00edtima leve. De acordo com o<strong> Samu<\/strong>, o motorista do ve\u00edculo n\u00e3o se feriu.<\/p>\n<p>O acidente aconteceu na altura do<strong> quil\u00f4metro 129<\/strong>, na pista sentido capital. <span style=\"background-color:#f7cc62\" class=\"td_text_highlight_marker\">Tr\u00eas faixas e o acostamento da rodovia foram bloqueados.<\/span> O tr\u00e1fego flui pelo recuo do canteiro central e bordo da faixa 1, <strong>n\u00e3o houve congestionamento<\/strong>.<\/p>\n<p>Segundo os <strong>Correios<\/strong>, houve uma opera\u00e7\u00e3o durante a madrugada e <strong>toda carga foi recuperada<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Rio Grande do Sul<\/strong><\/h4>\n<p>O estado chegou a <strong>100 mortes provocadas pelos temporais<\/strong>, na <strong>quarta-feira (8)<\/strong>. O <strong>Rio Grande do Sul <\/strong>registra 130 desparecidos e 374 feridos e h\u00e1 230,4 mil pessoas fora de casa. A previs\u00e3o do tempo desta quinta-feira (9) no estado \u00e9 de sol sem nuvens no c\u00e9u e baixas temperaturas, as chuvas retornam na <strong>sexta-feira (10)<\/strong>.<\/p>\n<p>SAIBA MAIS<br \/>Tombamento de caminh\u00e3o deixa v\u00edtima e causa interdi\u00e7\u00e3o no Trev\u00e3o de Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on<\/strong> no WhatsApp. Para entrar no grupo, basta <a href=\"https:\/\/chat.whatsapp.com\/GFH9HUMUTHNFJdnyEd0xxq\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Shows do Bruno Mars ser\u00e3o cancelados?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/carreta-com-doacoes-de-ribeirao-preto-para-o-rio-grande-do-sul-tomba-no-caminho\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Na noite desta quarta-feira (8), uma carreta dos Correios com doa\u00e7\u00f5es de Ribeir\u00e3o Preto para as v\u00edtimas das chuvas no Rio Grande do Sul tombou e parte da carga caiu na Rodovia dos Bandeirantes (SP-348), na altura de Santa B\u00e1rbara d\u2019Oeste. Segundo a concession\u00e1ria que administra a rodovia, a AutoBAn, houve uma v\u00edtima leve. &#8230; <a title=\"Carreta com doa\u00e7\u00f5es de Ribeir\u00e3o Preto para o Rio Grande do Sul tomba no caminho\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/09\/carreta-com-doacoes-de-ribeirao-preto-para-o-rio-grande-do-sul-tomba-no-caminho\/\" aria-label=\"Leia mais sobre Carreta com doa\u00e7\u00f5es de Ribeir\u00e3o Preto para o Rio Grande do Sul tomba no caminho\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":49189,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-49188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreta_2024-05-09_11-54-51_jpg_2024-05-09_11-54-51.webp.webp?fit=833%2C583&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreta_2024-05-09_11-54-51_jpg_2024-05-09_11-54-51.webp.webp?fit=833%2C583&ssl=1",833,583,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreta_2024-05-09_11-54-51_jpg_2024-05-09_11-54-51.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreta_2024-05-09_11-54-51_jpg_2024-05-09_11-54-51.webp.webp?fit=300%2C210&ssl=1",300,210,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreta_2024-05-09_11-54-51_jpg_2024-05-09_11-54-51.webp.webp?fit=768%2C538&ssl=1",768,538,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreta_2024-05-09_11-54-51_jpg_2024-05-09_11-54-51.webp.webp?fit=833%2C583&ssl=1",833,583,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreta_2024-05-09_11-54-51_jpg_2024-05-09_11-54-51.webp.webp?fit=833%2C583&ssl=1",833,583,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreta_2024-05-09_11-54-51_jpg_2024-05-09_11-54-51.webp.webp?fit=833%2C583&ssl=1",833,583,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Na noite desta quarta-feira (8), uma carreta dos Correios com doa\u00e7\u00f5es de Ribeir\u00e3o Preto para as v\u00edtimas das chuvas no Rio Grande do Sul tombou e parte da carga caiu na Rodovia dos Bandeirantes (SP-348), na altura de Santa B\u00e1rbara d\u2019Oeste. Segundo a concession\u00e1ria que administra a rodovia, a AutoBAn, houve uma v\u00edtima leve.&hellip;","jetpack-related-posts":[{"id":65034,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/10\/carreta-tomba-na-rodovia-anhanguera-apos-pneu-estourar\/","url_meta":{"origin":49188,"position":0},"title":"Carreta tomba na rodovia Anhanguera ap\u00f3s pneu estourar","author":"ismaelcolosi.com.br","date":"10 de Setembro de 2024","format":false,"excerpt":"[ad_1] Uma carreta tombou, no come\u00e7o da tarde desta ter\u00e7a-feira (10), na rodovia Anhanguera, pr\u00f3ximo a entrada do aeroporto Leite Lopes, em Ribeir\u00e3o Preto. O acidente aconteceu ap\u00f3s o pneu dianteiro estourar na altura do quil\u00f4metro 312. Segundo informa\u00e7\u00f5es apuradas pela EPTV, o motorista da carreta seguia pela rodovia no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/capotamento-anhanguera_2024-09-10_16-19-15_jpg_2024-09-10_16-19-15.webp.webp?fit=1200%2C913&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/capotamento-anhanguera_2024-09-10_16-19-15_jpg_2024-09-10_16-19-15.webp.webp?fit=1200%2C913&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/capotamento-anhanguera_2024-09-10_16-19-15_jpg_2024-09-10_16-19-15.webp.webp?fit=1200%2C913&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/capotamento-anhanguera_2024-09-10_16-19-15_jpg_2024-09-10_16-19-15.webp.webp?fit=1200%2C913&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/capotamento-anhanguera_2024-09-10_16-19-15_jpg_2024-09-10_16-19-15.webp.webp?fit=1200%2C913&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":57413,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/21\/carreta-sai-da-pista-arranca-cerca-e-tomba-ao-lado-de-rodovia-em-ribeirao-preto\/","url_meta":{"origin":49188,"position":1},"title":"Carreta sai da pista, arranca cerca e tomba ao lado de rodovia em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"21 de Julho de 2024","format":false,"excerpt":"[ad_1] Um caminh\u00e3o canavieiro tombou na manh\u00e3 desta domingo (21), ap\u00f3s sair da pista da rodovia C\u00e2ndido Portinari (SP-334) no km 324, em Ribeir\u00e3o Preto. Segundo a concession\u00e1ria Via Paulista, o ve\u00edculo atingiu uma cerca e parou em uma \u00e1rea al\u00e9m do acostamento. Ainda conforme a concession\u00e1ria, n\u00e3o h\u00e1 v\u00edtimas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/ACIDENTE_2024-07-21_14-07-03_jpg_2024-07-21_14-07-03.webp.webp?fit=1200%2C847&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/ACIDENTE_2024-07-21_14-07-03_jpg_2024-07-21_14-07-03.webp.webp?fit=1200%2C847&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/ACIDENTE_2024-07-21_14-07-03_jpg_2024-07-21_14-07-03.webp.webp?fit=1200%2C847&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/ACIDENTE_2024-07-21_14-07-03_jpg_2024-07-21_14-07-03.webp.webp?fit=1200%2C847&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/ACIDENTE_2024-07-21_14-07-03_jpg_2024-07-21_14-07-03.webp.webp?fit=1200%2C847&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":60199,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/14\/apos-mais-de-6-horas-carreta-continua-tombada-no-anel-viario-sul-em-ribeirao-preto\/","url_meta":{"origin":49188,"position":2},"title":"Ap\u00f3s mais de 6 horas, carreta continua tombada no Anel Vi\u00e1rio Sul em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"14 de Agosto de 2024","format":false,"excerpt":"[ad_1] O caminh\u00e3o carregado com cana-de-a\u00e7\u00facar que tombou na manh\u00e3 desta quarta-(14), no Anel Vi\u00e1rio Sul de Ribeir\u00e3o Preto, virou um desafio para as equipes da concession\u00e1ria que administram o trecho. A carreta est\u00e1 carregada com 60 toneladas, tombou na al\u00e7a de acesso que liga a rodovia Ant\u00f4nio Machado Santana\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-08-14_22-22-59_png_2024-08-14_22-22-59.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-08-14_22-22-59_png_2024-08-14_22-22-59.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-08-14_22-22-59_png_2024-08-14_22-22-59.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-08-14_22-22-59_png_2024-08-14_22-22-59.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-08-14_22-22-59_png_2024-08-14_22-22-59.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48692,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/05\/doacoes-para-o-rs-continuam-nesta-semana-veja-como-ajudar-em-ribeirao-preto\/","url_meta":{"origin":49188,"position":3},"title":"Doa\u00e7\u00f5es para o RS continuam nesta semana; Veja como ajudar em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"5 de Maio de 2024","format":false,"excerpt":"[ad_1] As doa\u00e7\u00f5es de alimentos, \u00e1gua mineral, produtos de higiene e limpeza e roupas para as v\u00edtimas das enchentes no Rio Grande do Sul e em Santa Catarina continuam nesta semana. Os interessados podem procurar as ag\u00eancias dos Correios, a Aeaarp e o Fundo Social de Solidariedade de Ribeir\u00e3o Preto\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__enchentes-rs_2024-05-05_20-09-41.webp.webp?fit=1162%2C692&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__enchentes-rs_2024-05-05_20-09-41.webp.webp?fit=1162%2C692&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__enchentes-rs_2024-05-05_20-09-41.webp.webp?fit=1162%2C692&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__enchentes-rs_2024-05-05_20-09-41.webp.webp?fit=1162%2C692&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__enchentes-rs_2024-05-05_20-09-41.webp.webp?fit=1162%2C692&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55870,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/06\/motorista-morre-apos-carreta-com-carga-tombar-em-rodovia-na-regiao-de-ribeirao-preto\/","url_meta":{"origin":49188,"position":4},"title":"Motorista morre ap\u00f3s carreta com carga tombar em rodovia na regi\u00e3o de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"6 de Julho de 2024","format":false,"excerpt":"[ad_1] Um motorista morreu ap\u00f3s uma carreta carregada com a\u00e7\u00facar tombar na rodovia Deputado Cunha Bueno (SP 253), pr\u00f3ximo ao quil\u00f4metro 207, entre Prad\u00f3polis e Jaboticabal, na tarde deste s\u00e1bado (6). Segundo a apura\u00e7\u00e3o da EPTV, o ve\u00edculo tombou na rodovia logo ap\u00f3s um dos pneus estourarem. O condutor do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-06_18-01-10_jpg_2024-07-06_18-01-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-06_18-01-10_jpg_2024-07-06_18-01-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-06_18-01-10_jpg_2024-07-06_18-01-10.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-06_18-01-10_jpg_2024-07-06_18-01-10.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-06_18-01-10_jpg_2024-07-06_18-01-10.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44167,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/26\/carreta-tomba-no-trevao-da-anhanguera-em-ribeirao-preto-veja-o-video\/","url_meta":{"origin":49188,"position":5},"title":"Carreta tomba no Trev\u00e3o da Anhanguera em Ribeir\u00e3o Preto; Veja o v\u00eddeo","author":"ismaelcolosi.com.br","date":"26 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Uma carreta tombou no Trev\u00e3o da rodovia Anhanguera, em Ribeir\u00e3o Preto, na manh\u00e3 desta ter\u00e7a-feira (26) \u2013 veja o v\u00eddeo abaixo. VEJA O V\u00cdDEO Ver essa foto no Instagram Uma publica\u00e7\u00e3o compartilhada por acidade on Ribeir\u00e3o (@acidadeonribeirao) A carga de amendoim transportada pela carreta, que seguia na al\u00e7a sentido\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__carreta-tomba.webp.webp?fit=1200%2C696&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__carreta-tomba.webp.webp?fit=1200%2C696&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__carreta-tomba.webp.webp?fit=1200%2C696&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__carreta-tomba.webp.webp?fit=1200%2C696&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__carreta-tomba.webp.webp?fit=1200%2C696&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-cNm","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49188"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/49189"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}