{"id":48970,"date":"2024-05-07T19:07:08","date_gmt":"2024-05-07T22:07:08","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/prefeitura-no-interior-de-sp-abre-concurso-publico-com-salarios-de-r-38-mil\/"},"modified":"2024-05-07T19:07:08","modified_gmt":"2024-05-07T22:07:08","slug":"prefeitura-no-interior-de-sp-abre-concurso-publico-com-salarios-de-r-38-mil","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/prefeitura-no-interior-de-sp-abre-concurso-publico-com-salarios-de-r-38-mil\/","title":{"rendered":"Prefeitura no interior de SP abre concurso p\u00fablico com sal\u00e1rios de R$ 3,8 mil"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>A <strong>Prefeitura de Piracicaba<\/strong>, no interior de S\u00e3o Paulo, abriu <strong>concurso p\u00fablico<\/strong> com sal\u00e1rios que variam entre R$ 2,8 mil e R$ 3,8 mil. <strong>S\u00e3o dez vagas de n\u00edvel fundamental e m\u00e9dio.<\/strong><\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">As inscri\u00e7\u00f5es devem ser realizadas no per\u00edodo entre <strong>15 de maio e 13 de junho<\/strong> pela internet (<a href=\"https:\/\/www.vunesp.com.br\/PMPR2403\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>).<\/mark> O valor da taxa de inscri\u00e7\u00e3o varia entre<strong> R$ 57<\/strong> e <strong>R$ 72<\/strong>.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>A banca respons\u00e1vel pela organiza\u00e7\u00e3o e aplica\u00e7\u00e3o da prova \u00e9 a <strong>Funda\u00e7\u00e3o para o Vestibular da Universidade Estadual Paulista J\u00falio de Mesquita Filho (Vunesp)<\/strong>.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Confira as vagas dispon\u00edveis:<\/strong><\/h3>\n<h4 class=\"wp-block-heading\"><strong>N\u00edvel fundamental<\/strong><\/h4>\n<ul>\n<li>Borracheiro \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<ul>\n<li>Mec\u00e2nico de m\u00e1quinas \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<ul>\n<li>Mec\u00e2nico \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<h4 class=\"wp-block-heading\"><strong>N\u00edvel m\u00e9dio<\/strong><\/h4>\n<ul>\n<li>Agente de abastecimento \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<ul>\n<li>Eletricista \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<ul>\n<li>Lubrificador \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<ul>\n<li>Motorista \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<ul>\n<li>Oficineiro em artes \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<ul>\n<li>Oficineiro em atividades art\u00edsticas (dan\u00e7a, m\u00fasica e teatro) \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<ul>\n<li>Operador de m\u00e1quinas \u2013 40h semanais (1 vaga)<\/li>\n<\/ul>\n<p>A prova objetiva est\u00e1 prevista para o dia <strong>18 de agosto de 2024<\/strong>. O <strong>edital <\/strong>completo pode ser conferido<a href=\"https:\/\/www.vunesp.com.br\/PMPR2403\" target=\"_blank\" rel=\"noreferrer noopener\"> clicando aqui.<\/a><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>\u00daltimos dias de inscri\u00e7\u00f5es para o processo seletivo da Etec de Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/GFH9HUMUTHNFJdnyEd0xxq\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Como fazer saque calamidade do FGTS?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/economia\/prefeitura-no-interior-de-sp-abre-concurso-publico-com-salarios-de-r-38-mil\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Prefeitura de Piracicaba, no interior de S\u00e3o Paulo, abriu concurso p\u00fablico com sal\u00e1rios que variam entre R$ 2,8 mil e R$ 3,8 mil. S\u00e3o dez vagas de n\u00edvel fundamental e m\u00e9dio. As inscri\u00e7\u00f5es devem ser realizadas no per\u00edodo entre 15 de maio e 13 de junho pela internet (clique aqui). O valor da &#8230; <a title=\"Prefeitura no interior de SP abre concurso p\u00fablico com sal\u00e1rios de R$ 3,8 mil\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/prefeitura-no-interior-de-sp-abre-concurso-publico-com-salarios-de-r-38-mil\/\" aria-label=\"Read more about Prefeitura no interior de SP abre concurso p\u00fablico com sal\u00e1rios de R$ 3,8 mil\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":48971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-48970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico-12.jpg?fit=1500%2C1000&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico-12.jpg?fit=1500%2C1000&ssl=1",1500,1000,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico-12.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico-12.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico-12.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico-12.jpg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico-12.jpg?fit=1500%2C1000&ssl=1",1500,1000,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico-12.jpg?fit=1500%2C1000&ssl=1",1500,1000,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Prefeitura de Piracicaba, no interior de S\u00e3o Paulo, abriu concurso p\u00fablico com sal\u00e1rios que variam entre R$ 2,8 mil e R$ 3,8 mil. S\u00e3o dez vagas de n\u00edvel fundamental e m\u00e9dio. As inscri\u00e7\u00f5es devem ser realizadas no per\u00edodo entre 15 de maio e 13 de junho pela internet (clique aqui). O valor da&hellip;","jetpack-related-posts":[{"id":70828,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/13\/veja-cinco-concursos-publicos-com-mais-de-110-vagas-no-interior-de-sp\/","url_meta":{"origin":48970,"position":0},"title":"Veja cinco concursos p\u00fablicos com mais de 110 vagas no interior de SP","author":"ismaelcolosi.com.br","date":"13 de October de 2024","format":false,"excerpt":"[ad_1] Os interessados em concorrer a uma vaga em concurso p\u00fablico contam com mais de 110 oportunidades em cinco editais dispon\u00edveis no interior de S\u00e3o Paulo. As oportunidades s\u00e3o para cargos de n\u00edvel m\u00e9dio, t\u00e9cnico e superior. Os sal\u00e1rios variam entre R$ 2,1 mil e R$ 12,6 mil. Confira a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":67327,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/22\/veja-sete-concursos-publicos-com-mais-de-200-vagas-no-interior-de-sp\/","url_meta":{"origin":48970,"position":1},"title":"Veja sete concursos p\u00fablicos com mais de 200 vagas no interior de SP","author":"ismaelcolosi.com.br","date":"22 de September de 2024","format":false,"excerpt":"[ad_1] Voc\u00ea procura por uma oportunidade de emprego no servi\u00e7o p\u00fablico? O acidade on Ribeir\u00e3o separou uma lista com sete concursos p\u00fablico que t\u00eam, somados, mais de 200 vagas dispon\u00edveis no interior de S\u00e3o Paulo. As vagas nos concursos p\u00fablicos s\u00e3o de n\u00edvel fundamental, m\u00e9dio, t\u00e9cnico e superior com sal\u00e1rios\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45782,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/07\/veja-quatro-concursos-publicos-com-as-inscricoes-abertas-no-interior-de-sp\/","url_meta":{"origin":48970,"position":2},"title":"Veja quatro concursos p\u00fablicos com as inscri\u00e7\u00f5es abertas no interior de SP","author":"ismaelcolosi.com.br","date":"7 de April de 2024","format":false,"excerpt":"[ad_1] Para quem est\u00e1 em busca de uma oportunidade de emprego no servi\u00e7o p\u00fablico, o acidade on Ribeir\u00e3o separou quatro concursos p\u00fablicos com as inscri\u00e7\u00f5es abertas no interior de S\u00e3o Paulo. S\u00e3o mais de 400 vagas e sal\u00e1rios de at\u00e9 R$ 8 mil. Prefeitura de Ribeir\u00e3o Preto A Prefeitura de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/prova-concurso-publico-2.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/prova-concurso-publico-2.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/prova-concurso-publico-2.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/prova-concurso-publico-2.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/prova-concurso-publico-2.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1105,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/10\/veja-cinco-concursos-publicos-no-interior-de-sp-com-salarios-de-ate-r-21-mil\/","url_meta":{"origin":48970,"position":3},"title":"Veja cinco concursos p\u00fablicos no interior de SP com sal\u00e1rios de at\u00e9 R$ 21 mil","author":"ismaelcolosi.com.br","date":"10 de November de 2023","format":false,"excerpt":"[ad_1] Nesta semana, diversos concursos p\u00fablicos foram abertos no interior de S\u00e3o Paulo. O acidade on Ribeir\u00e3o separou cinco concursos com vagas de n\u00edvel fundamental, m\u00e9dio, t\u00e9cnico e superior e sal\u00e1rios de at\u00e9 R$ 21 mil. Veja os concursos p\u00fablicos: Prefeitura de Ribeir\u00e3o Preto A Prefeitura de Ribeir\u00e3o Preto publicou\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concurso-publico-9.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concurso-publico-9.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concurso-publico-9.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concurso-publico-9.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concurso-publico-9.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37070,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/14\/prefeitura-no-interior-de-sp-tem-concurso-publico-com-53-vagas-e-salarios-de-r-3-mil\/","url_meta":{"origin":48970,"position":4},"title":"Prefeitura no interior de SP tem concurso p\u00fablico com 53 vagas e sal\u00e1rios de R$ 3 mil","author":"ismaelcolosi.com.br","date":"14 de February de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Terra Roxa, no interior de S\u00e3o Paulo, tem concurso p\u00fablico com 53 vagas e sal\u00e1rios de at\u00e9 R$ 3,2 mil. As oportunidades s\u00e3o de n\u00edvel fundamental, m\u00e9dio e superior. As inscri\u00e7\u00f5es devem ser realizadas at\u00e9 o dia 25 de fevereiro pela internet (clique aqui). O valor\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55880,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/06\/prefeitura-no-interior-de-sp-abre-concurso-publico-com-salarios-de-ate-r-33-mil\/","url_meta":{"origin":48970,"position":5},"title":"Prefeitura no interior de SP abre concurso p\u00fablico com sal\u00e1rios de at\u00e9 R$ 3,3 mil","author":"ismaelcolosi.com.br","date":"6 de July de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Brodowski, no interior de S\u00e3o Paulo, publicou o edital para inscri\u00e7\u00f5es em concurso p\u00fablico para o cadastro de reserva. As vagas s\u00e3o de n\u00edvel fundamental, m\u00e9dio e superior e os sal\u00e1rios variam entre R$ 1,5 mil e R$ 3,3 mil. Para a fun\u00e7\u00e3o de m\u00e9dico o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-cJQ","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=48970"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/48971"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=48970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=48970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=48970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}