{"id":48831,"date":"2024-05-07T06:48:56","date_gmt":"2024-05-07T09:48:56","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/abstinencia-sexual-afeta-o-desempenho-no-trabalho\/"},"modified":"2024-05-07T06:48:56","modified_gmt":"2024-05-07T09:48:56","slug":"abstinencia-sexual-afeta-o-desempenho-no-trabalho","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/abstinencia-sexual-afeta-o-desempenho-no-trabalho\/","title":{"rendered":"Abstin\u00eancia sexual afeta o desempenho no trabalho"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div id=\"attachment_609539\" class=\"wp-caption alignnone style=\" max-width:=\"\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-609539 size-full\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-768x512.jpg?resize=678%2C452&#038;ssl=1\" http:=\"\" alt=\"\" width=\"678\" height=\"452\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-768x512.jpg\"\/><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-609539 size-full\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-768x512.jpg?resize=678%2C452&#038;ssl=1\" alt=\"\" width=\"678\" height=\"452\"\/><\/p>\n<p class=\"wp-caption-text\">As repercuss\u00f5es da abstin\u00eancia sexual no desempenho da equipe podem ser sutis, mas significativas<\/p>\n<\/div>\n<p>Um fen\u00f4meno conhecido como<strong> \u201capag\u00e3o sexual\u201d<\/strong> tem atra\u00eddo cada vez mais a aten\u00e7\u00e3o de psic\u00f3logos e soci\u00f3logos e, agora, tamb\u00e9m virou assunto para l\u00edderes de empresas e profissionais de RH.<\/p>\n<p>Esse cen\u00e1rio \u2013 que define um <strong>decl\u00ednio significativo na atividade sexual, especialmente entre jovens adultos<\/strong> \u2013 tem implica\u00e7\u00f5es que v\u00e3o muito al\u00e9m do que se imagina. Influencia o bem-estar geral, a din\u00e2mica social e at\u00e9 mesmo a lideran\u00e7a e o desempenho no trabalho.<\/p>\n<p>A onda de endorfina e outros horm\u00f4nios indutores de felicidade relacionados \u00e0 atividade sexual, como a dopamina e a ocitocina, desempenha um papel fundamental na mentalidade de lideran\u00e7a e no engajamento.<\/p>\n<ul>\n<li><strong>Siga a <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u\" target=\"_blank\" rel=\"noopener\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias sobre neg\u00f3cios, carreira, tecnologia e estilo de vida<\/strong><\/li>\n<\/ul>\n<p>Os l\u00edderes que apresentam n\u00edveis mais elevados desses horm\u00f4nios tendem a demonstrar mais empatia, paci\u00eancia e criatividade em suas fun\u00e7\u00f5es. Esses est\u00edmulos emocionais e psicol\u00f3gicos podem melhorar a tomada de decis\u00f5es e promover a inova\u00e7\u00e3o e a colabora\u00e7\u00e3o.<\/p>\n<p>A abstin\u00eancia sexual suscitou debates sobre as suas causas, desde distra\u00e7\u00f5es com as redes sociais at\u00e9 press\u00f5es econ\u00f4micas e transforma\u00e7\u00f5es nas normas sociais. Em 2021, um total de 26% dos americanos com 18 anos ou mais n\u00e3o faziam sexo h\u00e1 um ano, de acordo com a <a href=\"https:\/\/www.docdroid.net\/MsXOsV4\/tables-sda2-pdf\" target=\"_blank\" rel=\"noopener\">pesquisa sociol\u00f3gica General Social Survey de 2021<\/a>. Especialistas observam a mesma tend\u00eancia no Brasil.<\/p>\n<h2>Como isso afeta a lideran\u00e7a<\/h2>\n<p>Lideran\u00e7a n\u00e3o envolve apenas definir metas e gerar receita. Trata-se de compreender e navegar pelas din\u00e2micas pessoais e sociais que influenciam o desempenho da equipe.<\/p>\n<p>Al\u00e9m do ato f\u00edsico, o sexo promove conex\u00f5es \u00edntimas, que s\u00e3o fundamentais para o apoio emocional e a compreens\u00e3o entre os parceiros. Essas rela\u00e7\u00f5es contribuem significativamente n\u00e3o apenas para o aumento dos n\u00edveis hormonais, mas tamb\u00e9m para a felicidade.<\/p>\n<p>A onda hormonal <strong>melhora o humor e reduz os n\u00edveis de estresse<\/strong>, promovendo uma sensa\u00e7\u00e3o de bem-estar. O efeito redutor do estresse pode levar a um comportamento mais sereno, permitindo que os l\u00edderes enfrentem situa\u00e7\u00f5es de alta press\u00e3o com uma abordagem calma e equilibrada.<\/p>\n<p>Por outro lado, quando uma pessoa, especialmente um l\u00edder, n\u00e3o est\u00e1 nesse estado de libera\u00e7\u00e3o de endorfinas, isso pode causar:<\/p>\n<ul>\n<li>Falta de coes\u00e3o na equipe: Os la\u00e7os sociais s\u00e3o mais fracos, pois as pessoas s\u00e3o menos propensas a se envolver em atividades que promovam relacionamentos pessoais pr\u00f3ximos;<\/li>\n<li>Aumento dos n\u00edveis de estresse: A falta de conex\u00f5es pode levar a n\u00edveis mais elevados de estresse e ansiedade, afetando o desempenho geral no trabalho;<\/li>\n<li>Diminui\u00e7\u00e3o da produtividade: O bem-estar dos membros da equipe est\u00e1 intimamente ligado \u00e0 produtividade. Um decl\u00ednio no bem-estar pessoal pode levar \u00e0 redu\u00e7\u00e3o das entregas ou na qualidade delas;<\/li>\n<li>Desafios na motiva\u00e7\u00e3o: Motivar uma equipe que enfrenta problemas pessoais requer compreens\u00e3o e esfor\u00e7o;<\/li>\n<li>Risco de cultura de trabalho t\u00f3xica: Como l\u00edder, voc\u00ea deve criar um ambiente de trabalho que promova a inclus\u00e3o e a seguran\u00e7a psicol\u00f3gica. A falta de conex\u00f5es pessoais pode levar a um aumento dos sentimentos de isolamento e contribuir para a manuten\u00e7\u00e3o de culturas de trabalho t\u00f3xicas.<\/li>\n<\/ul>\n<p><strong>Leia tamb\u00e9m:<\/strong><\/p>\n<h2>Como afeta a equipe<\/h2>\n<p>As repercuss\u00f5es do apag\u00e3o sexual no desempenho da equipe podem ser sutis, mas significativas. Aqui est\u00e1 o que voc\u00ea pode notar:<\/p>\n<ul>\n<li>Menor engajamento: Profissionais que est\u00e3o pessoalmente insatisfeitos podem demonstrar menos entusiasmo e engajamento no trabalho;<\/li>\n<li>Aumento do absente\u00edsmo: Problemas de sa\u00fade mental decorrentes da solid\u00e3o ou da falta de rela\u00e7\u00f5es \u00edntimas podem resultar em aus\u00eancias mais frequentes;<\/li>\n<li>Dificuldade de colabora\u00e7\u00e3o: A colabora\u00e7\u00e3o requer empatia e compreens\u00e3o, que podem ser prejudicadas pelo isolamento ou por problemas pessoais.<\/li>\n<\/ul>\n<h2>Como liderar em um cen\u00e1rio de abstin\u00eancia sexual<\/h2>\n<p>Ser um bom gestor nesse cen\u00e1rio significa adaptar o seu estilo de lideran\u00e7a para enfrentar os desafios apresentados.<\/p>\n<h3>Promova a comunica\u00e7\u00e3o aberta<\/h3>\n<p>Criar uma cultura em que os membros da equipe se sintam confort\u00e1veis \u200b\u200bem compartilhar seus problemas profissionais pode ajud\u00e1-lo a resolver as quest\u00f5es antes que elas afetem o desempenho.<\/p>\n<h3>Promova o equil\u00edbrio entre vida profissional e pessoal<\/h3>\n<p>Incentivar um equil\u00edbrio saud\u00e1vel entre trabalho e vida pessoal pode ajudar os funcion\u00e1rios a controlar o estresse e a manter o bem-estar. Os l\u00edderes podem implementar hor\u00e1rios de trabalho flex\u00edveis, permitindo que os funcion\u00e1rios adaptem os seus hor\u00e1rios em fun\u00e7\u00e3o das obriga\u00e7\u00f5es e prefer\u00eancias pessoais, reduzindo o estresse e aumentando a produtividade. Al\u00e9m disso, podem incentivar pausas regulares e momentos de desconex\u00e3o de dispositivos eletr\u00f4nicos, o que ajuda a prevenir o esgotamento e a melhorar a sa\u00fade mental.<\/p>\n<h3>Ofere\u00e7a apoio<\/h3>\n<p>Fornecer acesso a recursos de sa\u00fade mental ou servi\u00e7os de aconselhamento demonstra cuidado com o bem-estar geral da sua equipe, para al\u00e9m do desempenho deles no trabalho.<\/p>\n<h3>Incentive programas de exerc\u00edcios f\u00edsicos<\/h3>\n<p>Incentive sua equipe a incorporar a atividade f\u00edsica nas suas rotinas di\u00e1rias. Isso pode ser feito com um desafio para toda a empresa que rastreie etapas ou minutos ativos, recompensas para quem praticar um esporte ou um evento que leve todos a fazer um treino juntos, o que ajuda a motivar a equipe. Al\u00e9m disso, oferecer subs\u00eddios para inscri\u00e7\u00e3o em academias ou criar um espa\u00e7o dedicado \u00e0 pr\u00e1tica de exerc\u00edcios no escrit\u00f3rio pode tornar a atividade f\u00edsica mais acess\u00edvel e atraente.<\/p>\n<h3>Como motivar sua equipe<\/h3>\n<ul>\n<li>Organize atividades que incentivem conex\u00f5es e amizades genu\u00ednas entre os membros da equipe;<\/li>\n<li>Reconhe\u00e7a p\u00fablica e pessoalmente o trabalho e as conquistas da sua equipe;<\/li>\n<li>Ofere\u00e7a oportunidades de crescimento profissional.<\/li>\n<\/ul>\n<p>Ao compreender as mudan\u00e7as sociais que podem estar afetando a sua equipe e adaptar sua abordagem de lideran\u00e7a de acordo com isso, voc\u00ea vai conseguir manter o desempenho, o engajamento e a satisfa\u00e7\u00e3o do time.<\/p>\n<p>Os bons l\u00edderes reconhecem que os problemas no ambiente de trabalho est\u00e3o frequentemente relacionados com a vida pessoal dos profissionais.<\/p>\n<p><em>*Cheryl Robinson \u00e9 colaboradora da Forbes US, autora da s\u00e9rie de livros infantis \u201cThe Happy Habits Club\u201d, doutora em educa\u00e7\u00e3o em lideran\u00e7a organizacional e apresentadora do podcast Embrace the Pivot.<\/em><\/p>\n<\/div>\n<p><script type=\"rocketlazyloadscript\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2024\/05\/como-a-abstinencia-sexual-afeta-a-lideranca-e-o-desempenho-no-trabalho\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] As repercuss\u00f5es da abstin\u00eancia sexual no desempenho da equipe podem ser sutis, mas significativas Um fen\u00f4meno conhecido como \u201capag\u00e3o sexual\u201d tem atra\u00eddo cada vez mais a aten\u00e7\u00e3o de psic\u00f3logos e soci\u00f3logos e, agora, tamb\u00e9m virou assunto para l\u00edderes de empresas e profissionais de RH. Esse cen\u00e1rio \u2013 que define um decl\u00ednio significativo na atividade &#8230; <a title=\"Abstin\u00eancia sexual afeta o desempenho no trabalho\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/abstinencia-sexual-afeta-o-desempenho-no-trabalho\/\" aria-label=\"Leia mais sobre Abstin\u00eancia sexual afeta o desempenho no trabalho\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":48832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-48831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-1024x683.jpg?fit=1024%2C683&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-1024x683.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-1024x683.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-1024x683.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-burnout-ansiedade-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] As repercuss\u00f5es da abstin\u00eancia sexual no desempenho da equipe podem ser sutis, mas significativas Um fen\u00f4meno conhecido como \u201capag\u00e3o sexual\u201d tem atra\u00eddo cada vez mais a aten\u00e7\u00e3o de psic\u00f3logos e soci\u00f3logos e, agora, tamb\u00e9m virou assunto para l\u00edderes de empresas e profissionais de RH. Esse cen\u00e1rio \u2013 que define um decl\u00ednio significativo na atividade&hellip;","jetpack-related-posts":[{"id":16946,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/16\/estudo-aponta-bebida-que-homens-devem-abandonar-antes-de-terem-filhos\/","url_meta":{"origin":48831,"position":0},"title":"Estudo aponta bebida que homens devem abandonar antes de terem filhos","author":"ismaelcolosi.com.br","date":"16 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: Depositphotos\/ufabizphotoHomens devem abandonar o \u00e1lcool 3 meses antes de tentarem ter filhos Deseja se tornar pai? Ent\u00e3o \u00e9 melhor deixar o \u00e1lcool de lado com anteced\u00eancia. Um estudo, realizado pela Texas A&M University, aponta que o consumo de bebidas alco\u00f3licas pode interferir negativamente no desenvolvimento fetal, mesmo que\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-178322854-xl-scaled-e1702743867140.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-178322854-xl-scaled-e1702743867140.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-178322854-xl-scaled-e1702743867140.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-178322854-xl-scaled-e1702743867140.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-178322854-xl-scaled-e1702743867140.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15400,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/confira-alimentos-que-podem-elevar-a-libido\/","url_meta":{"origin":48831,"position":1},"title":"Confira alimentos que podem elevar a libido","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Os alimentos podem ser bons aliados na busca por uma melhora na hora de sentir prazer. Alguns alimentos tidos como afrodis\u00edacos entram na lista de aliados da \u2018hora H\u2019Os chamados afrodis\u00edacos s\u00e3o subst\u00e2ncias que elevam o fluxo sangu\u00edneo nos \u00f3rg\u00e3os geniais e acham agu\u00e7ando horm\u00f4nios sexuais e por consequ\u00eancia,\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a0abda5fb31664.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a0abda5fb31664.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a0abda5fb31664.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a0abda5fb31664.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a0abda5fb31664.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":78214,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/03\/geriatra-alerta-para-crescente-numero-de-casos-de-hiv-entre-idosos\/","url_meta":{"origin":48831,"position":2},"title":"Geriatra Alerta para Crescente N\u00famero de Casos de HIV entre Idosos","author":"ismaelcolosi.com.br","date":"3 de Dezembro de 2024","format":false,"excerpt":"[ad_1] O aumento de casos de HIV entre idosos tem chamado a aten\u00e7\u00e3o de especialistas da \u00e1rea da sa\u00fade no Brasil. Segundo dados apresentados em um evento nacional de sa\u00fade p\u00fablica, a popula\u00e7\u00e3o acima dos 60 anos tem registrado uma alta significativa no n\u00famero de diagn\u00f3sticos nos \u00faltimos anos. A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/cartilha-vacinahiv.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/cartilha-vacinahiv.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/cartilha-vacinahiv.webp.webp?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/cartilha-vacinahiv.webp.webp?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/cartilha-vacinahiv.webp.webp?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":32483,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/25\/livro-reportagem-sobre-violencia-sexual-sera-lancado-nesta-quinta-em-rp\/","url_meta":{"origin":48831,"position":3},"title":"Livro-reportagem sobre viol\u00eancia sexual ser\u00e1 lan\u00e7ado nesta quinta em RP","author":"ismaelcolosi.com.br","date":"25 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 25 de janeiro de 2024 | 11:4025 de janeiro de 2024 | 11:41 0O livro-reportagem \u201cQuando as vozes se calam\u201d, com hist\u00f3rias reais de mulheres v\u00edtimas de viol\u00eancia sexual na regi\u00e3o de Ribeir\u00e3o Preto, ser\u00e1 lan\u00e7ado nesta quinta-feira, 25, \u00e0s 19h na Livraria Travessa no Ribeir\u00e3o Shopping.O projeto nasceu\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/e53bd033-99f9-4257-b389-e98156f3380b-scaled.jpg?fit=454%2C645&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13134,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/09\/utm_sourcerssutm_mediumrssutm_campaignbandidos-abusam-sexualmente-de-mulher-durante-roubo-a-uma-fazenda-em-serra-azul\/","url_meta":{"origin":48831,"position":4},"title":"Bandidos abusam sexualmente de mulher durante roubo a uma fazenda em Serra Azul \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"9 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Quatro vagabundos abusaram sexualmente de uma jovem durante um assalto a uma fazenda na zona Rural da cidade de Serra Azul.\u00a0 Segundo informa\u00e7\u00f5es da Pol\u00edcia, durante a madrugada quatro vagabundos armados em um Monza invadiram a fazenda. Ap\u00f3s render o casal e os dois filhos, as v\u00edtimas foram divididas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/estupro.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/estupro.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/estupro.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/estupro.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":73395,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/26\/estudo-revela-ineficiencias-no-tratamento-tradicional-contra-drogas\/","url_meta":{"origin":48831,"position":5},"title":"Estudo Revela Inefici\u00eancias no Tratamento Tradicional contra Drogas","author":"ismaelcolosi.com.br","date":"26 de Outubro de 2024","format":false,"excerpt":"[ad_1] Um estudo recente divulgado por especialistas em sa\u00fade mental e depend\u00eancia qu\u00edmica trouxe \u00e0 tona falhas significativas nas abordagens tradicionais de tratamento contra o uso de drogas. A pesquisa, que envolveu institui\u00e7\u00f5es brasileiras e internacionais, aponta que os m\u00e9todos convencionais de tratamento, como terapias de abstin\u00eancia e programas de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/12.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/12.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/12.webp.webp?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/12.webp.webp?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/12.webp.webp?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-cHB","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=48831"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/48832"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=48831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=48831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=48831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}