{"id":48785,"date":"2024-05-06T16:31:57","date_gmt":"2024-05-06T19:31:57","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/06\/onda-de-calor-no-interior-de-sp-se-estende-e-tem-nova-data-para-acabar-confira\/"},"modified":"2024-05-06T16:31:57","modified_gmt":"2024-05-06T19:31:57","slug":"onda-de-calor-no-interior-de-sp-se-estende-e-tem-nova-data-para-acabar-confira","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/06\/onda-de-calor-no-interior-de-sp-se-estende-e-tem-nova-data-para-acabar-confira\/","title":{"rendered":"Onda de calor no interior de SP se estende e tem nova data para acabar; Confira"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>A <strong>onda de calor<\/strong> que atinge o <strong>interior de S\u00e3o Paulo<\/strong> desde o dia 22 de abril, tinha previs\u00e3o para acabar nessa sexta-feira (10), contudo, a <strong>meteorologia <\/strong>informou, nesta segunda-feira (06), que o fen\u00f4meno <strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">vai novamente se estender por um per\u00edodo maior no estado.<\/mark><\/strong><\/p>\n<p>De acordo com a <strong>Climatempo<\/strong>, a grande e forte <strong>massa de ar quente<\/strong> que est\u00e1 cobrindo amplas \u00e1reas do Centro-Sul do pa\u00eds continuar\u00e1 atuando com intensidade <strong>at\u00e9 o dia 14 de maio<\/strong>.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<figure class=\"wp-block-pullquote\">\n<blockquote>\n<p>Ela [massa de ar quente] \u00e9 mantida por um forte bloqueio atmosf\u00e9rico, que deixa o ar muito seco e quente, e dificulta a forma\u00e7\u00e3o de nuvens nas regi\u00f5es Sudeste e Centro-Oeste, al\u00e9m de barrar instabilidades sobre o Sul do Brasil<\/p>\n<p><cite>Climatempo<\/cite><\/p><\/blockquote>\n<\/figure>\n<h3 class=\"wp-block-heading\"><strong>Alerta vermelho para onda de calor<\/strong><\/h3>\n<p>Ainda de acordo com a plataforma <strong>Climatempo<\/strong>, s\u00e3o esperadas <strong>temperaturas 5\u00b0C acima da m\u00e9dia <\/strong>em todo o <strong>estado de S\u00e3o Paulo<\/strong>.<\/p>\n<p>Vale ressaltar que, o <strong>Instituto Nacional de Meteorologia (Inmet) <\/strong>tamb\u00e9m emitiu um <strong>alerta vermelho<\/strong> para diversas regi\u00f5es do <strong>interior de S\u00e3o Paulo<\/strong>.<\/p>\n<p>O comunicado refor\u00e7a que as altas temperaturas devem se estender por per\u00edodo maior do que cinco dias e pode trazer risco \u00e0 sa\u00fade. <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Ele \u00e9 v\u00e1lido at\u00e9 \u00e0s 18h do dia 9 de maio.<\/mark><\/p>\n<h4 class=\"wp-block-heading\"><strong>Confira as \u00e1reas afetadas pelo aviso do Inmet<\/strong><\/h4>\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/05\/AnyConv.com__WhatsApp-Image-2024-05-06-at-15.13.20_2024-05-06_19-26-04-1024x1024.webp?resize=429%2C457&#038;ssl=1\" alt=\"\" class=\"wp-image-80556\" width=\"429\" height=\"457\"\/><figcaption class=\"wp-element-caption\">Climatempo diz que onda de calor deve durar at\u00e9 o dia 15 de maio em todo o estado de SP. (Foto: Reprodu\u00e7\u00e3o \/ Climatempo)<\/figcaption><\/figure>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Interior de SP vai ganhar novo parque aqu\u00e1tico; Veja quando e o local<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/GFH9HUMUTHNFJdnyEd0xxq\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Quem \u00e9 Julia Wendell, que afirma ser Madeleine McCann?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/onda-de-calor-no-interior-de-sp-se-estende-e-tem-nova-data-para-acabar-confira\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A onda de calor que atinge o interior de S\u00e3o Paulo desde o dia 22 de abril, tinha previs\u00e3o para acabar nessa sexta-feira (10), contudo, a meteorologia informou, nesta segunda-feira (06), que o fen\u00f4meno vai novamente se estender por um per\u00edodo maior no estado. De acordo com a Climatempo, a grande e forte massa &#8230; <a title=\"Onda de calor no interior de SP se estende e tem nova data para acabar; Confira\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/06\/onda-de-calor-no-interior-de-sp-se-estende-e-tem-nova-data-para-acabar-confira\/\" aria-label=\"Read more about Onda de calor no interior de SP se estende e tem nova data para acabar; Confira\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":48259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-48785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__trbr5828-scaled.webp.webp?fit=2560%2C1707&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__trbr5828-scaled.webp.webp?fit=2560%2C1707&ssl=1",2560,1707,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__trbr5828-scaled.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__trbr5828-scaled.webp.webp?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__trbr5828-scaled.webp.webp?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__trbr5828-scaled.webp.webp?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__trbr5828-scaled.webp.webp?fit=1536%2C1024&ssl=1",1536,1024,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__trbr5828-scaled.webp.webp?fit=2048%2C1366&ssl=1",2048,1366,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A onda de calor que atinge o interior de S\u00e3o Paulo desde o dia 22 de abril, tinha previs\u00e3o para acabar nessa sexta-feira (10), contudo, a meteorologia informou, nesta segunda-feira (06), que o fen\u00f4meno vai novamente se estender por um per\u00edodo maior no estado. De acordo com a Climatempo, a grande e forte massa&hellip;","jetpack-related-posts":[{"id":60196,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/14\/calorao-vai-voltar-veja-previsao-para-os-proximos-dias-no-interior-de-sp\/","url_meta":{"origin":48785,"position":0},"title":"Calor\u00e3o vai voltar? Veja previs\u00e3o para os pr\u00f3ximos dias no interior de SP","author":"ismaelcolosi.com.br","date":"14 de August de 2024","format":false,"excerpt":"[ad_1] Depois de um per\u00edodo de frio intenso no interior de S\u00e3o Paulo, os meteorologistas alertam para um retorno significativo do calor v\u00e1rias regi\u00f5es. De acordo com a Climatempo, uma nova e forte massa de ar quente deve elevar as temperaturas, criando um cen\u00e1rio de verdadeira \u201cgangorra t\u00e9rmica\u201c. A partir\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__CLIMA_QUENTE_NA_CIDADE_DE_CAMPINAS_SP_CoDIGO-19_173574-1068x712-1.webp.webp?fit=1068%2C712&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__CLIMA_QUENTE_NA_CIDADE_DE_CAMPINAS_SP_CoDIGO-19_173574-1068x712-1.webp.webp?fit=1068%2C712&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__CLIMA_QUENTE_NA_CIDADE_DE_CAMPINAS_SP_CoDIGO-19_173574-1068x712-1.webp.webp?fit=1068%2C712&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__CLIMA_QUENTE_NA_CIDADE_DE_CAMPINAS_SP_CoDIGO-19_173574-1068x712-1.webp.webp?fit=1068%2C712&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__CLIMA_QUENTE_NA_CIDADE_DE_CAMPINAS_SP_CoDIGO-19_173574-1068x712-1.webp.webp?fit=1068%2C712&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48942,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/entenda-a-relacao-da-onda-de-calor-no-interior-de-sp-com-as-chuvas-no-rs\/","url_meta":{"origin":48785,"position":1},"title":"Entenda a rela\u00e7\u00e3o da onda de calor no interior de SP com as chuvas no RS","author":"ismaelcolosi.com.br","date":"7 de May de 2024","format":false,"excerpt":"[ad_1] A onda de calor de atinge o interior de S\u00e3o Paulo desde o dia 22 de abril est\u00e1 impactando os temporais que atingem o Rio Grande do Sul nos \u00faltimos dias, de acordo com a meteorologia. Isso porque os fen\u00f4menos est\u00e3o acontecendo devido a um bloqueio atmosf\u00e9rico que deixa\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/c83445d5-a4aa-4fe7-b45f-39c7c9f43879_2024-05-07_19-33-31_jpeg_2024-05-07_19-33-31.webp.webp?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/c83445d5-a4aa-4fe7-b45f-39c7c9f43879_2024-05-07_19-33-31_jpeg_2024-05-07_19-33-31.webp.webp?fit=768%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/c83445d5-a4aa-4fe7-b45f-39c7c9f43879_2024-05-07_19-33-31_jpeg_2024-05-07_19-33-31.webp.webp?fit=768%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/c83445d5-a4aa-4fe7-b45f-39c7c9f43879_2024-05-07_19-33-31_jpeg_2024-05-07_19-33-31.webp.webp?fit=768%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":61078,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/20\/onda-de-calor-ou-frente-fria-entenda-como-fica-a-situacao-no-interior-de-sp\/","url_meta":{"origin":48785,"position":2},"title":"Onda de calor ou frente fria? Entenda como fica a situa\u00e7\u00e3o no interior de SP","author":"ismaelcolosi.com.br","date":"20 de August de 2024","format":false,"excerpt":"[ad_1] Todo o interior de S\u00e3o Paulo segue em alerta para onda de calor, que come\u00e7ou no \u00faltimo fim de semana, segundo o Inmet (Instituto Nacional de Meteorologia). Contudo, os meteorologistas acenam para chegada de uma frente fria no pr\u00f3ximo fim de semana, que pode derrubar as temperaturas em algumas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/onda-de-calor-frente-fria_2024-08-20_10-46-52_jpeg_2024-08-20_10-46-52.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/onda-de-calor-frente-fria_2024-08-20_10-46-52_jpeg_2024-08-20_10-46-52.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/onda-de-calor-frente-fria_2024-08-20_10-46-52_jpeg_2024-08-20_10-46-52.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/onda-de-calor-frente-fria_2024-08-20_10-46-52_jpeg_2024-08-20_10-46-52.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/onda-de-calor-frente-fria_2024-08-20_10-46-52_jpeg_2024-08-20_10-46-52.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":60421,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/15\/cidades-do-interior-de-sp-estao-em-alerta-de-perigo-potencial-para-onda-de-calor-veja-lista\/","url_meta":{"origin":48785,"position":3},"title":"Cidades do interior de SP est\u00e3o em alerta de perigo potencial para onda de calor; Veja lista","author":"ismaelcolosi.com.br","date":"15 de August de 2024","format":false,"excerpt":"[ad_1] Uma nova onda de calor deve atingir o interior de S\u00e3o Paulo e provocar altas temperaturas em diversas regi\u00f5es a partir deste domingo (18), de acordo com a meteorologia. O ar gelado provocado por uma forte massa de ar frio come\u00e7ou a se afastar nesta quinta-feira (15) e uma\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20230824_153104-1.jpg?fit=1200%2C823&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20230824_153104-1.jpg?fit=1200%2C823&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20230824_153104-1.jpg?fit=1200%2C823&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20230824_153104-1.jpg?fit=1200%2C823&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20230824_153104-1.jpg?fit=1200%2C823&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":61290,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/21\/antes-de-frente-fria-interior-de-sp-deve-registrar-pico-de-calor-saiba-quando\/","url_meta":{"origin":48785,"position":4},"title":"Antes de\u00a0frente fria, interior de SP deve registrar pico de calor; Saiba quando","author":"ismaelcolosi.com.br","date":"21 de August de 2024","format":false,"excerpt":"[ad_1] As temperaturas seguem extremas antes de uma frente fria prevista para avan\u00e7a pelo Brasil a partir desta quinta-feira (22). Segundo a Climatempo, esta nova frente fria tem caracter\u00edstica continental, est\u00e1 associada a um ciclone extratropical no mar e tem expectativa de trazer chuva e derrubar as temperaturas no Centro-Sul.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-21-at-07.21.47_2024-08-21_10-22-33_jpeg_2024-08-21_10-22-34.webp.webp?fit=1200%2C647&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-21-at-07.21.47_2024-08-21_10-22-33_jpeg_2024-08-21_10-22-34.webp.webp?fit=1200%2C647&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-21-at-07.21.47_2024-08-21_10-22-33_jpeg_2024-08-21_10-22-34.webp.webp?fit=1200%2C647&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-21-at-07.21.47_2024-08-21_10-22-33_jpeg_2024-08-21_10-22-34.webp.webp?fit=1200%2C647&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-21-at-07.21.47_2024-08-21_10-22-33_jpeg_2024-08-21_10-22-34.webp.webp?fit=1200%2C647&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":63102,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/30\/forte-frente-fria-tem-data-para-chegar-ao-pais-veja-previsao-para-setembro\/","url_meta":{"origin":48785,"position":5},"title":"Forte frente fria tem data para chegar ao pa\u00eds; Veja previs\u00e3o para setembro","author":"ismaelcolosi.com.br","date":"30 de August de 2024","format":false,"excerpt":"[ad_1] Apesar de uma nova massa de ar quente e seco se estabelecer sobre o Brasil no decorrer da pr\u00f3xima semana, a primeira forte frente fria de setembro j\u00e1 tem data para chegar ao pa\u00eds, de acordo com os meteorologistas. De acordo com a Climatempo, a expectativa \u00e9 de que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725059994_frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725059994_frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725059994_frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725059994_frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725059994_frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-cGR","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=48785"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/48259"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=48785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=48785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=48785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}