{"id":47468,"date":"2024-04-25T17:34:29","date_gmt":"2024-04-25T20:34:29","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/25\/homem-morre-apos-ser-atropelado-em-frente-a-rodoviaria-de-ribeirao-preto\/"},"modified":"2024-04-25T17:34:29","modified_gmt":"2024-04-25T20:34:29","slug":"homem-morre-apos-ser-atropelado-em-frente-a-rodoviaria-de-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/25\/homem-morre-apos-ser-atropelado-em-frente-a-rodoviaria-de-ribeirao-preto\/","title":{"rendered":"Homem morre ap\u00f3s ser atropelado em frente a rodovi\u00e1ria de Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Um <strong>homem morreu <\/strong>ap\u00f3s ser atropelado em frente ao <strong>Terminal Rodovi\u00e1rio de Ribeir\u00e3o Preto<\/strong>, na tarde desta quinta-feira (25).<\/p>\n<p>De acordo com as informa\u00e7\u00f5es do<strong> Corpo de Bombeiros (CB)<\/strong>, uma equipe foi acionada para atender uma <strong>ocorr\u00eancia de atropelamento<\/strong> no cruzamento da avenida Jer\u00f4nimo Gon\u00e7alves com a alameda Botafogo.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>Segundo o <strong>CB<\/strong>, foi constatado o <strong>\u00f3bito da v\u00edtima ainda no local do atropelamento<\/strong>. <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre a identidade do homem.<\/mark><\/p>\n<p>As causas do acidente, contudo, dever\u00e3o ser <strong>investigadas<\/strong>.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Entenda por que o t\u00fanel de Ribeir\u00e3o Preto foi interditado nesta quinta-feira<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark>FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp:\u00a0<strong>(16) 99117 7802.<\/strong><\/p>\n<p>LEIA MAIS<\/p>\n<p>Jogo Elsie ter\u00e1 suporte para o portugu\u00eas brasileiro<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/homem-morre-apos-ser-atropelado-em-frente-a-rodoviaria-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Um homem morreu ap\u00f3s ser atropelado em frente ao Terminal Rodovi\u00e1rio de Ribeir\u00e3o Preto, na tarde desta quinta-feira (25). De acordo com as informa\u00e7\u00f5es do Corpo de Bombeiros (CB), uma equipe foi acionada para atender uma ocorr\u00eancia de atropelamento no cruzamento da avenida Jer\u00f4nimo Gon\u00e7alves com a alameda Botafogo. Segundo o CB, foi constatado &#8230; <a title=\"Homem morre ap\u00f3s ser atropelado em frente a rodovi\u00e1ria de Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/25\/homem-morre-apos-ser-atropelado-em-frente-a-rodoviaria-de-ribeirao-preto\/\" aria-label=\"Read more about Homem morre ap\u00f3s ser atropelado em frente a rodovi\u00e1ria de Ribeir\u00e3o Preto\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":47469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-47468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-25-at-17.12.10.webp.webp?fit=1600%2C1204&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-25-at-17.12.10.webp.webp?fit=1600%2C1204&ssl=1",1600,1204,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-25-at-17.12.10.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-25-at-17.12.10.webp.webp?fit=300%2C226&ssl=1",300,226,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-25-at-17.12.10.webp.webp?fit=768%2C578&ssl=1",768,578,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-25-at-17.12.10.webp.webp?fit=1024%2C771&ssl=1",1024,771,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-25-at-17.12.10.webp.webp?fit=1536%2C1156&ssl=1",1536,1156,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-25-at-17.12.10.webp.webp?fit=1600%2C1204&ssl=1",1600,1204,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Um homem morreu ap\u00f3s ser atropelado em frente ao Terminal Rodovi\u00e1rio de Ribeir\u00e3o Preto, na tarde desta quinta-feira (25). De acordo com as informa\u00e7\u00f5es do Corpo de Bombeiros (CB), uma equipe foi acionada para atender uma ocorr\u00eancia de atropelamento no cruzamento da avenida Jer\u00f4nimo Gon\u00e7alves com a alameda Botafogo. Segundo o CB, foi constatado&hellip;","jetpack-related-posts":[{"id":56627,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/13\/identificado-homem-morto-apos-atropelamento-em-avenida-de-ribeirao-preto\/","url_meta":{"origin":47468,"position":0},"title":"Identificado homem morto ap\u00f3s atropelamento em avenida de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"13 de July de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Civil identificou o homem morto ap\u00f3s ser atropelado por uma moto enquanto atravessava a avenida F\u00e1bio Barreto na faixa de pedestre, na tarde desta sexta-feira (12), em Ribeir\u00e3o Preto. Segundo o boletim de ocorr\u00eancia (BO), a v\u00edtima, Jos\u00e9 Roberto Pereira de Sousa, de 57 anos, foi arremessada\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":43621,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/22\/ciclista-atropelado-na-regiao-morre-no-hc-ue\/","url_meta":{"origin":47468,"position":1},"title":"Ciclista atropelado na regi\u00e3o morre no HC-UE","author":"ismaelcolosi.com.br","date":"22 de March de 2024","format":false,"excerpt":"[ad_1] Homem teria sofrido tr\u00eas paradas cardiorrespirat\u00f3rias ap\u00f3s atropelamento e n\u00e3o resistiu aos ferimentos 22 de mar\u00e7o de 2024 | 12:09 1 Por: Adalberto Luque Um homem de 76 anos morreu, no final da tarde desta quinta-feira (21), ap\u00f3s ser atropelado horas antes. O acidente ocorreu na Rua Vereador Jos\u00e9\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-22-mar-2024-ciclista-morto-foto-alfredo-risk-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-22-mar-2024-ciclista-morto-foto-alfredo-risk-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-22-mar-2024-ciclista-morto-foto-alfredo-risk-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-22-mar-2024-ciclista-morto-foto-alfredo-risk-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":56599,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/12\/homem-morre-apos-ser-atropelado-por-moto-em-ribeirao-preto\/","url_meta":{"origin":47468,"position":2},"title":"Homem morre ap\u00f3s ser atropelado por moto em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"12 de July de 2024","format":false,"excerpt":"[ad_1] Um homem, de 63 anos, morreu ap\u00f3s ser atropelado por uma moto no final da tarde desta sexta-feira (12), na avenida F\u00e1bio Barretos, no bairro Campos El\u00edseos, em Ribeir\u00e3o Preto. C\u00e2meras de seguran\u00e7a registraram o momento em que o homem estava atravessando na faixa de pedestres da avenida e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-07-12T180659.153_2024-07-12_21-07-28_png_2024-07-12_21-07-28.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":50811,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/19\/homem-de-54-anos-morre-em-ribeirao-preto-apos-ser-encontrado-atropelado\/","url_meta":{"origin":47468,"position":3},"title":"Homem de 54 anos morre em Ribeir\u00e3o Preto ap\u00f3s ser encontrado atropelado","author":"ismaelcolosi.com.br","date":"19 de May de 2024","format":false,"excerpt":"[ad_1] Um homem de 54 anos morreu na \u00faltima sexta-feira (17), em um hospital de Ribeir\u00e3o Preto, ap\u00f3s ser encontrado atropelado. Segundo o boletim de ocorr\u00eancia (BO), Luciano Cesar de Lima foi levado como desconhecido para a Santa Casa, depois de ter sido encontrado desacordado em via p\u00fablica, na quarta-feira\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716142137_cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716142137_cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716142137_cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716142137_cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":52146,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/04\/homem-morre-atropelado-na-rodovia-anhanguera-em-ribeirao-preto\/","url_meta":{"origin":47468,"position":4},"title":"Homem morre atropelado na rodovia Anhanguera em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"4 de June de 2024","format":false,"excerpt":"[ad_1] Um homem, ainda n\u00e3o identificado, morreu na noite desta segunda-feira (3), ap\u00f3s ser atropelado no quil\u00f4metro 18 da rodovia Anhanguera (SP-330), em Ribeir\u00e3o Preto. Um carro e um caminh\u00e3o, que seguiam atr\u00e1s, bateram ao tentar desviar do corpo. Segundo o\u00a0Boletim de Ocorr\u00eancia (B.O.), o motorista do carro que se\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/policia_militar_1024x576_17072021134619.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/policia_militar_1024x576_17072021134619.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/policia_militar_1024x576_17072021134619.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/policia_militar_1024x576_17072021134619.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1547,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/13\/homem-morre-apos-ser-atropelado-no-ipiranga\/","url_meta":{"origin":47468,"position":5},"title":"Homem morre ap\u00f3s ser atropelado no Ipiranga","author":"ismaelcolosi.com.br","date":"13 de November de 2023","format":false,"excerpt":"[ad_1] V\u00edtima estava tentando atravessar rua movimentada do bairro quando foi arremessado ap\u00f3s ser atingido por ve\u00edculo em movimento 13 de novembro de 2023 | 10:1413 de novembro de 2023 | 10:15 2Por: Adalberto LuqueUm homem de 77 anos morreu, na noite deste s\u00e1bado (11), depois ser atropelado enquanto atravessava\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/00-13-nov-2023-atropelamento-idoso-foto-reproducao-scaled.jpg?fit=1000%2C554&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/00-13-nov-2023-atropelamento-idoso-foto-reproducao-scaled.jpg?fit=1000%2C554&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/00-13-nov-2023-atropelamento-idoso-foto-reproducao-scaled.jpg?fit=1000%2C554&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/00-13-nov-2023-atropelamento-idoso-foto-reproducao-scaled.jpg?fit=1000%2C554&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-clC","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47468"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/47469"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}