{"id":4719,"date":"2023-11-22T06:32:57","date_gmt":"2023-11-22T09:32:57","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/22\/alemanha-oferece-intercambio-gratuito-para-brasileiros\/"},"modified":"2023-11-22T06:32:57","modified_gmt":"2023-11-22T09:32:57","slug":"alemanha-oferece-intercambio-gratuito-para-brasileiros","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/22\/alemanha-oferece-intercambio-gratuito-para-brasileiros\/","title":{"rendered":"Alemanha oferece interc\u00e2mbio gratuito para brasileiros"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Est\u00e3o abertas as inscri\u00e7\u00f5es para o Internationale Journalisten-Programme, o programa de interc\u00e2mbio profissional, permite a jornalistas da <a href=\"https:\/\/catracalivre.com.br\/educacao\/holanda-oferece-bolsas-de-graduacao-e-mestrado-a-brasileiros\/\" target=\"_blank\" rel=\"noopener\">Am\u00e9rica Latina<\/a> atuarem em um ve\u00edculo de comunica\u00e7\u00e3o da Alemanha por dois meses com aux\u00edlio financeiro.<\/p>\n<p>A previs\u00e3o \u00e9 de que os profissionais trabalhem na reda\u00e7\u00e3o de um ve\u00edculo alem\u00e3o em Berlim entre maio e junho de 2024.<\/p>\n<div id=\"attachment_2297887\" class=\"wp-caption aligncenter\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2297887\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"franckreporter\/iStock\" decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2297887 size-large\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/09\/bolsas-de-estudo-alemanha-910x607.jpg?resize=910%2C607&#038;ssl=1\" alt=\"Alemanha oferece interc\u00e2mbio gratuito para brasileiros\" width=\"910\" height=\"607\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/09\/bolsas-de-estudo-alemanha-910x607.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/09\/bolsas-de-estudo-alemanha-450x300.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/09\/bolsas-de-estudo-alemanha-768x513.jpg 768w\" sizes=\"(max-width: 910px) 100vw, 910px\"\/><\/p>\n<p>Cr\u00e9ditos: franckreporter\/iStock<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Alemanha oferece interc\u00e2mbio gratuito para brasileiros<\/span><\/p>\n<\/div>\n<p>O o objetivo central \u00e9 que os selecionados trabalhem como correspondentes da reda\u00e7\u00e3o de seu pa\u00eds de origem. Durante a estadia, os estagi\u00e1rios contar\u00e3o com a ajuda de uma m\u00eddia alem\u00e3 em Berlim para desenvolver o seu trabalho.<\/p>\n<p>Desta forma poder\u00e3o conhecer a realidade pol\u00edtica e econ\u00f3mica da Alemanha, al\u00e9m de conhecer a cultura e a mentalidade do seu povo.<\/p>\n<p>Fundado em 1997, o projeto visa estreitar as rela\u00e7\u00f5es entre Alemanha e Am\u00e9rica Latina tamb\u00e9m no campo das comunica\u00e7\u00f5es.<\/p>\n<h2>Quem pode participar do programa na Alemanha?<\/h2>\n<p>Os candidatos devem ter idade entre 25 e 38 anos e bons conhecimentos no idioma alem\u00e3o \u2013somente em casos excepcionais ser\u00e3o aceitos tamb\u00e9m flu\u00eancia em ingl\u00eas ou espanhol\u2013, terem v\u00ednculo empregat\u00edcio com um ve\u00edculo de comunica\u00e7\u00e3o brasileiro ou trabalharem na reda\u00e7\u00e3o de empresas p\u00fablicas de comunica\u00e7\u00e3o.<\/p>\n<p>Profissionais empregados em ag\u00eancias de Rela\u00e7\u00f5es P\u00fablicas ou no servi\u00e7o p\u00fablico n\u00e3o poder\u00e3o participar.<\/p>\n<p>As inscri\u00e7\u00f5es v\u00e3o at\u00e9 17 de dezembro de 2024. Mais informa\u00e7\u00f5es no link: <a href=\"http:\/\/www.ijp.org\/latino\" target=\"_blank\" rel=\"noopener\">www.ijp.org\/latino<\/a>.<\/p>\n<p>Os interessados dever\u00e3o enviar sua candidatura completa em um \u00fanico documento em PDF para o e-mail<a href=\"https:\/\/catracalivre.com.br\/educacao\/alemanha-oferece-intercambio-gratuito-para-brasileiros\/pr-100@saop.diplo.de\" target=\"_blank\" rel=\"noopener\"> pr-100@saop.diplo.de<\/a>. Os arquivos devem ter no m\u00e1ximo 5MB. N\u00e3o ser\u00e3o aceitas candidaturas em papel.<\/p>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/educacao\/alemanha-oferece-intercambio-gratuito-para-brasileiros\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Est\u00e3o abertas as inscri\u00e7\u00f5es para o Internationale Journalisten-Programme, o programa de interc\u00e2mbio profissional, permite a jornalistas da Am\u00e9rica Latina atuarem em um ve\u00edculo de comunica\u00e7\u00e3o da Alemanha por dois meses com aux\u00edlio financeiro. A previs\u00e3o \u00e9 de que os profissionais trabalhem na reda\u00e7\u00e3o de um ve\u00edculo alem\u00e3o em Berlim entre maio e junho de &#8230; <a title=\"Alemanha oferece interc\u00e2mbio gratuito para brasileiros\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/22\/alemanha-oferece-intercambio-gratuito-para-brasileiros\/\" aria-label=\"Leia mais sobre Alemanha oferece interc\u00e2mbio gratuito para brasileiros\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":4720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-4719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bolsas-de-estudo-alemanha.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bolsas-de-estudo-alemanha.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bolsas-de-estudo-alemanha.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bolsas-de-estudo-alemanha.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bolsas-de-estudo-alemanha.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bolsas-de-estudo-alemanha.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bolsas-de-estudo-alemanha.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bolsas-de-estudo-alemanha.jpg?fit=1200%2C638&ssl=1",1200,638,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Est\u00e3o abertas as inscri\u00e7\u00f5es para o Internationale Journalisten-Programme, o programa de interc\u00e2mbio profissional, permite a jornalistas da Am\u00e9rica Latina atuarem em um ve\u00edculo de comunica\u00e7\u00e3o da Alemanha por dois meses com aux\u00edlio financeiro. A previs\u00e3o \u00e9 de que os profissionais trabalhem na reda\u00e7\u00e3o de um ve\u00edculo alem\u00e3o em Berlim entre maio e junho de&hellip;","jetpack-related-posts":[{"id":51408,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/27\/migracao-de-enfermeiros-para-o-exterior-gera-atrito-entre-brasil-e-alemanha-entenda\/","url_meta":{"origin":4719,"position":0},"title":"Migra\u00e7\u00e3o de enfermeiros para o exterior gera atrito entre Brasil e Alemanha; entenda","author":"ismaelcolosi.com.br","date":"27 de Maio de 2024","format":false,"excerpt":"[ad_1] Deutsche Wellei Deutsche Welle 27\/05\/2024 - 13:32 A visita do presidente Luiz In\u00e1cio Lula da Silva e uma comitiva de ministros a Berlim, em dezembro, teve elogios rec\u00edprocos e aprofundamento de parcerias, mas um tema provocou mal-estar entre os dois pa\u00edses: os esfor\u00e7os da Alemanha para atrair enfermeiros brasileiros.O\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/69143267_303.jpg?fit=700%2C394&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/69143267_303.jpg?fit=700%2C394&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/69143267_303.jpg?fit=700%2C394&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/69143267_303.jpg?fit=700%2C394&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":67963,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/estudantes-de-escola-publica-de-ribeirao-participam-de-intercambio-no-exterior\/","url_meta":{"origin":4719,"position":1},"title":"Estudantes de escola p\u00fablica de Ribeir\u00e3o participam de interc\u00e2mbio no exterior","author":"ismaelcolosi.com.br","date":"26 de Setembro de 2024","format":false,"excerpt":"[ad_1] O programa in\u00e9dito de interc\u00e2mbio do Governo do Estado de S\u00e3o Paulo, levar\u00e1 estudantes da rede estadual para Austr\u00e1lia, Canad\u00e1, Nova Zel\u00e2ndia e Reino Unido na primeira turma do Prontos pro Mundo. Na regi\u00e3o de Ribeir\u00e3o Preto, s\u00e3o 16 estudantes selecionados. O interc\u00e2mbio ter\u00e1 dura\u00e7\u00e3o de tr\u00eas meses, ser\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":11134,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/05\/governo-de-sp-lanca-bolsas-para-intercambio-nos-eua\/","url_meta":{"origin":4719,"position":2},"title":"Governo de SP lan\u00e7a bolsas para interc\u00e2mbio nos EUA","author":"ismaelcolosi.com.br","date":"5 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O governo de S\u00e3o Paulo lan\u00e7ou programa para conceder mil bolsas de interc\u00e2mbio gratuitas para estudantes do ensino m\u00e9dio. S\u00e3o bolsas para col\u00e9gios em cinco pa\u00edses: Estados Unidos, Canad\u00e1, Nova Zel\u00e2ndia, Austr\u00e1lia e Inglaterra. A experi\u00eancia ter\u00e1 dura\u00e7\u00e3o de um semestre. Cr\u00e9ditos: Stadtratte\/iStockGoverno de SP lan\u00e7a programa de interc\u00e2mbio\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":83789,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/03\/14\/cresce-a-demanda-por-intercambios-para-executivos-e-empreendedores\/","url_meta":{"origin":4719,"position":3},"title":"Cresce a Demanda por Interc\u00e2mbios para Executivos e Empreendedores","author":"ismaelcolosi.com.br","date":"14 de Mar\u00e7o de 2025","format":false,"excerpt":"[ad_1] \r Getty Images\r Profissionais dos setores de seguros, sa\u00fade, TI, bancos, redes hoteleiras e agroneg\u00f3cio est\u00e3o entre os que mais buscam esses interc\u00e2mbios\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 Interc\u00e2mbio j\u00e1 n\u00e3o \u00e9 exclusividade de jovens em in\u00edcio de carreira. Cada vez mais, executivos e\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-mulher-carreira-intercambio-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-mulher-carreira-intercambio-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-mulher-carreira-intercambio-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-mulher-carreira-intercambio-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-mulher-carreira-intercambio-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":788,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/09\/projeto-leva-alunos-da-rede-publica-de-ribeirao-e-regiao-para-intercambio-em-portugal\/","url_meta":{"origin":4719,"position":4},"title":"Projeto leva alunos da rede p\u00fablica de Ribeir\u00e3o e regi\u00e3o para interc\u00e2mbio em Portugal","author":"ismaelcolosi.com.br","date":"9 de Novembro de 2023","format":false,"excerpt":"[ad_1] Um grupo de alunos do oitavo ano de escolas p\u00fablicas de Ribeir\u00e3o Preto e Serrana ir\u00e3o viajar, neste s\u00e1bado (11), para Lisboa, em Portugal, para visitar pontos hist\u00f3ricos da cidade e participar de discuss\u00f5es sobre coloniza\u00e7\u00e3o com estudantes e professores portugueses. A viagem faz parte da premia\u00e7\u00e3o da s\u00e9tima\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71752,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/17\/ribeirao-preto-recebe-feira-de-intercambio-com-entrada-gratuita\/","url_meta":{"origin":4719,"position":5},"title":"Ribeir\u00e3o Preto recebe feira de interc\u00e2mbio com entrada gratuita","author":"ismaelcolosi.com.br","date":"17 de Outubro de 2024","format":false,"excerpt":"[ad_1] A 1\u00aa Expo Interc\u00e2mbio Ribeir\u00e3o Preto chega a cidade no pr\u00f3ximo s\u00e1bado (19). O evento voltado para a educa\u00e7\u00e3o internacional acontecer\u00e1 no hotel Wyndham Garden, das 14h \u00e0s 18h e ter\u00e1 entrada gratuita. Na programa\u00e7\u00e3o, palestras e rodas de conversa com intercambistas que dividir\u00e3o com o p\u00fablico suas experi\u00eancias,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-1e7","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4719"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/4720"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}