{"id":46884,"date":"2024-04-15T15:55:09","date_gmt":"2024-04-15T18:55:09","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/15\/o-que-se-sabe-sobre-homem-morto-enquanto-conversava-com-a-ex-mulher-em-ribeirao-preto\/"},"modified":"2024-04-15T15:55:09","modified_gmt":"2024-04-15T18:55:09","slug":"o-que-se-sabe-sobre-homem-morto-enquanto-conversava-com-a-ex-mulher-em-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/15\/o-que-se-sabe-sobre-homem-morto-enquanto-conversava-com-a-ex-mulher-em-ribeirao-preto\/","title":{"rendered":"O que se sabe sobre homem morto enquanto conversava com a ex-mulher em Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Um homem, de 43 anos, <strong>foi morto a tiros durante um assalto<\/strong>, na noite da \u00faltima quinta-feira (11), na rua Lu\u00eds Favaro, no Residencial C\u00e2ndido Portinari, zona Leste de Ribeir\u00e3o Preto, local onde teria <strong>marcado um encontro<\/strong> para conversar com a <strong>ex-mulher<\/strong>.<\/p>\n<p>A v\u00edtima, identificada como <strong>Matheus Pereira de Freitas<\/strong>, segundo o <strong>boletim de ocorr\u00eancia (BO)<\/strong>, foi atingida por ao menos quatro disparos, sendo que <strong>dois foram na nuca<\/strong>.<\/p>\n<p>A mulher disse a pol\u00edcia que um <strong>homem armado surgiu de um \u00e1rea com mato<\/strong> e abordou os dois, exigindo os <strong>celulares <\/strong>de ambos. Em seguida, Matheus tentou correr e foi atingido pelos disparos.\u00a0<mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>Ap\u00f3s o ocorrido, o criminoso fugiu do local com o ve\u00edculo da v\u00edtima. <\/strong><\/mark><\/p>\n<h4 class=\"wp-block-heading\"><strong>O que aconteceu?<\/strong><\/h4>\n<p>A ex-mulher de Matheus tamb\u00e9m disse \u00e0 <strong>Pol\u00edcia Militar (PM)<\/strong> que o homem teria <strong>marcado um encontro<\/strong> na esquina de sua resid\u00eancia para que ambos pudessem conversar.<\/p>\n<p>Durante o encontro, por\u00e9m, a mulher afirmou que um <strong>carro <\/strong>n\u00e3o identificado passou em <strong>alta velocidade<\/strong> e que <strong>ambos atravessaram a rua<\/strong> e ficaram perto de um caminh\u00e3o estacionado do lado oposto.<\/p>\n<p>Em seguida, de acordo com a vers\u00e3o da ex, <strong>o criminoso surgiu de um mato e anunciou o assalto<\/strong>. <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">A ex-mulher disse que correu a pedido de Matheus. <strong>Ao tentar correr, por\u00e9m, ele acabou baleado.<\/strong><\/mark><\/p>\n<p>A mulher deixou o local em seu carro e o <strong>criminoso fugiu no autom\u00f3vel da v\u00edtima<\/strong>, um Hyundai HB20 branco, que foi <strong>localizado <\/strong>abandonado no fim da noite de quinta, pr\u00f3ximo \u00e0 Fazenda da Barra, tamb\u00e9m na regi\u00e3o Leste.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Alguma c\u00e2mera de seguran\u00e7a flagrou o ocorrido?<\/strong><\/h4>\n<p>A <strong>Pol\u00edcia Civil<\/strong> constatou que <strong>havia c\u00e2meras de seguran\u00e7a<\/strong> nas proximidades do local onde o crime aconteceu, contudo, os equipamentos <strong>n\u00e3o registraram a grava\u00e7\u00e3o<\/strong>. Os vizinhos disseram \u00e0 pol\u00edcia que somente ouviram os disparos.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Como est\u00e3o as investiga\u00e7\u00f5es?<\/strong><\/h4>\n<p>O caso foi registrado na <strong>Central de Pol\u00edcia Judici\u00e1ria (CPJ) de Ribeir\u00e3o Preto<\/strong> como <strong>latroc\u00ednio<\/strong>, <strong>localiza\u00e7\u00e3o\/apreens\u00e3o de ve\u00edculo<\/strong> e <strong>roubo<\/strong>, j\u00e1 que o carro da v\u00edtima foi levado pelo criminoso na a\u00e7\u00e3o.<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Contudo, a <strong>Secret\u00e1ria de Seguran\u00e7a P\u00fablica (SSP)<\/strong> informou, nesta segunda-feira (15), que o caso segue sob investiga\u00e7\u00e3o do <strong>Departamento Estadual de Investiga\u00e7\u00f5es Criminais (DEIC) de Ribeir\u00e3o<\/strong> e que realiza dilig\u00eancias para <strong>identificar e prender o autor do crime<\/strong>.<\/mark><\/p>\n<h4 class=\"wp-block-heading\"><strong>Preocupa\u00e7\u00e3o<\/strong><\/h4>\n<p>Um irm\u00e3o de Matheus disse \u00e0 pol\u00edcia que a v\u00edtima teria demonstrado <strong>preocupa\u00e7\u00e3o <\/strong>ao marcar o encontro com a ex-mulher e que chegou a enviar sua localiza\u00e7\u00e3o pelo celular.<\/p>\n<p>A ex-mulher entregou o seu aparelho celular para a pol\u00edcia na presen\u00e7a de um advogado. <strong>Ela tamb\u00e9m est\u00e1 qualificada como v\u00edtima no BO.<\/strong><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Caminh\u00e3o desgovernado atropela e mata homem que trabalhava em rodovia na regi\u00e3o de Ribeir\u00e3o<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/GFH9HUMUTHNFJdnyEd0xxq\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Por que as universidades federais entraram em greve?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/o-que-se-sabe-sobre-homem-morto-enquanto-conversava-com-a-ex-mulher-em-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Um homem, de 43 anos, foi morto a tiros durante um assalto, na noite da \u00faltima quinta-feira (11), na rua Lu\u00eds Favaro, no Residencial C\u00e2ndido Portinari, zona Leste de Ribeir\u00e3o Preto, local onde teria marcado um encontro para conversar com a ex-mulher. A v\u00edtima, identificada como Matheus Pereira de Freitas, segundo o boletim de &#8230; <a title=\"O que se sabe sobre homem morto enquanto conversava com a ex-mulher em Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/15\/o-que-se-sabe-sobre-homem-morto-enquanto-conversava-com-a-ex-mulher-em-ribeirao-preto\/\" aria-label=\"Leia mais sobre O que se sabe sobre homem morto enquanto conversava com a ex-mulher em Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":46885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-46884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713207310_cpj_1024x576_04082020121137.jpg?fit=1024%2C575&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713207310_cpj_1024x576_04082020121137.jpg?fit=1024%2C575&ssl=1",1024,575,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713207310_cpj_1024x576_04082020121137.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713207310_cpj_1024x576_04082020121137.jpg?fit=300%2C168&ssl=1",300,168,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713207310_cpj_1024x576_04082020121137.jpg?fit=768%2C431&ssl=1",768,431,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713207310_cpj_1024x576_04082020121137.jpg?fit=1024%2C575&ssl=1",1024,575,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713207310_cpj_1024x576_04082020121137.jpg?fit=1024%2C575&ssl=1",1024,575,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713207310_cpj_1024x576_04082020121137.jpg?fit=1024%2C575&ssl=1",1024,575,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Um homem, de 43 anos, foi morto a tiros durante um assalto, na noite da \u00faltima quinta-feira (11), na rua Lu\u00eds Favaro, no Residencial C\u00e2ndido Portinari, zona Leste de Ribeir\u00e3o Preto, local onde teria marcado um encontro para conversar com a ex-mulher. A v\u00edtima, identificada como Matheus Pereira de Freitas, segundo o boletim de&hellip;","jetpack-related-posts":[{"id":46511,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/12\/homem-e-morto-a-tiros-em-roubo-enquanto-conversava-com-a-ex-mulher-em-ribeirao\/","url_meta":{"origin":46884,"position":0},"title":"Homem \u00e9 morto a tiros em roubo enquanto conversava com a ex-mulher em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"12 de Abril de 2024","format":false,"excerpt":"[ad_1] Um homem de 43 anos foi morto a tiros na noite desta quinta-feira (11), em uma rua no Residencial C\u00e2ndido Portinari, zona Leste de Ribeir\u00e3o Preto, onde conversava com a ex-mulher. O caso foi registrado como latroc\u00ednio, j\u00e1 que o carro da v\u00edtima foi roubado pelo criminoso na a\u00e7\u00e3o.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1712922179_policia_qru_1024x576_25052021184749.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1712922179_policia_qru_1024x576_25052021184749.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1712922179_policia_qru_1024x576_25052021184749.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1712922179_policia_qru_1024x576_25052021184749.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":53690,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/18\/policia-reconstitui-morte-de-jovem-baleada-em-condominio-na-zona-leste-de-ribeirao-preto\/","url_meta":{"origin":46884,"position":1},"title":"Pol\u00edcia reconstitui morte de jovem baleada em condom\u00ednio na zona Leste de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"18 de Junho de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Civil realizou nesta ter\u00e7a-feira (18), a reconstitui\u00e7\u00e3o da morte de Ana J\u00falia dos Santos Borsoi, de 19 anos, em um condom\u00ednio na zona Leste de Ribeir\u00e3o Preto. A jovem morreu ap\u00f3s ser atingida no t\u00f3rax por um disparo de arma de fogo, realizado no dia 27 de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35157,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/05\/o-que-se-sabe-sobre-a-execucao-da-publicitaria-em-ribeirao-preto\/","url_meta":{"origin":46884,"position":2},"title":"O que se sabe sobre a execu\u00e7\u00e3o da publicit\u00e1ria em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"5 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A publicit\u00e1ria Dayane Isabel Roncari, de 33 anos, executada em frente a uma casa no Jardim Maria Goretti, na zona Oeste de Ribeir\u00e3o Preto, na noite do \u00faltimo domingo (3), estaria sendo jurada de morte, de acordo com o B.O. (boletim de ocorr\u00eancia). A v\u00edtima foi morta depois de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/dayane.jpeg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/dayane.jpeg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/dayane.jpeg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/dayane.jpeg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/dayane.jpeg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":46812,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/15\/homem-e-morto-a-tiros-e-mulher-e-baleada-na-zona-norte-de-ribeirao-preto\/","url_meta":{"origin":46884,"position":3},"title":"Homem \u00e9 morto a tiros e mulher \u00e9 baleada na zona Norte de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"15 de Abril de 2024","format":false,"excerpt":"[ad_1] Um homem de 26 anos foi morto a tiros na madrugada deste domingo (14), na rua Hermelindo Del Rosso, no Jardim J\u00f3quei Clube, zona Norte de Ribeir\u00e3o Preto. Uma mulher de 24 anos tamb\u00e9m foi atingida pelos disparos e acabou socorrida. De acordo com o boletim de ocorr\u00eancia (BO),\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2023-12-23-at-12.01.31.jpeg?fit=480%2C245&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":47975,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/29\/o-que-se-sabe-sobre-morte-de-jovem-baleada-por-marido-em-ribeirao-preto\/","url_meta":{"origin":46884,"position":4},"title":"O que se sabe sobre morte de jovem baleada por marido em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"29 de Abril de 2024","format":false,"excerpt":"[ad_1] A jovem Ana J\u00falia dos Santos Borsoi, de 19 anos, que morreu ap\u00f3s ser atingida no t\u00f3rax por um disparo de arma de fogo realizado pelo marido, foi sepultada nesta segunda-feira (29). A vers\u00e3o apresentada por Matheus Augusto Pinto, companheiro de Ana J\u00falia, de que o disparo foi acidental,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48145,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/30\/mp-acompanha-investigacoes-sobre-jovem-morta-baleada-pelo-marido-em-ribeirao-preto\/","url_meta":{"origin":46884,"position":5},"title":"MP acompanha investiga\u00e7\u00f5es sobre jovem morta baleada pelo marido em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"30 de Abril de 2024","format":false,"excerpt":"[ad_1] O MP-SP (Minist\u00e9rio P\u00fablico de S\u00e3o Paulo) est\u00e1 acompanhando o caso da jovem Ana J\u00falia dos Santos Borsoi, de 19 anos, que morreu no domingo (28), ap\u00f3s ser atingida no t\u00f3rax por um disparo de arma de fogo realizado pelo marido. A\u00a0vers\u00e3o apresentada\u00a0por\u00a0Matheus Augusto Pinto, companheiro de Ana J\u00falia,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23-1_2024-04-29_23-57-41_jpg.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-ccc","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=46884"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46884\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/46885"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=46884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=46884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=46884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}