{"id":46882,"date":"2024-04-15T15:41:28","date_gmt":"2024-04-15T18:41:28","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/15\/40-mil-vagas-em-lojas-para-trabalhar-no-comercio\/"},"modified":"2024-04-15T15:41:28","modified_gmt":"2024-04-15T18:41:28","slug":"40-mil-vagas-em-lojas-para-trabalhar-no-comercio","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/15\/40-mil-vagas-em-lojas-para-trabalhar-no-comercio\/","title":{"rendered":"40 mil vagas em lojas para trabalhar no com\u00e9rcio"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Est\u00e1 se aproximando uma das principais datas comemorativas no com\u00e9rcio: o Dia das M\u00e3es, comemorado no segundo s\u00e1bado do m\u00eas de maio, movimentando anualmente milh\u00f5es de reais em vendas. Se voc\u00ea est\u00e1 buscando <strong>vagas em lojas<\/strong> e outros setores do com\u00e9rcio, <strong>este \u00e9 o momento para se candidatar<\/strong> \u00e0s oportunidades de emprego abertas.<\/p>\n<p>Pensando especialmente nesses trabalhadores, realizamos uma <strong>Sele\u00e7\u00e3o Especial de Vagas no Com\u00e9rcio<\/strong>, espalhadas por todo o Brasil, para voc\u00ea enviar o seu CV de forma 100% gratuita pela Catho. Vamos l\u00e1?<\/p>\n<h2 class=\"wp-block-heading\"><strong>Mais de 40 mil vagas em lojas para enviar o curr\u00edculo<\/strong><\/h2>\n<p>Segundo um estudo da Voxus (2023), os setores do com\u00e9rcio com maior proje\u00e7\u00e3o de vendas no ano passado, durante o Dia das M\u00e3es, foram <strong>Vestu\u00e1rio e Sa\u00fade &amp; Beleza<\/strong>. Se o seu desejo \u00e9 <strong>trabalhar com vendas<\/strong> nessas \u00e1reas, confira as oportunidades abertas em grandes marcas:<\/p>\n<p>Vagas na Gregory (vestu\u00e1rio casual)<\/p>\n<p>Vagas na Hering (vestu\u00e1rio)<\/p>\n<p>Vagas na Bayard (vestu\u00e1rio esportivo)<\/p>\n<p>Vagas na Decathlon (vestu\u00e1rio esportivo)<\/p>\n<p>Vagas na Mohagany (produtos de beleza)<\/p>\n<p>Vagas na Morana (acess\u00f3rios e bijouterias)<\/p>\n<p>Vagas na Usaflex (cal\u00e7ados)<\/p>\n<h3 class=\"wp-block-heading\"><strong>OPORTUNIDADES DE EMPREGO NO COM\u00c9RCIO das principais cidades<\/strong><\/h3>\n<p>+12.000 vagas de vendas em S\u00e3o Paulo<\/p>\n<p>+3.000 vagas de vendas em Belo Horizonte<\/p>\n<p>+2.000 vagas de vendas em Curitiba<\/p>\n<p>+1.000 vagas de vendas em Salvador<\/p>\n<p>+2.000 vagas de vendas em Goi\u00e2nia<\/p>\n<p><strong>N\u00e3o encontrou a sua cidade acima? <\/strong>Acesse a busca da Catho e confira as vagas da sua regi\u00e3o: CLIQUE AQUI<\/p>\n<div id=\"banner_bottom\"><img data-recalc-dims=\"1\" decoding=\"async\" style=\"with:100%\" data-gtm-event-category=\"catho:lp-carreira-sucesso\" data-gtm-event-action=\"carreira-sucesso:banner-artigo\" data-gtm-event-label=\"botao:banner\" src=\"https:\/\/i0.wp.com\/s24534.pcdn.co\/carreira-sucesso\/wp-content\/uploads\/sites\/3\/2024\/02\/Banner-Acelera-Catho-970x250-1.jpeg?w=1200&#038;ssl=1\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/s24534.pcdn.co\/carreira-sucesso\/wp-content\/uploads\/sites\/3\/2024\/02\/Banner-Acelera-Catho-970x250-1.jpeg?w=1200&#038;ssl=1\" style=\"with:100%\" data-gtm-event-category=\"catho:lp-carreira-sucesso\" data-gtm-event-action=\"carreira-sucesso:banner-artigo\" data-gtm-event-label=\"botao:banner\"\/><\/noscript><\/div>\n<\/p><\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.catho.com.br\/carreira-sucesso\/vagas-lojas\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Est\u00e1 se aproximando uma das principais datas comemorativas no com\u00e9rcio: o Dia das M\u00e3es, comemorado no segundo s\u00e1bado do m\u00eas de maio, movimentando anualmente milh\u00f5es de reais em vendas. Se voc\u00ea est\u00e1 buscando vagas em lojas e outros setores do com\u00e9rcio, este \u00e9 o momento para se candidatar \u00e0s oportunidades de emprego abertas. Pensando &#8230; <a title=\"40 mil vagas em lojas para trabalhar no com\u00e9rcio\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/15\/40-mil-vagas-em-lojas-para-trabalhar-no-comercio\/\" aria-label=\"Leia mais sobre 40 mil vagas em lojas para trabalhar no com\u00e9rcio\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":46883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-46882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/vagas-maes.jpg?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/vagas-maes.jpg?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/vagas-maes.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/vagas-maes.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/vagas-maes.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/vagas-maes.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/vagas-maes.jpg?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/vagas-maes.jpg?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Est\u00e1 se aproximando uma das principais datas comemorativas no com\u00e9rcio: o Dia das M\u00e3es, comemorado no segundo s\u00e1bado do m\u00eas de maio, movimentando anualmente milh\u00f5es de reais em vendas. Se voc\u00ea est\u00e1 buscando vagas em lojas e outros setores do com\u00e9rcio, este \u00e9 o momento para se candidatar \u00e0s oportunidades de emprego abertas. Pensando&hellip;","jetpack-related-posts":[{"id":49443,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/10\/area-azul-em-ribeirao-preto-sera-gratuita-na-vespera-do-dia-das-maes\/","url_meta":{"origin":46882,"position":0},"title":"\u00c1rea Azul em Ribeir\u00e3o Preto ser\u00e1 gratuita na v\u00e9spera do \u2018Dia das M\u00e3es\u2019","author":"ismaelcolosi.com.br","date":"10 de Maio de 2024","format":false,"excerpt":"[ad_1] A cobran\u00e7a do estacionamento na \u00c1rea Azul da regi\u00e3o Central de Ribeir\u00e3o Preto e imedia\u00e7\u00f5es das avenidas Saudade e Dom Pedro I ser\u00e1 suspensa neste s\u00e1bado (11), v\u00e9spera do \u201cDia das M\u00e3es\u201d. O an\u00fancio foi feito na tarde desta sexta-feira (10) pela Acirp (Associa\u00e7\u00e3o Comercial e Industrial de Ribeir\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/area-azul-saudade-22_2024-05-10_19-01-22_jpg_2024-05-10_19-01-22.webp.webp?fit=960%2C693&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/area-azul-saudade-22_2024-05-10_19-01-22_jpg_2024-05-10_19-01-22.webp.webp?fit=960%2C693&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/area-azul-saudade-22_2024-05-10_19-01-22_jpg_2024-05-10_19-01-22.webp.webp?fit=960%2C693&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/area-azul-saudade-22_2024-05-10_19-01-22_jpg_2024-05-10_19-01-22.webp.webp?fit=960%2C693&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42446,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/14\/rp-comercio-cresce-31-em-fevereiro\/","url_meta":{"origin":46882,"position":1},"title":"RP: Com\u00e9rcio cresce 3,1% em fevereiro\u00a0","author":"ismaelcolosi.com.br","date":"14 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Depois de registrar crescimento m\u00e9dio de 0,72% no acumulado do ano passado, em compara\u00e7\u00e3o com 2022, as vendas nas lojas ribeir\u00e3o-pretanas dispararam 7,3% em janeiro e, em fevereiro, cresceram 3,1% em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2023, aponta levantamento do Centro de Pesquisas do Varejo (CPV), mantido pelo Sindicato\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8fdb1231-4850-46f2-86dd-055bc4f20df7.jpg?fit=620%2C351&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8fdb1231-4850-46f2-86dd-055bc4f20df7.jpg?fit=620%2C351&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8fdb1231-4850-46f2-86dd-055bc4f20df7.jpg?fit=620%2C351&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":51676,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/29\/mais-de-6-mil-vagas-abertas-na-area\/","url_meta":{"origin":46882,"position":2},"title":"mais de 6 mil vagas abertas na \u00e1rea","author":"ismaelcolosi.com.br","date":"29 de Maio de 2024","format":false,"excerpt":"[ad_1] Comemora-se, em 3 de junho, o Dia do Profissional de RH (Recursos Humanos), um perfil de trabalhadoras e trabalhadores que contribuem de forma direta para o bom funcionamento das empresas. A escolha da data se relaciona \u00e0 funda\u00e7\u00e3o da Federa\u00e7\u00e3o Mundial de Associa\u00e7\u00f5es de Gest\u00e3o de Pessoas (na sigla,\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Dia-do-Profissional-de-RH.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Dia-do-Profissional-de-RH.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Dia-do-Profissional-de-RH.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Dia-do-Profissional-de-RH.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Dia-do-Profissional-de-RH.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37478,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/16\/emprego-recua-35-no-comercio-paulista\/","url_meta":{"origin":46882,"position":3},"title":"Emprego recua 35% no com\u00e9rcio paulista \u00a0","author":"ismaelcolosi.com.br","date":"16 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O ritmo de crescimento do mercado de trabalho no com\u00e9rcio paulista desacelerou ao longo de 2023, aponta a Pesquisa do Emprego no Estado de S\u00e3o Paulo (PESP) da Federa\u00e7\u00e3o do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo do Estado de S\u00e3o Paulo (FecomercioSP). O total de empregos gerados sofreu uma\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Fecomercio-Alfredo-Risk-scaled.jpg?fit=1000%2C622&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Fecomercio-Alfredo-Risk-scaled.jpg?fit=1000%2C622&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Fecomercio-Alfredo-Risk-scaled.jpg?fit=1000%2C622&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Fecomercio-Alfredo-Risk-scaled.jpg?fit=1000%2C622&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":74534,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/31\/50-vagas-de-emprego-em-franca-sp-220\/","url_meta":{"origin":46882,"position":4},"title":"50 vagas de emprego em Franca-SP","author":"ismaelcolosi.com.br","date":"31 de Outubro de 2024","format":false,"excerpt":"OPERADOR DE ENVASECom experiencia comprovada. Ambos os sexos. Exig\u00eancias: Agilidade, responsabilidade, boa disposi\u00e7\u00e3o, flex\u00edvel p\/ trabalho em equipe, no\u00e7\u00e3o de mec\u00e2nica ser\u00e1 diferencial. Hor\u00e1rio - seg. a sexta das 7:12 as 17:00 com 1hr de intervalo, Salario R$2.600,00 enviar curr\u00edculo p\/ rh@msacosmeticos.com.br Compartilhe: Dobradeira a m\u00e1quinaContrata-se Dobradeira a m\u00e1quina para\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730422078_cropped-vagas-abertas-azul_widelg.jpg?fit=512%2C512&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":53729,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/19\/aniversario-de-ribeirao-saiba-quais-sao-as-empresas-mais-antigas-da-cidade\/","url_meta":{"origin":46882,"position":5},"title":"Anivers\u00e1rio de Ribeir\u00e3o: Saiba quais s\u00e3o as empresas mais antigas da cidade","author":"ismaelcolosi.com.br","date":"19 de Junho de 2024","format":false,"excerpt":"[ad_1] Ao chegar aos 168 anos, Ribeir\u00e3o Preto tem no com\u00e9rcio um fato para se orgulhar: empresas que atravessam gera\u00e7\u00f5es de fam\u00edlias e mant\u00eam suas atividades h\u00e1 d\u00e9cadas, algumas das quais centen\u00e1rias. O economista Jos\u00e9 Rita Moreira diz que, historicamente, a cidade foi eleita na regi\u00e3o como o centro de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-01.10.11_2024-06-19_04-17-07_jpeg_2024-06-19_04-17-07.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-01.10.11_2024-06-19_04-17-07_jpeg_2024-06-19_04-17-07.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-01.10.11_2024-06-19_04-17-07_jpeg_2024-06-19_04-17-07.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-01.10.11_2024-06-19_04-17-07_jpeg_2024-06-19_04-17-07.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-01.10.11_2024-06-19_04-17-07_jpeg_2024-06-19_04-17-07.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-cca","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=46882"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/46883"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=46882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=46882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=46882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}