{"id":4683,"date":"2023-11-22T03:09:31","date_gmt":"2023-11-22T06:09:31","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/22\/concurso-publico-de-camara-de-carmo-do-paranaiba-oferece-remuneracao-de-ate-5-mil\/"},"modified":"2023-11-22T03:09:31","modified_gmt":"2023-11-22T06:09:31","slug":"concurso-publico-de-camara-de-carmo-do-paranaiba-oferece-remuneracao-de-ate-5-mil","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/22\/concurso-publico-de-camara-de-carmo-do-paranaiba-oferece-remuneracao-de-ate-5-mil\/","title":{"rendered":"Concurso p\u00fablico de C\u00e2mara de Carmo do Parana\u00edba oferece remunera\u00e7\u00e3o de at\u00e9 $ 5 mil"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div id=\"attachment_2311877\" class=\"wp-caption alignnone\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2311877\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"IStock\" decoding=\"async\" fetchpriority=\"high\" class=\"size-medium wp-image-2311877\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956-450x294.jpg?resize=450%2C294&#038;ssl=1\" alt=\"Concurso P\u00fablico de C\u00e2mara de Carmo do Parana\u00edba\" width=\"450\" height=\"294\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956-450x294.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956-910x594.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956-768x501.jpg 768w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg 1267w\" sizes=\"(max-width: 450px) 100vw, 450px\"\/><\/p>\n<p>Cr\u00e9ditos: IStock<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Concurso P\u00fablico de C\u00e2mara de Carmo do Parana\u00edba<\/span><\/p>\n<\/div>\n<p>A C\u00e2mara de Carmo do Parana\u00edba, no estado de\u00a0Minas Gerais anuncia o edital de n\u00ba 01\/2023 para <a href=\"https:\/\/catracalivre.com.br\/educacao\/concurso-publico-9-habitos-para-quem-esta-se-preparando\/\" target=\"_blank\" rel=\"noopener\">concurso<\/a> p\u00fablico, que visa o preenchimento de quatro vagas imediatas, al\u00e9m de formar cadastro reserva. As oportunidades s\u00e3o destinadas a profissionais alfabetizados e de n\u00edveis fundamental, m\u00e9dio e superior. Os contratados estar\u00e3o subordinados ao regime estatut\u00e1rio.<\/p>\n<p>A remunera\u00e7\u00e3o bruta inicial oferecida em c<a href=\"https:\/\/catracalivre.com.br\/carreira\/12-concursos-publicos-abrem-inscricoes-mais-de-400-vagas\/\" target=\"_blank\" rel=\"noopener\">oncurso<\/a> p\u00fablico varia de\u00a0R$ 1.564,67 a R$ 5.035,38, por regime de trabalho de 20 ou 30 horas por semana.<\/p>\n<h2>As vagas disponibilizadas est\u00e3o distribu\u00eddas entre os seguintes cargos:<\/h2>\n<p>Consultor Legislativo \u2013 Advogado:\u00a0oportunidade de n\u00edvel superior;<\/p>\n<p>Consultor Cont\u00e1bil \u2013\u00a0Contador:\u00a0oportunidade de n\u00edvel superior;<\/p>\n<p>Oficial Legislativo:\u00a0oportunidade de n\u00edvel m\u00e9dio;<\/p>\n<p>Recepcionista:\u00a0oportunidade de n\u00edvel m\u00e9dio;<\/p>\n<p>Auxiliar Legislativo:\u00a0oportunidade de n\u00edvel fundamental;<\/p>\n<p>Motorista:\u00a0oportunidade de n\u00edvel fundamental;<\/p>\n<p>Auxiliar de Servi\u00e7os Gerais:\u00a0oportunidade para profissional alfabetizado.<\/p>\n<p>As inscri\u00e7\u00f5es devem ser realizadas atrav\u00e9s do <a href=\"https:\/\/portal.unique.selecao.site\/edital\/ver\/44\" target=\"_blank\" rel=\"noopener\">site<\/a> oficial at\u00e9 o dia 22 de novembro de 2023. A taxa tem valor de que varia entre\u00a0R$ 35,00 a R$ 75,00.<\/p>\n<div class=\"partner d-flex rounded shadow-sm p-2 mb-3 align-items-center\" id=\"partner\" data-print=\"ignore\">\n<div class=\"image mr-2\">\n<img data-recalc-dims=\"1\" src=\"https:\/\/i0.wp.com\/robohash.org\/b730afd4cf5c5d237c7f93163ed023b6.png?resize=110%2C110&#038;ssl=1\" width=\"110\" height=\"110\" title=\"Thatyana Costa\" loading=\"lazy\" decoding=\"async\" class=\"rounded-circle\"\/>\n<\/div>\n<\/div>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/educacao\/concurso-publico-de-camara-de-carmo-do-paranaiba-oferece-remuneracao-de-ate-5-mil\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Cr\u00e9ditos: IStock Concurso P\u00fablico de C\u00e2mara de Carmo do Parana\u00edba A C\u00e2mara de Carmo do Parana\u00edba, no estado de\u00a0Minas Gerais anuncia o edital de n\u00ba 01\/2023 para concurso p\u00fablico, que visa o preenchimento de quatro vagas imediatas, al\u00e9m de formar cadastro reserva. As oportunidades s\u00e3o destinadas a profissionais alfabetizados e de n\u00edveis fundamental, m\u00e9dio&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":4684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-4683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg?fit=1200%2C638&ssl=1",1200,638,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-182059956.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Cr\u00e9ditos: IStock Concurso P\u00fablico de C\u00e2mara de Carmo do Parana\u00edba A C\u00e2mara de Carmo do Parana\u00edba, no estado de\u00a0Minas Gerais anuncia o edital de n\u00ba 01\/2023 para concurso p\u00fablico, que visa o preenchimento de quatro vagas imediatas, al\u00e9m de formar cadastro reserva. As oportunidades s\u00e3o destinadas a profissionais alfabetizados e de n\u00edveis fundamental, m\u00e9dio&hellip;&nbsp;","jetpack-related-posts":[{"id":69299,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/04\/morre-em-ribeirao-preto-o-pecuarista-adir-do-carmo-leonel\/","url_meta":{"origin":4683,"position":0},"title":"Morre em Ribeir\u00e3o Preto o pecuarista Adir do Carmo Leonel","author":"ismaelcolosi.com.br","date":"4 de Outubro de 2024","format":false,"excerpt":"[ad_1] Morreu em Ribeir\u00e3o Preto, nesta sexta-feira (4), o pecuarista Adir do Carmo Leonel, aos 85 anos. Adir ficou conhecido por ser uma das maiores refer\u00eancias da pecu\u00e1ria nacional. Em nota, ABCZ (Associa\u00e7\u00e3o Brasileira dos Criadores de Zebu) lamentou a morte do pecuarista. Segundo a entidade, Adir do Carmo Leonel\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/adir-do-carmo-leonel_2024-10-04_17-35-12_jpg_2024-10-04_17-35-12.webp.webp?fit=1200%2C785&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/adir-do-carmo-leonel_2024-10-04_17-35-12_jpg_2024-10-04_17-35-12.webp.webp?fit=1200%2C785&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/adir-do-carmo-leonel_2024-10-04_17-35-12_jpg_2024-10-04_17-35-12.webp.webp?fit=1200%2C785&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/adir-do-carmo-leonel_2024-10-04_17-35-12_jpg_2024-10-04_17-35-12.webp.webp?fit=1200%2C785&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/adir-do-carmo-leonel_2024-10-04_17-35-12_jpg_2024-10-04_17-35-12.webp.webp?fit=1200%2C785&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":77658,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/27\/ribeirao-preto-e-alvo-de-operacao-nacional\/","url_meta":{"origin":4683,"position":1},"title":"Ribeir\u00e3o Preto \u00e9 alvo de opera\u00e7\u00e3o nacional","author":"ismaelcolosi.com.br","date":"27 de Novembro de 2024","format":false,"excerpt":"[ad_1] Por: Adalberto Luque Ribeir\u00e3o Preto \u00e9 um dos alvos de uma opera\u00e7\u00e3o nacional que est\u00e1 sendo realizada na manh\u00e3 desta quarta-feira (27), para cumprir 106 mandados de pris\u00e3o nos estados de Minas Gerais, S\u00e3o Paulo, Rio de Janeiro, Paran\u00e1, Mato Grosso do Sul, Mato Grosso e Goi\u00e1s. O objetivo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/27nov2024-operacaoexodo-foto-mpmg.jpg?fit=650%2C430&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/27nov2024-operacaoexodo-foto-mpmg.jpg?fit=650%2C430&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/27nov2024-operacaoexodo-foto-mpmg.jpg?fit=650%2C430&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":39286,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/24\/camera-flagra-abandono-de-filhotes-em-ribeirao-preto-video\/","url_meta":{"origin":4683,"position":2},"title":"C\u00e2mera flagra abandono de filhotes em Ribeir\u00e3o Preto; V\u00eddeo","author":"ismaelcolosi.com.br","date":"24 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Uma c\u00e2mera de seguran\u00e7a flagrou o abandono de sete filhotes de cachorro na tarde da \u00faltima sexta-feira (23) em Ribeir\u00e3o Preto, no bairro Ad\u00e3o do Carmo, zona Oeste da cidade. De acordo com as filmagens, um homem chega em um carro, abre o porta-malas do ve\u00edculo e deixa um\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Design-sem-nome-5.jpg?fit=960%2C693&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Design-sem-nome-5.jpg?fit=960%2C693&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Design-sem-nome-5.jpg?fit=960%2C693&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Design-sem-nome-5.jpg?fit=960%2C693&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5624,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/24\/zeze-di-camargo-se-envolve-em-polemica-por-fala-sobre-gays-encara-tetra-com-ator-carmo-dalla-vecchia-e-duras-criticas-nas-web\/","url_meta":{"origin":4683,"position":3},"title":"Zez\u00e9 Di Camargo se envolve em pol\u00eamica por fala sobre gays encara tetra com ator Carmo Dalla Vecchia e duras cr\u00edticas nas web","author":"ismaelcolosi.com.br","date":"24 de Novembro de 2023","format":false,"excerpt":"[ad_1] O cantor sertanejo Zez\u00e9 Di Camargo acabou se envolvendo em um pol\u00eamica ap\u00f3s fazer um coment\u00e1rio considerado preconceituoso a respeito dos homossexuais.A fala de Zez\u00e9 Di Camargo atingiu em cheio o ator Carmo Dalla Vecchia, de 52 anos, que resolveu se pronunciar a respeito o que acabou chamando a\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6560257e476477136.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6560257e476477136.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6560257e476477136.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6560257e476477136.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6560257e476477136.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":18558,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/20\/ganhadora-de-r-2-milhoes-na-nota-fiscal-paulista-e-professora-em-ribeirao-preto\/","url_meta":{"origin":4683,"position":4},"title":"Ganhadora de R$ 2 milh\u00f5es na Nota Fiscal Paulista \u00e9 professora em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"20 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A\u00a0Nota Fiscal Paulista premiou uma professora aposentada de Ribeir\u00e3o Preto. Ela recebeu, nesta ter\u00e7a-feira (19), R$ 2 milh\u00f5es, o maior pr\u00eamio do ano, em cerim\u00f4nia na Secretaria da Fazenda e Planejamento de S\u00e3o Paulo (Sefaz-SP). \u201cEsse dinheiro veio em boa hora, estou me sentindo feliz e aben\u00e7oada\u201d, comemora a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-16.26.15.jpeg?fit=1200%2C707&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-16.26.15.jpeg?fit=1200%2C707&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-16.26.15.jpeg?fit=1200%2C707&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-16.26.15.jpeg?fit=1200%2C707&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-16.26.15.jpeg?fit=1200%2C707&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":25407,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/07\/vereadores-receberam-em-media-31-pedidos-por-dia-de-tapa-buracos-em-2023\/","url_meta":{"origin":4683,"position":5},"title":"Tapa buracos: vereadores receberam em m\u00e9dia 31 pedidos por dia em 2023","author":"ismaelcolosi.com.br","date":"7 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Levantamento feito pelo Tribuna Ribeir\u00e3o junto ao Portal da C\u00e2mara Municipal revela que no ano passado foram protocolados pelos vereadores na Prefeitura de Ribeir\u00e3o Preto, 11.248 requerimentos e indica\u00e7\u00f5es solicitando algum tipo de servi\u00e7o de infraestrutura da cidade. Isso corresponde a uma m\u00e9dia di\u00e1ria de 31 pedidos.\u00a0Deste total, 7.952\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1-fotoburacos-creditoalfredorisk.jpg?fit=960%2C535&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1-fotoburacos-creditoalfredorisk.jpg?fit=960%2C535&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1-fotoburacos-creditoalfredorisk.jpg?fit=960%2C535&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1-fotoburacos-creditoalfredorisk.jpg?fit=960%2C535&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-1dx","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4683"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/4684"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}