{"id":46721,"date":"2024-04-13T15:48:58","date_gmt":"2024-04-13T18:48:58","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/13\/feira-com-musica-ao-vivo-cerveja-e-food-trucks-acontece-neste-domingo-em-ribeirao-preto\/"},"modified":"2024-04-13T15:48:58","modified_gmt":"2024-04-13T18:48:58","slug":"feira-com-musica-ao-vivo-cerveja-e-food-trucks-acontece-neste-domingo-em-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/13\/feira-com-musica-ao-vivo-cerveja-e-food-trucks-acontece-neste-domingo-em-ribeirao-preto\/","title":{"rendered":"Feira com m\u00fasica ao vivo, cerveja e food trucks acontece neste domingo em Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Neste <strong>domingo (14)<\/strong> acontece mais uma edi\u00e7\u00e3o da <strong>Feira do Coletivo<\/strong> na <strong>pra\u00e7a 7 de Setembro<\/strong>, no\u00a0<strong>Centro\u00a0<\/strong>de <strong>Ribeir\u00e3o Preto<\/strong>. O evento \u00e9 <strong>gratuito<\/strong> e <strong>aberto ao p\u00fablico<\/strong>.<\/p>\n<p>O evento acontece das <strong>15h \u00e0s 21h<\/strong> e conta com cervejas e chopes artesanais,<em> <\/em>food trucks, expositores, oficinas, feira de ado\u00e7\u00e3o de animais e m\u00fasica ao vivo.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Programa\u00e7\u00e3o<\/strong><\/h4>\n<p>Est\u00e3o na programa\u00e7\u00e3o da feira <strong>40 marcas autorais<\/strong>\u00a0de\u00a0<strong>moda<\/strong>,\u00a0<strong>arte<\/strong>,\u00a0<strong>bem-estar<\/strong>,\u00a0<strong>infantil<\/strong>\u00a0e\u00a0<strong>gastronomia<\/strong>.<\/p>\n<p>Os interessados poder\u00e3o participar de uma\u00a0<strong>aula de yoga<\/strong>\u00a0ou realizar leituras terap\u00eauticas com um tar\u00f3logo por\u00a0<strong>valores acess\u00edveis<\/strong>.\u00a0<mark style=\"background-color:#fcb900\" class=\"has-inline-color\">A feira tamb\u00e9m conta com\u00a0<strong>recrea\u00e7\u00e3o infantil e pintura facial<\/strong>.<\/mark><\/p>\n<p>A <strong>Feira do Coletivo<\/strong> tamb\u00e9m recebe o cantor <strong>Danilo Teoro<\/strong> e a banda <strong>Train Folk<\/strong> para um show ao vivo com releituras de m\u00fasicas dos g\u00eaneros Folk, Blues, Rock, Country e Rockabilly.<\/p>\n<h4 class=\"wp-block-heading\"><strong>SERVI\u00c7O<\/strong><\/h4>\n<p><em>Feira do Coletivo em Ribeir\u00e3o Preto<\/em><\/p>\n<p>Data: 14 de abril \u2013 domingo<br \/>Hor\u00e1rio: das 15h \u00e0s 21h<br \/>Entrada: gratuita<br \/>Local: Pra\u00e7a 7 de Setembro \u2013 Rua Sete de Setembro, 579, Centro <\/p>\n<p>SAIBA MAIS<br \/>Ribeir\u00e3o Preto recebe um dos maiores eventos sobre autismo neste m\u00eas; Veja como participar<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta <a href=\"https:\/\/chat.whatsapp.com\/GFH9HUMUTHNFJdnyEd0xxq\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>BBB 24: Matteus puxa torcida contra Isabelle<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/feira-com-musica-ao-vivo-cerveja-e-food-trucks-acontece-neste-domingo-em-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Neste domingo (14) acontece mais uma edi\u00e7\u00e3o da Feira do Coletivo na pra\u00e7a 7 de Setembro, no\u00a0Centro\u00a0de Ribeir\u00e3o Preto. O evento \u00e9 gratuito e aberto ao p\u00fablico. O evento acontece das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, food trucks, expositores, oficinas, feira de ado\u00e7\u00e3o de animais e m\u00fasica ao vivo. &#8230; <a title=\"Feira com m\u00fasica ao vivo, cerveja e food trucks acontece neste domingo em Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/13\/feira-com-musica-ao-vivo-cerveja-e-food-trucks-acontece-neste-domingo-em-ribeirao-preto\/\" aria-label=\"Leia mais sobre Feira com m\u00fasica ao vivo, cerveja e food trucks acontece neste domingo em Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":46722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-46721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1280%2C920&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1280%2C920&ssl=1",1280,920,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=300%2C216&ssl=1",300,216,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=768%2C552&ssl=1",768,552,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1024%2C736&ssl=1",1024,736,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1280%2C920&ssl=1",1280,920,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1280%2C920&ssl=1",1280,920,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Neste domingo (14) acontece mais uma edi\u00e7\u00e3o da Feira do Coletivo na pra\u00e7a 7 de Setembro, no\u00a0Centro\u00a0de Ribeir\u00e3o Preto. O evento \u00e9 gratuito e aberto ao p\u00fablico. O evento acontece das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, food trucks, expositores, oficinas, feira de ado\u00e7\u00e3o de animais e m\u00fasica ao vivo.&hellip;","jetpack-related-posts":[{"id":46408,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/11\/ribeirao-preto-tem-feira-com-cerveja-artesanal-food-trucks-e-musica-ao-vivo-no-final-de-semana\/","url_meta":{"origin":46721,"position":0},"title":"Ribeir\u00e3o Preto tem feira com cerveja artesanal, food trucks e m\u00fasica ao vivo no final de semana","author":"ismaelcolosi.com.br","date":"11 de Abril de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe mais uma edi\u00e7\u00e3o da Feira do Coletivo, neste domingo (14), na pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 gratuito e aberto ao p\u00fablico. A feira vai acontecer das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, food trucks, expositores, oficinas,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52894,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/11\/ribeirao-preto-tem-edicao-especial-de-feira-com-cerveja-artesanal-food-trucks-e-musica\/","url_meta":{"origin":46721,"position":1},"title":"Ribeir\u00e3o Preto tem edi\u00e7\u00e3o especial de feira com cerveja artesanal, food trucks e m\u00fasica","author":"ismaelcolosi.com.br","date":"11 de Junho de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe, neste domingo (16), a Feira do Coletivo em edi\u00e7\u00e3o especial de Festa Junina, na pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 gratuito e aberto ao p\u00fablico. A feira acontece das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, comidas t\u00edpicas,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14376,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/ribeirao-preto-tem-feira-com-cerveja-artesanal-food-trucks-e-musica\/","url_meta":{"origin":46721,"position":2},"title":"Ribeir\u00e3o Preto tem feira com cerveja artesanal, food trucks e m\u00fasica","author":"ismaelcolosi.com.br","date":"12 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe, no dia 17 de dezembro, a Feira do Coletivo em edi\u00e7\u00e3o especial de Natal, na Pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 gratuito e aberto ao p\u00fablico. \u00a0 A feira acontece das 14h \u00e0s 21h e conta com cerveja artesanal, foodtrucks, expositores,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33721,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/30\/ribeirao-tem-feira-pre-carnaval-com-cerveja-artesanal-food-trucks-e-musica-veja-quando\/","url_meta":{"origin":46721,"position":3},"title":"Ribeir\u00e3o tem feira pr\u00e9-Carnaval com cerveja artesanal, food trucks e m\u00fasica; Veja quando","author":"ismaelcolosi.com.br","date":"30 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe, neste domingo (4), a Feira do Coletivo em edi\u00e7\u00e3o especial de Carnaval, na pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 gratuito e aberto ao p\u00fablico. A feira acontece das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, foodtrucks, expositores, oficinas,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1143%2C761&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1143%2C761&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1143%2C761&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1143%2C761&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1143%2C761&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51680,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/29\/ribeirao-preto-tem-festival-de-cerveja-artesanal-com-food-trucks-e-musica-veja-quando\/","url_meta":{"origin":46721,"position":4},"title":"Ribeir\u00e3o Preto tem festival de cerveja artesanal com food trucks e m\u00fasica; Veja quando","author":"ismaelcolosi.com.br","date":"29 de Maio de 2024","format":false,"excerpt":"[ad_1] A 3\u00aa edi\u00e7\u00e3o do Craft Beer, festival de cervejas artesanais em Ribeir\u00e3o Preto, acontece neste s\u00e1bado (1\u00ba) e domingo (2), no Teatro de Arena do mun\u00edcipio. Ser\u00e3o mais de 80 r\u00f3tulos de cerveja artesanal, food trucks e diversas atra\u00e7\u00f5es que somam 16 horas de m\u00fasica. O line-up de shows\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/chopp_cerveja_1024x576_15102020113247.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/chopp_cerveja_1024x576_15102020113247.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/chopp_cerveja_1024x576_15102020113247.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/chopp_cerveja_1024x576_15102020113247.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":55313,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/02\/ribeirao-preto-tem-feira-de-vinil-com-musica-ao-vivo-chope-artesanal-e-food-trucks\/","url_meta":{"origin":46721,"position":5},"title":"Ribeir\u00e3o Preto tem feira de vinil com m\u00fasica ao vivo, chope artesanal e food trucks","author":"ismaelcolosi.com.br","date":"2 de Julho de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto\u00a0recebe no s\u00e1bado (6), a\u00a0Feira de Vinil Ribeir\u00e3o, das 10h \u00e0s 19h, na Cer\u00e2mica S\u00e3o Luiz, na zona Norte da cidade. O evento \u00e9\u00a0gratuito\u00a0e\u00a0aberto ao p\u00fablico. A feira conta com cervejas e chopes artesanais, food trucks, expositores, parque infantil, bate-papo cultural, tatuagem e piercing. A programa\u00e7\u00e3o musical fica\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/container-1867697_1280_2024-07-02_12-45-08_jpg_2024-07-02_12-45-08.webp.webp?fit=1200%2C740&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/container-1867697_1280_2024-07-02_12-45-08_jpg_2024-07-02_12-45-08.webp.webp?fit=1200%2C740&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/container-1867697_1280_2024-07-02_12-45-08_jpg_2024-07-02_12-45-08.webp.webp?fit=1200%2C740&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/container-1867697_1280_2024-07-02_12-45-08_jpg_2024-07-02_12-45-08.webp.webp?fit=1200%2C740&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/container-1867697_1280_2024-07-02_12-45-08_jpg_2024-07-02_12-45-08.webp.webp?fit=1200%2C740&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-c9z","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=46721"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/46722"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=46721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=46721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=46721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}