{"id":45349,"date":"2024-04-03T18:51:10","date_gmt":"2024-04-03T21:51:10","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/gaby-amarantos-e-xenia-franca-participam-de-concerto-junto-a-brasil-jazz-sinfonica\/"},"modified":"2024-04-03T18:51:10","modified_gmt":"2024-04-03T21:51:10","slug":"gaby-amarantos-e-xenia-franca-participam-de-concerto-junto-a-brasil-jazz-sinfonica","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/gaby-amarantos-e-xenia-franca-participam-de-concerto-junto-a-brasil-jazz-sinfonica\/","title":{"rendered":"Gaby Amarantos e X\u00eania Fran\u00e7a participam de concerto junto \u00e0 Brasil Jazz Sinf\u00f4nica"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<h3 class=\"fn__maintitle\"><span>Gaby Amarantos e X\u00eania Fran\u00e7a participam de concerto junto \u00e0 Brasil Jazz Sinf\u00f4nica<\/span><\/h3>\n<\/div>\n<div>\n<p>Neste\u00a0<strong>domingo (7\/4)<\/strong>, a apresentadora\u00a0<strong>Chris Maksud<\/strong>\u00a0e o maestro\u00a0<strong>Guga Petri<\/strong>\u00a0recebem, junto \u00e0\u00a0<strong>Brasil Jazz Sinf\u00f4nica<\/strong>,\u00a0<strong>Gaby Amarantos<\/strong>\u00a0e\u00a0<strong>X\u00eania Fran\u00e7a<\/strong>\u00a0em um concerto in\u00e9dito. A apresenta\u00e7\u00e3o, que aconteceu na Sala S\u00e3o Paulo, vai ao ar a partir das\u00a0<strong>20h<\/strong>, na tela da\u00a0<strong>TV Cultura<\/strong>.<\/p>\n<p>As convidadas cantam m\u00fasicas autorais, como\u00a0<i>Renascer<\/i>,\u00a0<i>Miragem<\/i>\u00a0e\u00a0<i>Pra que me Chamas<\/i>, de X\u00eania Fran\u00e7a, e interpretam\u00a0<i>O Vento<\/i>\u00a0e\u00a0<i>A Lenda do Abaet\u00e9<\/i>, de Dorival Caymmi;\u00a0<i>For\u00e7as da Natureza<\/i>, de Jo\u00e3o Batista Nogueira Jr. e Paulo Cesar Pinheiro;\u00a0<i>Chuva<\/i>, de Lara Renno e Thalma de Freitas; assim como\u00a0<i>N\u00e3o Vou Te Deixar<\/i>, de Per Hakan Gessle;\u00a0<i>Ex Mai Love<\/i>, de Veloso Dias;\u00a0<i>Evid\u00eancias<\/i>, de Paulo Valle e Jos\u00e9 Augusto;\u00a0<i>Esot\u00e9rico<\/i>, de Gilberto Gil; e\u00a0<i>Sinh\u00e1 Pureza<\/i>, de Aurino Pinduca.<\/p>\n<div class=\"popito_fn_votewrap\">\n<h3 class=\"vote_title\">Como voc\u00ea vota? <\/h3>\n<div class=\"popito_fn_votes \" data-id=\"1881\">\n<p>0 People voted this article. 0 Upvotes &#8211; 0 Downvotes.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/popito.com.br\/gaby-amarantos-e-xenia-franca-participam-de-concerto-junto-a-brasil-jazz-sinfonica\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Gaby Amarantos e X\u00eania Fran\u00e7a participam de concerto junto \u00e0 Brasil Jazz Sinf\u00f4nica Neste\u00a0domingo (7\/4), a apresentadora\u00a0Chris Maksud\u00a0e o maestro\u00a0Guga Petri\u00a0recebem, junto \u00e0\u00a0Brasil Jazz Sinf\u00f4nica,\u00a0Gaby Amarantos\u00a0e\u00a0X\u00eania Fran\u00e7a\u00a0em um concerto in\u00e9dito. A apresenta\u00e7\u00e3o, que aconteceu na Sala S\u00e3o Paulo, vai ao ar a partir das\u00a020h, na tela da\u00a0TV Cultura. As convidadas cantam m\u00fasicas autorais, como\u00a0Renascer,\u00a0Miragem\u00a0e\u00a0Pra &#8230; <a title=\"Gaby Amarantos e X\u00eania Fran\u00e7a participam de concerto junto \u00e0 Brasil Jazz Sinf\u00f4nica\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/gaby-amarantos-e-xenia-franca-participam-de-concerto-junto-a-brasil-jazz-sinfonica\/\" aria-label=\"Leia mais sobre Gaby Amarantos e X\u00eania Fran\u00e7a participam de concerto junto \u00e0 Brasil Jazz Sinf\u00f4nica\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":45350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[5445,137,287,957,5444,5417,5447,5110,114,5446],"class_list":["post-45349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-amarantos","tag-brasil","tag-concerto","tag-franca","tag-gaby","tag-jazz","tag-junto","tag-participam","tag-sinfonica","tag-xenia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ebce680071b38396441bfd85f2b2b54d.jpeg?fit=1200%2C800&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ebce680071b38396441bfd85f2b2b54d.jpeg?fit=1200%2C800&ssl=1",1200,800,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ebce680071b38396441bfd85f2b2b54d.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ebce680071b38396441bfd85f2b2b54d.jpeg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ebce680071b38396441bfd85f2b2b54d.jpeg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ebce680071b38396441bfd85f2b2b54d.jpeg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ebce680071b38396441bfd85f2b2b54d.jpeg?fit=1200%2C800&ssl=1",1200,800,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ebce680071b38396441bfd85f2b2b54d.jpeg?fit=1200%2C800&ssl=1",1200,800,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Gaby Amarantos e X\u00eania Fran\u00e7a participam de concerto junto \u00e0 Brasil Jazz Sinf\u00f4nica Neste\u00a0domingo (7\/4), a apresentadora\u00a0Chris Maksud\u00a0e o maestro\u00a0Guga Petri\u00a0recebem, junto \u00e0\u00a0Brasil Jazz Sinf\u00f4nica,\u00a0Gaby Amarantos\u00a0e\u00a0X\u00eania Fran\u00e7a\u00a0em um concerto in\u00e9dito. A apresenta\u00e7\u00e3o, que aconteceu na Sala S\u00e3o Paulo, vai ao ar a partir das\u00a020h, na tela da\u00a0TV Cultura. As convidadas cantam m\u00fasicas autorais, como\u00a0Renascer,\u00a0Miragem\u00a0e\u00a0Pra&hellip;","jetpack-related-posts":[{"id":18465,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/20\/famoso-cantor-de-ex-mai-love-que-fez-parcerias-com-gaby-amarantos-e-fafa-de-belem-tem-falecimento-confirmado\/","url_meta":{"origin":45349,"position":0},"title":"Famoso cantor de &#8216;Ex Mai Love&#8217;, que fez parcerias com Gaby Amarantos e Faf\u00e1 de Bel\u00e9m, tem falecimento confirmado","author":"ismaelcolosi.com.br","date":"20 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Nesta ter\u00e7a-feira, dia 19 de dezembro, na regi\u00e3o de Bel\u00e9m, no Par\u00e1, foi confirmada a not\u00edcia do falecimento do cantor, compositor e poeta paraense Veloso Dias. Muitos se encontram entristecidos com a sua morte.O cantor e compositor ficou conhecido n\u00e3o apenas por sua contribui\u00e7\u00e3o para \u00e0 m\u00fasica, mas tamb\u00e9m\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65830ae42e8709588.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65830ae42e8709588.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65830ae42e8709588.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65830ae42e8709588.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65830ae42e8709588.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45216,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/brasil-jazz-sinfonica-toca-de-pink-floyd-a-guns-n-roses-no-tributo-ao-rock-internacional-no-teatro-b32\/","url_meta":{"origin":45349,"position":1},"title":"Brasil Jazz Sinf\u00f4nica toca de Pink Floyd a Guns N\u2019 Roses no &#8220;Tributo ao Rock internacional&#8221;","author":"ismaelcolosi.com.br","date":"3 de Abril de 2024","format":false,"excerpt":"[ad_1] Brasil Jazz Sinf\u00f4nica toca de Pink Floyd a Guns N\u2019 Roses no \u201cTributo ao Rock internacional\u201dA\u00a0Brasil Jazz Sinf\u00f4nica\u00a0se prepara para uma experi\u00eancia musical \u00fanica e emocionante com seu pr\u00f3ximo concerto, nesta\u00a0sexta-feira (5\/4), no\u00a0Teatro B32, que promete celebrar os\u00a0grandes \u00edcones do rock internacional\u00a0de uma maneira totalmente nova. Sob a reg\u00eancia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/orquestra-sao-joao-da-boa-vista.png?fit=1200%2C722&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/orquestra-sao-joao-da-boa-vista.png?fit=1200%2C722&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/orquestra-sao-joao-da-boa-vista.png?fit=1200%2C722&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/orquestra-sao-joao-da-boa-vista.png?fit=1200%2C722&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/orquestra-sao-joao-da-boa-vista.png?fit=1200%2C722&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":18503,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/20\/morre-cantor-amado-apos-problema-renal-e-famosos-lamentam-a-perda-sentiremos-falta-de-voce\/","url_meta":{"origin":45349,"position":2},"title":"Morre cantor amado ap\u00f3s problema renal e famosos lamentam a perda: &#8216;Sentiremos falta de voc\u00ea&#8217;","author":"ismaelcolosi.com.br","date":"20 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Nesta semana, o Brasil perdeu mais um de seus grandes nomes da m\u00fasica. Faleceu o cantor Veloso Dias, que se tornou bastante conhecido em todo o pa\u00eds por compor m\u00fasicas de grande sucesso.Entre as composi\u00e7\u00f5es famosas de Veloso Dias est\u00e1 Ex Mais Love, que fez sucesso na voz da\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6583294574f078691.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6583294574f078691.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6583294574f078691.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6583294574f078691.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6583294574f078691.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45962,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/08\/lancamento-pabllo-vittar-09-04-e-o-fim-da-pirataria-no-tecnobrega\/","url_meta":{"origin":45349,"position":3},"title":"Lan\u00e7amento Pabllo Vittar (09\/04) e o fim da pirataria no tecnobrega","author":"ismaelcolosi.com.br","date":"8 de Abril de 2024","format":false,"excerpt":"[ad_1] Lan\u00e7amento Pabllo Vittar (09\/04) e o fim da pirataria no tecnobregaO tecnobrega no\u00a0mainstream: o fim da \u201cpirataria do bem\u201d na m\u00fasica popular? Uma das maiores representantes do tecnobrega \u2013 g\u00eanero paraense que mistura refer\u00eancias internacionais como m\u00fasica eletr\u00f4nica e pop \u2013, Gaby Amarantos come\u00e7ou a carreira dando voz a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/pabllo-vittar-coletiva-foto.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/pabllo-vittar-coletiva-foto.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/pabllo-vittar-coletiva-foto.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/pabllo-vittar-coletiva-foto.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/pabllo-vittar-coletiva-foto.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71429,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/16\/concertos-eptv-obras-de-haydn-mozart-e-brahms-chegam-a-franca\/","url_meta":{"origin":45349,"position":4},"title":"Concertos EPTV: Obras de Haydn, Mozart e Brahms chegam a Franca","author":"ismaelcolosi.com.br","date":"16 de Outubro de 2024","format":false,"excerpt":"[ad_1] O Minist\u00e9rio do Turismo e a CPFL Energia apresentam a s\u00e9rie Concertos EPTV. Com a proposta permanente de levar m\u00fasica da melhor qualidade ao interior do Estado de S\u00e3o Paulo, a Temporada 2024 dos Concertos EPTV come\u00e7ou no m\u00eas de setembro e continua agora em outubro. Os concertos contam\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/concertos-eptv_2024-10-16_15-46-03_jpg_2024-10-16_15-46-03.webp.webp?fit=900%2C556&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/concertos-eptv_2024-10-16_15-46-03_jpg_2024-10-16_15-46-03.webp.webp?fit=900%2C556&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/concertos-eptv_2024-10-16_15-46-03_jpg_2024-10-16_15-46-03.webp.webp?fit=900%2C556&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/concertos-eptv_2024-10-16_15-46-03_jpg_2024-10-16_15-46-03.webp.webp?fit=900%2C556&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":63551,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/02\/concertos-eptv-apresenta-obras-de-brahms-e-musicas-chinesas-em-ribeirao\/","url_meta":{"origin":45349,"position":5},"title":"&#8216;Concertos EPTV&#8217; apresenta obras de Brahms e m\u00fasicas chinesas em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"2 de Setembro de 2024","format":false,"excerpt":"[ad_1] O Theatro Pedro II, em Ribeir\u00e3o Preto, recebe a temperada 2024 dos Concertos EPTV nesta ter\u00e7a-feira (3), com obras de Brahms e m\u00fasicas tradicionais chinesas. A entrada \u00e9 gratuita e os ingressos devem ser retirados no dia da apresenta\u00e7\u00e3o, das 10h \u00e0s 20h \u2013 a entrada est\u00e1 sujeita a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2023-09-01-at-15.04.23-1.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2023-09-01-at-15.04.23-1.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2023-09-01-at-15.04.23-1.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2023-09-01-at-15.04.23-1.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2023-09-01-at-15.04.23-1.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-bNr","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45349"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/45350"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}