{"id":45343,"date":"2024-04-03T18:24:39","date_gmt":"2024-04-03T21:24:39","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/conta-de-energia-vai-ficar-mais-cara-em-ribeirao-preto-entenda\/"},"modified":"2024-04-03T18:24:39","modified_gmt":"2024-04-03T21:24:39","slug":"conta-de-energia-vai-ficar-mais-cara-em-ribeirao-preto-entenda","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/conta-de-energia-vai-ficar-mais-cara-em-ribeirao-preto-entenda\/","title":{"rendered":"Conta de energia vai ficar mais cara em Ribeir\u00e3o Preto; Entenda"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>A <strong>Aneel (Ag\u00eancia Nacional de Energia El\u00e9trica)<\/strong> aprovou, nessa ter\u00e7a-feira (2), o <strong>reajuste tarif\u00e1rio<\/strong> da <strong>CPFL Paulista (Companhia Paulista de For\u00e7a e Luz)<\/strong>, concession\u00e1ria de energia em <strong>Ribeir\u00e3o Preto<\/strong>.<\/p>\n<p>De acordo com a ag\u00eancia,<strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\"> as novas tarifas t\u00eam vig\u00eancia a partir de segunda-feira (8)<\/mark><\/strong> e foi aprovado em uma reuni\u00e3o da diretoria colegiada.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Reajuste<\/strong><\/h4>\n<p>Foi aprovado um <strong>aumento de 1,79% nas tarifas<\/strong> da distribuidora que atende cerca de 4,94 milh\u00f5es de unidades consumidoras em 234 munic\u00edpios paulista.<\/p>\n<p>J\u00e1 em rela\u00e7\u00e3o aos<strong> consumidores cativos<\/strong>, o <strong>efeito m\u00e9dio<\/strong> para o consumidor ser\u00e1 de <strong>1,46%<\/strong>, sendo <strong>1,77%, em m\u00e9dia, para baixa tens\u00e3o<\/strong>, enquanto o aumento para os <strong>consumidores de alta tens\u00e3o \u00e9 de 0,80%, em m\u00e9dia.<\/strong><\/p>\n<h4 class=\"wp-block-heading\"><strong>Justificativa<\/strong><\/h4>\n<p>A Aneel ainda informou que os fatores que mais impactaram no c\u00e1lculo da revis\u00e3o foram os custos com encargos setoriais e transmiss\u00e3o de energia.\u00a0<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Justi\u00e7a manda prender acusada de matar corretor em Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/GFH9HUMUTHNFJdnyEd0xxq\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Quem vai sair do BBB 24? Veja enquete atualizada<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/economia\/conta-de-energia-vai-ficar-mais-cara-em-ribeirao-preto-entenda\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Aneel (Ag\u00eancia Nacional de Energia El\u00e9trica) aprovou, nessa ter\u00e7a-feira (2), o reajuste tarif\u00e1rio da CPFL Paulista (Companhia Paulista de For\u00e7a e Luz), concession\u00e1ria de energia em Ribeir\u00e3o Preto. De acordo com a ag\u00eancia, as novas tarifas t\u00eam vig\u00eancia a partir de segunda-feira (8) e foi aprovado em uma reuni\u00e3o da diretoria colegiada. Reajuste &#8230; <a title=\"Conta de energia vai ficar mais cara em Ribeir\u00e3o Preto; Entenda\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/conta-de-energia-vai-ficar-mais-cara-em-ribeirao-preto-entenda\/\" aria-label=\"Leia mais sobre Conta de energia vai ficar mais cara em Ribeir\u00e3o Preto; Entenda\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":45344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-45343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/aneel_aprovou_1200x675_05042022120752.jpg?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/aneel_aprovou_1200x675_05042022120752.jpg?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/aneel_aprovou_1200x675_05042022120752.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/aneel_aprovou_1200x675_05042022120752.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/aneel_aprovou_1200x675_05042022120752.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/aneel_aprovou_1200x675_05042022120752.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/aneel_aprovou_1200x675_05042022120752.jpg?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/aneel_aprovou_1200x675_05042022120752.jpg?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Aneel (Ag\u00eancia Nacional de Energia El\u00e9trica) aprovou, nessa ter\u00e7a-feira (2), o reajuste tarif\u00e1rio da CPFL Paulista (Companhia Paulista de For\u00e7a e Luz), concession\u00e1ria de energia em Ribeir\u00e3o Preto. De acordo com a ag\u00eancia, as novas tarifas t\u00eam vig\u00eancia a partir de segunda-feira (8) e foi aprovado em uma reuni\u00e3o da diretoria colegiada. Reajuste&hellip;","jetpack-related-posts":[{"id":45127,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/02\/tarifa-residencial-de-energia-sobe-179-dia-8\/","url_meta":{"origin":45343,"position":0},"title":"Tarifa residencial de energia sobe 1,79% dia 8","author":"ismaelcolosi.com.br","date":"2 de Abril de 2024","format":false,"excerpt":"[ad_1] Nesta semana, a Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) definiu o reajuste da conta de luz na \u00e1rea de atua\u00e7\u00e3o da Companhia Paulista de For\u00e7a e Luz (CPFL Paulista), que atende cerca de 330.000 consumidores em Ribeir\u00e3o Preto e mais 4,5 milh\u00f5es de clientes espalhados por outras 233 cidades\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/e8b90f6e-f2f2-45fb-81bb-41634ccb8fd9.jpg?fit=750%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/e8b90f6e-f2f2-45fb-81bb-41634ccb8fd9.jpg?fit=750%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/e8b90f6e-f2f2-45fb-81bb-41634ccb8fd9.jpg?fit=750%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/e8b90f6e-f2f2-45fb-81bb-41634ccb8fd9.jpg?fit=750%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":13281,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/09\/recua-o-preco-da-tarifa-do-gas-natural-neste-domingo\/","url_meta":{"origin":45343,"position":1},"title":"Recua o pre\u00e7o da tarifa do g\u00e1s natural neste domingo","author":"ismaelcolosi.com.br","date":"9 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 9 de dezembro de 2023 | 18:009 de dezembro de 2023 | 9:35 0A Ag\u00eancia Reguladora de Servi\u00e7os P\u00fablicos do Estado de S\u00e3o Paulo (Aresp) publicou, na quinta-feira, 7 de dezembro, a delibera\u00e7\u00e3o n\u00ba 1.476 que reajusta as tarifas do g\u00e1s natural comercializado no noroeste paulista, \u00e1rea de concess\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/gas-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/gas-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/gas-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/gas-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31941,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/23\/aneel-diz-que-conta-de-luz-deve-subir-56-em-2024-entenda\/","url_meta":{"origin":45343,"position":2},"title":"Aneel diz que conta de luz deve subir 5,6% em 2024; Entenda","author":"ismaelcolosi.com.br","date":"23 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) informou, que a conta de luz deve subir, em m\u00e9dia, 5,6% em 2024. A proje\u00e7\u00e3o est\u00e1 acima do IPCA (principal \u00edndice brasileiro de infla\u00e7\u00e3o) projetado pelo mercado para o per\u00edodo, de 3,86%, de acordo com o relat\u00f3rio Focus, divulgado pelo Banco Central.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/falta_de_1024x576_29052021093524.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/falta_de_1024x576_29052021093524.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/falta_de_1024x576_29052021093524.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/falta_de_1024x576_29052021093524.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44776,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/30\/energia-nao-tera-valor-adicional-5\/","url_meta":{"origin":45343,"position":3},"title":"Energia n\u00e3o ter\u00e1 valor adicional\u00a0","author":"ismaelcolosi.com.br","date":"30 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 30 de mar\u00e7o de 2024 | 16:3030 de mar\u00e7o de 2024 | 13:34 0 A Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) anunciou que manter\u00e1 a bandeira verde acionada em abril para todos os brasileiros. Com a decis\u00e3o, a conta de luz continuar\u00e1 sem cobran\u00e7a adicional pelo 24\u00ba m\u00eas seguido,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/0eaa1c68-c4bb-411f-b4d7-2e8b5987813f.jpg?fit=600%2C352&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/0eaa1c68-c4bb-411f-b4d7-2e8b5987813f.jpg?fit=600%2C352&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/0eaa1c68-c4bb-411f-b4d7-2e8b5987813f.jpg?fit=600%2C352&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":33420,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/29\/liminar-suspende-reajuste-da-tarifa-do-vale-transporte\/","url_meta":{"origin":45343,"position":4},"title":"Liminar suspende reajuste da tarifa do vale transporte","author":"ismaelcolosi.com.br","date":"29 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A ju\u00edza Lucilene Aparecida Canella de Melo, da 2\u00aa Vara da Fazenda P\u00fablica de Ribeir\u00e3o Preto, concedeu uma liminar suspendendo o reajuste do vale-transporte em que passaria de R$ 5,00 para R$ 6,00 a partir de quinta-feira,1 de fevereiro. A decis\u00e3o foi dada no dia 26 de fevereiro e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1-44-scaled.jpg?fit=700%2C446&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1-44-scaled.jpg?fit=700%2C446&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1-44-scaled.jpg?fit=700%2C446&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1-44-scaled.jpg?fit=700%2C446&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44740,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/30\/teto-para-reajuste-de-medicamentos-em-2024-fica-em-45\/","url_meta":{"origin":45343,"position":5},"title":"Teto para reajuste de medicamentos em 2024 fica em 4,5%","author":"ismaelcolosi.com.br","date":"30 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 30 de mar\u00e7o de 2024 | 10:13 0 A C\u00e2mara de Regula\u00e7\u00e3o do Mercado de Medicamentos (CMED) fixou o teto de reajuste para rem\u00e9dios em 4,5% neste ano, informou nesta sexta-feira (29) o Minist\u00e9rio da Sa\u00fade (MS). O percentual de aumento, o menor desde 2020, poder\u00e1 ser aplicado a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/precos-de-medicamentos-sofrem-reajuste-de-ate-10-8.jpg?fit=960%2C636&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/precos-de-medicamentos-sofrem-reajuste-de-ate-10-8.jpg?fit=960%2C636&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/precos-de-medicamentos-sofrem-reajuste-de-ate-10-8.jpg?fit=960%2C636&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/precos-de-medicamentos-sofrem-reajuste-de-ate-10-8.jpg?fit=960%2C636&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-bNl","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45343"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/45344"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}