{"id":45175,"date":"2024-04-02T18:37:09","date_gmt":"2024-04-02T21:37:09","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/02\/vagas-de-empregos-na-santa-helena-para-trabalhar-em-home-office-remoto-em-ribeirao-preto-sp-pelotas-rs-e-uruguaiana-rs-6\/"},"modified":"2024-04-02T18:37:09","modified_gmt":"2024-04-02T21:37:09","slug":"vagas-de-empregos-na-santa-helena-para-trabalhar-em-home-office-remoto-em-ribeirao-preto-sp-pelotas-rs-e-uruguaiana-rs-6","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/02\/vagas-de-empregos-na-santa-helena-para-trabalhar-em-home-office-remoto-em-ribeirao-preto-sp-pelotas-rs-e-uruguaiana-rs-6\/","title":{"rendered":"Vagas de empregos na Santa Helena para trabalhar em Home Office (Remoto) em Ribeir\u00e3o Preto-SP, Pelotas-RS e Uruguaiana-RS"},"content":{"rendered":"<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista Trade Marketing SR em S\u00e3o Paulo - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6803546?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Analista Trade Marketing SR<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Assistente Atendimento ado Cliente em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6931326?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Assistente Atendimento ado Cliente<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Enfermeiro do Trabalho em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6889188?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Enfermeiro do Trabalho<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Inspetor de Qualidade em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6671242?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Inspetor de Qualidade<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" id=\"h1\" class=\"sc-eACynP jLQMmr sc-e9dd4d1-5 cEgRjA\">Santa Helena Ind\u00fastria de Alimentos S\/A <\/h1>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista Trade Marketing SR em S\u00e3o Paulo - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6803546?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Analista Trade Marketing SR<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<h2 data-testid=\"section-Conhe\u00e7a mais sobre n\u00f3s-title\" class=\"sc-6fde0c52-0 haCHdH\">Conhe\u00e7a mais sobre n\u00f3s<\/h2>\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" id=\"h1\" class=\"sc-eACynP jLQMmr sc-e9dd4d1-5 cEgRjA\">Santa Helena Ind\u00fastria de Alimentos S\/A <\/h1>\n<p>Presente no mercado desde 1942, a Santa Helena \u00e9 a maior ind\u00fastria de alimentos \u00e0 base de amendoim do Brasil. Quando o assunto \u00e9 amendoim, somos refer\u00eancia nacional! Nosso prop\u00f3sito? LEVAR O MELHOR DO AMENDOIM AO ALCANCE DE TODOS.\u00a0<\/p>\n<h2 data-testid=\"section-VENHA PARA A MELHOR DO AMENDOIM, VENHA TRABALHAR NA SANTA HELENA!-title\" class=\"sc-6fde0c52-0 haCHdH\">VENHA PARA A MELHOR DO AMENDOIM, VENHA TRABALHAR NA SANTA HELENA!<\/h2>\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" id=\"h1\" class=\"sc-eACynP jLQMmr sc-e9dd4d1-5 cEgRjA\">Santa Helena Ind\u00fastria de Alimentos S\/A <\/h1>\n<div class=\"sc-f5007364-7 cYAFjr\">\n<div role=\"status\" class=\"sc-f5007364-0 cDdpev\">12 vagas encontradas para 0 filtros aplicados<\/div>\n<div aria-hidden=\"true\" data-testid=\"job-list-amount\" class=\"sc-f5007364-8 dCDcPy\">12 vagas<\/div>\n<div class=\"sc-f5007364-8 dCDcPy\">\n<div class=\"sc-4284ca6f-3 iPhDzt\">\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"10\" id=\"label-items-por-pagina\" for=\"items-por-pagina\" class=\"sc-brKeYL dtexMX\">Itens por p\u00e1gina<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-98110-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-98110-placeholder\">10<\/div>\n<style data-emotion=\"css 1hac4vs-dummyInput\">.css-1hac4vs-dummyInput{background:0;border:0;caret-color:transparent;font-size:inherit;grid-area:1\/1\/2\/3;outline:0;padding:0;width:1px;color:transparent;left:-100px;opacity:0;position:relative;-webkit-transform:scale(.01);-moz-transform:scale(.01);-ms-transform:scale(.01);transform:scale(.01);}<\/style>\n<p><input id=\"items-por-pagina\" tabindex=\"0\" inputmode=\"none\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-items-por-pagina\" role=\"combobox\" aria-readonly=\"true\" aria-describedby=\"react-select-98110-placeholder\" class=\"css-1hac4vs-dummyInput\"><\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"items-por-pagina\" value=\"\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2 data-testid=\"section-VENHA PARA A MELHOR DO AMENDOIM, VENHA TRABALHAR NA SANTA HELENA!-title\" class=\"sc-6fde0c52-0 haCHdH\">VENHA PARA A MELHOR DO AMENDOIM, VENHA TRABALHAR NA SANTA HELENA!<\/h2>\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" id=\"h1\" class=\"sc-eACynP jLQMmr sc-e9dd4d1-5 cEgRjA\">Santa Helena Ind\u00fastria de Alimentos S\/A <\/h1>\n<h2 data-testid=\"section-SOBRE N\u00d3S-title\" class=\"sc-6fde0c52-0 haCHdH\">SOBRE N\u00d3S<\/h2>\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" id=\"h1\" class=\"sc-eACynP jLQMmr sc-e9dd4d1-5 cEgRjA\">Santa Helena Ind\u00fastria de Alimentos S\/A <\/h1>\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" id=\"h1\" class=\"sc-eACynP jLQMmr sc-e9dd4d1-5 cEgRjA\">Santa Helena Ind\u00fastria de Alimentos S\/A <\/h1>\n<p>Presente no mercado desde 1942, a Santa Helena \u00e9 a maior ind\u00fastria de alimentos \u00e0 base de amendoim do Brasil. Quando o assunto \u00e9 amendoim, somos refer\u00eancia nacional! Nosso prop\u00f3sito? LEVAR O MELHOR DO AMENDOIM AO ALCANCE DE TODOS.\u00a0<\/p>\n<h2 data-testid=\"section-VENHA PARA A MELHOR DO AMENDOIM, VENHA TRABALHAR NA SANTA HELENA!-title\" class=\"sc-6fde0c52-0 haCHdH\">VENHA PARA A MELHOR DO AMENDOIM, VENHA TRABALHAR NA SANTA HELENA!<\/h2>\n<section data-testid=\"job-list\" id=\"job-listing\" class=\"sc-f5007364-1 hRVHMy\">\n<h2 data-testid=\"section-VENHA PARA A MELHOR DO AMENDOIM, VENHA TRABALHAR NA SANTA HELENA!-title\" class=\"sc-6fde0c52-0 haCHdH\">VENHA PARA A MELHOR DO AMENDOIM, VENHA TRABALHAR NA SANTA HELENA!<\/h2>\n<div data-testid=\"section-VENHA PARA A MELHOR DO AMENDOIM, VENHA TRABALHAR NA SANTA HELENA!-description\" class=\"sc-6fde0c52-1 iAgJhf\">\n<p>Buscamos talentos proativos, com autonomia, esp\u00edrito de lideran\u00e7a e senso de dono. Estimulamos a criatividade e o aprendizado cont\u00ednuo para que possamos inovar sempre, mantendo a qualidade de nossos produtos e a reputa\u00e7\u00e3o de nossas marcas. Se voc\u00ea \u00e9 o tipo de pessoa que sonha grande, a Santa Helena \u00e9 o seu lugar. Somos uma empresa que valoriza pessoas com um prop\u00f3sito de vida e que carrega valores claros e transparentes. Temos oportunidades por todo o Brasil! Gostou? Venha trabalhar com a gente!<\/p>\n<\/div>\n<div data-testid=\"old-job-filters\">\n<form aria-label=\"Busca de Vagas\" data-testid=\"job-search-form\" class=\"sc-d52d7ce9-0 gnWcBe\"><label for=\"job-search\" class=\"sc-d52d7ce9-1 bBVWZj\">Busca de Vagas<\/label><span role=\"searchbox\" aria-label=\"jobSearchFilterLabel\" class=\"sc-bbpGSz dLHSKU\"><input type=\"input\" data-testid=\"job-search\" label=\"jobSearchFilterLabel\" name=\"jobSearch\" placeholder=\"Digite o nome da vaga\" value=\"\" id=\"job-search\" aria-labelledby=\"input-job-search\" aria-describedby=\"react-aria-3 react-aria-4\" class=\"sc-jItqcz sc-UxxwN jsApaO bMvAsC\"><button aria-labelledby=\"job-search\" class=\"sc-irTswW boqOgV sc-jJgynQ jjsrBz\" id=\"job-search-button\"><\/p>\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M15.5 14h-.79l-.28-.27C15.41 12.59 16 11.11 16 9.5 16 5.91 13.09 3 9.5 3S3 5.91 3 9.5 5.91 16 9.5 16c1.61 0 3.09-.59 4.23-1.57l.27.28v.79l5 4.99L20.49 19l-4.99-5zm-6 0C7.01 14 5 11.99 5 9.5S7.01 5 9.5 5 14 7.01 14 9.5 11.99 14 9.5 14z\"><\/path><\/svg><\/div>\n<p><\/button><\/span><\/form>\n<form aria-label=\"Op\u00e7\u00f5es de Filtro de Vaga\" class=\"sc-d52d7ce9-2 fREpEo\">\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todas\" id=\"label-job-types\" for=\"job-types\" class=\"sc-brKeYL dtexMX\">Tipo de Vaga<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-98107-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-98107-placeholder\">Todas<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-types\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-types\" role=\"combobox\" aria-describedby=\"react-select-98107-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"jobTypesFilter\" value=\"\"><\/div>\n<\/div>\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todos\" id=\"label-job-workplaces\" for=\"job-workplaces\" class=\"sc-brKeYL dtexMX\">Locais de Trabalho<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-98108-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-98108-placeholder\">Todos<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-workplaces\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-workplaces\" role=\"combobox\" aria-describedby=\"react-select-98108-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"workplacesFilter\" value=\"\"><\/div>\n<\/div>\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todas\" id=\"label-job-departments\" for=\"job-departments\" class=\"sc-brKeYL dtexMX\">\u00c1reas<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-98109-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-98109-placeholder\">Todas<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-departments\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-departments\" role=\"combobox\" aria-describedby=\"react-select-98109-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"departmentsFilter\" value=\"\"><\/div>\n<\/div>\n<\/form>\n<\/div>\n<div class=\"sc-f5007364-7 cYAFjr\">\n<div role=\"status\" class=\"sc-f5007364-0 cDdpev\">12 vagas encontradas para 0 filtros aplicados<\/div>\n<div aria-hidden=\"true\" data-testid=\"job-list-amount\" class=\"sc-f5007364-8 dCDcPy\">12 vagas<\/div>\n<div class=\"sc-f5007364-8 dCDcPy\">\n<div class=\"sc-4284ca6f-3 iPhDzt\">\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"10\" id=\"label-items-por-pagina\" for=\"items-por-pagina\" class=\"sc-brKeYL dtexMX\">Itens por p\u00e1gina<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-98110-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-98110-placeholder\">10<\/div>\n<style data-emotion=\"css 1hac4vs-dummyInput\">.css-1hac4vs-dummyInput{background:0;border:0;caret-color:transparent;font-size:inherit;grid-area:1\/1\/2\/3;outline:0;padding:0;width:1px;color:transparent;left:-100px;opacity:0;position:relative;-webkit-transform:scale(.01);-moz-transform:scale(.01);-ms-transform:scale(.01);transform:scale(.01);}<\/style>\n<p><input id=\"items-por-pagina\" tabindex=\"0\" inputmode=\"none\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-items-por-pagina\" role=\"combobox\" aria-readonly=\"true\" aria-describedby=\"react-select-98110-placeholder\" class=\"css-1hac4vs-dummyInput\"><\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"items-por-pagina\" value=\"\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<ul aria-label=\"Lista de Vagas\" data-testid=\"job-list__list\">\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista Trade Marketing SR em S\u00e3o Paulo - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6803546?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Analista Trade Marketing SR<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Assistente Atendimento ado Cliente em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6931326?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Assistente Atendimento ado Cliente<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Enfermeiro do Trabalho em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6889188?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Enfermeiro do Trabalho<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Inspetor de Qualidade em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6671242?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Inspetor de Qualidade<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Mantenedor Mec\u00e2nico em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6892515?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Mantenedor Mec\u00e2nico<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Mantenedor Polivalente em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6892435?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Mantenedor Polivalente<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como \ud83e\udd5c N\u00e3o encontrou sua vaga? Cadastre seu curr\u00edculo aqui!\ud83e\udd5c em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/260570?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">\ud83e\udd5c N\u00e3o encontrou sua vaga? Cadastre seu curr\u00edculo aqui!\ud83e\udd5c<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Representante Comercial PJ - Pelotas e regi\u00e3o em Pelotas - RS\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/1732231?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Representante Comercial PJ &#8211; Pelotas e regi\u00e3o<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Pelotas &#8211; RS<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Representante Comercial PJ - Uruguaiana e regi\u00e3o em Uruguaiana - RS\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/1732246?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Representante Comercial PJ &#8211; Uruguaiana e regi\u00e3o<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uruguaiana &#8211; RS<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Vendedor - Canal Distribuidor | Minas Gerais em Ribeir\u00e3o Preto - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6903957?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Vendedor &#8211; Canal Distribuidor | Minas Gerais<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Vendedor PL - Belo Horizonte em Trabalho Remoto\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6894050?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Vendedor PL &#8211; Belo Horizonte<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Trabalho Remoto<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Vendedor SR em S\u00e3o Paulo - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/santahelena.gupy.io\/jobs\/6860161?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 BfEwa\">Vendedor SR<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<\/ul>\n<div class=\"sc-f5007364-9 gXOSFh\">\n<nav aria-label=\"Pagina\u00e7\u00e3o do resultado da busca\">\n<ul class=\"sc-llcuoN bHIMne\">\n<li class=\"sc-jnsZEu dVzXoV\"><button data-testid=\"pagination-prev-button\" aria-disabled=\"false\" aria-label=\"V\u00e1 para p\u00e1gina anterior\" class=\"sc-hsiEis fXWJKC\">\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M15.41 7.41L14 6l-6 6 6 6 1.41-1.41L10.83 12z\"><\/path><\/svg><\/div>\n<p><\/button><\/li>\n<li class=\"sc-jnsZEu dVzXoV\"><button data-testid=\"pagination-next-button\" aria-disabled=\"false\" aria-label=\"V\u00e1 para pr\u00f3xima p\u00e1gina\" class=\"sc-hsiEis fXWJKC\">\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M10 6L8.59 7.41 13.17 12l-4.58 4.59L10 18l6-6z\"><\/path><\/svg><\/div>\n<p><\/button><\/li>\n<\/ul>\n<\/nav>\n<\/div>\n<\/section>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Analista Trade Marketing SR S\u00e3o Paulo &#8211; SP e H\u00edbrido Efetivo Assistente Atendimento ado Cliente Ribeir\u00e3o Preto &#8211; SP Efetivo Enfermeiro do Trabalho Ribeir\u00e3o Preto &#8211; SP Efetivo Inspetor de Qualidade Ribeir\u00e3o Preto &#8211; SP Efetivo Santa Helena Ind\u00fastria de Alimentos S\/A Analista Trade Marketing SR S\u00e3o Paulo &#8211; SP e H\u00edbrido Efetivo Conhe\u00e7a mais &#8230; <a title=\"Vagas de empregos na Santa Helena para trabalhar em Home Office (Remoto) em Ribeir\u00e3o Preto-SP, Pelotas-RS e Uruguaiana-RS\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/02\/vagas-de-empregos-na-santa-helena-para-trabalhar-em-home-office-remoto-em-ribeirao-preto-sp-pelotas-rs-e-uruguaiana-rs-6\/\" aria-label=\"Read more about Vagas de empregos na Santa Helena para trabalhar em Home Office (Remoto) em Ribeir\u00e3o Preto-SP, Pelotas-RS e Uruguaiana-RS\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":45176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-45175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas-de-empregos-em-ribeirao-preto-regiao-brasil"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/images.png?fit=348%2C145&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/images.png?fit=348%2C145&ssl=1",348,145,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/images.png?resize=150%2C145&ssl=1",150,145,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/images.png?fit=300%2C125&ssl=1",300,125,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/images.png?fit=348%2C145&ssl=1",348,145,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/images.png?fit=348%2C145&ssl=1",348,145,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/images.png?fit=348%2C145&ssl=1",348,145,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/images.png?fit=348%2C145&ssl=1",348,145,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"Analista Trade Marketing SR S\u00e3o Paulo &#8211; SP e H\u00edbrido Efetivo Assistente Atendimento ado Cliente Ribeir\u00e3o Preto &#8211; SP Efetivo Enfermeiro do Trabalho Ribeir\u00e3o Preto &#8211; SP Efetivo Inspetor de Qualidade Ribeir\u00e3o Preto &#8211; SP Efetivo Santa Helena Ind\u00fastria de Alimentos S\/A Analista Trade Marketing SR S\u00e3o Paulo &#8211; SP e H\u00edbrido Efetivo Conhe\u00e7a mais&hellip;","jetpack-related-posts":[{"id":35577,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/06\/vagas-de-emprego-no-carrefour-em-ribeirao-preto-sp-5\/","url_meta":{"origin":45175,"position":0},"title":"Vagas de emprego no Carrefour em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"6 de February de 2024","format":false,"excerpt":"Sobre a empresa Somos l\u00edderes no mercado brasileiro de varejo alimentar, com bandeiras e marcas devidamente estabelecidas e reconhecidas pelos consumidores brasileiros. Possu\u00edmos mais de quinhentos pontos de vendas, presentes em todos os estados, entre hipermercados, supermercados, lojas de proximidade, atacados, e-commerce, postos de combust\u00edveis e drogarias. H\u00e1 mais de\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41372,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/07\/vagas-de-emprego-no-carrefour-em-ribeirao-preto-sp-6\/","url_meta":{"origin":45175,"position":1},"title":"Vagas de emprego no Carrefour em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"7 de March de 2024","format":false,"excerpt":"Sobre a empresa Somos l\u00edderes no mercado brasileiro de varejo alimentar, com bandeiras e marcas devidamente estabelecidas e reconhecidas pelos consumidores brasileiros. Possu\u00edmos mais de quinhentos pontos de vendas, presentes em todos os estados, entre hipermercados, supermercados, lojas de proximidade, atacados, e-commerce, postos de combust\u00edveis e drogarias. H\u00e1 mais de\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":80623,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/31\/vagas-de-emprego-no-carrefour-em-ribeirao-preto-sp-19\/","url_meta":{"origin":45175,"position":2},"title":"Vagas de emprego no Carrefour em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"31 de December de 2024","format":false,"excerpt":"Sobre a empresa J\u00e1 imaginou trabalhar no maior empregador privado do pa\u00eds? Vem com a gente! Somos 130 mil colaboradores e colaboradoras unidos no prop\u00f3sito de contribuir para uma alimenta\u00e7\u00e3o mais acess\u00edvel e de qualidade aos brasileiros e brasileiras, colaborando assim com a sa\u00fade e o bem-estar de todos e\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1735654070_WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1735654070_WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1735654070_WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1735654070_WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1735654070_WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45756,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/06\/vagas-de-emprego-no-carrefour-em-ribeirao-preto-sp-7\/","url_meta":{"origin":45175,"position":3},"title":"Vagas de emprego no Carrefour em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"6 de April de 2024","format":false,"excerpt":"Sobre a empresa Somos l\u00edderes no mercado brasileiro de varejo alimentar, com bandeiras e marcas devidamente estabelecidas e reconhecidas pelos consumidores brasileiros. Possu\u00edmos mais de quinhentos pontos de vendas, presentes em todos os estados, entre hipermercados, supermercados, lojas de proximidade, atacados, e-commerce, postos de combust\u00edveis e drogarias. H\u00e1 mais de\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":60277,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/15\/vagas-de-emprego-no-carrefour-em-ribeirao-preto-sp-13\/","url_meta":{"origin":45175,"position":4},"title":"Vagas de emprego no Carrefour em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"15 de August de 2024","format":false,"excerpt":"Sobre a empresa Somos l\u00edderes no mercado brasileiro de varejo alimentar, com bandeiras e marcas devidamente estabelecidas e reconhecidas pelos consumidores brasileiros. Possu\u00edmos mais de quinhentos pontos de vendas, presentes em todos os estados, entre hipermercados, supermercados, lojas de proximidade, atacados, e-commerce, postos de combust\u00edveis e drogarias. H\u00e1 mais de\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":83472,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/03\/01\/vagas-de-emprego-no-carrefour-em-ribeirao-preto-sp-22\/","url_meta":{"origin":45175,"position":5},"title":"Vagas de emprego no Carrefour em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"1 de March de 2025","format":false,"excerpt":"Sobre a empresa J\u00e1 imaginou trabalhar no maior empregador privado do pa\u00eds? Vem com a gente! Somos 130 mil colaboradores e colaboradoras unidos no prop\u00f3sito de contribuir para uma alimenta\u00e7\u00e3o mais acess\u00edvel e de qualidade aos brasileiros e brasileiras, colaborando assim com a sa\u00fade e o bem-estar de todos e\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2022-05-12-at-14.36.49.jpeg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-bKD","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45175"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/45176"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}