{"id":45084,"date":"2024-04-02T10:36:20","date_gmt":"2024-04-02T13:36:20","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/02\/mulher-morre-apos-explosao-de-rechaud\/"},"modified":"2024-04-02T10:36:20","modified_gmt":"2024-04-02T13:36:20","slug":"mulher-morre-apos-explosao-de-rechaud","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/02\/mulher-morre-apos-explosao-de-rechaud\/","title":{"rendered":"Mulher morre ap\u00f3s explos\u00e3o de rechaud"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-379205\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<p>\n<span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published updated\" datetime=\"2024-04-02T09:45:55-03:00\">2 de abril de 2024 | 9:45<\/time><\/span> <\/p>\n<p><span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"379205\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Mulher%20morre%20ap\u00f3s%20explos\u00e3o%20de%20rechaud%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/mulher-morre-apos-explosao-de-rechaud\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span> <\/header>\n<div class=\"penci-entry-content entry-content\">\n<p>Maria Cristina Graminha Rossini, de 68 anos, morreu nesta segunda-feira, 1\u00ba, depois de sofrer queimaduras pelo corpo durante a explos\u00e3o de um rechaud.<\/p>\n<p>Segundo o boletim de ocorr\u00eancia ela havia havia utilizado \u00e1lcool para acender o fogareiro de metal na noite do \u00faltimo s\u00e1bado (30), quando houve a explos\u00e3o.<\/p>\n<p>A v\u00edtima foi socorrida e encaminhada at\u00e9 a UPA Oeste, depois transferida para o HC-UE de Ribeir\u00e3o Preto<\/p>\n<p>N\u00e3o h\u00e1 informa\u00e7\u00f5es sobre o local onde ocorreu o acidente.<\/p>\n<p>\u00a0<\/p>\n<\/div>\n<footer class=\"penci-entry-footer\">\n <\/footer>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/mulher-morre-apos-explosao-de-rechaud\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 2 de abril de 2024 | 9:45 0 Maria Cristina Graminha Rossini, de 68 anos, morreu nesta segunda-feira, 1\u00ba, depois de sofrer queimaduras pelo corpo durante a explos\u00e3o de um rechaud. Segundo o boletim de ocorr\u00eancia ela havia havia utilizado \u00e1lcool para acender o fogareiro de metal na noite do \u00faltimo s\u00e1bado (30), quando &#8230; <a title=\"Mulher morre ap\u00f3s explos\u00e3o de rechaud\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/02\/mulher-morre-apos-explosao-de-rechaud\/\" aria-label=\"Leia mais sobre Mulher morre ap\u00f3s explos\u00e3o de rechaud\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":45085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[37,5390,271,325,5391],"class_list":["post-45084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-apos","tag-explosao","tag-morre","tag-mulher","tag-rechaud"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/hcemergencia.jpg?fit=800%2C500&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/hcemergencia.jpg?fit=800%2C500&ssl=1",800,500,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/hcemergencia.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/hcemergencia.jpg?fit=300%2C188&ssl=1",300,188,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/hcemergencia.jpg?fit=768%2C480&ssl=1",768,480,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/hcemergencia.jpg?fit=800%2C500&ssl=1",800,500,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/hcemergencia.jpg?fit=800%2C500&ssl=1",800,500,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/hcemergencia.jpg?fit=800%2C500&ssl=1",800,500,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 2 de abril de 2024 | 9:45 0 Maria Cristina Graminha Rossini, de 68 anos, morreu nesta segunda-feira, 1\u00ba, depois de sofrer queimaduras pelo corpo durante a explos\u00e3o de um rechaud. Segundo o boletim de ocorr\u00eancia ela havia havia utilizado \u00e1lcool para acender o fogareiro de metal na noite do \u00faltimo s\u00e1bado (30), quando&hellip;","jetpack-related-posts":[{"id":72196,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/20\/morre-3a-vitima-de-explosao-em-industria-quimica-de-sertaozinho\/","url_meta":{"origin":45084,"position":0},"title":"Morre 3\u00aa v\u00edtima de explos\u00e3o em ind\u00fastria qu\u00edmica de Sert\u00e3ozinho","author":"ismaelcolosi.com.br","date":"20 de Outubro de 2024","format":false,"excerpt":"[ad_1] Morreu na manh\u00e3 deste domingo (20) a terceira v\u00edtima da explos\u00e3o em ind\u00fastria qu\u00edmica de Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto. A fam\u00edlia e a empresa Innove Qu\u00edmica confirmaram o falecimento de Gabriel Augusto da Silva, 24 anos. Ele estava internado em um hospital particular de Ribeir\u00e3o. A fam\u00edlia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71597,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/17\/morre-2a-vitima-de-explosao-em-industria-quimica-de-sertaozinho\/","url_meta":{"origin":45084,"position":1},"title":"Morre 2\u00aa v\u00edtima de explos\u00e3o em ind\u00fastria qu\u00edmica de Sert\u00e3ozinho","author":"ismaelcolosi.com.br","date":"17 de Outubro de 2024","format":false,"excerpt":"[ad_1] Morreu na madrugada desta quinta-feira (17) a segunda v\u00edtima da explos\u00e3o em ind\u00fastria qu\u00edmica de\u00a0Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto. Segundo informa\u00e7\u00f5es, Aparecido Ol\u00edmpio Bernardino, de 67 anos, estava internado no Hospital das Cl\u00ednicas \u2013 Unidade de Emerg\u00eancia (HC-UE). *Not\u00edcia em atualiza\u00e7\u00e3o [ad_2] Source link","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":72352,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/21\/cetesb-aplica-multa-milionaria-em-industria-quimica-de-sertaozinho\/","url_meta":{"origin":45084,"position":2},"title":"Cetesb aplica multa milion\u00e1ria em ind\u00fastria qu\u00edmica de Sert\u00e3ozinho","author":"ismaelcolosi.com.br","date":"21 de Outubro de 2024","format":false,"excerpt":"[ad_1] A Cetesb (Companhia Ambiental do Estado de S\u00e3o Paulo) aplicou uma multa no valor de R$ 16,75 milh\u00f5es \u00e0 ind\u00fastria qu\u00edmica de Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto, por danos ambientais causados pela explos\u00e3o ocorrida no \u00faltimo dia 18 de agosto. Tr\u00eas pessoas morream. Segundo o \u00f3rg\u00e3o, foram considerados\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1200%2C678&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71402,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/16\/morre-vitima-de-explosao-em-industria-quimica-de-sertaozinho\/","url_meta":{"origin":45084,"position":3},"title":"Morre v\u00edtima de explos\u00e3o em ind\u00fastria qu\u00edmica de Sert\u00e3ozinho","author":"ismaelcolosi.com.br","date":"16 de Outubro de 2024","format":false,"excerpt":"[ad_1] Um homem de 27 anos, v\u00edtima da explos\u00e3o em ind\u00fastria qu\u00edmica de\u00a0Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto, morreu na madrugada desta quarta-feira (16). O Hospital das Cl\u00ednicas \u2013 Unidade de Emerg\u00eancia (HC-UE) confirmou o falecimento de Estev\u00e3o Felisberto Campanini, ocorrido \u00e0s 3h28. Outras tr\u00eas v\u00edtimas ainda seguiam internadas, das\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/hcue_hospital_500x320_08052018121430.jpg?fit=500%2C322&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":47694,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/27\/jovem-morre-apos-acender-disco-de-arado-com-alcool-combustivel-no-interior-de-sp\/","url_meta":{"origin":45084,"position":4},"title":"Jovem morre ap\u00f3s acender disco de arado com \u00e1lcool combust\u00edvel no interior de SP","author":"ismaelcolosi.com.br","date":"27 de Abril de 2024","format":false,"excerpt":"[ad_1] Uma jovem de 19 anos morreu na madrugada deste s\u00e1bado (27), em um hospital particular de Ribeir\u00e3o Preto, depois de n\u00e3o resistir aos ferimentos provocados por queimaduras ap\u00f3s acender um disco de arado com \u00e1lcool combust\u00edvel. O acidente ocorreu no \u00faltimo dia 21, em Porto Ferreira, no interior de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2023-10-01-at-15.55.52.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2023-10-01-at-15.55.52.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2023-10-01-at-15.55.52.jpeg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2023-10-01-at-15.55.52.jpeg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":58916,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/04\/tres-pessoas-morrem-em-queda-de-aviao-no-interior-de-sp\/","url_meta":{"origin":45084,"position":5},"title":"Tr\u00eas pessoas morrem em queda de avi\u00e3o no interior de SP","author":"ismaelcolosi.com.br","date":"4 de Agosto de 2024","format":false,"excerpt":"[ad_1] Tr\u00eas pessoas morreram neste s\u00e1bado (3), ap\u00f3s um avi\u00e3o de pequeno porte cair em uma propiedade rural no km 5 da rodovia Senador Teot\u00f4nio Vilela, em Birigui, munic\u00edpio do noroeste do estado de S\u00e3o Paulo. De acordo com o Corpo de Bombeiros, a aronave incendiou com a queda e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/AVIAO_2024-08-03_23-10-38_jpg_2024-08-03_23-10-38.webp.webp?fit=1200%2C717&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/AVIAO_2024-08-03_23-10-38_jpg_2024-08-03_23-10-38.webp.webp?fit=1200%2C717&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/AVIAO_2024-08-03_23-10-38_jpg_2024-08-03_23-10-38.webp.webp?fit=1200%2C717&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/AVIAO_2024-08-03_23-10-38_jpg_2024-08-03_23-10-38.webp.webp?fit=1200%2C717&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/AVIAO_2024-08-03_23-10-38_jpg_2024-08-03_23-10-38.webp.webp?fit=1200%2C717&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-bJa","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45084"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/45085"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}