{"id":44920,"date":"2024-04-01T11:55:01","date_gmt":"2024-04-01T14:55:01","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/01\/motorista-atropela-cachorro-e-foge\/"},"modified":"2024-04-01T11:55:01","modified_gmt":"2024-04-01T14:55:01","slug":"motorista-atropela-cachorro-e-foge","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/01\/motorista-atropela-cachorro-e-foge\/","title":{"rendered":"Motorista atropela cachorro e foge"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-379107\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<p>\n<span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-04-01T11:21:48-03:00\">1 de abril de 2024 | 11:21<\/time><time class=\"updated\" datetime=\"2024-04-01T11:24:52-03:00\">1 de abril de 2024 | 11:24<\/time><\/span> <\/p>\n<p><span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"379107\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Motorista%20atropela%20cachorro%20e%20foge%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/motorista-atropela-cachorro-e-foge\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span> <\/header>\n<div class=\"penci-entry-content entry-content\">\n<p>Um motorista atropelou e matou um cachorro, na noite deste domingo (31), na Thomaz Alberto Whately em Ribeir\u00e3o Preto.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<p>Segundo informa\u00e7\u00f5es, o motorista estava em alta velocidade quando atingiu o animal. Depois do acidente ele fugiu e com o atropelamento pe\u00e7as do carro ficaram ca\u00eddas na via.<\/p>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<p>Motoristas que passavam pela avenida tentaram socorrer o c\u00e3o, mas ele n\u00e3o resistiu. O motorista n\u00e3o foi identificado.<\/p>\n<\/div>\n<\/div>\n<footer class=\"penci-entry-footer\">\n <\/footer>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/motorista-atropela-cachorro-e-foge\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 1 de abril de 2024 | 11:211 de abril de 2024 | 11:24 0 Um motorista atropelou e matou um cachorro, na noite deste domingo (31), na Thomaz Alberto Whately em Ribeir\u00e3o Preto. Segundo informa\u00e7\u00f5es, o motorista estava em alta velocidade quando atingiu o animal. Depois do acidente ele fugiu e com o atropelamento &#8230; <a title=\"Motorista atropela cachorro e foge\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/01\/motorista-atropela-cachorro-e-foge\/\" aria-label=\"Leia mais sobre Motorista atropela cachorro e foge\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":44921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[5319,2945,1681,319],"class_list":["post-44920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-atropela","tag-cachorro","tag-foge","tag-motorista"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/0ac1a25a-2b01-43f0-bba9-ac5b3f74690b.jpg?fit=750%2C500&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/0ac1a25a-2b01-43f0-bba9-ac5b3f74690b.jpg?fit=750%2C500&ssl=1",750,500,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/0ac1a25a-2b01-43f0-bba9-ac5b3f74690b.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/0ac1a25a-2b01-43f0-bba9-ac5b3f74690b.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/0ac1a25a-2b01-43f0-bba9-ac5b3f74690b.jpg?fit=750%2C500&ssl=1",750,500,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/0ac1a25a-2b01-43f0-bba9-ac5b3f74690b.jpg?fit=750%2C500&ssl=1",750,500,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/0ac1a25a-2b01-43f0-bba9-ac5b3f74690b.jpg?fit=750%2C500&ssl=1",750,500,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/0ac1a25a-2b01-43f0-bba9-ac5b3f74690b.jpg?fit=750%2C500&ssl=1",750,500,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 1 de abril de 2024 | 11:211 de abril de 2024 | 11:24 0 Um motorista atropelou e matou um cachorro, na noite deste domingo (31), na Thomaz Alberto Whately em Ribeir\u00e3o Preto. Segundo informa\u00e7\u00f5es, o motorista estava em alta velocidade quando atingiu o animal. Depois do acidente ele fugiu e com o atropelamento&hellip;","jetpack-related-posts":[{"id":45633,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/05\/ciclista-morre-atropelado-e-motorista-foge-sem-prestar-socorro-em-rp\/","url_meta":{"origin":44920,"position":0},"title":"Ciclista morre atropelado e motorista foge sem prestar socorro em RP","author":"ismaelcolosi.com.br","date":"5 de Abril de 2024","format":false,"excerpt":"[ad_1] 5 de abril de 2024 | 11:57 0 Um ciclista morreu na noite desta quinta-feira (4), depois ser atropelado na Estrada Joanilda Martins dos Santos, em Ribeir\u00e3o Preto. Segundo o\u00a0boletim de ocorr\u00eancia (BO), a\u00a0v\u00edtima, identificada como\u00a0Edvan Pereira Corr\u00eaa, de 46 anos, foi\u00a0atingida\u00a0por um\u00a0ve\u00edculo, cujo tipo \u00e9 desconhecido, sofreu\u00a0esmagamento\u00a0na\u00a0cabe\u00e7a\u00a0e chegou\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/a556b282-c087-4259-bd5b-8d6db44af6c2.png?fit=768%2C354&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/a556b282-c087-4259-bd5b-8d6db44af6c2.png?fit=768%2C354&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/a556b282-c087-4259-bd5b-8d6db44af6c2.png?fit=768%2C354&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/a556b282-c087-4259-bd5b-8d6db44af6c2.png?fit=768%2C354&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37514,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/16\/cachorro-e-atropelado-por-onibus-no-centro-de-ribeirao-preto-veja-video\/","url_meta":{"origin":44920,"position":1},"title":"Cachorro \u00e9 atropelado por \u00f4nibus no Centro de Ribeir\u00e3o Preto; Veja v\u00eddeo","author":"ismaelcolosi.com.br","date":"16 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Um cachorro foi atropelado por um \u00f4nibus do transporte coletivo urbano nesta sexta-feira (16), no Centro de Ribeir\u00e3o Preto. Imagens de c\u00e2meras de seguran\u00e7a registraram o momento do atropelamento (veja v\u00eddeo abaixo). De acordo com o Cons\u00f3rcio Pr\u00f3Urbano, o motorista informou que n\u00e3o conseguiu evitar o atropelamento, mas disse\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-12.jpg?fit=644%2C519&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-12.jpg?fit=644%2C519&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-12.jpg?fit=644%2C519&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":47116,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/22\/ciclista-e-atropelado-por-carro-em-alta-velocidade-e-sobrevive-video\/","url_meta":{"origin":44920,"position":2},"title":"Ciclista \u00e9 atropelado por carro em alta velocidade e sobrevive; V\u00eddeo","author":"ismaelcolosi.com.br","date":"22 de Abril de 2024","format":false,"excerpt":"[ad_1] Um ciclista foi atropelado por um carro em alta velocidade na avenida Ant\u00f4nio Paschoal, em Sert\u00e3ozinho, regi\u00e3o de Ribeir\u00e3o Preto. A colis\u00e3o aconteceu na madrugada de domingo (21) e foi registrada por c\u00e2meras de seguran\u00e7a. As imagens mostram que o carro vinha na faixa da esquerda, quando perdeu o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/sertaozinho.webp.webp?fit=939%2C540&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/sertaozinho.webp.webp?fit=939%2C540&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/sertaozinho.webp.webp?fit=939%2C540&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/sertaozinho.webp.webp?fit=939%2C540&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":53500,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/17\/idosa-e-atropelada-em-faixa-de-pedestre-e-motorista-foge-em-ribeirao-preto-veja-o-video\/","url_meta":{"origin":44920,"position":3},"title":"Idosa \u00e9 atropelada em faixa de pedestre e motorista foge em Ribeir\u00e3o Preto; Veja o v\u00eddeo","author":"ismaelcolosi.com.br","date":"17 de Junho de 2024","format":false,"excerpt":"[ad_1] Uma idosa de 62 anos foi atropelada, enquanto atravessa em cima da faixa de pedestre, no in\u00edcio da noite deste domingo (16). O acidente ocorreu no cruzamento das alamedas Josephina Brussolo Girotto com a Domingos F. Villas Boas, no bairro Parque dos Lagos, na zona Leste de Ribeir\u00e3o Preto.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-7_2024-06-17_14-38-18_jpg_2024-06-17_14-38-18.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-7_2024-06-17_14-38-18_jpg_2024-06-17_14-38-18.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-7_2024-06-17_14-38-18_jpg_2024-06-17_14-38-18.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-7_2024-06-17_14-38-18_jpg_2024-06-17_14-38-18.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-7_2024-06-17_14-38-18_jpg_2024-06-17_14-38-18.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28465,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/15\/caminhao-atropela-um-colide-contra-arvore-e-pega-fogo-em-seguida-dois-morreram-em-acidente-impactante\/","url_meta":{"origin":44920,"position":4},"title":"Caminh\u00e3o atropela um, colide contra \u00e1rvore e pega fogo em seguida; dois morreram em acidente impactante","author":"ismaelcolosi.com.br","date":"15 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Um grave acidente chocou a regi\u00e3o de Concei\u00e7\u00e3o de Jacu\u00edpe, a quase 100 km de Salvador, na tarde desta segunda, dia 15 de janeiro, quando um caminh\u00e3o se envolveu em uma s\u00e9rie de eventos tr\u00e1gicos.O motorista do ve\u00edculo atropelou Uilian Pereira dos Santos, um jovem vendedor de frutas de\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5cdd8052dc1396.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5cdd8052dc1396.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5cdd8052dc1396.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5cdd8052dc1396.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5cdd8052dc1396.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":56850,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/15\/ciclista-e-atropelado-em-marginal-de-rodovia-em-ribeirao-e-motorista-foge-sem-prestar-socorro\/","url_meta":{"origin":44920,"position":5},"title":"Ciclista \u00e9 atropelado em marginal de rodovia em Ribeir\u00e3o e motorista foge sem prestar socorro","author":"ismaelcolosi.com.br","date":"15 de Julho de 2024","format":false,"excerpt":"[ad_1] Um ciclista de 32 anos ficou em estado grave, ap\u00f3s ser atropelado na manh\u00e3 desta segunda-feira (15) na marginal da rodovia Anhanguera, pr\u00f3ximo ao quil\u00f4metro 311, no bairro Residencial Palmares em Ribeir\u00e3o Preto. Segundo o boletim de ocorr\u00eancia, uma testemunha informou aos policiais rodovi\u00e1rios que estava parado na faixa\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-07-15_20-55-31_png_2024-07-15_20-55-31.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-07-15_20-55-31_png_2024-07-15_20-55-31.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-07-15_20-55-31_png_2024-07-15_20-55-31.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-07-15_20-55-31_png_2024-07-15_20-55-31.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-07-15_20-55-31_png_2024-07-15_20-55-31.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-bGw","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=44920"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/44921"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=44920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=44920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=44920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}