{"id":43574,"date":"2024-03-22T08:51:07","date_gmt":"2024-03-22T11:51:07","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/22\/o-caminho-para-a-saude-financeira-familiar\/"},"modified":"2024-03-22T08:51:07","modified_gmt":"2024-03-22T11:51:07","slug":"o-caminho-para-a-saude-financeira-familiar","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/22\/o-caminho-para-a-saude-financeira-familiar\/","title":{"rendered":"O caminho para a sa\u00fade financeira familiar\u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p>\n<span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-03-22T08:20:28-03:00\">22 de mar\u00e7o de 2024 | 8:20<\/time><time class=\"updated\" datetime=\"2024-03-22T08:16:11-03:00\">22 de mar\u00e7o de 2024 | 8:16<\/time><\/span> <\/p>\n<p><span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"378058\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=O%20caminho%20para%20a%20sa\u00fade%20financeira%20familiar\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/o-caminho-para-a-saude-financeira-familiar\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span> <\/div>\n<div>\n<p><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">Julio<\/span><span class=\"NormalTextRun SCXW139387963 BCX8\"> Cesar<\/span> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW139387963 BCX8\">Verga\u00e7as<\/span><span class=\"NormalTextRun SCXW139387963 BCX8\"> Fernandes *<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><a class=\"Hyperlink SCXW139387963 BCX8\" href=\"http:\/\/www.santander.com.br\/\" target=\"_blank\" rel=\"noopener\"><span class=\"TextRun Underlined SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW139387963 BCX8\" data-ccp-charstyle=\"Hyperlink\">www.santander.com.br<\/span><\/span><\/a><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">Despesas como viagens, IPVA, IPTU e compra de material escolar impactam fortemente o or\u00e7amento dom\u00e9stico no in\u00edcio do ano e<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">trazem preocupa\u00e7\u00e3o para quem quer manter a sa\u00fade financeira familiar, evitando a inadimpl\u00eancia<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">e o endividamento. Dados do Serasa de dezembro \u00faltimo apontavam que<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">mais de 71 milh\u00f5es de pessoas<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">estavam<\/span><span class=\"NormalTextRun SCXW139387963 BCX8\"> inadimplentes no Brasil, o equivalente a 43,4% da popula\u00e7\u00e3o. Em S\u00e3o Paulo, a taxa foi de quase 46%, colocando o estado como o oitavo com a maior parcela no pa\u00eds.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">Para passar por essa fase do ano com mais <\/span><span class=\"NormalTextRun SCXW139387963 BCX8\">tranquilidade<\/span><span class=\"NormalTextRun SCXW139387963 BCX8\"> e evitar fazer parte dessas estat\u00edsticas, o ideal \u00e9 montar um or\u00e7amento anual.<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">Isso<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">significa levantar os poss\u00edveis ganhos e despesas no ano, e verificar qual a estimativa de dinheiro j\u00e1 comprometido e de potencial de reserva. Com isso, \u00e9 poss\u00edvel ter um controle maior dos gastos, evitando assim \u201carmadilhas\u201d que podem surgir quando se est\u00e1 restrito a um olhar de curto prazo, o famoso \u2013 e perigoso \u2013 \u201cdepois eu pago\u201d.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">Para aqueles que, ao montarem esse planejamento, encontrarem dificuldades para manter a sa\u00fade financeira, tenho algumas dicas:<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">\u2013 Economizar: avalie se h\u00e1 condi\u00e7\u00f5es de reduzir gastos com itens do cotidiano como transporte, luz, g\u00e1s, \u00e1gua e pacote de TV por assinatura, internet e celular. Colocar tudo na ponta do l\u00e1pis para analisar eventuais economias, mesmo que pequenas, pode fazer muita diferen\u00e7a ao longo do ano;<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">\u2013 Ter uma reserva financeira de emerg\u00eancia: diante de qualquer problema inesperado que exija o uso de recursos,<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">uma reserva de emerg\u00eancia permite que se mantenha o foco no longo prazo. Mas n\u00e3o deixe de tentar realizar seus sonhos, planejando uma reserva de curto prazo para objetivos como viagens, cursos, compras de um eletrodom\u00e9stico ou at\u00e9 a troca do carro; <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">\u2013 Renegociar d\u00edvidas: caso haja d\u00edvidas pr\u00e9vias, \u00e9 necess\u00e1rio avaliar se h\u00e1 margem para negocia\u00e7\u00e3o.<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">Este pode ser um meio para aumentar a capacidade de investimento no ano;<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">\u2013 Criar metas: tra\u00e7ar metas de conquistas de curto, m\u00e9dio e <\/span><span class=\"NormalTextRun SCXW139387963 BCX8\">longo prazos<\/span><span class=\"NormalTextRun SCXW139387963 BCX8\"> ajuda <\/span><span class=\"NormalTextRun SCXW139387963 BCX8\">a fomentar a disciplina. Pense no futuro de sua fam\u00edlia e na pr\u00f3pria aposentadoria. Observe o que \u00e9 poss\u00edvel atingir em um curto espa\u00e7o de tempo, mas tamb\u00e9m n\u00e3o deixar de contemplar o futuro, pois o tempo \u00e9 um grande aliado dos investimentos;<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">\u2013 Olhar para o futuro: avalie<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">a<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">contrata\u00e7\u00e3o produtos de longo prazo, como uma previd\u00eancia privada. Busque por vantagens tribut\u00e1rias, tenha disciplina (<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW139387963 BCX8\">fazendoaportes<\/span><span class=\"NormalTextRun SCXW139387963 BCX8\"> mensais) e diversifique<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">os<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">investimentos de acordo com o seu perfil, momento de vida e objetivos.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">Al\u00e9m dessas dicas, h\u00e1 aplicativos e planilhas que facilitam o planejamento. E as fam\u00edlias podem aproveitar iniciativas oferecidas pelo mercado de renegocia\u00e7\u00e3o de d\u00edvidas, contrata\u00e7\u00e3o de financiamentos mais baratos e ofertas de cr\u00e9dito nas modalidades pessoal, consignado e com <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW139387963 BCX8\">garantias.<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW139387963 BCX8\">Por\u00e9m,\u00e9<\/span><span class=\"NormalTextRun SCXW139387963 BCX8\"> importante \u00e9 seguir as orienta\u00e7\u00f5es<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">de<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">especialistas<\/span> <span class=\"NormalTextRun SCXW139387963 BCX8\">certificados e de institui\u00e7\u00f5es financeiras confi\u00e1veis. Assim, al\u00e9m de evitar dores de cabe\u00e7a, \u00e9 poss\u00edvel realizar sonhos e metas que, no momento, constam apenas no papel.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW139387963 BCX8\"><span class=\"SCXW139387963 BCX8\">\u00a0<\/span><br class=\"SCXW139387963 BCX8\"\/><\/span><span class=\"TextRun SCXW139387963 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW139387963 BCX8\">* <\/span><span class=\"NormalTextRun SCXW139387963 BCX8\">S\u00eanior <\/span><span class=\"NormalTextRun SCXW139387963 BCX8\">Head<\/span><span class=\"NormalTextRun SCXW139387963 BCX8\"> Rede SP Interior do Santander Brasil<\/span><\/span><span class=\"EOP SCXW139387963 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/o-caminho-para-a-saude-financeira-familiar\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 22 de mar\u00e7o de 2024 | 8:2022 de mar\u00e7o de 2024 | 8:16 0 Julio Cesar Verga\u00e7as Fernandes *\u00a0www.santander.com.br\u00a0\u00a0Despesas como viagens, IPVA, IPTU e compra de material escolar impactam fortemente o or\u00e7amento dom\u00e9stico no in\u00edcio do ano e trazem preocupa\u00e7\u00e3o para quem quer manter a sa\u00fade financeira familiar, evitando a inadimpl\u00eancia e o endividamento. &#8230; <a title=\"O caminho para a sa\u00fade financeira familiar\u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/22\/o-caminho-para-a-saude-financeira-familiar\/\" aria-label=\"Leia mais sobre O caminho para a sa\u00fade financeira familiar\u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":43575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[5160,4092,5161,71,158],"class_list":["post-43574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-caminho","tag-familiar","tag-financeira","tag-para","tag-saude"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/vergaca.jpeg?fit=735%2C327&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/vergaca.jpeg?fit=735%2C327&ssl=1",735,327,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/vergaca.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/vergaca.jpeg?fit=300%2C133&ssl=1",300,133,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/vergaca.jpeg?fit=735%2C327&ssl=1",735,327,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/vergaca.jpeg?fit=735%2C327&ssl=1",735,327,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/vergaca.jpeg?fit=735%2C327&ssl=1",735,327,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/vergaca.jpeg?fit=735%2C327&ssl=1",735,327,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 22 de mar\u00e7o de 2024 | 8:2022 de mar\u00e7o de 2024 | 8:16 0 Julio Cesar Verga\u00e7as Fernandes *\u00a0www.santander.com.br\u00a0\u00a0Despesas como viagens, IPVA, IPTU e compra de material escolar impactam fortemente o or\u00e7amento dom\u00e9stico no in\u00edcio do ano e trazem preocupa\u00e7\u00e3o para quem quer manter a sa\u00fade financeira familiar, evitando a inadimpl\u00eancia e o endividamento.&hellip;","jetpack-related-posts":[{"id":52152,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/04\/ans-autoriza-reajuste-de-ate-691-nos-planos-de-saude-individuais-entenda\/","url_meta":{"origin":43574,"position":0},"title":"ANS autoriza reajuste de at\u00e9 6,91% nos planos de sa\u00fade individuais; Entenda","author":"ismaelcolosi.com.br","date":"4 de Junho de 2024","format":false,"excerpt":"[ad_1] A Ag\u00eancia Nacional de Sa\u00fade Suplementar (ANS) estabeleceu o limite de 6,91% para o reajuste anual dos planos de sa\u00fade individuais e familiares regulamentados, v\u00e1lidos para contratos firmados a partir de 1\u00ba de janeiro de 1999 ou adaptados \u00e0 Lei n\u00ba 9.656\/98. Esse porcentual ser\u00e1 aplic\u00e1vel no per\u00edodo de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/visita_ao_1024x576_09022021131056.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/visita_ao_1024x576_09022021131056.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/visita_ao_1024x576_09022021131056.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/visita_ao_1024x576_09022021131056.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34620,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/nova-ubs-deve-atender-em-marco\/","url_meta":{"origin":43574,"position":1},"title":"Nova UBS deve atender em mar\u00e7o\u00a0","author":"ismaelcolosi.com.br","date":"2 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 2 de fevereiro de 2024 | 18:002 de fevereiro de 2024 | 8:45 0A prefeitura de Ribeir\u00e3o Preto ir\u00e1 inaugurar , ainda no primeiro semestre deste ano, a nova Unidade B\u00e1sica de Sa\u00fade do Centro, na rua S\u00e3o Jos\u00e9, entre os n\u00fameros 1.254 e 1.262. A UBS ir\u00e1 suprir\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/NovaUBS-Divulgacao-01-scaled.jpeg?fit=860%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/NovaUBS-Divulgacao-01-scaled.jpeg?fit=860%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/NovaUBS-Divulgacao-01-scaled.jpeg?fit=860%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/NovaUBS-Divulgacao-01-scaled.jpeg?fit=860%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":59676,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/11\/trabalhar-em-familia-da-certo\/","url_meta":{"origin":43574,"position":2},"title":"trabalhar em fam\u00edlia d\u00e1 certo?","author":"ismaelcolosi.com.br","date":"11 de Agosto de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 \u00a0 Apesar da convic\u00e7\u00e3o de que neg\u00f3cios e fam\u00edlia n\u00e3o se misturam, muitos profissionais fazem essa rela\u00e7\u00e3o dar certo. Segundo o IBGE (Instituto Brasileiro de Geografia e Estat\u00edstica), 90% das empresas no Brasil t\u00eam perfil familiar, respondem por mais da metade do\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/joao-adibe-e-filhos-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/joao-adibe-e-filhos-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/joao-adibe-e-filhos-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/joao-adibe-e-filhos-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":20441,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/25\/como-sera-2024\/","url_meta":{"origin":43574,"position":3},"title":"Como ser\u00e1 2024?\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"25 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A pergunta que muitos se fazem nesta virada \u00e9: como ser\u00e1 o pr\u00f3ximo ano? O que esperar de 2024?\u00a0Para tentar responder, a reportagem do Tribuna Ribeir\u00e3o ouviu o que dizem a Astrologia, a Numerologia e Umbanda. Com sutis diversidades, a astr\u00f3loga Ana Clara Franzon, o pai de santo Marco\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/4-Previsoes-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/4-Previsoes-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/4-Previsoes-scaled.jpg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/4-Previsoes-scaled.jpg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41703,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/10\/cinco-paises-seguros-para-mulheres-que-viajam-sozinhas\/","url_meta":{"origin":43574,"position":4},"title":"Cinco pa\u00edses seguros para mulheres que viajam sozinhas\u00a0","author":"ismaelcolosi.com.br","date":"10 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 10 de mar\u00e7o de 2024 | 15:0010 de mar\u00e7o de 2024 | 11:46 0Na \u00faltima sexta-feira, 8 de mar\u00e7o, foi celebrado o Dia Internacional da Mulher. Este m\u00eas tem se consolidado como um per\u00edodo especial de conscientiza\u00e7\u00e3o, reflex\u00e3o e debate. Por\u00e9m, sabemos que ainda \u00e9 preciso trilhar um longo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/SUICA.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/SUICA.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/SUICA.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/SUICA.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":16524,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/15\/8-sinais-menos-conhecidos-da-demencia\/","url_meta":{"origin":43574,"position":5},"title":"8 sinais menos conhecidos da dem\u00eancia","author":"ismaelcolosi.com.br","date":"15 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: Getty ImagesProblemas em gerenciar as finan\u00e7as pessoais, como pagar contas ou entender declara\u00e7\u00f5es financeiras, tamb\u00e9m \u00e9 considerado um dos sintomas vinculados \u00e0 dem\u00eancia \u2013 iStock\/Getty Images Embora a perda de mem\u00f3ria seja um dos sintomas mais conhecidos e associados \u00e0 dem\u00eancia, existem outros sinais que podem surgir antes.\u00a0Algumas\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1369285084.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1369285084.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1369285084.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1369285084.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1369285084.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-bkO","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43574"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/43575"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}