{"id":42835,"date":"2024-03-17T13:29:19","date_gmt":"2024-03-17T16:29:19","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/17\/auxiliar-veterinarioa-araraquara-2\/"},"modified":"2024-03-17T13:29:19","modified_gmt":"2024-03-17T16:29:19","slug":"auxiliar-veterinarioa-araraquara-2","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/17\/auxiliar-veterinarioa-araraquara-2\/","title":{"rendered":"Auxiliar Veterin\u00e1rio(a) (Araraquara)"},"content":{"rendered":"<p><main data-testid=\"content-wrapper\" id=\"main\" class=\"sc-e9dd4d1-0 lkRshA\"><\/p>\n<section data-testid=\"company-description\" id=\"about\" class=\"sc-c1003a30-0 bTlhYQ\">\n<h2 data-testid=\"section-Breve hist\u00f3rico do Hospital VFP-title\" class=\"sc-6fde0c52-0 haCHdH\">Breve hist\u00f3rico do Hospital VFP<\/h2>\n<div class=\"sc-c1003a30-1 ekXBFd\">\n<p>O Hospital Veterin\u00e1rio VFP \u00e9 um hospital de apoio ao m\u00e9dico veterin\u00e1rio, foi inaugurado em julho do ano de 2020 com 5 colaboradores contratados apenas, al\u00e9m dos dois s\u00f3cios administradores. Em menos de dois anos, a empresa j\u00e1 contava com uma equipe de mais de 30 colaboradores. Em junho de 2023, a unidade matriz de Ribeir\u00e3o Preto passou de 40 colaboradores.<\/p>\n<p><\/p>\n<p>\ud83c\udfe5 Atualmente, o Hospital Veterin\u00e1rio VFP de Ribeir\u00e3o Preto j\u00e1 passa de 60 pessoas na equipe e nossos principais diferenciais s\u00e3o:<\/p>\n<p><\/p>\n<p>\u2705 Equipe certificada e especializada ao atendimento de pacientes graves<\/p>\n<p><\/p>\n<p>\u2705 Equipamentos de alta tecnologia com o que tem mais de avan\u00e7ado na medicina<\/p>\n<p><\/p>\n<p>\u2705 Comunica\u00e7\u00e3o eficiente com m\u00e9dicos veterin\u00e1rios parceiros atrav\u00e9s de sistema pr\u00f3prio de gest\u00e3o de encaminhamentos<\/p>\n<p><\/p>\n<p>\u2705 Estrutura organizacional equiparada aos melhores hospitais do mundo<\/p>\n<p><\/p>\n<p>\u2705 Auditorias e controle de qualidade de assist\u00eancia, limpeza e organiza\u00e7\u00e3o realizadas periodicamente<\/p>\n<p><\/p>\n<p>\ud83d\ude80 O Hospital VFP \u00e9 tido como refer\u00eancia na medicina veterin\u00e1ria intensiva no quesito qualidade e inova\u00e7\u00e3o no Brasil e, em 2024, novas unidades pr\u00f3prias e franqueadas ser\u00e3o inauguradas em Araraquara, S\u00e3o Jos\u00e9 dos Campos, Uberl\u00e2ncia e Piracicaba.<\/p>\n<p><\/p>\n<p>\u267b Nosso hospital vive sob a cultura de aprendizagem, com valoriza\u00e7\u00e3o de stakeholders e com as melhores tecnologias do mercado para que a assist\u00eancia m\u00e9dica veterin\u00e1ria seja eficiente.<\/p>\n<p><\/p>\n<p>Venha trabalhar conosco! \ud83d\ude91<\/p>\n<\/div>\n<\/section>\n<section aria-label=\"Se\u00e7\u00e3o de v\u00eddeos\" data-testid=\"video-section\" class=\"sc-ed722fcc-0 ifqNqA\">\n<h2 data-testid=\"section-Veja como \u00e9 o modelo assistencial do Hospital VFP-title\" class=\"sc-6fde0c52-0 haCHdH\">Veja como \u00e9 o modelo assistencial do Hospital VFP<\/h2>\n<div class=\"sc-ed722fcc-1 jDKGiy\"><iframe data-testid=\"video-iframe\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/aFGFfjWS_40?hl=pt\" title=\"V\u00eddeo sobre a empresa 1\" width=\"100%\" class=\"sc-ed722fcc-2 kGunFs\"><\/iframe><\/div>\n<\/section>\n<section data-testid=\"gallery\">\n<h2 data-testid=\"section-Nossos pilares estrat\u00e9gicos-title\" class=\"sc-6fde0c52-0 haCHdH\">Nossos pilares estrat\u00e9gicos<\/h2>\n<div data-testid=\"section-Nossos pilares estrat\u00e9gicos-description\" class=\"sc-6fde0c52-1 iAgJhf\"><\/p>\n<p><strong>Conhecimento T\u00e9cnico<\/strong><\/p>\n<p><\/p>\n<p>Profissionais com certifica\u00e7\u00f5es peri\u00f3dicas para o exerc\u00edcio da sua fun\u00e7\u00e3o<\/p>\n<p><\/p>\n<p>Auditoria di\u00e1ria de prontu\u00e1rios<\/p>\n<p><\/p>\n<p>Promo\u00e7\u00e3o de cursos e eventos nas \u00e1reas de anestesiologia, terapia intensiva, cl\u00ednica cir\u00fargica e cl\u00ednica m\u00e9dica<\/p>\n<p><\/p>\n<p>Subs\u00eddio aos profissionais para realiza\u00e7\u00e3o de cursos de p\u00f3s-gradua\u00e7\u00e3o e educa\u00e7\u00e3o continuada<\/p>\n<p><\/p>\n<p>Treinamentos t\u00e9cnicos de entrada e reciclagens peri\u00f3dicas em todos os setores do hospital<\/p>\n<p><strong>Comunica\u00e7\u00e3o<\/strong><\/p>\n<p><\/p>\n<p>Sistema de comunica\u00e7\u00e3o pr\u00f3prio para gerir encaminhamentos<\/p>\n<p><\/p>\n<p>An\u00e1lise de liga\u00e7\u00f5es telef\u00f4nicas para promo\u00e7\u00e3o de treinamentos<\/p>\n<p><\/p>\n<p>Padroniza\u00e7\u00e3o de boletins para aumentar efici\u00eancia na troca de plant\u00f5es<\/p>\n<p><\/p>\n<p>Reuni\u00f5es individuais para alinhamento de expectativas<\/p>\n<p><\/p>\n<p>Reuni\u00f5es coletivas para o desenvolvimento da comunica\u00e7\u00e3o de alta performance<\/p>\n<p><\/p>\n<p>Treinamento di\u00e1rio do senso de urg\u00eancia<\/p>\n<p><strong>Limpeza e Organiza\u00e7\u00e3o<\/strong><\/p>\n<p><\/p>\n<p>Treinamento constante para manuten\u00e7\u00e3o de ambiente limpo e organizado com o objetivo de se tornar mais produtivo<\/p>\n<p><\/p>\n<p>Execu\u00e7\u00e3o de checklist de reposi\u00e7\u00e3o, manuten\u00e7\u00e3o e organiza\u00e7\u00e3o de itens e equipamentos<\/p>\n<p><\/p>\n<p>Treinamento especializado para equipe de limpeza com o objetivo de controle de infec\u00e7\u00e3o hospitalar<\/p>\n<p><\/p>\n<p>Auditoria de limpeza hospitalar com realiza\u00e7\u00e3o de mapa microbiol\u00f3gico<\/p>\n<\/div>\n<section aria-hidden=\"true\" class=\"sc-ee78b7b3-3 bVEXQO\">\n<div data-testid=\"mainImage\" role=\"img\" class=\"sc-ee78b7b3-0 ggxLIU\"><\/div>\n<\/section>\n<\/section>\n<section data-testid=\"job-list\" id=\"job-listing\" class=\"sc-f5007364-1 hRVHMy\">\n<h2 data-testid=\"section-Nossas oportunidades-title\" class=\"sc-6fde0c52-0 haCHdH\">Nossas oportunidades<\/h2>\n<div data-testid=\"old-job-filters\">\n<form aria-label=\"Busca de Vagas\" data-testid=\"job-search-form\" class=\"sc-d52d7ce9-0 gnWcBe\"><label for=\"job-search\" class=\"sc-d52d7ce9-1 bBVWZj\">Busca de Vagas<\/label><span role=\"searchbox\" aria-label=\"jobSearchFilterLabel\" class=\"sc-bbpGSz dLHSKU\"><input type=\"input\" data-testid=\"job-search\" label=\"jobSearchFilterLabel\" name=\"jobSearch\" placeholder=\"Digite o nome da vaga\" value=\"\" id=\"job-search\" aria-labelledby=\"input-job-search\" aria-describedby=\"react-aria-3 react-aria-4\" class=\"sc-jItqcz sc-UxxwN jsApaO bMvAsC\"><button aria-labelledby=\"job-search\" class=\"sc-irTswW boqOgV sc-jJgynQ jjsrBz\" id=\"job-search-button\"><\/p>\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M15.5 14h-.79l-.28-.27C15.41 12.59 16 11.11 16 9.5 16 5.91 13.09 3 9.5 3S3 5.91 3 9.5 5.91 16 9.5 16c1.61 0 3.09-.59 4.23-1.57l.27.28v.79l5 4.99L20.49 19l-4.99-5zm-6 0C7.01 14 5 11.99 5 9.5S7.01 5 9.5 5 14 7.01 14 9.5 11.99 14 9.5 14z\"><\/path><\/svg><\/div>\n<p><\/button><\/span><\/form>\n<form aria-label=\"Op\u00e7\u00f5es de Filtro de Vaga\" class=\"sc-d52d7ce9-2 fREpEo\">\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todas\" id=\"label-job-types\" for=\"job-types\" class=\"sc-brKeYL dtexMX\">Tipo de Vaga<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-413551-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-413551-placeholder\">Todas<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-types\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-types\" role=\"combobox\" aria-describedby=\"react-select-413551-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"jobTypesFilter\" value=\"\"><\/div>\n<\/div>\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todos\" id=\"label-job-workplaces\" for=\"job-workplaces\" class=\"sc-brKeYL dtexMX\">Locais de Trabalho<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-413552-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-413552-placeholder\">Todos<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-workplaces\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-workplaces\" role=\"combobox\" aria-describedby=\"react-select-413552-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"workplacesFilter\" value=\"\"><\/div>\n<\/div>\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todas\" id=\"label-job-departments\" for=\"job-departments\" class=\"sc-brKeYL dtexMX\">\u00c1reas<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-413553-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-413553-placeholder\">Todas<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-departments\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-departments\" role=\"combobox\" aria-describedby=\"react-select-413553-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"departmentsFilter\" value=\"\"><\/div>\n<\/div>\n<\/form>\n<\/div>\n<div class=\"sc-f5007364-7 cYAFjr\">\n<div role=\"status\" class=\"sc-f5007364-0 cDdpev\">13 vagas encontradas para 0 filtros aplicados<\/div>\n<div aria-hidden=\"true\" data-testid=\"job-list-amount\" class=\"sc-f5007364-8 dCDcPy\">13 vagas<\/div>\n<div class=\"sc-f5007364-8 dCDcPy\">\n<div class=\"sc-4284ca6f-3 iPhDzt\">\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"10\" id=\"label-items-por-pagina\" for=\"items-por-pagina\" class=\"sc-brKeYL dtexMX\">Itens por p\u00e1gina<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-413554-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-413554-placeholder\">10<\/div>\n<style data-emotion=\"css 1hac4vs-dummyInput\">.css-1hac4vs-dummyInput{background:0;border:0;caret-color:transparent;font-size:inherit;grid-area:1\/1\/2\/3;outline:0;padding:0;width:1px;color:transparent;left:-100px;opacity:0;position:relative;-webkit-transform:scale(.01);-moz-transform:scale(.01);-ms-transform:scale(.01);transform:scale(.01);}<\/style>\n<p><input id=\"items-por-pagina\" tabindex=\"0\" inputmode=\"none\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-items-por-pagina\" role=\"combobox\" aria-readonly=\"true\" aria-describedby=\"react-select-413554-placeholder\" class=\"css-1hac4vs-dummyInput\"><\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"items-por-pagina\" value=\"\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<ul aria-label=\"Lista de Vagas\" data-testid=\"job-list__list\">\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar Administrativo Junior em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6613413?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">Auxiliar Administrativo Junior<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar de Limpeza Hospitalar (Araraquara) em Araraquara - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531704?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">Auxiliar de Limpeza Hospitalar (Araraquara)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Araraquara &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar de Limpeza Hospitalar (Ribeir\u00e3o Preto) em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531703?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">Auxiliar de Limpeza Hospitalar (Ribeir\u00e3o Preto)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar Veterin\u00e1rio(a) (Araraquara) em Araraquara - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531700?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">Auxiliar Veterin\u00e1rio(a) (Araraquara)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Araraquara &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar Veterin\u00e1rio(a) (Ribeir\u00e3o Preto) em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531699?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">Auxiliar Veterin\u00e1rio(a) (Ribeir\u00e3o Preto)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como M\u00e9dico(a) Veterin\u00e1rio(a) de Atendimento (Araraquara) em Araraquara - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531690?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">M\u00e9dico(a) Veterin\u00e1rio(a) de Atendimento (Araraquara)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Araraquara &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como M\u00e9dico(a) Veterin\u00e1rio(a) de Atendimento (Ribeir\u00e3o Preto) em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531676?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">M\u00e9dico(a) Veterin\u00e1rio(a) de Atendimento (Ribeir\u00e3o Preto)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como M\u00e9dico(a) Veterin\u00e1rio(a) de Prescri\u00e7\u00e3o (Araraquara) em Araraquara - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531695?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">M\u00e9dico(a) Veterin\u00e1rio(a) de Prescri\u00e7\u00e3o (Araraquara)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Araraquara &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como M\u00e9dico(a) Veterin\u00e1rio(a) de Prescri\u00e7\u00e3o (Ribeir\u00e3o Preto) em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531692?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">M\u00e9dico(a) Veterin\u00e1rio(a) de Prescri\u00e7\u00e3o (Ribeir\u00e3o Preto)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como M\u00e9dico(a) Veterin\u00e1rio(a) de UTI (Araraquara) em Araraquara - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531697?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">M\u00e9dico(a) Veterin\u00e1rio(a) de UTI (Araraquara)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Araraquara &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como M\u00e9dico(a) Veterin\u00e1rio(a) de UTI (Ribeir\u00e3o Preto) em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531696?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">M\u00e9dico(a) Veterin\u00e1rio(a) de UTI (Ribeir\u00e3o Preto)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Recepcionista Hospitalar (Araraquara) em Araraquara - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531702?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">Recepcionista Hospitalar (Araraquara)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Araraquara &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Recepcionista Hospitalar (Ribeir\u00e3o Preto) em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531701?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">Recepcionista Hospitalar (Ribeir\u00e3o Preto)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<\/ul>\n<div class=\"sc-f5007364-9 gXOSFh\">\n<nav aria-label=\"Pagina\u00e7\u00e3o do resultado da busca\">\n<ul class=\"sc-llcuoN bHIMne\">\n<li class=\"sc-jnsZEu dVzXoV\"><button data-testid=\"pagination-prev-button\" aria-disabled=\"false\" aria-label=\"V\u00e1 para p\u00e1gina anterior\" class=\"sc-hsiEis fXWJKC\">\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M15.41 7.41L14 6l-6 6 6 6 1.41-1.41L10.83 12z\"><\/path><\/svg><\/div>\n<p><\/button><\/li>\n<li class=\"sc-jnsZEu dVzXoV\"><button data-testid=\"pagination-next-button\" aria-disabled=\"false\" aria-label=\"V\u00e1 para pr\u00f3xima p\u00e1gina\" class=\"sc-hsiEis fXWJKC\">\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M10 6L8.59 7.41 13.17 12l-4.58 4.59L10 18l6-6z\"><\/path><\/svg><\/div>\n<p><\/button><\/li>\n<\/ul>\n<\/nav>\n<\/div>\n<\/section>\n<p><a aria-label=\"Central de ajuda Gupy para pessoas candidatas\" data-testid=\"help-button\" rel=\"noreferrer noopener\" href=\"https:\/\/support-candidates.gupy.io\/hc\/pt-br\" class=\"sc-645a84e3-0 dCWYzQ\" target=\"_blank\">?<\/a><\/main><\/p>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar Administrativo Junior em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6613413?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">Auxiliar Administrativo Junior<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar de Limpeza Hospitalar (Araraquara) em Araraquara - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vfphospitalveterinario.gupy.io\/jobs\/6531704?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 fuEmEw\">Auxiliar de Limpeza Hospitalar (Araraquara)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Araraquara &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Breve hist\u00f3rico do Hospital VFP O Hospital Veterin\u00e1rio VFP \u00e9 um hospital de apoio ao m\u00e9dico veterin\u00e1rio, foi inaugurado em julho do ano de 2020 com 5 colaboradores contratados apenas, al\u00e9m dos dois s\u00f3cios administradores. Em menos de dois anos, a empresa j\u00e1 contava com uma equipe de mais de 30 colaboradores. Em junho de &#8230; <a title=\"Auxiliar Veterin\u00e1rio(a) (Araraquara)\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/17\/auxiliar-veterinarioa-araraquara-2\/\" aria-label=\"Leia mais sobre Auxiliar Veterin\u00e1rio(a) (Araraquara)\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":42836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-42835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas-de-empregos-em-ribeirao-preto-regiao-brasil"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGA.jpg?fit=960%2C960&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGA.jpg?fit=960%2C960&ssl=1",960,960,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGA.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGA.jpg?fit=300%2C300&ssl=1",300,300,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGA.jpg?fit=768%2C768&ssl=1",768,768,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGA.jpg?fit=960%2C960&ssl=1",960,960,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGA.jpg?fit=960%2C960&ssl=1",960,960,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGAISMAELCOLOSIVAGAVAGA.jpg?fit=960%2C960&ssl=1",960,960,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"Breve hist\u00f3rico do Hospital VFP O Hospital Veterin\u00e1rio VFP \u00e9 um hospital de apoio ao m\u00e9dico veterin\u00e1rio, foi inaugurado em julho do ano de 2020 com 5 colaboradores contratados apenas, al\u00e9m dos dois s\u00f3cios administradores. Em menos de dois anos, a empresa j\u00e1 contava com uma equipe de mais de 30 colaboradores. Em junho de&hellip;","jetpack-related-posts":[{"id":80476,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/26\/recepcionista-hospitalar-ribeirao-preto-4\/","url_meta":{"origin":42835,"position":0},"title":"Recepcionista Hospitalar (Ribeir\u00e3o Preto)","author":"ismaelcolosi.com.br","date":"26 de Dezembro de 2024","format":false,"excerpt":"Recepcionista Hospitalar (Ribeir\u00e3o Preto) Publicada em 09 de outubro de 2024 Inscri\u00e7\u00f5es abertas at\u00e9 31 de janeiro de 2025 Local de trabalho: Ribeir\u00e3o Preto - SPRibeir\u00e3o Preto - SP Tipo de vaga: EfetivoEfetivo Modelo de trabalho: PresencialPresencial Descri\u00e7\u00e3o da vaga \ud83c\udfe5O Hospital VFP \u00e9 tido como refer\u00eancia na medicina veterin\u00e1ria\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":69660,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/07\/veja-as-vagas-de-empregos-para-trabalhar-no-hospital-veterinario-vfp-em-ribeirao-preto-sp-14\/","url_meta":{"origin":42835,"position":1},"title":"Veja as vagas de empregos para trabalhar no Hospital Veterin\u00e1rio VFP em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"7 de Outubro de 2024","format":false,"excerpt":"Breve hist\u00f3rico do Hospital VFPO Hospital Veterin\u00e1rio VFP \u00e9 um hospital de apoio ao m\u00e9dico veterin\u00e1rio, foi inaugurado em julho do ano de 2020 com 5 colaboradores contratados apenas, al\u00e9m dos dois s\u00f3cios administradores. Em menos de dois anos, a empresa j\u00e1 contava com uma equipe de mais de 30\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/vfp-hospital-veterinario-1.png?fit=500%2C499&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":73695,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/28\/veja-as-vagas-de-empregos-para-trabalhar-no-hospital-veterinario-vfp-em-ribeirao-preto-sp-15\/","url_meta":{"origin":42835,"position":2},"title":"Veja as vagas de empregos para trabalhar no Hospital Veterin\u00e1rio VFP em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"28 de Outubro de 2024","format":false,"excerpt":"Breve hist\u00f3rico do Hospital VFPO Hospital Veterin\u00e1rio VFP \u00e9 um hospital de apoio ao m\u00e9dico veterin\u00e1rio, foi inaugurado em julho do ano de 2020 com 5 colaboradores contratados apenas, al\u00e9m dos dois s\u00f3cios administradores. Em menos de dois anos, a empresa j\u00e1 contava com uma equipe de mais de 30\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730126697_vfp-hospital-veterinario-1.png?fit=500%2C499&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":82746,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/02\/10\/veja-as-vagas-de-empregos-para-trabalhar-no-hospital-veterinario-vfp-em-ribeirao-preto-sp-20\/","url_meta":{"origin":42835,"position":3},"title":"Veja as vagas de empregos para trabalhar no Hospital Veterin\u00e1rio VFP em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"10 de Fevereiro de 2025","format":false,"excerpt":"Breve hist\u00f3rico do Hospital VFPO Hospital Veterin\u00e1rio VFP \u00e9 um hospital de apoio ao m\u00e9dico veterin\u00e1rio, foi inaugurado em julho do ano de 2020 com 5 colaboradores contratados apenas, al\u00e9m dos dois s\u00f3cios administradores. Em menos de dois anos, a empresa j\u00e1 contava com uma equipe de mais de 30\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/vfp-hospital-veterinario-1.png?fit=500%2C499&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":76819,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/18\/veja-as-vagas-de-empregos-para-trabalhar-no-hospital-veterinario-vfp-em-ribeirao-preto-sp-16\/","url_meta":{"origin":42835,"position":4},"title":"Veja as vagas de empregos para trabalhar no Hospital Veterin\u00e1rio VFP em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"18 de Novembro de 2024","format":false,"excerpt":"Breve hist\u00f3rico do Hospital VFPO Hospital Veterin\u00e1rio VFP \u00e9 um hospital de apoio ao m\u00e9dico veterin\u00e1rio, foi inaugurado em julho do ano de 2020 com 5 colaboradores contratados apenas, al\u00e9m dos dois s\u00f3cios administradores. Em menos de dois anos, a empresa j\u00e1 contava com uma equipe de mais de 30\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/vfp-hospital-veterinario-1.png?fit=500%2C499&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":54277,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/24\/veja-as-vagas-de-empregos-para-trabalhar-no-hospital-veterinario-vfp-em-ribeirao-preto-sp-9\/","url_meta":{"origin":42835,"position":5},"title":"Veja as vagas de empregos para trabalhar no Hospital Veterin\u00e1rio VFP em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"24 de Junho de 2024","format":false,"excerpt":"Breve hist\u00f3rico do Hospital VFPO Hospital Veterin\u00e1rio VFP \u00e9 um hospital de apoio ao m\u00e9dico veterin\u00e1rio, foi inaugurado em julho do ano de 2020 com 5 colaboradores contratados apenas, al\u00e9m dos dois s\u00f3cios administradores. Em menos de dois anos, a empresa j\u00e1 contava com uma equipe de mais de 30\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/1719235782_vfp-hospital-veterinario-1.png?fit=500%2C499&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-b8T","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=42835"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/42836"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=42835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=42835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=42835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}