{"id":42412,"date":"2024-03-14T13:24:30","date_gmt":"2024-03-14T16:24:30","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/14\/kiko-zambianchi-faz-show-beneficente\/"},"modified":"2024-03-14T13:24:30","modified_gmt":"2024-03-14T16:24:30","slug":"kiko-zambianchi-faz-show-beneficente","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/14\/kiko-zambianchi-faz-show-beneficente\/","title":{"rendered":"Kiko Zambianchi faz show beneficente \u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p><span data-contrast=\"auto\">A Casa das Mangueiras \u00e9 mantida com apoio institucional e financeiro de toda a sociedade civil e poder p\u00fablico, al\u00e9m de estrat\u00e9gias de gera\u00e7\u00e3o de receita pr\u00f3pria. O projeto Ritmo do Bem, por exemplo, nasceu para colaborar com as atividades da institui\u00e7\u00e3o. <\/span><\/p>\n<p><span data-contrast=\"auto\">Para isso, Ribeir\u00e3o Preto receber\u00e1 nesta quinta-feira, 14 de mar\u00e7o, \u00e0s 20 horas, uma noite de show beneficente com o cantor e compositor Kiko Zambianchi e as participa\u00e7\u00f5es especiais de Rod Hanna (Rodrigo Laguna e Nora Hanna) e do m\u00fasico \u00c1lvaro Petersen.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">As hist\u00f3rias de vida e carreiras profissionais dos artistas est\u00e3o interligadas com a m\u00fasica, a amizade entre eles e a cidade de Ribeir\u00e3o Preto. Toda essa sinergia movimentar\u00e1 o show beneficente no Espa\u00e7o Bella Citt\u00e0, em prol da Casa das Mangueiras.<\/span><\/p>\n<p><span data-contrast=\"auto\">Todos s\u00e3o artistas da \u201ccasa\u201d\u2019 e com carreiras s\u00f3lidas projetadas nacionalmente. Kiko Zambianchi \u00e9 quem comandar\u00e1 o show solid\u00e1rio, recebendo no palco Rod Hanna e \u00c1lvaro Petersen como convidados especiais, para uma noite em que o setlist promete a mistura de m\u00fasicas j\u00e1 consagradas e de novos singles passeando pela MPB, black music, pop rock nacional e disco music.<\/span><\/p>\n<p><span data-contrast=\"auto\">\u201cSer\u00e1 um grande show, juntamente com grandes amigos, parceiros da m\u00fasica e em especial todos ribeir\u00e3o-pretanos. \u00c1lvaro Petersen \u00e9 um parceiro meu de longa data. A gente teve banda aqui em Ribeir\u00e3o, chamava \u2018Vida de Rua\u2019, muitos anos atr\u00e1s\u201d, diz Kiko Zambianchi. <\/span><\/p>\n<p><span data-contrast=\"auto\">\u201cAtualmente, estamos realizando um trabalho juntos com composi\u00e7\u00f5es para uma produtora na Fran\u00e7a. Outro convidado especial ser\u00e1 a banda Rod Hanna, conhecida por todo mundo. Produzi o primeiro CD deles e eles sempre me convidaram para participar dos shows. Dessa vez, o convite \u00e9 meu e eles aceitaram participar deste projeto especial\u201d, comenta o artista.<\/span><\/p>\n<p><span data-contrast=\"auto\">Toda renda obtida pelo evento ser\u00e1 100% destinada \u00e0 Casa das Mangueiras, que desenvolve um trabalho social com crian\u00e7as e adolescentes h\u00e1 50 anos. Os ingressos do show podem ser adquiridos pelo valor de R$ 80 no pr\u00f3prio site (<\/span><a href=\"https:\/\/www.instagram.com\/ritmodobem.rp\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">https:\/\/www.instagram.com\/ritmodobem.rp\/<\/span><\/a><span data-contrast=\"auto\">) e, tamb\u00e9m, diretamente na Casa das Mangueiras.<\/span><\/p>\n<p><span data-contrast=\"auto\">Fica na rua Tupinamb\u00e1 n\u00ba 1.457, Vila Recreio, Ribeir\u00e3o Preto, de segunda a sexta-feira, das 7h30 \u00e0s 17 horas, e na loja Arezzo da avenida Presidente Vargas n\u00ba 551, Jardim Sumar\u00e9. O Espa\u00e7o Bella Citt\u00e0 fica no quil\u00f4metro 304 da Rodovia Anhanguera (SP-330), no Jardim Manoel Penna, Zona Leste de Ribeir\u00e3o Preto<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Kiko Zambianchi \u2013 <\/span><\/b><span data-contrast=\"auto\">Com mais de 35 anos de carreira, o cantor, guitarrista e compositor ribeir\u00e3o-pretano Kiko Zambianchi \u00e9 autor de grandes hits da MPB e do pop rock nacional. Desde que estreou musicalmente com o disco \u201cChoque\u201d, lan\u00e7ado pela gravadora EMI em 1985, viu diversas de suas can\u00e7\u00f5es transformadas em temas para programas televisivos. <\/span><\/p>\n<p><span data-contrast=\"auto\">Ficou conhecido, ainda, por composi\u00e7\u00f5es gravadas por Marina Lima, Lulu Santos, Ira!, Paulo Ricardo, Erasmo Carlos e Capital Inicial \u2013 parceria em que Kiko fez os arranjos para o Ac\u00fastico MTV da banda brasiliense, que tamb\u00e9m gravou o hit \u201cPrimeiros Erros\u201d, sucesso de 1985. <\/span><\/p>\n<p><span data-contrast=\"auto\">Outras m\u00fasicas consagradas do artista s\u00e3o \u201cRolam as Pedras\u201d e \u201cEu Te Amo Voc\u00ea\u201d. No final do ano passado, Zambianchi lan\u00e7ou o novo single \u201cQuero Viver a Vida\u201d. A can\u00e7\u00e3o foi inspirada no per\u00edodo de isolamento da pandemia da covid-19. A faixa incorpora influ\u00eancias da black music, apresentando uma pegada Motown, ao mesmo tempo flerta com a MPB.<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Rod Hanna \u2013 <\/span><\/b><span data-contrast=\"auto\">Mesmo com as mudan\u00e7as que ocorreram na hist\u00f3ria da m\u00fasica ao longo dos anos, h\u00e1 g\u00eaneros que sempre permanecem vivos, como o disco music, estilo que esteve no auge na d\u00e9cada de 1970 e foi nome certo nos flashbacks desde ent\u00e3o. \u00c9 tamb\u00e9m este g\u00eanero que faz parte do DNA da banda Rod Hanna. <\/span><\/p>\n<p><span data-contrast=\"auto\">Formada pelo casal ribeir\u00e3o-pretano Rodrigo Laguna e Nora Hanna, o grupo est\u00e1 na estrada h\u00e1 mais de 30 anos e \u00e9 considerado como um dos mais completos e perform\u00e1ticos do mundo da disco music. No show, grandes sucessos dos anos 1970 de bandas como ABBA, Bee Gees, Kool and the Gang e Donna Summer.<\/span><\/p>\n<p><span data-contrast=\"auto\">Dos anos 80 \u00e3 Vanda trar\u00e1 Erasure, Madonna e A-h\u00e1; e dos anos 90 Cher, Spice Girls e Backstreet Boys, al\u00e9m de tributos especais ao grupo Queen, Rita Lee, Roberto Carlos e Tim Maia. Com sete \u00e1lbuns lan\u00e7ados, a banda Rod Hanna est\u00e1 em atividade desde 1994. O primeiro CD do grupo foi produzido pelo m\u00fasico Kiko Zambianchi.<\/span><\/p>\n<p><b><span data-contrast=\"auto\">\u00c1lvaro Petersen \u2013 <\/span><\/b><span data-contrast=\"auto\">A arte est\u00e1 presente na vida de \u00c1lvaro Petersen desde sempre. O ribeir\u00e3o-pretano deixou a cidade na adolesc\u00eancia e partiu para Campinas para os estudos universit\u00e1rios, onde tamb\u00e9m participou da banda Luz Azul, nos anos 90. No entanto, o contato com m\u00fasicas e artistas veio ainda na juventude, em Ribeir\u00e3o Preto. <\/span><\/p>\n<p><span data-contrast=\"auto\">Petersen participou de um concurso em um col\u00e9gio onde conheceu o amigo Kiko Zambianchi. Os dois formaram a banda \u201cVida de Rua\u201d. Ele tamb\u00e9m deu vida, movimentos e vozes a personagens como, por exemplo, a Celeste e Godofredo, do Castelo R\u00e1-Tim-Bum, da TV Cultura, por 27 anos, dentre outros. <\/span><\/p>\n<p><span data-contrast=\"auto\">Em 2012 e 2014, \u00c1lvaro Petersen lan\u00e7ou dois discos com m\u00fasicas autorais. Uma delas leva o nome da \u00e1rvore \u201cSibipiruna\u201d, com inspira\u00e7\u00e3o da esp\u00e9cie nativa do Brasil localizada na avenida Nove de Julho, em Ribeir\u00e3o Preto. Al\u00e9m de m\u00fasico, Petersen \u00e9 compositor, ator, produtor e professor de dire\u00e7\u00e3o de arte.<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Servi\u00e7o<\/span><\/b><br \/><b><span data-contrast=\"auto\">Show<\/span><\/b><span data-contrast=\"auto\">: projeto <\/span>\u00a0<span data-contrast=\"auto\">Ritmo do Bem<\/span> <b><span data-contrast=\"auto\">(Casa das <\/span><\/b>\u00a0<b><span data-contrast=\"auto\">Mangueiras)<\/span><\/b><br \/><b><span data-contrast=\"auto\">Com<\/span><\/b><span data-contrast=\"auto\">: Kiko <\/span>\u00a0<span data-contrast=\"auto\">Zambianchi, Rod <\/span>\u00a0<span data-contrast=\"auto\">Hanna e \u00c1lvaro <\/span>\u00a0<span data-contrast=\"auto\">Petersen<\/span><br \/><b><span data-contrast=\"auto\">Quando:<\/span><\/b><span data-contrast=\"auto\"> quinta-feira,<\/span> <span data-contrast=\"auto\">14 de mar\u00e7o<\/span><br \/><b><span data-contrast=\"auto\">Hor\u00e1rio:<\/span><\/b><span data-contrast=\"auto\"> \u00e0s 20<\/span> <span data-contrast=\"auto\">horas<\/span><br \/><b><span data-contrast=\"auto\">Onde:<\/span><\/b><span data-contrast=\"auto\"> Espa\u00e7o <\/span>\u00a0<span data-contrast=\"auto\">Bella Citt\u00e0 <\/span><br \/><span data-contrast=\"auto\">Endere\u00e7o: km 304 da <\/span>\u00a0<span data-contrast=\"auto\">Rodovia Anhanguera, <\/span>\u00a0<span data-contrast=\"auto\">Jardim Manoel Penna<\/span><br \/><b><span data-contrast=\"auto\">Ingresso:<\/span><\/b><span data-contrast=\"auto\"> R$ 80<\/span><br \/><b><span data-contrast=\"auto\">Vendas:<\/span><\/b><span data-contrast=\"auto\"> Casa das <\/span>\u00a0<span data-contrast=\"auto\">Mangueiras, loja <\/span><br \/><span data-contrast=\"auto\">Arezzo e site<\/span> <a href=\"https:\/\/www.instagram.com\/ritmodobem.rp\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">https:\/\/www.instagram.com\/ritmodobem.rp\/<\/span><\/a><br \/><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/kiko-zambianchi-faz-show-beneficente\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Casa das Mangueiras \u00e9 mantida com apoio institucional e financeiro de toda a sociedade civil e poder p\u00fablico, al\u00e9m de estrat\u00e9gias de gera\u00e7\u00e3o de receita pr\u00f3pria. O projeto Ritmo do Bem, por exemplo, nasceu para colaborar com as atividades da institui\u00e7\u00e3o. Para isso, Ribeir\u00e3o Preto receber\u00e1 nesta quinta-feira, 14 de mar\u00e7o, \u00e0s 20 &#8230; <a title=\"Kiko Zambianchi faz show beneficente \u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/14\/kiko-zambianchi-faz-show-beneficente\/\" aria-label=\"Leia mais sobre Kiko Zambianchi faz show beneficente \u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":42413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[5017,365,4701,360,4702],"class_list":["post-42412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-beneficente","tag-faz","tag-kiko","tag-show","tag-zambianchi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=966%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=966%2C645&ssl=1",966,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=768%2C513&ssl=1",768,513,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=966%2C645&ssl=1",966,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=966%2C645&ssl=1",966,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=966%2C645&ssl=1",966,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Casa das Mangueiras \u00e9 mantida com apoio institucional e financeiro de toda a sociedade civil e poder p\u00fablico, al\u00e9m de estrat\u00e9gias de gera\u00e7\u00e3o de receita pr\u00f3pria. O projeto Ritmo do Bem, por exemplo, nasceu para colaborar com as atividades da institui\u00e7\u00e3o. Para isso, Ribeir\u00e3o Preto receber\u00e1 nesta quinta-feira, 14 de mar\u00e7o, \u00e0s 20&hellip;","jetpack-related-posts":[{"id":41191,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/06\/ritmo-do-bem-kiko-zambianchi-traz-classicos-nacionais-em-show-em-ribeirao-preto\/","url_meta":{"origin":42412,"position":0},"title":"Kiko Zambianchi traz cl\u00e1ssicos nacionais em show em Ribeir\u00e3o Preto \u2013 Portal Popito","author":"ismaelcolosi.com.br","date":"6 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Rod Hanna e \u00c1lvaro Petersen far\u00e3o participa\u00e7\u00e3o especial com setlist que misturar\u00e1 MBP, pop rock e disco music; todos eles, artistas da \u2018casa\u2019, se unem em evento beneficente em prol da Casa das Mangueiras no dia 14 de mar\u00e7o. Ingressos est\u00e3o \u00e0 venda As hist\u00f3rias de vida e carreiras\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40156,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/01\/kiko-zambianchi-faz-show-beneficente-em-ribeirao-preto-saiba-como-participar\/","url_meta":{"origin":42412,"position":1},"title":"Kiko Zambianchi faz show beneficente em Ribeir\u00e3o Preto; Saiba como participar","author":"ismaelcolosi.com.br","date":"1 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O cantor e compositor ribeir\u00e3o-pretano Kiko Zambianchi faz show beneficente com participa\u00e7\u00e3o especial de Rod Hanna e \u00c1lvaro Petersen, no dia 14 de mar\u00e7o, em Ribeir\u00e3o Preto. A apresenta\u00e7\u00e3o musical e a\u00e7\u00e3o de solidariedade faz parte do Projeto \u201cRitmo do Bem\u201d, que tem como objetivo levantar fundos para a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41840,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/veja-como-comprar-ingresso-para-o-show-beneficente-de-kiko-zambianchi-em-ribeirao\/","url_meta":{"origin":42412,"position":2},"title":"Veja como comprar ingresso para o show beneficente de Kiko Zambianchi em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"11 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O show beneficente do cantor e compositor ribeir\u00e3o-pretano Kiko Zambianchi acontece nesta quinta-feira (14) com participa\u00e7\u00e3o especial de Rod Hanna e \u00c1lvaro Petersen. O event ser\u00e1 \u00e0s 20h, no espa\u00e7o Bella Citt\u00e0 em Ribeir\u00e3o Preto. A apresenta\u00e7\u00e3o musical e a\u00e7\u00e3o solid\u00e1ria faz parte do projeto \u201cRitmo do Bem\u201d, que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40402,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/03\/kiko-zambianchi-e-rod-hanna-no-ritmo-do-bem\/","url_meta":{"origin":42412,"position":3},"title":"Kiko Zambianchi e Rod Hanna no Ritmo do Bem\u00a0","author":"ismaelcolosi.com.br","date":"3 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] No pr\u00f3ximo dia 14 de mar\u00e7o, \u00e0s 20 horas, no Espa\u00e7o Bella Citt\u00e0, em Ribeir\u00e3o Preto, acontece show do cantor ribeir\u00e3o-pretano Kiko Zambianchi e as participa\u00e7\u00f5es especiais de Rod Hanna e do m\u00fasico \u00c1lvaro Petersen. Toda renda obtida ser\u00e1 integralmente destinada para a Casa das Mangueiras. A apresenta\u00e7\u00e3o faz\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=800%2C532&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=800%2C532&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=800%2C532&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=800%2C532&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43062,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/19\/projeto-ritmo-do-bem\/","url_meta":{"origin":42412,"position":4},"title":"Projeto \u201cRitmo do Bem\u201d &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"19 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 19 de mar\u00e7o de 2024 | 9:0318 de mar\u00e7o de 2024 | 13:04 0O projeto \u201cRitmo do Bem\u201d realizdo no Espa\u00e7o Bella Citt\u00e0, em benef\u00edcio da Casa das Mangueiras, com o cantor Kiko Zambianchi e a participa\u00e7\u00e3o de convidados especiais como a banda Hod Hanna e o m\u00fasico \u00c1lvaro\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":48890,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/kiko-zambianchi-participa-da-escolha-de-semifinalistas-do-concurso-epra-cantar\/","url_meta":{"origin":42412,"position":5},"title":"Kiko Zambianchi participa da escolha de semifinalistas do concurso \u2018\u00c9Pra Cantar\u2019","author":"ismaelcolosi.com.br","date":"7 de Maio de 2024","format":false,"excerpt":"[ad_1] O cantor e compositor ribeir\u00e3o-pretano Kiko Zambianchi foi um dos jurados que definiu presencialmente na segunda-feira (6), os 20 semifinalistas do concurso musical \u201c\u00c9Pra Cantar\u201d, realizado pela EPTV, afiliada da Rede Globo. A escolha dos candidatos que seguir\u00e3o na disputa do concurso aconteceu na sede da EPTV Campinas e,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-06_21-49-33_jpg_2024-05-06_21-49-34.webp.webp?fit=779%2C430&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-06_21-49-33_jpg_2024-05-06_21-49-34.webp.webp?fit=779%2C430&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-06_21-49-33_jpg_2024-05-06_21-49-34.webp.webp?fit=779%2C430&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-06_21-49-33_jpg_2024-05-06_21-49-34.webp.webp?fit=779%2C430&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-b24","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=42412"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/42413"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=42412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=42412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=42412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}