{"id":42114,"date":"2024-03-12T21:52:28","date_gmt":"2024-03-13T00:52:28","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/12\/oswaldo-montenegro-celebra-50-anos-de-carreira-com-turne-especial-em-ribeirao-preto\/"},"modified":"2024-03-12T21:52:28","modified_gmt":"2024-03-13T00:52:28","slug":"oswaldo-montenegro-celebra-50-anos-de-carreira-com-turne-especial-em-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/12\/oswaldo-montenegro-celebra-50-anos-de-carreira-com-turne-especial-em-ribeirao-preto\/","title":{"rendered":"Oswaldo Montenegro celebra 50 anos de carreira com turn\u00ea especial em Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_101\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>O cantor e compositor <strong>Oswaldo Montenegro<\/strong> vem a <strong>Ribeir\u00e3o Preto<\/strong> com o show \u2018<strong>Celebrando 50 anos de Estrada<\/strong>\u2019, no dia 25 de maio, no <strong>Theatro Pedro II<\/strong>, no Centro da cidade.<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>Os ingressos podem ser adquiridos on-line (<a href=\"https:\/\/ingressodigital.com\/evento\/11046\/Oswaldo_Montenegro___Celebrando_50_anos_de_Estrada\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>) ou bilheteria do Theatro \u2013<a href=\"https:\/\/www.theatropedro2.com.br\/comprar-ingresso.php\" target=\"_blank\" rel=\"noreferrer noopener\"> clique para conferir o hor\u00e1rio de funcionamento.<\/a><\/strong><\/mark><\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>No espet\u00e1culo, o p\u00fablico poder\u00e1 acompanhar a <strong>trajet\u00f3ria de Montenegro<\/strong>, que durante todo o show, <strong>interage com imagens de sua vida e carreira projetadas num imenso tel\u00e3o<\/strong>. Al\u00e9m disso, ser\u00e1 poss\u00edvel assistir ao Menestrel tocando simultaneamente mais de um instrumento.<\/p>\n<p>Sucessos como \u201c<strong>Bandolins<\/strong>\u201d, \u201c<strong>A Lista<\/strong>\u201d, \u201c<strong>Lua e Flor<\/strong>\u201d, \u201c<strong>Intui\u00e7\u00e3o<\/strong>\u201d e as rec\u00e9m-lan\u00e7adas \u201c<strong>Lembrei de N\u00f3s<\/strong>\u201d e \u201c<strong>O melhor da vida ainda vai acontecer<\/strong>\u201d, v\u00e3o se unir \u00e0s historias e cenas virtuais, que revelar\u00e3o as origens das can\u00e7\u00f5es.<\/p>\n<p>O <strong>show<\/strong> em <strong>Ribeir\u00e3o Preto<\/strong> ainda contar\u00e1 com a participa\u00e7\u00e3o de <strong>Madalena Salles<\/strong>, a flautista-irm\u00e3 do Menestrel e do o multi-instrumentista <strong>Alexandre Meu Rei<\/strong>.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Ingressos<\/strong><\/h3>\n<ul>\n<li>Plateia A: (t\u00e9rreo em frente ao palco): R$ 230 inteira | R$ 115 meia-entrada\u00a0<\/li>\n<\/ul>\n<ul>\n<li>Plateia B: (t\u00e9rreo em frente ao palco): R$ 200 inteira | R$ 100 meia-entrada<\/li>\n<\/ul>\n<ul>\n<li>Frisa: (t\u00e9rreo em frente ao palco): R$ 200 inteira | R$ 100 meia-entrada\u00a0\u00a0<\/li>\n<\/ul>\n<ul>\n<li>Balc\u00e3o Nobre (1\u00ba andar): R$ 180 inteira | R$ 90 meia-entrada<\/li>\n<\/ul>\n<ul>\n<li>Balc\u00e3o Simples (2\u00ba andar): R$ 150 inteira | R$ 75 meia-entrada<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\"><strong>Servi\u00e7o<\/strong><\/h3>\n<h4 class=\"wp-block-heading\"><em>Oswaldo Montenegro \u2013 Celebrando 50 anos de Estrada<\/em><\/h4>\n<p>Quando: 25 de maio de 2024 (s\u00e1bado)<\/p>\n<p>Hor\u00e1rio: \u00e0s 20h<\/p>\n<p>Onde: Theatro Pedro II \u2013 rua \u00c1lvares Cabral, 370 \u2013 Centro, Ribeir\u00e3o Preto<\/p>\n<p>Classifica\u00e7\u00e3o: 12 anos<\/p>\n<p>Ingressos: a partir de R$ 75 \u2013<a href=\"https:\/\/ingressodigital.com\/evento\/11046\/Oswaldo_Montenegro___Celebrando_50_anos_de_Estrada\" target=\"_blank\" rel=\"noreferrer noopener\"> clique aqui para adquirir<\/a><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Cemit\u00e9rio da Saudade de Ribeir\u00e3o recebe nova edi\u00e7\u00e3o de visita cultural guiada; Veja quando<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do<strong>\u00a0acidade on<\/strong>\u00a0no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/GFH9HUMUTHNFJdnyEd0xxq\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Wanessa Camargo admite atitudes racistas no BBB 24 e faz pedido de desculpas a Davi<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/oswaldo-montenegro-celebra-50-anos-de-carreira-com-turne-especial-em-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O cantor e compositor Oswaldo Montenegro vem a Ribeir\u00e3o Preto com o show \u2018Celebrando 50 anos de Estrada\u2019, no dia 25 de maio, no Theatro Pedro II, no Centro da cidade. Os ingressos podem ser adquiridos on-line (clique aqui) ou bilheteria do Theatro \u2013 clique para conferir o hor\u00e1rio de funcionamento. No espet\u00e1culo, o &#8230; <a title=\"Oswaldo Montenegro celebra 50 anos de carreira com turn\u00ea especial em Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/12\/oswaldo-montenegro-celebra-50-anos-de-carreira-com-turne-especial-em-ribeirao-preto\/\" aria-label=\"Read more about Oswaldo Montenegro celebra 50 anos de carreira com turn\u00ea especial em Ribeir\u00e3o Preto\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":42115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-42114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/OswaldoMontenegrofazshowcomorquestraemRibeiroPreto_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/OswaldoMontenegrofazshowcomorquestraemRibeiroPreto_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1",1200,900,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/OswaldoMontenegrofazshowcomorquestraemRibeiroPreto_Tamanho_2_image.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/OswaldoMontenegrofazshowcomorquestraemRibeiroPreto_Tamanho_2_image.jpg?fit=300%2C225&ssl=1",300,225,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/OswaldoMontenegrofazshowcomorquestraemRibeiroPreto_Tamanho_2_image.jpg?fit=768%2C576&ssl=1",768,576,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/OswaldoMontenegrofazshowcomorquestraemRibeiroPreto_Tamanho_2_image.jpg?fit=1024%2C768&ssl=1",1024,768,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/OswaldoMontenegrofazshowcomorquestraemRibeiroPreto_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1",1200,900,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/OswaldoMontenegrofazshowcomorquestraemRibeiroPreto_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1",1200,900,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O cantor e compositor Oswaldo Montenegro vem a Ribeir\u00e3o Preto com o show \u2018Celebrando 50 anos de Estrada\u2019, no dia 25 de maio, no Theatro Pedro II, no Centro da cidade. Os ingressos podem ser adquiridos on-line (clique aqui) ou bilheteria do Theatro \u2013 clique para conferir o hor\u00e1rio de funcionamento. No espet\u00e1culo, o&hellip;","jetpack-related-posts":[{"id":51189,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/23\/oswaldo-montenegro-faz-show-em-ribeirao-preto-neste-fim-de-semana-2\/","url_meta":{"origin":42114,"position":0},"title":"Oswaldo Montenegro faz show em Ribeir\u00e3o Preto neste fim de semana","author":"ismaelcolosi.com.br","date":"23 de May de 2024","format":false,"excerpt":"[ad_1] O show do cantor e compositor Oswaldo Montenegro \u201cCelebrando 50 anos de Estrada\u201d em Ribeir\u00e3o Preto, acontece neste s\u00e1bado (25), no Theatro Pedro II. Com a turn\u00ea em comemora\u00e7\u00e3o aos 50 anos de carreira, a apresenta\u00e7\u00e3o est\u00e1 marcada para \u00e0s 20h e permitir\u00e1 ao p\u00fablico reviver a trajet\u00f3ria do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51182,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/23\/oswaldo-montenegro-faz-show-em-ribeirao-preto-neste-fim-de-semana\/","url_meta":{"origin":42114,"position":1},"title":"Oswaldo Montenegro faz show em Ribeir\u00e3o Preto neste fim de semana","author":"ismaelcolosi.com.br","date":"23 de May de 2024","format":false,"excerpt":"[ad_1] O show do cantor e compositor Oswaldo Montenegro \u201cCelebrando 50 anos de Estrada\u201d em Ribeir\u00e3o Preto, acontece neste s\u00e1bado (25), no Theatro Pedro II. Com a turn\u00ea em comemora\u00e7\u00e3o aos 50 anos de carreira, a apresenta\u00e7\u00e3o est\u00e1 marcada para \u00e0s 20h e permitir\u00e1 ao p\u00fablico reviver a trajet\u00f3ria do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-36_2024-05-23_19-09-45_jpg_2024-05-23_19-09-45.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42068,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/12\/oswaldo-montenegro-fara-show-no-pedro-ii\/","url_meta":{"origin":42114,"position":2},"title":"Oswaldo Montenegro far\u00e1 show no Pedro II \u00a0","author":"ismaelcolosi.com.br","date":"12 de March de 2024","format":false,"excerpt":"[ad_1] O cantor e compositor Oswaldo Montenegro estar\u00e1 no Theatro Pedro II, em Ribeir\u00e3o Preto, em 25 de maio, s\u00e1bado, com o show da nova turn\u00ea, em que comemora 50 anos de carreira. Sucessos como \u201cBandolins\u201d, \u201cA Lista\u201d, \u201cLua e Flor\u201d, \u201cIntui\u00e7\u00e3o\u201d e as rec\u00e9m-lan\u00e7adas \u201cLembrei de N\u00f3s\u201d e \u201cO\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Oswaldo-Ele-Daniela-Santos-Divulgacao-scaled.jpg?fit=1000%2C565&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Oswaldo-Ele-Daniela-Santos-Divulgacao-scaled.jpg?fit=1000%2C565&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Oswaldo-Ele-Daniela-Santos-Divulgacao-scaled.jpg?fit=1000%2C565&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Oswaldo-Ele-Daniela-Santos-Divulgacao-scaled.jpg?fit=1000%2C565&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2873,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/16\/cantor-guilherme-de-sa-se-apresenta-no-theatro-pedro-ii-em-ribeirao-preto\/","url_meta":{"origin":42114,"position":3},"title":"Cantor Guilherme de S\u00e1 se apresenta no Theatro Pedro II em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"16 de November de 2023","format":false,"excerpt":"[ad_1] O cantor Guilherme de S\u00e1 se apresenta em Ribeir\u00e3o Preto, nesta sexta-feira (17), no Theatro Pedro II, a partir das 20h, com o show \u2018Minimalista Tour\u2019. Os ingressos ainda est\u00e3o dispon\u00edveis. Cantor, compositor, escritor, produtor musical e arranjador brasileiro, Guilherme foi vocalista da banda Rosa de Saron de 2001\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-09-01-at-15.04.23-1-1.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-09-01-at-15.04.23-1-1.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-09-01-at-15.04.23-1-1.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-09-01-at-15.04.23-1-1.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-09-01-at-15.04.23-1-1.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":49158,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/08\/clarice-falcao-traz-seu-novo-show-para-ribeirao-preto-veja-quando\/","url_meta":{"origin":42114,"position":4},"title":"Clarice Falc\u00e3o traz seu novo show para Ribeir\u00e3o Preto; Veja quando","author":"ismaelcolosi.com.br","date":"8 de May de 2024","format":false,"excerpt":"[ad_1] A cantora Clarice Falc\u00e3o desembarca no palco do Theatro Pedro II, em Ribeir\u00e3o Preto, com seu novo show \u201cTRUQUE\u201c. A apresenta\u00e7\u00e3o acontece no dia 28 de junho, a partir das 20h. Os ingressos est\u00e3o dispon\u00edveis e podem ser adquiridos de forma on-line (clique aqui). Clarice ganhou destaque como atriz\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":54799,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/27\/clarice-falcao-se-apresenta-em-ribeirao-preto-veja-como-comprar-ingresso\/","url_meta":{"origin":42114,"position":5},"title":"Clarice Falc\u00e3o se apresenta em Ribeir\u00e3o Preto; Veja como comprar ingresso","author":"ismaelcolosi.com.br","date":"27 de June de 2024","format":false,"excerpt":"[ad_1] A cantora Clarice Falc\u00e3o se apresenta em Ribeir\u00e3o Preto, nesta sexta-feira (28), \u00e0s 20h, no Theatro Pedro II, localizado no Centro do munic\u00edpio, com o seu novo show \u201cTRUQUE\u201d. Os ingressos para o espet\u00e1culo ainda est\u00e3o dispon\u00edveis e podem ser adquiridos de forma on-line (clique aqui) ou na bilheteria\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-31_2024-05-08_22-25-11_png_2024-05-08_22-25-12.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-aXg","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=42114"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/42115"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=42114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=42114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=42114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}