{"id":41877,"date":"2024-03-11T18:47:21","date_gmt":"2024-03-11T21:47:21","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/producao-de-motos-sobe-148-em-fevereiro\/"},"modified":"2024-03-11T18:47:21","modified_gmt":"2024-03-11T21:47:21","slug":"producao-de-motos-sobe-148-em-fevereiro","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/producao-de-motos-sobe-148-em-fevereiro\/","title":{"rendered":"Produ\u00e7\u00e3o de motos sobe 14,8% em fevereiro"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"Corpo\">A produ\u00e7\u00e3o de motos em fevereiro teve crescimento de 14,8% na compara\u00e7\u00e3o com o mesmo m\u00eas do ano passado, somando 139,8 mil unidades. Foi o melhor resultado para o m\u00eas em dez anos. Frente a janeiro, por\u00e9m, houve queda de 1% na produ\u00e7\u00e3o de motocicletas<\/p>\n<p>O balan\u00e7o foi divulgado nesta segunda-feira, 11, pela Abraciclo, a entidade que representa as montadoras de motos do polo industrial de Manaus (AM), onde se concentra a maior parte da produ\u00e7\u00e3o nacional do ve\u00edculo.<\/p>\n<p>Nos dois primeiros meses do ano, o setor produziu 281 mil motos, com alta de 14,9% frente ao primeiro bimestre de 2023 e tamb\u00e9m mostrando o maior volume, entre iguais per\u00edodos, em dez anos.<\/p>\n<p>Na avalia\u00e7\u00e3o do presidente da Abraciclo, Marcos Bento, o desempenho reflete o bom momento da ind\u00fastria de duas rodas. \u201cApesar do m\u00eas de fevereiro ter menos dias \u00fateis, a produ\u00e7\u00e3o de motocicletas apresentou um resultado bastante positivo. Isso comprova o esfor\u00e7o das fabricantes em aumentar a produtividade para atender a crescente demanda do mercado\u201d, comentou o executivo.<\/p>\n<p><b>Vendas<\/b><\/p>\n<p>Nos dois primeiros meses do ano, foram vendidas 279,7 mil motocicletas no Brasil, 32,4% acima do volume registrado no mesmo per\u00edodo de 2023. Foi o melhor in\u00edcio de ano em vendas desde 2008.<\/p>\n<p>O desempenho reflete a demanda por ve\u00edculos mais baratos e econ\u00f4micos, assim como o crescimento dos servi\u00e7os de entrega (delivery).<\/p>\n<p><b>Proje\u00e7\u00f5es<\/b><\/p>\n<p>A proje\u00e7\u00e3o da Abraciclo \u00e9 produzir 1,69 milh\u00e3o de motocicletas em 2024, alta de 7,4% em rela\u00e7\u00e3o ao registrado no ano passado, o que, se confirmado, ser\u00e1 o melhor desempenho em 12 anos.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/producao-de-motos-sobe-148-em-fevereiro\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A produ\u00e7\u00e3o de motos em fevereiro teve crescimento de 14,8% na compara\u00e7\u00e3o com o mesmo m\u00eas do ano passado, somando 139,8 mil unidades. Foi o melhor resultado para o m\u00eas em dez anos. Frente a janeiro, por\u00e9m, houve queda de 1% na produ\u00e7\u00e3o de motocicletas O balan\u00e7o foi divulgado nesta segunda-feira, 11, pela Abraciclo, &#8230; <a title=\"Produ\u00e7\u00e3o de motos sobe 14,8% em fevereiro\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/producao-de-motos-sobe-148-em-fevereiro\/\" aria-label=\"Leia mais sobre Produ\u00e7\u00e3o de motos sobe 14,8% em fevereiro\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":41878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[684,1593,1312,1352],"class_list":["post-41877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-fevereiro","tag-motos","tag-producao","tag-sobe"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/57a428d3-8839-41ab-b57c-41fd42a00463-scaled.jpg?fit=1000%2C500&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/57a428d3-8839-41ab-b57c-41fd42a00463-scaled.jpg?fit=1000%2C500&ssl=1",1000,500,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/57a428d3-8839-41ab-b57c-41fd42a00463-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/57a428d3-8839-41ab-b57c-41fd42a00463-scaled.jpg?fit=300%2C150&ssl=1",300,150,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/57a428d3-8839-41ab-b57c-41fd42a00463-scaled.jpg?fit=768%2C384&ssl=1",768,384,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/57a428d3-8839-41ab-b57c-41fd42a00463-scaled.jpg?fit=1000%2C500&ssl=1",1000,500,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/57a428d3-8839-41ab-b57c-41fd42a00463-scaled.jpg?fit=1000%2C500&ssl=1",1000,500,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/57a428d3-8839-41ab-b57c-41fd42a00463-scaled.jpg?fit=1000%2C500&ssl=1",1000,500,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A produ\u00e7\u00e3o de motos em fevereiro teve crescimento de 14,8% na compara\u00e7\u00e3o com o mesmo m\u00eas do ano passado, somando 139,8 mil unidades. Foi o melhor resultado para o m\u00eas em dez anos. Frente a janeiro, por\u00e9m, houve queda de 1% na produ\u00e7\u00e3o de motocicletas O balan\u00e7o foi divulgado nesta segunda-feira, 11, pela Abraciclo,&hellip;","jetpack-related-posts":[{"id":14856,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/seca-no-amazonas-afeta-producao-de-motos-diz-abraciclo\/","url_meta":{"origin":41877,"position":0},"title":"Seca no Amazonas afeta produ\u00e7\u00e3o de motos, diz Abraciclo","author":"ismaelcolosi.com.br","date":"12 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A produ\u00e7\u00e3o de motos ficou perto da estabilidade na passagem de outubro para novembro, refletindo as dificuldades de recebimento de pe\u00e7as e escoamento da produ\u00e7\u00e3o das montadoras do polo industrial de Manaus por conta da seca severa no rio Amazonas e seus afluentes. No total, 131,9 mil motos sa\u00edram\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/motos-scaled.jpg?fit=1000%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/motos-scaled.jpg?fit=1000%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/motos-scaled.jpg?fit=1000%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/motos-scaled.jpg?fit=1000%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44291,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/27\/furtos-aumentam-no-primeiro-bimestre\/","url_meta":{"origin":41877,"position":1},"title":"Furtos aumentam no primeiro bimestre \u00a0","author":"ismaelcolosi.com.br","date":"27 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A Secretaria de Seguran\u00e7a P\u00fablica do Estado de S\u00e3o Paulo (SSP\/SP) nesta segunda-feira, 25 de mar\u00e7o, os resultados das \u201cEstat\u00edsticas da Criminalidade\u201d. Em Ribeir\u00e3o Preto, apenas os furtos em geral e de ve\u00edculos cresceram no primeiro bimestre deste ano, em compara\u00e7\u00e3o com o mesmo per\u00edodo de 2023, sendo que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/CrimeRP-Guilherme-Sircili.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/CrimeRP-Guilherme-Sircili.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/CrimeRP-Guilherme-Sircili.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/CrimeRP-Guilherme-Sircili.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/CrimeRP-Guilherme-Sircili.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40585,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/vendas-de-veiculos-sobem-272-em-um-ano\/","url_meta":{"origin":41877,"position":2},"title":"Vendas de ve\u00edculos sobem 27,2% em um ano","author":"ismaelcolosi.com.br","date":"4 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 4 de mar\u00e7o de 2024 | 18:004 de mar\u00e7o de 2024 | 15:14 0As vendas de ve\u00edculos tiveram no m\u00eas passado crescimento de 27,2% frente a fevereiro de 2023, chegando a 165,2 mil unidades emplacadas, entre carros de passeio, utilit\u00e1rios leves, caminh\u00f5es e \u00f4nibus. Mesmo com menos dias de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Venda-de-Usadosss.jpg?fit=690%2C420&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Venda-de-Usadosss.jpg?fit=690%2C420&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Venda-de-Usadosss.jpg?fit=690%2C420&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":37518,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/16\/venda-de-etanol-sobe-3822\/","url_meta":{"origin":41877,"position":3},"title":"Venda de etanol\u00a0sobe 38,22% \u00a0","author":"ismaelcolosi.com.br","date":"16 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A moagem de cana-de-a\u00e7\u00facar na segunda quinzena de janeiro na regi\u00e3o Centro-Sul totalizou 714,01 mil toneladas. Nesse mesmo per\u00edodo, no ano anterior, a quantidade processada foi de 307,30 mil toneladas. No acumulado da safra 2023\/2024, a moagem atingiu 646,05 milh\u00f5es de toneladas, ante 543,14 milh\u00f5es de toneladas registradas no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Cana-Divulgacao.png?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Cana-Divulgacao.png?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Cana-Divulgacao.png?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Cana-Divulgacao.png?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41534,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/08\/producao-de-veiculos-cresce-243-no-brasil\/","url_meta":{"origin":41877,"position":4},"title":"Produ\u00e7\u00e3o de ve\u00edculos cresce 24,3% no Brasil\u00a0","author":"ismaelcolosi.com.br","date":"8 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 8 de mar\u00e7o de 2024 | 17:007 de mar\u00e7o de 2024 | 20:57 0A produ\u00e7\u00e3o de ve\u00edculos automotores no Brasil cresceu 24,3% em fevereiro na compara\u00e7\u00e3o com o mesmo m\u00eas do ano passado, com 189.684 unidades produzidas. Na compara\u00e7\u00e3o anual, o aumento foi de 17,4%. Os dados foram divulgados\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Veiculos-Rafa-Neddermeyer-Ag.Br_-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Veiculos-Rafa-Neddermeyer-Ag.Br_-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Veiculos-Rafa-Neddermeyer-Ag.Br_-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Veiculos-Rafa-Neddermeyer-Ag.Br_-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37052,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/14\/mulher-morre-em-acidente-na-zona-oeste\/","url_meta":{"origin":41877,"position":5},"title":"Mulher morre em acidente na zona Oeste","author":"ismaelcolosi.com.br","date":"14 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] V\u00edtima estava em motocicleta que colidiu contra ve\u00edculo 14 de fevereiro de 2024 | 8:38 0Por: Adalberto LuqueUma jovem de 24 anos morreu, na madrugada desta segunda-feira (12), ap\u00f3s um acidente ocorrido na Avenida Bandeirantes, Vila Virg\u00ednia, zona Oeste de Ribeir\u00e3o Preto. A v\u00edtima estaria em uma motocicleta.Segundo informa\u00e7\u00f5es,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/LUQUE-Samu-02-Foto-Alfredo-Risk-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/LUQUE-Samu-02-Foto-Alfredo-Risk-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/LUQUE-Samu-02-Foto-Alfredo-Risk-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/LUQUE-Samu-02-Foto-Alfredo-Risk-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/LUQUE-Samu-02-Foto-Alfredo-Risk-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-aTr","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41877"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/41878"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}