{"id":41843,"date":"2024-03-11T16:25:55","date_gmt":"2024-03-11T19:25:55","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/hc-ribeirao-preto-comeca-testes-de-terapia-celular-contra-o-cancer-nesta-semana\/"},"modified":"2024-03-11T16:25:55","modified_gmt":"2024-03-11T19:25:55","slug":"hc-ribeirao-preto-comeca-testes-de-terapia-celular-contra-o-cancer-nesta-semana","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/hc-ribeirao-preto-comeca-testes-de-terapia-celular-contra-o-cancer-nesta-semana\/","title":{"rendered":"HC Ribeir\u00e3o Preto come\u00e7a testes de terapia celular contra o c\u00e2ncer nesta semana"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O<strong> Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto<\/strong> vai come\u00e7ar na pr\u00f3xima sexta-feira (15) o teste de terapia celular contra o c\u00e2ncer. De acordo com a <strong>USP (Universidade de S\u00e3o Paulo)<\/strong>, ter\u00e1 in\u00edcio a inclus\u00e3o dos candidatos no estudo cl\u00ednico das fases 1 e 2 no <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">tratamento com c\u00e9lulas CAR-T em pacientes com linfoma e leucemia.<\/mark><\/p>\n<p>O tratamento foi desenvolvido no CTC (Centro de Terapia Celular), no <strong>Hemocentro de Ribeir\u00e3o Preto<\/strong>.\u00a0 <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">O tratamento \u00e9 destinado para pacientes com leucemia linfoide aguda de c\u00e9lulas B e linfoma n\u00e3o Hodgkin de c\u00e9lulas B que n\u00e3o responderam ou apresentaram o retorno da doen\u00e7a ap\u00f3s a primeira linha de tratamento convencional.<\/mark><\/p>\n<p>O in\u00edcio do estudo foi anunciado na semana passada durante a Confer\u00eancia Estadual de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o, e vai tratar 81 pacientes at\u00e9 o ano que vem.<\/p>\n<p>\u201cInicialmente ser\u00e3o quatro pacientes tratados no Hospital das Cl\u00ednicas da USP em Ribeir\u00e3o Preto. Os dados ser\u00e3o ent\u00e3o submetidos \u00e0 Anvisa [Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria] para avalia\u00e7\u00e3o da seguran\u00e7a e, se tudo correr bem, os outros centros envolvidos no estudo poder\u00e3o come\u00e7ar a tratar outros candidatos\u201d, disse \u00e0 Ag\u00eancia Fapesp Diego Cl\u00e9, coordenador m\u00e9dico do Hemocentro de Ribeir\u00e3o Preto.<\/p>\n<p>Al\u00e9m do <strong>Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto<\/strong>, participam do estudo o <strong>Hospital das Cl\u00ednicas da Faculdade de Medicina da USP em S\u00e3o Paulo<\/strong>, o <strong>Hospital de Cl\u00ednicas da Unicamp<\/strong> e os hospitais <strong>Benefic\u00eancia Portuguesa<\/strong> e<strong> S\u00edrio-Liban\u00eas<\/strong>, em S\u00e3o Paulo.<\/p>\n<h4 class=\"wp-block-heading\"><strong>O que \u00e9?<\/strong><\/h4>\n<p>O tratamento com c\u00e9lulas CAR-T foi desenvolvido em 2017 nos <strong>Estados Unidos <\/strong>e, desde 2019, no <strong>Brasil<\/strong>, pela<strong><a href=\"https:\/\/www.fmrp.usp.br\/pb\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Faculdade de Medicina de Ribeir\u00e3o Preto da USP<\/a><\/strong>, em colabora\u00e7\u00e3o com o<strong> Instituto Butantan<\/strong> e apoio da<strong> Fapesp (Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa do Estado de S\u00e3o Paulo).<\/strong><\/p>\n<p>A t\u00e9cnica consiste na retirada de linf\u00f3citos do pr\u00f3prio paciente, que s\u00e3o manipulados em laborat\u00f3rio e reaplicados no organismo. O objetivo \u00e9 preparar os linf\u00f3citos para identificar e eliminar c\u00e9lulas tumorais que n\u00e3o foram detidas por outros tratamentos como quimioterapia e transplante de medula.<\/p>\n<p>O Hemocentro de Ribeir\u00e3o Preto abriga a \u00fanica f\u00e1brica de c\u00e9lulas CAR-T da Am\u00e9rica Latina, uma das poucas no mundo que n\u00e3o pertencem a grandes ind\u00fastrias farmac\u00eauticas.<\/p>\n<p>At\u00e9 hoje, 20 pessoas foram tratadas com as c\u00e9lulas preparadas no <strong>N\u00facleo de Terapia Celular Avan\u00e7ada de Ribeir\u00e3o Preto (Nutera-RP)<\/strong>. O n\u00facleo pode preparar at\u00e9 300 tratamentos por ano.<\/p>\n<p>Na iniciativa privada, o tratamento importado pode custar at\u00e9 R$ 2 milh\u00f5es por paciente. O nacional, que pode ser adotado pelo SUS (Sistema \u00danico de Sa\u00fade), poder\u00e1 sair por um sexto desse valor.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Pacientes<\/strong><\/h4>\n<p>Os primeiros quatro pacientes tratados no Hospital das Cl\u00ednicas ter\u00e3o o sangue colhido, de onde os linf\u00f3citos T, um tipo de c\u00e9lula de defesa, ser\u00e3o isolados e modificados no <strong>Nutera-RP<\/strong>. Esse processo leva de 15 dias a um m\u00eas.<\/p>\n<p>Depois de internados, os pacientes receber\u00e3o ent\u00e3o uma infus\u00e3o das pr\u00f3prias c\u00e9lulas, agora reprogramadas para atacar as c\u00e9lulas tumorais. Ser\u00e3o 15 dias de interna\u00e7\u00e3o para acompanhar os poss\u00edveis efeitos colaterais, resultado da inflama\u00e7\u00e3o provocada pelo tratamento.<\/p>\n<p>Ap\u00f3s a alta, o paciente seguir\u00e1 sendo acompanhado em consultas semanais, at\u00e9 ter a primeira avalia\u00e7\u00e3o de efic\u00e1cia do tratamento, ap\u00f3s 30 dias da infus\u00e3o. Os testes ser\u00e3o repetidos ap\u00f3s 90 dias do in\u00edcio do tratamento. Todos os pacientes ser\u00e3o monitorados por cinco anos como parte do estudo.<\/p>\n<p><em>*Com informa\u00e7\u00f5es de Carlos Fioravanti, da Revista Pesquisa FAPESP.<\/em><\/p>\n<p>SAIBA MAIS<br \/>Eclipse lunar penumbral ser\u00e1 visto\u00a0em mar\u00e7o; Confira a data e entenda o fen\u00f4meno<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on<\/strong> no<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Instagram <\/a>e no<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on <\/strong>no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Kate Middleton \u00e9 fotografada ao lado de pr\u00edncipe William ap\u00f3s pol\u00eamica de foto manipulada<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/hc-ribeirao-preto-comeca-testes-de-terapia-celular-contra-o-cancer-nesta-semana\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto vai come\u00e7ar na pr\u00f3xima sexta-feira (15) o teste de terapia celular contra o c\u00e2ncer. De acordo com a USP (Universidade de S\u00e3o Paulo), ter\u00e1 in\u00edcio a inclus\u00e3o dos candidatos no estudo cl\u00ednico das fases 1 e 2 no tratamento com c\u00e9lulas CAR-T em pacientes com linfoma e &#8230; <a title=\"HC Ribeir\u00e3o Preto come\u00e7a testes de terapia celular contra o c\u00e2ncer nesta semana\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/hc-ribeirao-preto-comeca-testes-de-terapia-celular-contra-o-cancer-nesta-semana\/\" aria-label=\"Leia mais sobre HC Ribeir\u00e3o Preto come\u00e7a testes de terapia celular contra o c\u00e2ncer nesta semana\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":41844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-41843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__nutera-rp.webp.webp?fit=796%2C445&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__nutera-rp.webp.webp?fit=796%2C445&ssl=1",796,445,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__nutera-rp.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__nutera-rp.webp.webp?fit=300%2C168&ssl=1",300,168,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__nutera-rp.webp.webp?fit=768%2C429&ssl=1",768,429,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__nutera-rp.webp.webp?fit=796%2C445&ssl=1",796,445,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__nutera-rp.webp.webp?fit=796%2C445&ssl=1",796,445,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__nutera-rp.webp.webp?fit=796%2C445&ssl=1",796,445,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto vai come\u00e7ar na pr\u00f3xima sexta-feira (15) o teste de terapia celular contra o c\u00e2ncer. De acordo com a USP (Universidade de S\u00e3o Paulo), ter\u00e1 in\u00edcio a inclus\u00e3o dos candidatos no estudo cl\u00ednico das fases 1 e 2 no tratamento com c\u00e9lulas CAR-T em pacientes com linfoma e&hellip;","jetpack-related-posts":[{"id":42017,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/12\/usp-inicia-teste-contra-o-cancer\/","url_meta":{"origin":41843,"position":0},"title":"USP inicia teste contra o c\u00e2ncer\u00a0","author":"ismaelcolosi.com.br","date":"12 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 12 de mar\u00e7o de 2024 | 15:0012 de mar\u00e7o de 2024 | 9:27 0Com informa\u00e7\u00f5es de Carlos Fioravanti \u00a0(Revista Fapesp)\u00a0\u00a0Come\u00e7a na pr\u00f3xima sexta-feira, 15 de mar\u00e7o, o estudo cl\u00ednico com o uso de terapia CAR-T conduzido pelo Hemocentro de Ribeir\u00e3o Preto, em parceria com o Hospital das Cl\u00ednicas da\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Linfoma-Nut-Guilherme-Sircili-scaled.jpg?fit=1000%2C585&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Linfoma-Nut-Guilherme-Sircili-scaled.jpg?fit=1000%2C585&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Linfoma-Nut-Guilherme-Sircili-scaled.jpg?fit=1000%2C585&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Linfoma-Nut-Guilherme-Sircili-scaled.jpg?fit=1000%2C585&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42294,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/13\/entenda-como-funciona-a-terapia-celular-contra-o-cancer-do-hc-de-ribeirao\/","url_meta":{"origin":41843,"position":1},"title":"Entenda como funciona a terapia celular contra o c\u00e2ncer do HC de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"13 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto come\u00e7a nesta sexta-feira (15) os testes sobre o tratamento celular contra o c\u00e2ncer. Na primeira etapa, o tratamento com c\u00e9lulas CAR-T ser\u00e1 aplicado em quatro pacientes com linfoma e leucemia. O tratamento com c\u00e9lulas CAR-T foi desenvolvido em 2017 nos Estados Unidos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__celula-cart.webp.webp?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__celula-cart.webp.webp?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__celula-cart.webp.webp?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__celula-cart.webp.webp?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__celula-cart.webp.webp?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":25501,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/07\/entenda-como-funciona-a-terapia-celular-car-t-cell-contra-o-cancer\/","url_meta":{"origin":41843,"position":2},"title":"Entenda como funciona a terapia celular CAR-T Cell contra o c\u00e2ncer\u00a0","author":"ismaelcolosi.com.br","date":"7 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A terapia celular CAR-T Cell tem obtido resultado importante no tratamento de alguns tipos de c\u00e2ncer, por meio da reprograma\u00e7\u00e3o das c\u00e9lulas de defesa do corpo. A tecnologia celular CAR-T \u00e9 um tipo de imunoterapia que utiliza linf\u00f3citos T, c\u00e9lulas do sistema imunol\u00f3gico respons\u00e1veis por combater agentes patog\u00eanicos e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-cancer-foto-2-antes_depois-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-cancer-foto-2-antes_depois-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-cancer-foto-2-antes_depois-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-cancer-foto-2-antes_depois-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":19664,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/22\/hemocentro-rp-ministerio-da-saude-libera-r-100-milhoes-para-terapia-car-t-cell\/","url_meta":{"origin":41843,"position":3},"title":"Hemocentro RP: Minist\u00e9rio da Sa\u00fade libera R$ 100 milh\u00f5es para terapia CAR-T Cell\u00a0","author":"ismaelcolosi.com.br","date":"22 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Verba ser\u00e1 liberada pelo Programa de Acelera\u00e7\u00e3o do Crescimento\u00a0 22 de dezembro de 2023 | 17:0022 de dezembro de 2023 | 15:43 0O Minist\u00e9rio da Sa\u00fade confirmou o repasse de R$ 100 milh\u00f5es para o financiamento da pesquisa de desenvolvimento da terapia celular CAR-T Cell na Funda\u00e7\u00e3o Hemocentro de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2-hermocentro-energia_nuclear_usada_para_diagnostico_de_cancer-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2-hermocentro-energia_nuclear_usada_para_diagnostico_de_cancer-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2-hermocentro-energia_nuclear_usada_para_diagnostico_de_cancer-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2-hermocentro-energia_nuclear_usada_para_diagnostico_de_cancer-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44112,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/25\/ministra-da-saude-participa-de-lancamento-de-estudo-clinico-contra-cancer-no-hc-de-ribeirao\/","url_meta":{"origin":41843,"position":4},"title":"Ministra da Sa\u00fade participa de lan\u00e7amento de estudo cl\u00ednico contra c\u00e2ncer no HC de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"25 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A ministra da Sa\u00fade, N\u00edsia Trindade, esteve em Ribeir\u00e3o Preto, nesta segunda-feira (25), para participar do lan\u00e7amento de um estudo cl\u00ednico com a terapia que usa as c\u00e9lulas CAR-T para combate a linfoma n\u00e3o Hodgkin de c\u00e9lulas B e leucemia linf\u00f3ide de c\u00e9lulas B. Na ocasi\u00e3o, a ministra tamb\u00e9m\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44194,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/26\/ministra-da-saude-participa-de-lancamento-de-estudo-clinico-contra-cancer-no-hc-de-ribeirao-2\/","url_meta":{"origin":41843,"position":5},"title":"Ministra da Sa\u00fade participa de lan\u00e7amento de estudo cl\u00ednico contra c\u00e2ncer no HC de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"26 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A ministra da Sa\u00fade, N\u00edsia Trindade, esteve em Ribeir\u00e3o Preto, nesta segunda-feira (25), para participar do lan\u00e7amento de um estudo cl\u00ednico com a terapia que usa as c\u00e9lulas CAR-T para combate a linfoma n\u00e3o Hodgkin de c\u00e9lulas B e leucemia linf\u00f3ide de c\u00e9lulas B. Na ocasi\u00e3o, a ministra tamb\u00e9m\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-aST","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41843"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/41844"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}