{"id":41744,"date":"2024-03-11T07:22:59","date_gmt":"2024-03-11T10:22:59","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/carro-derruba-dois-postes-na-zona-norte-de-rp\/"},"modified":"2024-03-11T07:22:59","modified_gmt":"2024-03-11T10:22:59","slug":"carro-derruba-dois-postes-na-zona-norte-de-rp","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/carro-derruba-dois-postes-na-zona-norte-de-rp\/","title":{"rendered":"Carro derruba dois postes na zona Norte de RP"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-376865\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<h2 class=\"penci-post-subtitle\">N\u00e3o houve feridos na colis\u00e3o e postes foram trocados pela concession\u00e1ria de energia<\/h2>\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-03-11T07:20:45-03:00\">11 de mar\u00e7o de 2024 | 7:20<\/time><time class=\"updated\" datetime=\"2024-03-10T21:36:24-03:00\">10 de mar\u00e7o de 2024 | 21:36<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"376865\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">1<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Carro%20derruba%20dois%20postes%20na%20zona%20Norte%20de%20RP%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/carro-derruba-dois-postes-na-zona-norte-de-rp\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/header>\n<div class=\"penci-entry-content entry-content\">\n<p>Por: Adalberto Luque<\/p>\n<p>Um motorista derrubou dois postes ap\u00f3s uma colis\u00e3o, na manh\u00e3 deste domingo (10). O acidente ocorreu no cruzamento da Avenida Guido Golfeto com Travessa Esmeralda, Jardim Independ\u00eancia, zona Norte de Ribeir\u00e3o Preto.<\/p>\n<p>Segundo informa\u00e7\u00f5es, o motorista seguia pela Travessa Esmeralda e, ao cruzar a avenida, teria perdido o controle e colidido contra um poste, que caiu sobre o ve\u00edculo ap\u00f3s o impacto.<\/p>\n<figure id=\"attachment_376862\" aria-describedby=\"caption-attachment-376862\" style=\"width: 971px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" width=\"971\" height=\"645\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-scaled.jpg 971w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-300x199.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-1024x680.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-768x510.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-1536x1020.jpg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-480x320.jpg 480w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-280x186.jpg 280w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-960x638.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-602x400.jpg 602w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-585x389.jpg 585w\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-scaled.jpg?resize=971%2C645&#038;ssl=1\" data-sizes=\"(max-width: 971px) 100vw, 971px\" class=\"size-full wp-image-376862 lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-376862\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-scaled.jpg?resize=971%2C645&#038;ssl=1\" alt=\"\" width=\"971\" height=\"645\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-scaled.jpg 971w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-300x199.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-1024x680.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-768x510.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-1536x1020.jpg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-480x320.jpg 480w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-280x186.jpg 280w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-960x638.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-602x400.jpg 602w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-01-foto-max-gallao-mesquita-585x389.jpg 585w\" sizes=\"(max-width: 971px) 100vw, 971px\"\/><\/noscript><figcaption id=\"caption-attachment-376862\" class=\"wp-caption-text\">Concession\u00e1ria de energia efetuou a troca dos postes e restabeleceu a energia (Foto: Max Gall\u00e3o Mesquita)<\/figcaption><\/figure>\n<p>Com a queda, a fia\u00e7\u00e3o derrubou um poste ao lado. A CPFL Energia precisou ser acionada para a troca dos postes e restabelecer o fornecimento de energia nas imedia\u00e7\u00f5es. O acidente foi registrado na Central de Pol\u00edcia Judici\u00e1ria (CPJ) e as causas ser\u00e3o apuradas. N\u00e3o houve feridos na colis\u00e3o.<\/p>\n<\/div>\n<footer class=\"penci-entry-footer\"\/><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/carro-derruba-dois-postes-na-zona-norte-de-rp\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] N\u00e3o houve feridos na colis\u00e3o e postes foram trocados pela concession\u00e1ria de energia 11 de mar\u00e7o de 2024 | 7:2010 de mar\u00e7o de 2024 | 21:36 1 Por: Adalberto Luque Um motorista derrubou dois postes ap\u00f3s uma colis\u00e3o, na manh\u00e3 deste domingo (10). O acidente ocorreu no cruzamento da Avenida Guido Golfeto com Travessa &#8230; <a title=\"Carro derruba dois postes na zona Norte de RP\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/carro-derruba-dois-postes-na-zona-norte-de-rp\/\" aria-label=\"Leia mais sobre Carro derruba dois postes na zona Norte de RP\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":41745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[295,1929,618,397,4911,340],"class_list":["post-41744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-carro","tag-derruba","tag-dois","tag-norte","tag-postes","tag-zona"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-02-foto-max-gallao-mesquita-scaled.jpg?fit=954%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-02-foto-max-gallao-mesquita-scaled.jpg?fit=954%2C645&ssl=1",954,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-02-foto-max-gallao-mesquita-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-02-foto-max-gallao-mesquita-scaled.jpg?fit=300%2C203&ssl=1",300,203,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-02-foto-max-gallao-mesquita-scaled.jpg?fit=768%2C519&ssl=1",768,519,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-02-foto-max-gallao-mesquita-scaled.jpg?fit=954%2C645&ssl=1",954,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-02-foto-max-gallao-mesquita-scaled.jpg?fit=954%2C645&ssl=1",954,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-poste-caiu-02-foto-max-gallao-mesquita-scaled.jpg?fit=954%2C645&ssl=1",954,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] N\u00e3o houve feridos na colis\u00e3o e postes foram trocados pela concession\u00e1ria de energia 11 de mar\u00e7o de 2024 | 7:2010 de mar\u00e7o de 2024 | 21:36 1 Por: Adalberto Luque Um motorista derrubou dois postes ap\u00f3s uma colis\u00e3o, na manh\u00e3 deste domingo (10). O acidente ocorreu no cruzamento da Avenida Guido Golfeto com Travessa&hellip;","jetpack-related-posts":[{"id":41677,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/10\/motorista-perde-controle-e-carro-derruba-dois-postes-em-ribeirao-preto\/","url_meta":{"origin":41744,"position":0},"title":"Motorista perde controle e carro derruba dois postes em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"10 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Um motorista perdeu o controle da dire\u00e7\u00e3o e o carro que ele dirigia derrubou dois postes no Jardim Independ\u00eancia, na zona Norte de Ribeir\u00e3o Preto, na manh\u00e3 deste domingo (10). O acidente aconteceu no cruzamento da avenida Guido Golfeto com a travessa Esmeralda, pr\u00f3ximo da Maternidade Sinh\u00e1 Junqueira. Ningu\u00e9m\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__poste.webp.webp?fit=1200%2C811&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__poste.webp.webp?fit=1200%2C811&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__poste.webp.webp?fit=1200%2C811&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__poste.webp.webp?fit=1200%2C811&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__poste.webp.webp?fit=1200%2C811&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":50734,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/18\/carro-derruba-poste-e-provoca-bloqueio-de-avenida-em-ribeirao-preto\/","url_meta":{"origin":41744,"position":1},"title":"Carro derruba poste e provoca bloqueio de avenida em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"18 de Maio de 2024","format":false,"excerpt":"[ad_1] Um carro bateu em um poste na avenida Ant\u00f4nia Mugnatto Marincek, pr\u00f3ximo a entrada do Ribeir\u00e3o Verde, na zona Leste de Ribeir\u00e3o Preto. O acidente aconteceu por volta de 12h, deste s\u00e1bado (18) e provocou congestionamento. N\u00e3o h\u00e1 feridos no local e a Pol\u00edcia Militar foi acionada para atender\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/acidente-marincek_2024-05-18_18-34-36_jpg_2024-05-18_18-34-36.webp.webp?fit=757%2C618&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/acidente-marincek_2024-05-18_18-34-36_jpg_2024-05-18_18-34-36.webp.webp?fit=757%2C618&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/acidente-marincek_2024-05-18_18-34-36_jpg_2024-05-18_18-34-36.webp.webp?fit=757%2C618&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/acidente-marincek_2024-05-18_18-34-36_jpg_2024-05-18_18-34-36.webp.webp?fit=757%2C618&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":54556,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/26\/o-que-se-sabe-sobre-a-intensa-frente-fria-que-vai-derrubar-as-temperaturas-no-interior-de-sp\/","url_meta":{"origin":41744,"position":2},"title":"O que se sabe sobre a intensa frente fria que vai derrubar as temperaturas no interior de SP","author":"ismaelcolosi.com.br","date":"26 de Junho de 2024","format":false,"excerpt":"[ad_1] Uma intensa frente fria est\u00e1 prevista para se aproxima na sexta-feira (28) e poder\u00e1 derrubar as temperaturas em todas as regi\u00f5es do estado S\u00e3o Paulo. A Climatempo indica que \u00e1reas mais ao Norte do estado poder\u00e3o sentir os efeitos deste sistema. Em Ribeir\u00e3o Preto, por exemplo, a previs\u00e3o estendida\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/1719408805_DefesaCivildeSoPauloemitealertadebaixastemperaturasVejaapreviso_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/1719408805_DefesaCivildeSoPauloemitealertadebaixastemperaturasVejaapreviso_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/1719408805_DefesaCivildeSoPauloemitealertadebaixastemperaturasVejaapreviso_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/1719408805_DefesaCivildeSoPauloemitealertadebaixastemperaturasVejaapreviso_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/1719408805_DefesaCivildeSoPauloemitealertadebaixastemperaturasVejaapreviso_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58233,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/29\/motorista-perde-controle-e-carro-derruba-muro-de-casa-em-ribeirao-preto\/","url_meta":{"origin":41744,"position":3},"title":"Motorista perde controle e carro derruba muro de casa em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"29 de Julho de 2024","format":false,"excerpt":"[ad_1] Uma motorista perdeu o controle da dire\u00e7\u00e3o do carro e derrubou o muro de uma casa no bairro Adelino Simioni, na zona Norte de Ribeir\u00e3o Preto. O acidente aconteceu no final da manh\u00e3 desta segunda-feira (29). O caso aconteceu na esquina das ruas Egydio Petean e Edson Granzotto. De\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/acidente-ribeirao-preto_2024-07-29_16-39-46_jpg_2024-07-29_16-39-46.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/acidente-ribeirao-preto_2024-07-29_16-39-46_jpg_2024-07-29_16-39-46.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/acidente-ribeirao-preto_2024-07-29_16-39-46_jpg_2024-07-29_16-39-46.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/acidente-ribeirao-preto_2024-07-29_16-39-46_jpg_2024-07-29_16-39-46.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/acidente-ribeirao-preto_2024-07-29_16-39-46_jpg_2024-07-29_16-39-46.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":49179,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/09\/carro-derruba-poste-e-interdita-acesso-na-avenida-maurilio-biagi-em-ribeirao-preto\/","url_meta":{"origin":41744,"position":4},"title":"Carro derruba poste e interdita acesso na avenida Maur\u00edlio Biagi em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"9 de Maio de 2024","format":false,"excerpt":"[ad_1] Um carro derrubou um poste nesta quinta-feira (9) em um acesso pela avenida Maur\u00edlio Biagi, em Ribeir\u00e3o Preto. H\u00e1 interdi\u00e7\u00e3o total no acesso para as avenidas Presidente Kennedy e Alzira Couto Machado, no sentido Centro-bairro. A RP Mobi informou que uma equipe da CPFL Paulista est\u00e1 a caminho do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/rp-mobi-transerp.png?fit=600%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/rp-mobi-transerp.png?fit=600%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/rp-mobi-transerp.png?fit=600%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":49200,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/09\/carro-de-aplicativo-derruba-poste-e-interdita-acesso-na-avenida-maurilio-biagi-em-ribeirao-preto\/","url_meta":{"origin":41744,"position":5},"title":"Carro de aplicativo derruba poste e interdita acesso na avenida Maur\u00edlio Biagi em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"9 de Maio de 2024","format":false,"excerpt":"[ad_1] Um carro de aplicativo derrubou um poste nesta quinta-feira (9) em um acesso pela avenida Maur\u00edlio Biagi, em Ribeir\u00e3o Preto. H\u00e1 interdi\u00e7\u00e3o total no acesso para as avenidas Presidente Kennedy e Alzira Couto Machado, no sentido Centro-bairro. Segundo as primeiras informa\u00e7\u00f5es, o motorista teria sofrido ferimentos leves. A RP\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-09-at-07.50.13_2024-05-09_11-10-42_jpeg_2024-05-09_11-10-43.webp.webp?fit=1032%2C581&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-09-at-07.50.13_2024-05-09_11-10-42_jpeg_2024-05-09_11-10-43.webp.webp?fit=1032%2C581&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-09-at-07.50.13_2024-05-09_11-10-42_jpeg_2024-05-09_11-10-43.webp.webp?fit=1032%2C581&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-09-at-07.50.13_2024-05-09_11-10-42_jpeg_2024-05-09_11-10-43.webp.webp?fit=1032%2C581&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-aRi","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41744"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/41745"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}