{"id":41733,"date":"2024-03-10T21:34:45","date_gmt":"2024-03-11T00:34:45","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/10\/vagas-de-empregos-na-eurofarma-para-trabalhar-em-ribeirao-preto-sp-33\/"},"modified":"2024-03-10T21:34:45","modified_gmt":"2024-03-11T00:34:45","slug":"vagas-de-empregos-na-eurofarma-para-trabalhar-em-ribeirao-preto-sp-33","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/10\/vagas-de-empregos-na-eurofarma-para-trabalhar-em-ribeirao-preto-sp-33\/","title":{"rendered":"Vagas de empregos na Eurofarma para trabalhar em Ribeir\u00e3o Preto-SP"},"content":{"rendered":"<div>\n<header data-testid=\"home-page-header\" class=\"sc-2ce743e0-0 ikEMvF\">\n<nav aria-label=\"Menu principal\" class=\"sc-2ce743e0-1 csSlmz\">\n<div class=\"sc-2ce743e0-2 kQwtZJ\"><button role=\"link\" class=\"sc-irTswW bEjbuS sc-2ce743e0-3 bJCkvX\" aria-label=\"Informa\u00e7\u00f5es sobre a empresa\">Sobre<\/button><button role=\"link\" class=\"sc-irTswW bEjbuS sc-2ce743e0-3 bJCkvX\" aria-label=\"Lista de vagas publicadas pela empresa\">Vagas<\/button><\/div>\n<div class=\"sc-2ce743e0-4 dHgVYT\"><a href=\"https:\/\/eurofarma.gupy.io\/candidates\" data-testid=\"login-link\" accesskey=\"c\" class=\"sc-e19aebb-0 gziWLd\" target=\"_blank\" rel=\"noopener\">Fazer login como candidato(a)<\/a><\/div>\n<\/nav>\n<\/header>\n<div class=\"sc-e9dd4d1-1 lfFfSi\">\n<div class=\"sc-e9dd4d1-2 bWOeUI\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"Foto de capa da empresa\" src=\"https:\/\/i0.wp.com\/attachments.gupy.io\/production\/companies\/237\/career\/1\/images\/2023-11-24_13-44_bannerUrl.png?w=1200&#038;ssl=1\"><\/div>\n<div class=\"sc-e9dd4d1-3 fwSjGW\">\n<div class=\"sc-e9dd4d1-4 gUILIM\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"Logo da empresa\" src=\"https:\/\/i0.wp.com\/attachments.gupy.io\/production\/companies\/237\/career\/1\/images\/2022-04-04_13-10_logo.png?w=1200&#038;ssl=1\"><\/div>\n<div class=\"sc-e9dd4d1-6 hlIymR\">\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" aria-label=\"Voc\u00ea est\u00e1 na p\u00e1gina de carreira {{pageTitle}}\" class=\"sc-eACynP jLQMmr sc-e9dd4d1-5 cEgRjA\">Eurofarma<\/h1>\n<\/div>\n<div class=\"sc-e9dd4d1-7 iRZAen\"><\/div>\n<\/div>\n<\/div>\n<p><main data-testid=\"content-wrapper\" id=\"main\" class=\"sc-e9dd4d1-0 lkRshA\"><\/p>\n<section data-testid=\"company-description\" id=\"about\" class=\"sc-c1003a30-0 bTlhYQ\">\n<h2 data-testid=\"section-Eurofarma Laborat\u00f3rios-title\" class=\"sc-6fde0c52-0 haCHdH\">Eurofarma Laborat\u00f3rios<\/h2>\n<div class=\"sc-c1003a30-1 lnQWzD\">\n<p><span style=\"color:black\">Somos uma multinacional brasileira presente em 22 pa\u00edses, com\u00a0mais de\u00a050 anos de hist\u00f3ria e o prop\u00f3sito de promover acesso \u00e0 sa\u00fade para que todas as pessoas possam viver mais e melhor. \u00c9 isso que move a Eurofarma todos os dias. <\/span><\/p>\n<p><span style=\"color:black\">\u00a0<\/span><\/p>\n<p><span style=\"color:black\">Com mais de 11 mil colaboradores, atuamos em todos os principais segmentos farmac\u00eauticos e somos l\u00edderes em receitu\u00e1rio m\u00e9dico no Brasil.\u00a0<\/span><\/p>\n<p><span style=\"color:black\">\u00a0<\/span><\/p>\n<p><span style=\"color:black\">Sabemos do nosso importante papel de transforma\u00e7\u00e3o na sociedade, entendendo que as\u00a0pessoas s\u00e3o fundamentais na trajet\u00f3ria de crescimento, ao lado dos resultados, internacionaliza\u00e7\u00e3o, inova\u00e7\u00e3o e sustentabilidade, para nos tornarmos cada vez mais globais. Valorizamos o desenvolvimento profissional de nossos colaboradores, a diversidade e a inclus\u00e3o. Buscamos pluralidade de perfis, g\u00eaneros, ra\u00e7as, orienta\u00e7\u00f5es e identidades, pois acreditamos que contribui\u00e7\u00f5es e percep\u00e7\u00f5es de pessoas distintas nos ajudam a encontrar, juntos, solu\u00e7\u00f5es novas e sustent\u00e1veis em sa\u00fade.<\/span><\/p>\n<p><span style=\"color:black\">\u00a0<\/span><\/p>\n<p><span style=\"color:black\">Caso tenha interesse em nossas vagas e se identifique com o nosso prop\u00f3sito, inscreva-se em nossos processos seletivos.\u00a0<\/span><\/p>\n<p><span style=\"color:black\">\u00a0<\/span><\/p>\n<p><strong style=\"color:black\">Aqui voc\u00ea pode ser quem voc\u00ea \u00e9. Todas as pessoas s\u00e3o bem-vindas!<\/strong><\/p>\n<p class=\"ql-align-justify\"><span style=\"color:black\">\u00a0<\/span><\/p>\n<\/div>\n<\/section>\n<section data-testid=\"gallery\">\n<section aria-hidden=\"true\" class=\"sc-ee78b7b3-3 inqNwV\">\n<div data-testid=\"mainImage\" role=\"img\" class=\"sc-ee78b7b3-0 hSriDl\"><\/div>\n<div class=\"sc-ee78b7b3-1 wIbtD\">\n<div data-testid=\"secondaryImage1\" role=\"img\" class=\"sc-ee78b7b3-2 dKkepK\"><\/div>\n<div data-testid=\"secondaryImage2\" role=\"img\" class=\"sc-ee78b7b3-2 bUuRZQ\"><\/div>\n<\/div>\n<\/section>\n<\/section>\n<section data-testid=\"job-list\" id=\"job-listing\" class=\"sc-f5007364-1 hRVHMy\">\n<h2 data-testid=\"section-Nossas Oportunidades-title\" class=\"sc-6fde0c52-0 haCHdH\">Nossas Oportunidades<\/h2>\n<div data-testid=\"section-Nossas Oportunidades-description\" class=\"sc-6fde0c52-1 iAgJhf\">\n<p>Se voc\u00ea se identifica com nosso prop\u00f3sito de promover acesso \u00e0 sa\u00fade para que todas as pessoas possam viver mais e melhor e quer trabalhar em uma empresa empreendedora, inovadora, \u00e9tica e sustent\u00e1vel, queremos te convidar para participar de nosso processo seletivo.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Venha fazer parte da Eurofarma, uma das melhores empresas para trabalhar do pa\u00eds, segundo o\u202f<strong>#GPTW<\/strong>!\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Valorizamos nossas pessoas e acreditamos que uma boa experi\u00eancia na empresa \u00e9 a chave do sucesso para que possamos oferecer os melhores produtos e medicamentos para o nosso consumidor.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>#VemSerEuro #SomosEurofarma #GrupoEurofarma<\/strong>\u00a0<\/p>\n<\/div>\n<div data-testid=\"old-job-filters\">\n<form aria-label=\"Busca de Vagas\" data-testid=\"job-search-form\" class=\"sc-d52d7ce9-0 gnWcBe\"><label for=\"job-search\" class=\"sc-d52d7ce9-1 bBVWZj\">Busca de Vagas<\/label><span role=\"searchbox\" aria-label=\"jobSearchFilterLabel\" class=\"sc-bbpGSz dLHSKU\"><input type=\"input\" data-testid=\"job-search\" label=\"jobSearchFilterLabel\" name=\"jobSearch\" placeholder=\"Digite o nome da vaga\" value=\"\" id=\"job-search\" aria-labelledby=\"input-job-search\" aria-describedby=\"react-aria-3 react-aria-4\" class=\"sc-jItqcz sc-UxxwN jsApaO bMvAsC\"><button aria-labelledby=\"job-search\" class=\"sc-irTswW boqOgV sc-jJgynQ jjsrBz\" id=\"job-search-button\"><\/p>\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M15.5 14h-.79l-.28-.27C15.41 12.59 16 11.11 16 9.5 16 5.91 13.09 3 9.5 3S3 5.91 3 9.5 5.91 16 9.5 16c1.61 0 3.09-.59 4.23-1.57l.27.28v.79l5 4.99L20.49 19l-4.99-5zm-6 0C7.01 14 5 11.99 5 9.5S7.01 5 9.5 5 14 7.01 14 9.5 11.99 14 9.5 14z\"><\/path><\/svg><\/div>\n<p><\/button><\/span><\/form>\n<form aria-label=\"Op\u00e7\u00f5es de Filtro de Vaga\" class=\"sc-d52d7ce9-2 fREpEo\">\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todas\" id=\"label-job-types\" for=\"job-types\" class=\"sc-brKeYL dtexMX\">Tipo de Vaga<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-224631-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-224631-placeholder\">Todas<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-types\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-types\" role=\"combobox\" aria-describedby=\"react-select-224631-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"jobTypesFilter\" value=\"\"><\/div>\n<\/div>\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todos\" id=\"label-job-workplaces\" for=\"job-workplaces\" class=\"sc-brKeYL dtexMX\">Locais de Trabalho<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-224632-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-224632-placeholder\">Todos<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-workplaces\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-workplaces\" role=\"combobox\" aria-describedby=\"react-select-224632-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"workplacesFilter\" value=\"\"><\/div>\n<\/div>\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todas\" id=\"label-job-departments\" for=\"job-departments\" class=\"sc-brKeYL dtexMX\">\u00c1reas<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-224633-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-224633-placeholder\">Todas<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-departments\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-departments\" role=\"combobox\" aria-describedby=\"react-select-224633-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"departmentsFilter\" value=\"\"><\/div>\n<\/div>\n<\/form>\n<\/div>\n<div class=\"sc-f5007364-7 cYAFjr\">\n<div role=\"status\" class=\"sc-f5007364-0 cDdpev\">32 vagas encontradas para 0 filtros aplicados<\/div>\n<div aria-hidden=\"true\" data-testid=\"job-list-amount\" class=\"sc-f5007364-8 dCDcPy\">32 vagas<\/div>\n<div class=\"sc-f5007364-8 dCDcPy\">\n<div class=\"sc-4284ca6f-3 iPhDzt\">\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"10\" id=\"label-items-por-pagina\" for=\"items-por-pagina\" class=\"sc-brKeYL dtexMX\">Itens por p\u00e1gina<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-224634-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-224634-placeholder\">10<\/div>\n<style data-emotion=\"css 1hac4vs-dummyInput\">.css-1hac4vs-dummyInput{background:0;border:0;caret-color:transparent;font-size:inherit;grid-area:1\/1\/2\/3;outline:0;padding:0;width:1px;color:transparent;left:-100px;opacity:0;position:relative;-webkit-transform:scale(.01);-moz-transform:scale(.01);-ms-transform:scale(.01);transform:scale(.01);}<\/style>\n<p><input id=\"items-por-pagina\" tabindex=\"0\" inputmode=\"none\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-items-por-pagina\" role=\"combobox\" aria-readonly=\"true\" aria-describedby=\"react-select-224634-placeholder\" class=\"css-1hac4vs-dummyInput\"><\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"items-por-pagina\" value=\"\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<ul aria-label=\"Lista de Vagas\" data-testid=\"job-list__list\">\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista Demanda Sr  em Itapevi - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6753493?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Analista Demanda Sr <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista de Mercado SR (Efetividade &amp; Premia\u00e7\u00e3o) em S\u00e3o Paulo - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6847197?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Analista de Mercado SR (Efetividade &amp; Premia\u00e7\u00e3o)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista Desenvolvimento Anal\u00edtico Sr  em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6548349?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Analista Desenvolvimento Anal\u00edtico Sr <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como  Analista Desenvolvimento M\u00e9todos Anal\u00edticos Pleno (Foco em Produtos de Degrada\u00e7\u00e3o)  em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6839377?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\"> Analista Desenvolvimento M\u00e9todos Anal\u00edticos Pleno (Foco em Produtos de Degrada\u00e7\u00e3o) <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista de Valida\u00e7\u00e3o I - Sistemas Computadorizados VSC em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6846808?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Analista de Valida\u00e7\u00e3o I &#8211; Sistemas Computadorizados VSC<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista Fiscal SR  em S\u00e3o Paulo - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6584285?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Analista Fiscal SR <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista Mercado Pl (OTC) em S\u00e3o Paulo - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6848122?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Analista Mercado Pl (OTC)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista Servi\u00e7os Administrativos SR- Montes Claros em Montes Claros - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6676664?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Analista Servi\u00e7os Administrativos SR- Montes Claros<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Montes Claros &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista Trade Marketing Pl.   em S\u00e3o Paulo - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6851098?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Analista Trade Marketing Pl.  <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Assistente Administrativo Pl (Licita\u00e7\u00f5es) em S\u00e3o Paulo - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6843652?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Assistente Administrativo Pl (Licita\u00e7\u00f5es)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar Administrativo - Montes Claros em Montes Claros - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6835501?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Auxiliar Administrativo &#8211; Montes Claros<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Montes Claros &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar de Opera\u00e7\u00f5es - (Vaga exclusiva para PCD)  em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6667678?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Auxiliar de Opera\u00e7\u00f5es &#8211; (Vaga exclusiva para PCD) <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar de Opera\u00e7\u00f5es - (Vaga exclusiva para PCD)  em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6843549?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Auxiliar de Opera\u00e7\u00f5es &#8211; (Vaga exclusiva para PCD) <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Auxiliar Escrit\u00f3rio Nova Igua\u00e7u ( Exclusiva para PCD)  MOMENTA FARMAC\u00caUTICA em Rio de Janeiro - RJ\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6856870?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Auxiliar Escrit\u00f3rio Nova Igua\u00e7u ( Exclusiva para PCD)  MOMENTA FARMAC\u00caUTICA<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Rio de Janeiro &#8211; RJ<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Banco de Talentos  em S\u00e3o Paulo - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6125590?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Banco de Talentos <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Banco de Talentos - Auxiliar de Produ\u00e7\u00e3o  2023\/2024 em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/5538106?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Banco de Talentos &#8211; Auxiliar de Produ\u00e7\u00e3o  2023\/2024<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Banco de Talentos Inclusivo (Pessoas com Defici\u00eancia) em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6464601?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Banco de Talentos Inclusivo (Pessoas com Defici\u00eancia)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Banco de Talentos - Montes Claros  em Montes Claros - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/4314086?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Banco de Talentos &#8211; Montes Claros <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Montes Claros &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Banco Talentos  - Auxiliar de Vendas Digital (Exclusiva para PCD) em Trabalho Remoto\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/5031726?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Banco Talentos  &#8211; Auxiliar de Vendas Digital (Exclusiva para PCD)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Trabalho Remoto<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Especialista Seguran\u00e7a Corporativa- Montes Claros em Montes Claros - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6676719?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Especialista Seguran\u00e7a Corporativa- Montes Claros<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Montes Claros &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Especialista Servi\u00e7os Administrativos- Montes Claros em Montes Claros - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6676467?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Especialista Servi\u00e7os Administrativos- Montes Claros<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Montes Claros &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Gerente Transportes em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6699523?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Gerente Transportes<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Jovem Aprendiz  em Rio de Janeiro - RJ\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6177717?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Jovem Aprendiz <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Rio de Janeiro &#8211; RJ<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Monitora Expedi\u00e7\u00e3o ( Vaga afirmativa para Mulheres)  em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6702010?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Monitora Expedi\u00e7\u00e3o ( Vaga afirmativa para Mulheres) <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Oficial de Cozinha - Itapevi  em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6834379?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Oficial de Cozinha &#8211; Itapevi <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Oficial de Cozinha - Rib. Preto em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6821649?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Oficial de Cozinha &#8211; Rib. Preto<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Oficial de Servi\u00e7os - Rib. Preto - PCD   em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6834542?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Oficial de Servi\u00e7os &#8211; Rib. Preto &#8211; PCD  <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Operador de M\u00e1quina I -  (Envase e embalagem) em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6784494?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Operador de M\u00e1quina I &#8211;  (Envase e embalagem)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Operador de M\u00e1quina I -  (S\u00f3lidos Revestimento) em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6695792?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Operador de M\u00e1quina I &#8211;  (S\u00f3lidos Revestimento)<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Programa Aprendiz -  Exclusiva PCD  em Itapevi - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/3823705?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">Programa Aprendiz &#8211;  Exclusiva PCD <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Itapevi &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como T\u00e9cnico(a) de Automa\u00e7\u00e3o em S\u00e3o Paulo - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6846686?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">T\u00e9cnico(a) de Automa\u00e7\u00e3o<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como T\u00e9cnico em Seguran\u00e7a do Trabalho Jr. - Rib Preto em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/eurofarma.gupy.io\/jobs\/6314912?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gPLESq\">T\u00e9cnico em Seguran\u00e7a do Trabalho Jr. &#8211; Rib Preto<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<\/ul>\n<div class=\"sc-f5007364-9 gXOSFh\">\n<nav aria-label=\"Pagina\u00e7\u00e3o do resultado da busca\">\n<ul class=\"sc-llcuoN bHIMne\">\n<li class=\"sc-jnsZEu dVzXoV\"><button data-testid=\"pagination-prev-button\" aria-disabled=\"false\" aria-label=\"V\u00e1 para p\u00e1gina anterior\" class=\"sc-hsiEis fXWJKC\">\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M15.41 7.41L14 6l-6 6 6 6 1.41-1.41L10.83 12z\"><\/path><\/svg><\/div>\n<p><\/button><\/li>\n<li class=\"sc-jnsZEu dVzXoV\"><button data-testid=\"pagination-next-button\" aria-disabled=\"false\" aria-label=\"V\u00e1 para pr\u00f3xima p\u00e1gina\" class=\"sc-hsiEis fXWJKC\">\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M10 6L8.59 7.41 13.17 12l-4.58 4.59L10 18l6-6z\"><\/path><\/svg><\/div>\n<p><\/button><\/li>\n<\/ul>\n<\/nav>\n<\/div>\n<\/section>\n<div data-testid=\"text-Clique nos links para ser direcionado para as vagas das \u00e1reas abaixo:   \" id=\"Clique nos links para ser direcionado para as vagas das \u00e1reas abaixo:   \" class=\"sc-656fdbca-0 dOwHdQ\">\n<h2 data-testid=\"section-Clique nos links para ser direcionado para as vagas das \u00e1reas abaixo:   -title\" class=\"sc-6fde0c52-0 haCHdH\">Clique nos links para ser direcionado para as vagas das \u00e1reas abaixo:   <\/h2>\n<div class=\"sc-656fdbca-1 kduMEm\">\n<ul>\n<li>For\u00e7a Vendas Eurofarma: <a href=\"https:\/\/comercialeurofarma.gupy.io\/\" rel=\"noopener noreferrer\" target=\"_blank\">comercialeurofarma.gupy.io<\/a><\/li>\n<li>For\u00e7a Vendas Momenta: <a href=\"https:\/\/momenta.gupy.io\/\" rel=\"noopener noreferrer\" target=\"_blank\">momenta.gupy.io<\/a><\/li>\n<li>Opera\u00e7\u00f5es (Industrial, Log\u00edstica, Engenharia, demais): <a href=\"https:\/\/eurofarmaoperacoes.gupy.io\/\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/eurofarmaoperacoes.gupy.io\/<\/a><\/li>\n<li>Programa Est\u00e1gio Eurofarma: <a href=\"https:\/\/programaestagioeurofarma.gupy.io\/\" rel=\"noopener noreferrer\" target=\"_blank\">programaestagioeurofarma.gupy.io<\/a><\/li>\n<li>Pearson Sa\u00fade Animal: <a href=\"https:\/\/pearsonsaudeanimal.gupy.io\/\" rel=\"noopener noreferrer\" target=\"_blank\">pearsonsaudeanimal.gupy.io<\/a><\/li>\n<li>Banco Talentos &#8211; PCDs<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<section aria-label=\"Se\u00e7\u00e3o de Depoimentos\" class=\"sc-29bf64ed-0 VecyB\">\n<div class=\"sc-29bf64ed-1 gGQgCL\">\n<h2 data-testid=\"section-O que os funcion\u00e1rios dizem-title\" class=\"sc-6fde0c52-0 haCHdH\">O que os funcion\u00e1rios dizem<\/h2>\n<\/div>\n<\/section>\n<section aria-label=\"Se\u00e7\u00e3o de links da empresa\" data-testid=\"social-links\" id=\"social-links\" class=\"sc-a7a058e5-0 iIHkZK\">\n<h2 data-testid=\"section-Conhe\u00e7a mais sobre n\u00f3s-title\" class=\"sc-6fde0c52-0 haCHdH\">Conhe\u00e7a mais sobre n\u00f3s<\/h2>\n<ul aria-label=\"Lista de links\" class=\"sc-a7a058e5-1 fUuNpV\">\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.eurofarma.com.br\" class=\"sc-a7a058e5-2 ckdWCB\" target=\"_blank\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fas\" data-icon=\"earth-americas\" class=\"svg-inline--fa fa-earth-americas \" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M57.7 193l9.4 16.4c8.3 14.5 21.9 25.2 38 29.8L163 255.7c17.2 4.9 29 20.6 29 38.5v39.9c0 11 6.2 21 16 25.9s16 14.9 16 25.9v39c0 15.6 14.9 26.9 29.9 22.6c16.1-4.6 28.6-17.5 32.7-33.8l2.8-11.2c4.2-16.9 15.2-31.4 30.3-40l8.1-4.6c15-8.5 24.2-24.5 24.2-41.7v-8.3c0-12.7-5.1-24.9-14.1-33.9l-3.9-3.9c-9-9-21.2-14.1-33.9-14.1H257c-11.1 0-22.1-2.9-31.8-8.4l-34.5-19.7c-4.3-2.5-7.6-6.5-9.2-11.2c-3.2-9.6 1.1-20 10.2-24.5l5.9-3c6.6-3.3 14.3-3.9 21.3-1.5l23.2 7.7c8.2 2.7 17.2-.4 21.9-7.5c4.7-7 4.2-16.3-1.2-22.8l-13.6-16.3c-10-12-9.9-29.5 .3-41.3l15.7-18.3c8.8-10.3 10.2-25 3.5-36.7l-2.4-4.2c-3.5-.2-6.9-.3-10.4-.3C163.1 48 84.4 108.9 57.7 193zM464 256c0-36.8-9.6-71.4-26.4-101.5L412 164.8c-15.7 6.3-23.8 23.8-18.5 39.8l16.9 50.7c3.5 10.4 12 18.3 22.6 20.9l29.1 7.3c1.2-9 1.8-18.2 1.8-27.5zM0 256a256 256 0 1 1 512 0A256 256 0 1 1 0 256z\"><\/path><\/svg>Website<\/a><\/li>\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.linkedin.com\/company\/eurofarma\" class=\"sc-a7a058e5-2 ckdWCB\" target=\"_blank\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"linkedin-in\" class=\"svg-inline--fa fa-linkedin-in \" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>LinkedIn<\/a><\/li>\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/eurofarma\" class=\"sc-a7a058e5-2 ckdWCB\" target=\"_blank\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"facebook-f\" class=\"svg-inline--fa fa-facebook-f \" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path fill=\"currentColor\" d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg>Facebook<\/a><\/li>\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/eurofarma\" class=\"sc-a7a058e5-2 ckdWCB\" target=\"_blank\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"instagram\" class=\"svg-inline--fa fa-instagram \" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>Instagram<\/a><\/li>\n<\/ul>\n<\/section>\n<section aria-label=\"Se\u00e7\u00e3o de v\u00eddeos\" data-testid=\"video-section\" class=\"sc-ed722fcc-0 ifqNqA\">\n<h2 data-testid=\"section-Somos Eurofarma-title\" class=\"sc-6fde0c52-0 haCHdH\">Somos Eurofarma<\/h2>\n<div class=\"sc-ed722fcc-1 jDKGiy\"><iframe data-testid=\"video-iframe\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/pScUTc6sEIs?hl=pt\" title=\"V\u00eddeo sobre a empresa 1\" width=\"100%\" class=\"sc-ed722fcc-2 kGunFs\"><\/iframe><\/div>\n<\/section>\n<section data-testid=\"gallery\">\n<section aria-hidden=\"true\" class=\"sc-ee78b7b3-3 bVEXQO\">\n<div data-testid=\"mainImage\" role=\"img\" class=\"sc-ee78b7b3-0 hZLISI\"><\/div>\n<\/section>\n<\/section>\n<p><a aria-label=\"Central de ajuda Gupy para pessoas candidatas\" data-testid=\"help-button\" rel=\"noreferrer noopener\" href=\"https:\/\/support-candidates.gupy.io\/hc\/pt-br\" class=\"sc-645a84e3-0 dCWYzQ\" target=\"_blank\">?<\/a><\/main><\/p>\n<footer class=\"sc-8113e837-0 gJOYGk\">Powered by Gupy 2024. Todos os direitos reservados.<\/footer>\n<\/div>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>SobreVagas Fazer login como candidato(a) Eurofarma Eurofarma Laborat\u00f3rios Somos uma multinacional brasileira presente em 22 pa\u00edses, com\u00a0mais de\u00a050 anos de hist\u00f3ria e o prop\u00f3sito de promover acesso \u00e0 sa\u00fade para que todas as pessoas possam viver mais e melhor. \u00c9 isso que move a Eurofarma todos os dias. \u00a0 Com mais de 11 mil colaboradores, &#8230; <a title=\"Vagas de empregos na Eurofarma para trabalhar em Ribeir\u00e3o Preto-SP\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/10\/vagas-de-empregos-na-eurofarma-para-trabalhar-em-ribeirao-preto-sp-33\/\" aria-label=\"Leia mais sobre Vagas de empregos na Eurofarma para trabalhar em Ribeir\u00e3o Preto-SP\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":41734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-41733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas-de-empregos-em-ribeirao-preto-regiao-brasil"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710117286_Sem-titulo-6-22.jpg?fit=1231%2C720&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710117286_Sem-titulo-6-22.jpg?fit=1231%2C720&ssl=1",1231,720,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710117286_Sem-titulo-6-22.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710117286_Sem-titulo-6-22.jpg?fit=300%2C175&ssl=1",300,175,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710117286_Sem-titulo-6-22.jpg?fit=768%2C449&ssl=1",768,449,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710117286_Sem-titulo-6-22.jpg?fit=1024%2C599&ssl=1",1024,599,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710117286_Sem-titulo-6-22.jpg?fit=1231%2C720&ssl=1",1231,720,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710117286_Sem-titulo-6-22.jpg?fit=1231%2C720&ssl=1",1231,720,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"SobreVagas Fazer login como candidato(a) Eurofarma Eurofarma Laborat\u00f3rios Somos uma multinacional brasileira presente em 22 pa\u00edses, com\u00a0mais de\u00a050 anos de hist\u00f3ria e o prop\u00f3sito de promover acesso \u00e0 sa\u00fade para que todas as pessoas possam viver mais e melhor. \u00c9 isso que move a Eurofarma todos os dias. \u00a0 Com mais de 11 mil colaboradores,&hellip;","jetpack-related-posts":[{"id":17592,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/18\/20-vagas-de-empregos-entre-e-veja-oportunidades-de-trabalho-em-ribeirao-preto-sp-3\/","url_meta":{"origin":41733,"position":0},"title":"20 vagas de empregos: entre e veja oportunidades de trabalho em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"18 de Dezembro de 2023","format":false,"excerpt":"Lista de Vagas em Ribeir\u00e3o Preto Ribeir\u00e3o Preto - SP Santa Casa Ribeir\u00e3o Preto: Confira as Vagas Dispon\u00edveis Ver mais Ribeir\u00e3o Preto - SP AMBEV Contrata Ver mais Ribeir\u00e3o Preto - SP Cacau Show- Consultor Comercial Ver mais Ribeir\u00e3o Preto - SP Vendedor | Vans Ribeir\u00e3o Ver mais Ribeir\u00e3o Preto\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14848,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/20-vagas-de-empregos-entre-e-veja-oportunidades-de-trabalho-em-ribeirao-preto-sp\/","url_meta":{"origin":41733,"position":1},"title":"20 vagas de empregos: entre e veja oportunidades de trabalho em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"12 de Dezembro de 2023","format":false,"excerpt":"Vagas em Ribeir\u00e3o Preto: Destaques No data was found Lista de Vagas em Ribeir\u00e3o Preto Ribeir\u00e3o Preto - SP Cacau Show- Consultor Comercial Ver mais Ribeir\u00e3o Preto - SP Vendedor | Vans Ribeir\u00e3o Ver mais Ribeir\u00e3o Preto - SP MR. KITSCH \u2013 Vendedor(a) Ver mais Ribeir\u00e3o Preto - SP OCULARIUM\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702407740_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702407740_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702407740_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702407740_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702407740_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16852,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/16\/20-vagas-de-empregos-entre-e-veja-oportunidades-de-trabalho-em-ribeirao-preto-sp-2\/","url_meta":{"origin":41733,"position":2},"title":"20 vagas de empregos: entre e veja oportunidades de trabalho em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"16 de Dezembro de 2023","format":false,"excerpt":"Lista de Vagas em Ribeir\u00e3o Preto Ribeir\u00e3o Preto - SP Santa Casa Ribeir\u00e3o Preto: Confira as Vagas Dispon\u00edveis Ver mais Ribeir\u00e3o Preto - SP AMBEV Contrata Ver mais Ribeir\u00e3o Preto - SP Cacau Show- Consultor Comercial Ver mais Ribeir\u00e3o Preto - SP Vendedor | Vans Ribeir\u00e3o Ver mais Ribeir\u00e3o Preto\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14913,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/vagas-em-ribeirao-preto-destaques\/","url_meta":{"origin":41733,"position":3},"title":"Vagas em Ribeir\u00e3o Preto: Destaques","author":"ismaelcolosi.com.br","date":"12 de Dezembro de 2023","format":false,"excerpt":"Vagas em Ribeir\u00e3o Preto: Destaques No data was found Lista de Vagas em Ribeir\u00e3o Preto Ribeir\u00e3o Preto - SP Cacau Show- Consultor Comercial Ver mais Ribeir\u00e3o Preto - SP Vendedor | Vans Ribeir\u00e3o Ver mais Ribeir\u00e3o Preto - SP MR. KITSCH \u2013 Vendedor(a) Ver mais Ribeir\u00e3o Preto - SP OCULARIUM\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14880,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/14880\/","url_meta":{"origin":41733,"position":4},"title":"Vagas em Ribeir\u00e3o Preto: Destaques\u2026","author":"ismaelcolosi.com.br","date":"12 de Dezembro de 2023","format":false,"excerpt":"Vagas em Ribeir\u00e3o Preto: Destaques No data was found Lista de Vagas em Ribeir\u00e3o Preto Ribeir\u00e3o Preto - SP Cacau Show- Consultor Comercial Ver mais Ribeir\u00e3o Preto - SP Vendedor | Vans Ribeir\u00e3o Ver mais Ribeir\u00e3o Preto - SP MR. KITSCH \u2013 Vendedor(a) Ver mais Ribeir\u00e3o Preto - SP OCULARIUM\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702411852_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702411852_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702411852_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702411852_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702411852_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":65536,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/12\/vagas-de-emprego-para-engenheiro-civil-em-ribeirao-preto-sp-17\/","url_meta":{"origin":41733,"position":5},"title":"Vagas de emprego para Engenheiro Civil em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"12 de Setembro de 2024","format":false,"excerpt":"Engenheiro de Seguran\u00e7a do Trabalho Ribeir\u00e3o Preto - SP Efetivo COORDENADOR ASSISTENCIA TECNICA Ribeir\u00e3o Preto - SP Efetivo Engenheiro de Seguran\u00e7a do Trabalho Engenheiro de Seguran\u00e7a do Trabalho Engenheiro Civil-Projetista Or\ufffdamentista Est\u00e1gio em Engenharia Civil e Arquitetura - Ribeir\u00e3o Preto , SP Ribeir\u00e3o Preto - SP Banco de talentos Receba\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-aR7","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41733"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/41734"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}