{"id":41234,"date":"2024-03-07T08:58:46","date_gmt":"2024-03-07T11:58:46","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/07\/alimentacao-social-de-qualidade\/"},"modified":"2024-03-07T08:58:46","modified_gmt":"2024-03-07T11:58:46","slug":"alimentacao-social-de-qualidade","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/07\/alimentacao-social-de-qualidade\/","title":{"rendered":"Alimenta\u00e7\u00e3o social de qualidade\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-03-07T08:20:06-03:00\">7 de mar\u00e7o de 2024 | 8:20<\/time><time class=\"updated\" datetime=\"2024-03-06T18:24:37-03:00\">6 de mar\u00e7o de 2024 | 18:24<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"376454\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Alimenta\u00e7\u00e3o%20social%20de%20qualidade\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/alimentacao-social-de-qualidade\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p><span class=\"TextRun Highlight SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW235141520 BCX0\" data-ccp-charstyle=\"normaltextrun\" data-ccp-charstyle-defn=\"{&quot;ObjectId&quot;:&quot;996e88d2-fc20-4324-a24d-54c6eda31d45|5&quot;,&quot;ClassId&quot;:1073872969,&quot;Properties&quot;:[469775450,&quot;normaltextrun&quot;,201340122,&quot;1&quot;,134233614,&quot;true&quot;,469778129,&quot;normaltextrun&quot;,335572020,&quot;1&quot;,469778324,&quot;Default Paragraph Font&quot;]}\">Duarte Nogueira *<\/span><\/span><span class=\"TextRun Highlight SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW235141520 BCX0\" data-ccp-charstyle=\"scxw102242174\" data-ccp-charstyle-defn=\"{&quot;ObjectId&quot;:&quot;996e88d2-fc20-4324-a24d-54c6eda31d45|6&quot;,&quot;ClassId&quot;:1073872969,&quot;Properties&quot;:[469775450,&quot;scxw102242174&quot;,201340122,&quot;1&quot;,134233614,&quot;true&quot;,469778129,&quot;scxw102242174&quot;,335572020,&quot;1&quot;,469778324,&quot;Default Paragraph Font&quot;]}\">\u202f<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"TextRun Highlight SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW235141520 BCX0\" data-ccp-charstyle=\"normaltextrun\"><span class=\"__cf_email__\" data-cfemail=\"dabeafbba8aebfb4b5bdafbfb3a8bb9aa8b3b8bfb3a8bbb5aaa8bfaeb5f4a9aaf4bdb5acf4b8a8\">[email\u00a0protected]<\/span><\/span><\/span><span class=\"TextRun Highlight SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW235141520 BCX0\" data-ccp-charstyle=\"scxw102242174\">\u202f<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"TextRun SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW235141520 BCX0\">Na sexta-feira da semana passada, dia 1\u00ba de mar\u00e7o, assinei a Ordem de Servi\u00e7o para a constru\u00e7\u00e3o do novo restaurante Bom Prato de nossa cidade. A unidade ser\u00e1 constru\u00edda ao lado da <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW235141520 BCX0\">Coderp<\/span><span class=\"NormalTextRun SCXW235141520 BCX0\"> e pr\u00f3ximo ao terminal rodovi\u00e1rio urbano que est\u00e1 instalado entre a <\/span><span class=\"NormalTextRun SCXW235141520 BCX0\">rua<\/span><span class=\"NormalTextRun SCXW235141520 BCX0\"> Jos\u00e9 Bonif\u00e1cio e a avenida Jer\u00f4nimo Gon\u00e7alves, em uma \u00e1rea de 1.868,14 metros quadrados. A proximidade com o local de embarque e desembarque de passageiros facilitar\u00e1 o acesso dos cidad\u00e3os que dependem desse servi\u00e7o de transporte.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"TextRun SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW235141520 BCX0\">A licita\u00e7\u00e3o para a constru\u00e7\u00e3o do novo espa\u00e7o teve um valor m\u00e1ximo estipulado em R$ 5,6 milh\u00f5es. No entanto, houve uma economia de 16,5% aos cofres p\u00fablicos. A ASF Engenharia e Neg\u00f3cios Ltda. EPP foi <\/span><span class=\"NormalTextRun SCXW235141520 BCX0\">a<\/span><span class=\"NormalTextRun SCXW235141520 BCX0\"> empresa vencedora do certame, ao oferecer proposta de R$ 4,6 milh\u00f5es. A nova unidade substituir\u00e1 a que funciona h\u00e1 mais de 18 anos no pr\u00e9dio de n\u00famero 765 da <\/span><span class=\"NormalTextRun SCXW235141520 BCX0\">rua<\/span><span class=\"NormalTextRun SCXW235141520 BCX0\"> Saldanha Marinho e que serve 300 caf\u00e9s da manh\u00e3, 1750 almo\u00e7os e 300 jantares diariamente. Ribeir\u00e3o Preto conta ainda com a unidade Hospital das Cl\u00ednicas do Bom Prato, que serve 300 caf\u00e9s e 1400 almo\u00e7os todos os dias.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"TextRun SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW235141520 BCX0\">A unidade a ser constru\u00edda tem como objetivo atender as necessidades alimentares e de assist\u00eancia b\u00e1sica da popula\u00e7\u00e3o em situa\u00e7\u00e3o de vulnerabilidade, que vive na regi\u00e3o central. Construiremos um Bom Prato no centro da cidade nos moldes arquitet\u00f4nicos do Bom Prato do HC, para atender a popula\u00e7\u00e3o com todo conforto e qualidade. O local n\u00e3o servir\u00e1 apenas para alimenta\u00e7\u00e3o, mas tamb\u00e9m ser\u00e1 um espa\u00e7o de acolhimento e suporte.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"TextRun SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW235141520 BCX0\">Al\u00e9m das refei\u00e7\u00f5es di\u00e1rias, o pr\u00e9dio oferecer\u00e1 servi\u00e7os de higiene, como banho, corte de cabelo, barbearia e far\u00e1 doa\u00e7\u00e3o de roupas, visando atender as necessidades b\u00e1sicas daqueles que <\/span><span class=\"NormalTextRun SCXW235141520 BCX0\">frequentar\u00e3o<\/span><span class=\"NormalTextRun SCXW235141520 BCX0\"> o estabelecimento. Esperamos, com o novo Bom Prato Centro, n\u00e3o apenas suprir as necessidades alimentares b\u00e1sicas da popula\u00e7\u00e3o mais vulner\u00e1vel, mas tamb\u00e9m proporcionar um espa\u00e7o de dignidade e inclus\u00e3o para aqueles que mais necessitam.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"TextRun SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW235141520 BCX0\">Ap\u00f3s a constru\u00e7\u00e3o, o governo estadual escolher\u00e1 uma entidade assistencial para fazer a gest\u00e3o do restaurante, que <\/span><span class=\"NormalTextRun SCXW235141520 BCX0\">oferecer\u00e1,<\/span><span class=\"NormalTextRun SCXW235141520 BCX0\"> como j\u00e1 ocorre hoje, caf\u00e9 da manh\u00e3 a R$ 0,50 e almo\u00e7o ou jantar a R$ 1,00, com alimentos de qualidade e refei\u00e7\u00f5es balanceadas, preparadas com orienta\u00e7\u00e3o de nutricionistas. O <\/span><span class=\"NormalTextRun SCXW235141520 BCX0\">atendimento da popula\u00e7\u00e3o mais carente \u00e9 feito com o trabalho de institui\u00e7\u00f5es e com subs\u00eddio financeiro do governo estadual, que completa o valor das refei\u00e7\u00f5es, pagando a maior parte.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"TextRun SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW235141520 BCX0\">Pelo atendimento di\u00e1rio com produtos de qualidade, este \u00e9 um dos melhores, sen\u00e3o <\/span><span class=\"NormalTextRun SCXW235141520 BCX0\">o melhor, programas<\/span><span class=\"NormalTextRun SCXW235141520 BCX0\"> de alimenta\u00e7\u00e3o social que desempenha papel fundamental nas cidades onde \u00e9 instalado. \u00c9 por isso que muitos munic\u00edpios lutam para conseguir uma unidade. Ribeir\u00e3o Preto tem duas unidades que foram frutos de muito trabalho junto ao governo estadual. E elas existem n\u00e3o apenas pelo tamanho e import\u00e2ncia da cidade, mas para garantir alimenta\u00e7\u00e3o tamb\u00e9m aos doentes e seus acompanhantes que v\u00eam de outras cidades e estados para serem atendidos no Hospital das Cl\u00ednicas.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"TextRun SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW235141520 BCX0\">Por seu alcance social, o Bom Prato \u00e9 um programa social muito desejado. E n\u00f3s n\u00e3o medimos esfor\u00e7os para ter as unidades em nosso munic\u00edpio. No Bom Prato HC, investimos mais de R$ 4,6 milh\u00f5es e j\u00e1 colhemos bons resultados. No dia 22 de fevereiro o restaurante completou um ano, com um card\u00e1pio especial para comemorar as mais de 342 mil refei\u00e7\u00f5es e 71 mil caf\u00e9s da manh\u00e3 servidos no local. No que depender da prefeitura de Ribeir\u00e3o Preto o Bom Prato seguir\u00e1 atendendo sempre os que mais precisam, de forma inclusiva e com a qualidade j\u00e1 atestada por quem faz no restaurante as suas refei\u00e7\u00f5es di\u00e1rias.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW235141520 BCX0\"><span class=\"SCXW235141520 BCX0\">\u00a0<\/span><br class=\"SCXW235141520 BCX0\"\/><\/span><span class=\"TextRun SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW235141520 BCX0\">* Prefeito de Ribeir\u00e3o Preto<\/span><\/span><span class=\"TextRun SCXW235141520 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW235141520 BCX0\">\u00a0\u00a0<\/span><\/span><span class=\"EOP SCXW235141520 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/alimentacao-social-de-qualidade\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 7 de mar\u00e7o de 2024 | 8:206 de mar\u00e7o de 2024 | 18:24 0 Duarte Nogueira *\u202f\u00a0[email\u00a0protected]\u202f\u00a0\u00a0Na sexta-feira da semana passada, dia 1\u00ba de mar\u00e7o, assinei a Ordem de Servi\u00e7o para a constru\u00e7\u00e3o do novo restaurante Bom Prato de nossa cidade. A unidade ser\u00e1 constru\u00edda ao lado da Coderp e pr\u00f3ximo ao terminal rodovi\u00e1rio &#8230; <a title=\"Alimenta\u00e7\u00e3o social de qualidade\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/07\/alimentacao-social-de-qualidade\/\" aria-label=\"Leia mais sobre Alimenta\u00e7\u00e3o social de qualidade\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":41235,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[4815,785,4816,26,1754,786],"class_list":["post-41234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-alimentacao","tag-jornal","tag-qualidade","tag-ribeirao","tag-social","tag-tribuna"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/nogueira-atual.jpg?fit=800%2C500&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/nogueira-atual.jpg?fit=800%2C500&ssl=1",800,500,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/nogueira-atual.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/nogueira-atual.jpg?fit=300%2C188&ssl=1",300,188,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/nogueira-atual.jpg?fit=768%2C480&ssl=1",768,480,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/nogueira-atual.jpg?fit=800%2C500&ssl=1",800,500,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/nogueira-atual.jpg?fit=800%2C500&ssl=1",800,500,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/nogueira-atual.jpg?fit=800%2C500&ssl=1",800,500,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 7 de mar\u00e7o de 2024 | 8:206 de mar\u00e7o de 2024 | 18:24 0 Duarte Nogueira *\u202f\u00a0[email\u00a0protected]\u202f\u00a0\u00a0Na sexta-feira da semana passada, dia 1\u00ba de mar\u00e7o, assinei a Ordem de Servi\u00e7o para a constru\u00e7\u00e3o do novo restaurante Bom Prato de nossa cidade. A unidade ser\u00e1 constru\u00edda ao lado da Coderp e pr\u00f3ximo ao terminal rodovi\u00e1rio&hellip;","jetpack-related-posts":[{"id":33912,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/31\/diferente\/","url_meta":{"origin":41234,"position":0},"title":"Diferente &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"31 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 31 de janeiro de 2024 | 9:0329 de janeiro de 2024 | 11:43 0Prestigiad\u00edssimo o coquetel na comemora\u00e7\u00e3o de 1 ano da loja do Espa\u00e7o Coletivo Social da ONG Arco-\u00cdris, no 2\u00ba piso do Shopping Santa \u00darsula, que contou com desfile e muita gente papo cabe\u00e7a.\u00a0\u00a0\u00a0 [ad_2] Source link","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/7-scaled.jpg?fit=484%2C645&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":43062,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/19\/projeto-ritmo-do-bem\/","url_meta":{"origin":41234,"position":1},"title":"Projeto \u201cRitmo do Bem\u201d &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"19 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 19 de mar\u00e7o de 2024 | 9:0318 de mar\u00e7o de 2024 | 13:04 0O projeto \u201cRitmo do Bem\u201d realizdo no Espa\u00e7o Bella Citt\u00e0, em benef\u00edcio da Casa das Mangueiras, com o cantor Kiko Zambianchi e a participa\u00e7\u00e3o de convidados especiais como a banda Hod Hanna e o m\u00fasico \u00c1lvaro\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42795,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/17\/bodas-de-ouro-8\/","url_meta":{"origin":41234,"position":2},"title":"Bodas de Ouro &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"17 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 17 de mar\u00e7o de 2024 | 9:0315 de mar\u00e7o de 2024 | 16:40 0O querido casal, Mari\u00e2ngela e Enio Pasquali, est\u00e3o comemorando Bodas de Ouro, com a linda fam\u00edlia que constitu\u00edram.Reuniram o cl\u00e3 no Resort Vila Gal\u00e9, em Macei\u00f3, para desfrutarem da uni\u00e3o e alegria a beira das \u00e1guas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/17-8-scaled.jpg?fit=860%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/17-8-scaled.jpg?fit=860%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/17-8-scaled.jpg?fit=860%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/17-8-scaled.jpg?fit=860%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44736,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/30\/rodonaves-express\/","url_meta":{"origin":41234,"position":3},"title":"Rodonaves Express &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"30 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 30 de mar\u00e7o de 2024 | 9:0327 de mar\u00e7o de 2024 | 12:44 0 Ribeir\u00e3o Preto ganhou sua primeira unidade da Rodonaves Express, na avenida Presidente Vargas, um \u201cbra\u00e7o\u201d da RTE Rodonaves \u2013 a primeira empresa do Grupo Rodonaves e que \u00e9 refer\u00eancia nacional em transporte de carga no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1-g.jpg?fit=667%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1-g.jpg?fit=667%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1-g.jpg?fit=667%2C500&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":44561,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/28\/camara-aprova-loteria-municipal\/","url_meta":{"origin":41234,"position":4},"title":"C\u00e2mara aprova loteria municipal\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"28 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 28 de mar\u00e7o de 2024 | 14:0028 de mar\u00e7o de 2024 | 12:01 0 A C\u00e2mara de Vereadores aprovou, na sess\u00e3o da \u00faltima ter\u00e7a-feira, 26 de mar\u00e7o, projeto de lei que pretende quer criar, em Ribeir\u00e3o Preto, o servi\u00e7o p\u00fablico de loteria municipal. Apesar da aprova\u00e7\u00e3o, a lei precisa\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Loteria-Thaisa-Coroado-Camara.jpg?fit=750%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Loteria-Thaisa-Coroado-Camara.jpg?fit=750%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Loteria-Thaisa-Coroado-Camara.jpg?fit=750%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Loteria-Thaisa-Coroado-Camara.jpg?fit=750%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":39337,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/25\/victor-eds-traz-sua-expertise-em-criptomoedas-e-investimentos-em-coluna-no-tribuna\/","url_meta":{"origin":41234,"position":5},"title":"Victor Eds traz sua expertise em criptomoedas e investimentos em coluna no Tribuna\u00a0","author":"ismaelcolosi.com.br","date":"25 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 25 de fevereiro de 2024 | 8:3024 de fevereiro de 2024 | 20:10 0O jornalista Victor Eds, de 48 anos, bacharel em Comunica\u00e7\u00e3o Social com \u00eanfase em Marketing, est\u00e1 prestes a lan\u00e7ar uma coluna semanal no Tribuna Ribeir\u00e3o, abordando temas relacionados ao universo das criptomoedas e investimentos. Sua trajet\u00f3ria\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/2-CRIPTO-victor-cripto-scaled.jpg?fit=860%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/2-CRIPTO-victor-cripto-scaled.jpg?fit=860%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/2-CRIPTO-victor-cripto-scaled.jpg?fit=860%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/2-CRIPTO-victor-cripto-scaled.jpg?fit=860%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-aJ4","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41234"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/41235"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}