{"id":40546,"date":"2024-03-04T15:23:07","date_gmt":"2024-03-04T18:23:07","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/casamentos-de-idosos-sem-separacao-obrigatoria-de-bens\/"},"modified":"2024-03-04T15:23:07","modified_gmt":"2024-03-04T18:23:07","slug":"casamentos-de-idosos-sem-separacao-obrigatoria-de-bens","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/casamentos-de-idosos-sem-separacao-obrigatoria-de-bens\/","title":{"rendered":"Casamentos de idosos sem separa\u00e7\u00e3o obrigat\u00f3ria de bens\u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-03-04T15:00:44-03:00\">4 de mar\u00e7o de 2024 | 15:00<\/time><time class=\"updated\" datetime=\"2024-03-04T10:13:50-03:00\">4 de mar\u00e7o de 2024 | 10:13<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"375770\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Casamentos%20de%20idosos%20sem%20separa\u00e7\u00e3o%20obrigat\u00f3ria%20de%20bens\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/casamentos-de-idosos-sem-separacao-obrigatoria-de-bens\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p><span data-contrast=\"auto\">Pessoas com mais de 70 anos que desejam se casar ou viver em uni\u00e3o est\u00e1vel sem a exig\u00eancia do regime da separa\u00e7\u00e3o obrigat\u00f3ria de bens agora podem fazer esta op\u00e7\u00e3o em qualquer um dos 8.344 cart\u00f3rios de notas brasileiros. A possibilidade foi estabelecida por uma decis\u00e3o do Supremo Tribunal Federal (STF) que permitiu isso por meio de uma escritura p\u00fablica.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A partir de agora, a separa\u00e7\u00e3o de bens torna-se facultativa, sendo aplic\u00e1vel apenas na aus\u00eancia da manifesta\u00e7\u00e3o de vontade das partes. Essa medida concede aos casais nessa faixa et\u00e1ria a liberdade de escolher o modelo patrimonial que melhor atenda aos seus interesses, realizando uma escritura p\u00fablica de pacto antenupcial em cart\u00f3rio de notas. No ano passado, os cart\u00f3rios de notas de Ribeir\u00e3o Preto registraram um total de 323 atos de pacto antenupcial por idosos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A tese fixada pelo STF diz que \u201cnos casamentos e uni\u00f5es est\u00e1veis envolvendo pessoa maior de 70 anos, o regime de separa\u00e7\u00e3o de bens previsto no artigo 1.642, II do C\u00f3digo Civil, pode ser afastado por expressa manifesta\u00e7\u00e3o de vontade das partes, mediante escritura p\u00fablica\u201d. Caber\u00e1 ao cart\u00f3rio de notas orientar devidamente os interessados nessa faixa et\u00e1ria sobre a nova possibilidade, fornecendo informa\u00e7\u00f5es claras e acess\u00edveis, garantindo que os envolvidos compreendam as mudan\u00e7as e exer\u00e7am sua escolha de maneira consciente.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">De acordo com o presidente do Col\u00e9gio Notarial do Brasil \u2013 Se\u00e7\u00e3o S\u00e3o Paulo (CNB\/SP), Daniel Paes de Almeida, a decis\u00e3o do STF representa um avan\u00e7o significativo na autonomia das partes envolvidas. \u201cEssa mudan\u00e7a demonstra uma compreens\u00e3o mais ampla da liberdade contratual e possibilita a personaliza\u00e7\u00e3o dos contratos matrimoniais, atendendo \u00e0s vontades individuais e \u00e0 nova realidade da sociedade\u201d, afirmou.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Como fazer o Pacto Antenupcial<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O Pacto Antenupcial \u00e9 um contrato celebrado pelos noivos para estabelecer o regime de bens e as rela\u00e7\u00f5es patrimoniais que ser\u00e3o aplic\u00e1veis ao casamento ou \u00e0 uni\u00e3o est\u00e1vel. Necess\u00e1rio quando as partes querem optar por um regime de bens diferente do regime legal, que \u00e9 o regime da comunh\u00e3o parcial de bens, e agora passa a ser o caminho para os maiores de 70 anos que desejam contrair uma rela\u00e7\u00e3o sem a obrigatoriedade do regime da separa\u00e7\u00e3o obrigat\u00f3ria de bens.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O pacto antenupcial deve ser feito por escritura p\u00fablica de forma f\u00edsica em cart\u00f3rio de notas ou pela plataforma <\/span><a href=\"https:\/\/www.e-notariado.org.br\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">e-Notariado<\/span><\/a><span data-contrast=\"auto\"> e, posteriormente, deve ser levado ao cart\u00f3rio de Registro Civil onde ser\u00e1 realizado o casamento, bem como, ap\u00f3s a celebra\u00e7\u00e3o do casamento, ao Cart\u00f3rio de Registro de Im\u00f3veis do primeiro domic\u00edlio do casal para produzir efeitos perante terceiros e averbado na matr\u00edcula dos bens im\u00f3veis do casal. O regime de bens come\u00e7a a vigorar a partir da data do casamento e somente poder\u00e1 ser alterado mediante autoriza\u00e7\u00e3o judicial.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Antes do casamento ou da uni\u00e3o est\u00e1vel, as partes devem comparecer ao cart\u00f3rio de notas com os documentos pessoais (RG e CPF originais), para fazer o pacto antenupcial. O pre\u00e7o do ato \u00e9 tabelado por lei estadual.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/casamentos-de-idosos-sem-separacao-obrigatoria-de-bens\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 4 de mar\u00e7o de 2024 | 15:004 de mar\u00e7o de 2024 | 10:13 0 Pessoas com mais de 70 anos que desejam se casar ou viver em uni\u00e3o est\u00e1vel sem a exig\u00eancia do regime da separa\u00e7\u00e3o obrigat\u00f3ria de bens agora podem fazer esta op\u00e7\u00e3o em qualquer um dos 8.344 cart\u00f3rios de notas brasileiros. A &#8230; <a title=\"Casamentos de idosos sem separa\u00e7\u00e3o obrigat\u00f3ria de bens\u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/casamentos-de-idosos-sem-separacao-obrigatoria-de-bens\/\" aria-label=\"Leia mais sobre Casamentos de idosos sem separa\u00e7\u00e3o obrigat\u00f3ria de bens\u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":40547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[4747,2719,1633,4746,1025,4745],"class_list":["post-40546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-bens","tag-casamentos","tag-idosos","tag-obrigatoria","tag-sem","tag-separacao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/idososcasamento.jpg?fit=415%2C623&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/idososcasamento.jpg?fit=415%2C623&ssl=1",415,623,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/idososcasamento.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/idososcasamento.jpg?fit=200%2C300&ssl=1",200,300,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/idososcasamento.jpg?fit=415%2C623&ssl=1",415,623,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/idososcasamento.jpg?fit=415%2C623&ssl=1",415,623,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/idososcasamento.jpg?fit=415%2C623&ssl=1",415,623,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/idososcasamento.jpg?fit=415%2C623&ssl=1",415,623,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 4 de mar\u00e7o de 2024 | 15:004 de mar\u00e7o de 2024 | 10:13 0 Pessoas com mais de 70 anos que desejam se casar ou viver em uni\u00e3o est\u00e1vel sem a exig\u00eancia do regime da separa\u00e7\u00e3o obrigat\u00f3ria de bens agora podem fazer esta op\u00e7\u00e3o em qualquer um dos 8.344 cart\u00f3rios de notas brasileiros. A&hellip;","jetpack-related-posts":[{"id":21989,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/28\/revista-intima-e-amazonia-estao-na-pauta-do-stf-depois-do-recesso\/","url_meta":{"origin":40546,"position":0},"title":"Revista intima e Amaz\u00f4nia est\u00e3o na pauta do STF depois do recesso","author":"ismaelcolosi.com.br","date":"28 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 28 de dezembro de 2023 | 12:0027 de dezembro de 2023 | 16:41 0O ministro Lu\u00eds Roberto Barroso, presidente do Supremo Tribunal Federal, j\u00e1 definiu os assuntos que ser\u00e3o discutidos pela Corte no primeiro m\u00eas do ano judici\u00e1rio de 2024: o regime de separa\u00e7\u00e3o de bens no casamento de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/TerrorSTF-Fabio-Rodrigues-Pozzebom-Ag.Br_.-01-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/TerrorSTF-Fabio-Rodrigues-Pozzebom-Ag.Br_.-01-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/TerrorSTF-Fabio-Rodrigues-Pozzebom-Ag.Br_.-01-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/TerrorSTF-Fabio-Rodrigues-Pozzebom-Ag.Br_.-01-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41054,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/06\/receita-divulga-regras-para-irpf-2024-confira-prazos-e-limites\/","url_meta":{"origin":40546,"position":1},"title":"Receita divulga regras para IRPF 2024; confira prazos e limites","author":"ismaelcolosi.com.br","date":"6 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 6 de mar\u00e7o de 2024 | 14:306 de mar\u00e7o de 2024 | 13:57 0O prazo de entrega do Imposto de Renda Pessoa F\u00edsica (IRPF) em 2024 come\u00e7a em 15 de mar\u00e7o e vai at\u00e9 31 de maio. A Receita Federal divulgou hoje (6) as regras para a declara\u00e7\u00e3o do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/imposto-de-renda-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/imposto-de-renda-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/imposto-de-renda-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/imposto-de-renda-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":32297,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/24\/peca-infantil-o-casamento-de-dona-baratinha-no-teatro-municipal\/","url_meta":{"origin":40546,"position":2},"title":"Pe\u00e7a infantil &#8220;O casamento de Dona Baratinha&#8221; no Teatro Municipal \u00a0","author":"ismaelcolosi.com.br","date":"24 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 24 de janeiro de 2024 | 18:0023 de janeiro de 2024 | 18:43 0O espet\u00e1culo musical \u201cO casamento de Dona Baratinha\u201d, o primeiro conto infantil traduzido do portugu\u00eas de Portugal para o Brasil, estar\u00e1 em cartaz no Teatro Municipal de Ribeir\u00e3o Preto em 25 de fevereiro, \u00faltimo domingo do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Barata-Gesmar-Nunes-01-scaled.jpg?fit=520%2C645&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":38598,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/20\/o-espetaculo-o-casamento-de-dona-baratinha-acontece-no-teatro-municipal\/","url_meta":{"origin":40546,"position":3},"title":"O espet\u00e1culo \u201cO casamento de Dona Baratinha\u201d, acontece no Teatro Municipal","author":"ismaelcolosi.com.br","date":"20 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 20 de fevereiro de 2024 | 18:0019 de fevereiro de 2024 | 18:33 0O espet\u00e1culo musical \u201cO casamento de Dona Baratinha\u201d, o primeiro conto infantil traduzido do portugu\u00eas de Portugal para o Brasil, estar\u00e1 em cartaz no Teatro Municipal de Ribeir\u00e3o Preto neste domingo, 25 de fevereiro, a partir\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Barata-Gesmar-Nunes-01-1-scaled.jpg?fit=520%2C645&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":29856,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/19\/nany-people-se-apresenta-em-ribeirao-com-o-stand-up-como-salvar-um-casamento\/","url_meta":{"origin":40546,"position":4},"title":"Nany People se apresenta em Ribeir\u00e3o com o stand-up &#8216;Como Salvar Um Casamento&#8217;","author":"ismaelcolosi.com.br","date":"19 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A atriz e comediante Nany People volta a Ribeir\u00e3o Preto no dia 1\u00ba de mar\u00e7o para apresentar o seu novo espet\u00e1culo \u201cComo Salvar Um Casamento\u201c, no Teatro Municipal. A artista retorna \u00e0s suas ra\u00edzes teatrais num mon\u00f3logo que fez hist\u00f3ria em sua carreira. O espet\u00e1culo ter\u00e1 \u00fanica apresenta\u00e7\u00e3o e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/FOTO-CARDS-1.jpg?fit=640%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/FOTO-CARDS-1.jpg?fit=640%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/FOTO-CARDS-1.jpg?fit=640%2C500&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":41060,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/06\/veja-as-novas-regras-para-declaracao-do-imposto-de-renda-2024\/","url_meta":{"origin":40546,"position":5},"title":"Veja as novas regras para declara\u00e7\u00e3o do Imposto de Renda 2024","author":"ismaelcolosi.com.br","date":"6 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A Receita Federal divulgou nesta quarta-feira (6) as novas regras para declara\u00e7\u00e3o do Imposto de Renda Pessoa F\u00edsica 2024. O prazo para a entrega da declara\u00e7\u00e3o, ano-base 2023, ser\u00e1 de 15 de mar\u00e7o a 31 de maio. O programa para preenchimento ser\u00e1 liberado pela Receita Federal no mesmo dia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/imposto-de-renda.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/imposto-de-renda.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/imposto-de-renda.webp.webp?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/imposto-de-renda.webp.webp?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/imposto-de-renda.webp.webp?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-axY","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40546"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/40547"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}