{"id":40402,"date":"2024-03-03T12:16:33","date_gmt":"2024-03-03T15:16:33","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/03\/kiko-zambianchi-e-rod-hanna-no-ritmo-do-bem\/"},"modified":"2024-03-03T12:16:33","modified_gmt":"2024-03-03T15:16:33","slug":"kiko-zambianchi-e-rod-hanna-no-ritmo-do-bem","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/03\/kiko-zambianchi-e-rod-hanna-no-ritmo-do-bem\/","title":{"rendered":"Kiko Zambianchi e Rod Hanna no Ritmo do Bem\u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p><span data-contrast=\"auto\">No pr\u00f3ximo dia 14 de mar\u00e7o, \u00e0s 20 horas, no Espa\u00e7o Bella Citt\u00e0, em Ribeir\u00e3o Preto, acontece show do cantor ribeir\u00e3o-pretano Kiko Zambianchi e as participa\u00e7\u00f5es especiais de Rod Hanna e do m\u00fasico \u00c1lvaro Petersen. Toda renda obtida ser\u00e1 integralmente destinada para a Casa das Mangueiras. A apresenta\u00e7\u00e3o faz parte do projeto Ritmo do Bem, que nasceu para colaborar com as atividades da institui\u00e7\u00e3o.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u201cA realiza\u00e7\u00e3o do evento representa um papel fundamental na sustentabilidade financeira da Casa. Como uma organiza\u00e7\u00e3o comprometida com iniciativas sociais, nossa capacidade de arrecadar fundos \u00e9 crucial para expandir nossos programas, atender \u00e0s necessidades crescentes da comunidade e assegurar a continuidade de nossas atividades\u201d, afirma Jo\u00e3o Gabriel Fernandes Manzi, coordenador de projetos sociais da Casa das Mangueiras.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p><span data-contrast=\"auto\">Para ele, a import\u00e2ncia deste evento transcende a mera capta\u00e7\u00e3o de recursos. \u201c\u00c9 uma oportunidade de consolidar parcerias duradouras e envolver a cidade de Ribeir\u00e3o Preto em nossa miss\u00e3o. Ao participar deste show os patrocinadores, p\u00fablico, doadores e apoiadores n\u00e3o apenas contribuem financeiramente, mas tamb\u00e9m se tornam parte ativa de uma rede de solidariedade que trabalha em prol do bem-estar de crian\u00e7as e adolescente\u201d, avalia.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><b><span data-contrast=\"auto\">Ritmo do bem: m\u00fasica &amp; solidariedade<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Os ingressos para o show beneficente de Kiko Zambianchi e participa\u00e7\u00f5es especiais podem ser adquiridos por R$ 80,00. As vendas acontecem no site do projeto (Total Acesso) e diretamente na Casa das Mangueiras, de segunda a sexta-feira, das 7h30 \u00e0s 17h, na Vila Recreio.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Para a produ\u00e7\u00e3o do evento, a Casa das Mangueiras conta com o apoio da Bananas Eventos, produtora do Festival Jo\u00e3o Rock. Esta parceria \u00e9 fruto do projeto Rock das Mangueiras, idealizado para levar m\u00fasica e dan\u00e7a \u00e0s crian\u00e7as atendidas pela institui\u00e7\u00e3o.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Servi\u00e7o<\/span><\/b><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">\u201cRitmo do Bem\u201d<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Show beneficente de Kiko Zambianchi com a participa\u00e7\u00e3o especial de Rod Hanna e \u00c1lvaro Petersen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Data: 14 de mar\u00e7o de 2024<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Hor\u00e1rio: 20 horas<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Local: Espa\u00e7o Bella Citt\u00e0 | Endere\u00e7o: SP -330, km 304 \u2013s\/n \u2013 Jardim Manoel Penna, Ribeir\u00e3o Preto (SP)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Vendas de ingressos:\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Pelo site da Total Acesso:\u00a0 https:\/\/www.totalacesso.com\/events\/ritmodobem_kikozambianchi<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Casa das Mangueiras \u2013 Rua Tupinamb\u00e1, 1457 \u2013 Vila Recreio, Ribeir\u00e3o Preto.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Lote promocional: R$ 80,00.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b><span data-contrast=\"auto\">Casa das Mangueiras: trajet\u00f3ria marcada por a\u00e7\u00f5es socioeducativas e prote\u00e7\u00e3o a crian\u00e7as e adolescentes<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Por meio s\u00e9culo, a Casa das Mangueiras desenvolve um trabalho gratuito e transformador na vida de crian\u00e7as e adolescentes em situa\u00e7\u00e3o de risco ou vulnerabilidade social de Ribeir\u00e3o Preto. A institui\u00e7\u00e3o promove oportunidades de conviv\u00eancia e fortalecimento de v\u00ednculos para crian\u00e7as de 6 e adolescentes de at\u00e9 17 anos, estimulando o desenvolvimento e autonomia de cada um com aten\u00e7\u00e3o \u00e0 individualidade, interesses e potencialidades de cada faixa et\u00e1ria.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Localizada na Rua Tupinamb\u00e1, 1457, Vila Recreio, a entidade mant\u00e9m uma grande estrutura para atender 140 pessoas, com v\u00e1rios programas que auxiliam no desenvolvimento sociocultural atrav\u00e9s de oficinas, buscando o despertar de valores como respeito, cidadania, responsabilidade e solidariedade.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">Ao todo, a Casa das Mangueiras desenvolve 11 projetos sociais: Inclus\u00e3o Digital, Multiplique o Bem (projeto de rob\u00f3tica), Entre Versos (projeto poesia), Grava\u00e7\u00e3o (projeto audiovisual), Circo, Jud\u00f4 \u2013 Um Golpe de Solidariedade (projeto de jud\u00f4), Rock das Mangueiras (projeto de dan\u00e7as urbanas, viol\u00e3o, percuss\u00e3o e coral, em parceria com o festival Jo\u00e3o Rock), Educacroos (projeto de apoio pedag\u00f3gico por meio de gamifica\u00e7\u00e3o da aprendizagem), Bem-Estar (projeto de educa\u00e7\u00e3o em sa\u00fade), Artes C\u00eanicas e Artes Visuais.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">\u201cAl\u00e9m da acolhida das crian\u00e7as e adolescentes, a entidade realiza trabalho social com as fam\u00edlias na busca de auxiliar no processo de rompimento das vulnerabilidades que vivenciam, com atendimento social e psicossocial, acompanhamento, orienta\u00e7\u00e3o, grupos educativos com familiares, palestras e oficinas tem\u00e1ticas\u201d, explica Jo\u00e3o Gabriel Fernandes Manzi, coordenador de projetos sociais da Casa das Mangueiras.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">A institui\u00e7\u00e3o foi fundada em 8 de dezembro de 1973, na Rua Arnaldo Victaliano, no bairro Iguatemi. O nome \u201cCasa das Mangueiras\u201d foi dado pelas pr\u00f3prias crian\u00e7as por causa da grande quantidade das \u00e1rvores plantadas no terreno. H\u00e1 quase 40 anos, a entidade mudou de endere\u00e7o e continua seu trabalho no bairro Vila Recreio.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><b><span data-contrast=\"auto\">Recursos<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A Casa das Mangueiras \u00e9 mantida com apoio institucional e financeiro de toda a sociedade civil e poder p\u00fablico, al\u00e9m de estrat\u00e9gias de gera\u00e7\u00e3o de receita pr\u00f3pria.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Foto box Casa \u2013 Divulga\u00e7\u00e3o<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Casa das Mangueiras trabalha h\u00e1 50 anos em prol de crian\u00e7as e adolescentes em Ribeir\u00e3o Preto<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/kiko-zambianchi-e-rod-hanna-no-ritmo-do-bem\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] No pr\u00f3ximo dia 14 de mar\u00e7o, \u00e0s 20 horas, no Espa\u00e7o Bella Citt\u00e0, em Ribeir\u00e3o Preto, acontece show do cantor ribeir\u00e3o-pretano Kiko Zambianchi e as participa\u00e7\u00f5es especiais de Rod Hanna e do m\u00fasico \u00c1lvaro Petersen. Toda renda obtida ser\u00e1 integralmente destinada para a Casa das Mangueiras. A apresenta\u00e7\u00e3o faz parte do projeto Ritmo do &#8230; <a title=\"Kiko Zambianchi e Rod Hanna no Ritmo do Bem\u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/03\/kiko-zambianchi-e-rod-hanna-no-ritmo-do-bem\/\" aria-label=\"Read more about Kiko Zambianchi e Rod Hanna no Ritmo do Bem\u00a0\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":40403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[830,4703,4701,4704,2989,4702],"class_list":["post-40402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-bem","tag-hanna","tag-kiko","tag-ritmo","tag-rod","tag-zambianchi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=800%2C532&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=800%2C532&ssl=1",800,532,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=768%2C511&ssl=1",768,511,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=800%2C532&ssl=1",800,532,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=800%2C532&ssl=1",800,532,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/mangueira-kiko.jpg?fit=800%2C532&ssl=1",800,532,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] No pr\u00f3ximo dia 14 de mar\u00e7o, \u00e0s 20 horas, no Espa\u00e7o Bella Citt\u00e0, em Ribeir\u00e3o Preto, acontece show do cantor ribeir\u00e3o-pretano Kiko Zambianchi e as participa\u00e7\u00f5es especiais de Rod Hanna e do m\u00fasico \u00c1lvaro Petersen. Toda renda obtida ser\u00e1 integralmente destinada para a Casa das Mangueiras. A apresenta\u00e7\u00e3o faz parte do projeto Ritmo do&hellip;","jetpack-related-posts":[{"id":41191,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/06\/ritmo-do-bem-kiko-zambianchi-traz-classicos-nacionais-em-show-em-ribeirao-preto\/","url_meta":{"origin":40402,"position":0},"title":"Kiko Zambianchi traz cl\u00e1ssicos nacionais em show em Ribeir\u00e3o Preto \u2013 Portal Popito","author":"ismaelcolosi.com.br","date":"6 de March de 2024","format":false,"excerpt":"[ad_1] Rod Hanna e \u00c1lvaro Petersen far\u00e3o participa\u00e7\u00e3o especial com setlist que misturar\u00e1 MBP, pop rock e disco music; todos eles, artistas da \u2018casa\u2019, se unem em evento beneficente em prol da Casa das Mangueiras no dia 14 de mar\u00e7o. Ingressos est\u00e3o \u00e0 venda As hist\u00f3rias de vida e carreiras\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Rod-Hanna.jpg?fit=1200%2C721&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42412,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/14\/kiko-zambianchi-faz-show-beneficente\/","url_meta":{"origin":40402,"position":1},"title":"Kiko Zambianchi faz show beneficente \u00a0","author":"ismaelcolosi.com.br","date":"14 de March de 2024","format":false,"excerpt":"[ad_1] A Casa das Mangueiras \u00e9 mantida com apoio institucional e financeiro de toda a sociedade civil e poder p\u00fablico, al\u00e9m de estrat\u00e9gias de gera\u00e7\u00e3o de receita pr\u00f3pria. O projeto Ritmo do Bem, por exemplo, nasceu para colaborar com as atividades da institui\u00e7\u00e3o. Para isso, Ribeir\u00e3o Preto receber\u00e1 nesta quinta-feira,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=966%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=966%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=966%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Mangueiras-Kik-Priscila-Prade-scaled.jpg?fit=966%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":40156,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/01\/kiko-zambianchi-faz-show-beneficente-em-ribeirao-preto-saiba-como-participar\/","url_meta":{"origin":40402,"position":2},"title":"Kiko Zambianchi faz show beneficente em Ribeir\u00e3o Preto; Saiba como participar","author":"ismaelcolosi.com.br","date":"1 de March de 2024","format":false,"excerpt":"[ad_1] O cantor e compositor ribeir\u00e3o-pretano Kiko Zambianchi faz show beneficente com participa\u00e7\u00e3o especial de Rod Hanna e \u00c1lvaro Petersen, no dia 14 de mar\u00e7o, em Ribeir\u00e3o Preto. A apresenta\u00e7\u00e3o musical e a\u00e7\u00e3o de solidariedade faz parte do Projeto \u201cRitmo do Bem\u201d, que tem como objetivo levantar fundos para a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-18.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41840,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/veja-como-comprar-ingresso-para-o-show-beneficente-de-kiko-zambianchi-em-ribeirao\/","url_meta":{"origin":40402,"position":3},"title":"Veja como comprar ingresso para o show beneficente de Kiko Zambianchi em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"11 de March de 2024","format":false,"excerpt":"[ad_1] O show beneficente do cantor e compositor ribeir\u00e3o-pretano Kiko Zambianchi acontece nesta quinta-feira (14) com participa\u00e7\u00e3o especial de Rod Hanna e \u00c1lvaro Petersen. O event ser\u00e1 \u00e0s 20h, no espa\u00e7o Bella Citt\u00e0 em Ribeir\u00e3o Preto. A apresenta\u00e7\u00e3o musical e a\u00e7\u00e3o solid\u00e1ria faz parte do projeto \u201cRitmo do Bem\u201d, que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710184889_acidadeon_logos_Prancheta-1-copia-12_edited.jpg?fit=1199%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":43062,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/19\/projeto-ritmo-do-bem\/","url_meta":{"origin":40402,"position":4},"title":"Projeto \u201cRitmo do Bem\u201d &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"19 de March de 2024","format":false,"excerpt":"[ad_1] 19 de mar\u00e7o de 2024 | 9:0318 de mar\u00e7o de 2024 | 13:04 0O projeto \u201cRitmo do Bem\u201d realizdo no Espa\u00e7o Bella Citt\u00e0, em benef\u00edcio da Casa das Mangueiras, com o cantor Kiko Zambianchi e a participa\u00e7\u00e3o de convidados especiais como a banda Hod Hanna e o m\u00fasico \u00c1lvaro\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/19-6-1-scaled.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":48890,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/07\/kiko-zambianchi-participa-da-escolha-de-semifinalistas-do-concurso-epra-cantar\/","url_meta":{"origin":40402,"position":5},"title":"Kiko Zambianchi participa da escolha de semifinalistas do concurso \u2018\u00c9Pra Cantar\u2019","author":"ismaelcolosi.com.br","date":"7 de May de 2024","format":false,"excerpt":"[ad_1] O cantor e compositor ribeir\u00e3o-pretano Kiko Zambianchi foi um dos jurados que definiu presencialmente na segunda-feira (6), os 20 semifinalistas do concurso musical \u201c\u00c9Pra Cantar\u201d, realizado pela EPTV, afiliada da Rede Globo. A escolha dos candidatos que seguir\u00e3o na disputa do concurso aconteceu na sede da EPTV Campinas e,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-06_21-49-33_jpg_2024-05-06_21-49-34.webp.webp?fit=779%2C430&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-06_21-49-33_jpg_2024-05-06_21-49-34.webp.webp?fit=779%2C430&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-06_21-49-33_jpg_2024-05-06_21-49-34.webp.webp?fit=779%2C430&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Capturar_2024-05-06_21-49-33_jpg_2024-05-06_21-49-34.webp.webp?fit=779%2C430&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-avE","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40402"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/40403"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}