{"id":40158,"date":"2024-03-01T12:21:55","date_gmt":"2024-03-01T15:21:55","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/01\/comercial-pode-ter-retornos-para-encarar-o-xv-no-domingo\/"},"modified":"2024-03-01T12:21:55","modified_gmt":"2024-03-01T15:21:55","slug":"comercial-pode-ter-retornos-para-encarar-o-xv-no-domingo","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/01\/comercial-pode-ter-retornos-para-encarar-o-xv-no-domingo\/","title":{"rendered":"Comercial pode ter retornos para encarar o XV no domingo\u00a0\u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-03-01T12:00:55-03:00\">1 de mar\u00e7o de 2024 | 12:00<\/time><time class=\"updated\" datetime=\"2024-03-01T09:27:49-03:00\">1 de mar\u00e7o de 2024 | 9:27<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"375578\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Comercial%20pode%20ter%20retornos%20para%20encarar%20o%20XV%20no%20domingo\u00a0\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/comercial-pode-ter-retornos-para-encarar-o-xv-no-domingo\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p><span data-contrast=\"auto\">O Comercial pode ter boas noticias para a partida contra o XV de Piracicaba, que acontece no pr\u00f3ximo domingo. Cinco jogadores devem ficar a disposi\u00e7\u00e3o do t\u00e9cnico Ademir Fesan no final de semana.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Alan Lopes cumpriu suspens\u00e3o na \u00faltima rodada e est\u00e1 de volta ao time. Outros nomes como Gabriel Chiari, Luc\u00e3o, Claudemir e Lu\u00eds Felipe avan\u00e7aram para a transi\u00e7\u00e3o e est\u00e3o muito perto de retornar.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Claudemir \u00e9 um dos principais e mais experientes nomes do elenco Alvinegro. Sua utiliza\u00e7\u00e3o ser\u00e1 muito comemorada pelo t\u00e9cnico Ademir Fesan. Claudemir vem sofrendo com problemas f\u00edsicos desde que chegou ao clube.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O \u00fanico desfalque certo at\u00e9 o momento \u00e9 o do volante Maranh\u00e3o, que recebeu o terceiro cart\u00e3o amarelo na derrota por 1 a 0 para a Portuguesa Santista, no \u00faltimo s\u00e1bado.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Fesan comentou sobre a possibilidade de retorno e tamb\u00e9m reiterou a vontade dos atletas em melhorar a situa\u00e7\u00e3o do Le\u00e3o do Norte.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u201cTemos um elenco competitivo, alguns que estavam no departamento m\u00e9dico podem voltar. (\u2026) os jogadores est\u00e3o acreditando demais, em todos os treinos, no jogo eles correram, perdemos por 1 a 0 [para a Briosa], fora de casa, em bola parada, um resultado comum, mas lutando, competindo, que \u00e9 isso que precisamos, essa mente forte\u201d, afirmou.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O Comercial \u00e9 o lanterna da A2 com cinco pontos. O Le\u00e3o conta com os jogos como mandante para permanecer na divis\u00e3o. Dos quatro confrontos restantes, tr\u00eas ser\u00e3o em Ribeir\u00e3o Preto.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p>\u00a0<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/comercial-pode-ter-retornos-para-encarar-o-xv-no-domingo\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 1 de mar\u00e7o de 2024 | 12:001 de mar\u00e7o de 2024 | 9:27 0 O Comercial pode ter boas noticias para a partida contra o XV de Piracicaba, que acontece no pr\u00f3ximo domingo. Cinco jogadores devem ficar a disposi\u00e7\u00e3o do t\u00e9cnico Ademir Fesan no final de semana.\u00a0\u00a0 Alan Lopes cumpriu suspens\u00e3o na \u00faltima rodada &#8230; <a title=\"Comercial pode ter retornos para encarar o XV no domingo\u00a0\u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/01\/comercial-pode-ter-retornos-para-encarar-o-xv-no-domingo\/\" aria-label=\"Leia mais sobre Comercial pode ter retornos para encarar o XV no domingo\u00a0\u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":40159,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[705,338,4663,71,217,4662,502],"class_list":["post-40158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-comercial","tag-domingo","tag-encarar","tag-para","tag-pode","tag-retornos","tag-ter"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/bafo-scaled.jpg?fit=968%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/bafo-scaled.jpg?fit=968%2C645&ssl=1",968,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/bafo-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/bafo-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/bafo-scaled.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/bafo-scaled.jpg?fit=968%2C645&ssl=1",968,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/bafo-scaled.jpg?fit=968%2C645&ssl=1",968,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/bafo-scaled.jpg?fit=968%2C645&ssl=1",968,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 1 de mar\u00e7o de 2024 | 12:001 de mar\u00e7o de 2024 | 9:27 0 O Comercial pode ter boas noticias para a partida contra o XV de Piracicaba, que acontece no pr\u00f3ximo domingo. Cinco jogadores devem ficar a disposi\u00e7\u00e3o do t\u00e9cnico Ademir Fesan no final de semana.\u00a0\u00a0 Alan Lopes cumpriu suspens\u00e3o na \u00faltima rodada&hellip;","jetpack-related-posts":[{"id":35474,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/06\/sem-tecnico-comercial-busca-primeira-vitoria-diante-do-primavera\/","url_meta":{"origin":40158,"position":0},"title":"Sem t\u00e9cnico, Comercial busca primeira vit\u00f3ria diante do Primavera\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"6 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 6 de fevereiro de 2024 | 14:006 de fevereiro de 2024 | 8:09 0O Comercial vive momento muito delicado na temporada. Ainda sem vencer na S\u00e9rie A2, o Le\u00e3o do Norte vai encarar o Primavera nesta ter\u00e7a sem treinador. O clube comunicou a demiss\u00e3o de Luiz Carlos Martins na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-7-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-7-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-7-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-7-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42713,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/16\/comercial-fecha-participacao-na-serie-a2-diante-do-monte-azul\/","url_meta":{"origin":40158,"position":1},"title":"Comercial fecha participa\u00e7\u00e3o na S\u00e9rie A2 diante do Monte Azul\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"16 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 16 de mar\u00e7o de 2024 | 11:3016 de mar\u00e7o de 2024 | 10:53 0O Comercial fecha sua participa\u00e7\u00e3o na S\u00e9rie A2 neste s\u00e1bado. O Le\u00e3o do Norte encara o Monte Azul, \u00e0s 15h10, no est\u00e1dio Palma Travassos, em Ribeir\u00e3o Preto. Ambos os times j\u00e1 est\u00e3o rebaixados.\u00a0\u00a0Para a partida o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Comercial-12-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Comercial-12-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Comercial-12-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Comercial-12-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37636,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/17\/comercial-busca-primeira-vitoria-diante-do-sao-jose\/","url_meta":{"origin":40158,"position":2},"title":"Comercial busca primeira vit\u00f3ria diante do S\u00e3o Jos\u00e9\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"17 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 17 de fevereiro de 2024 | 13:0017 de fevereiro de 2024 | 9:14 0Em busca da primeira vit\u00f3ria na S\u00e9rie A2, o Comercial tem um duro desafio para encarar neste s\u00e1bado. O Le\u00e3o do Norte encara o l\u00edder S\u00e3o Jos\u00e9, \u00e0s 19h, no est\u00e1dio Martins Pereira.\u00a0\u00a0Para a partida, mais\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-13-scaled.jpeg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-13-scaled.jpeg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-13-scaled.jpeg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-13-scaled.jpeg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41399,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/07\/comercial-perde-para-o-juventus-no-santa-cruz-e-esta-rebaixado-para-serie-a3\/","url_meta":{"origin":40158,"position":3},"title":"Comercial perde para o Juventus no Santa Cruz e est\u00e1 rebaixado para S\u00e9rie A3","author":"ismaelcolosi.com.br","date":"7 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O Comercial est\u00e1 rebaixado para a S\u00e9rie A3 do Campeonato Paulista. O Le\u00e3o do Norte foi derrotado pelo Juventus com o placar de 2 a 1 na noite desta quinta-feira. Os gols da partida foram marcados por L\u00e9o Castro, duas vezes, para o Moleque Travesso, e Valdeir, para o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Comercial-scaled.jpeg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Comercial-scaled.jpeg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Comercial-scaled.jpeg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Comercial-scaled.jpeg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":36579,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/10\/com-wagner-lopes-comercial-visita-o-velo-clube\/","url_meta":{"origin":40158,"position":4},"title":"Com Wagner Lopes, Comercial visita o Velo Clube\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"10 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Ainda em busca da primeira vit\u00f3ria na S\u00e9rie A2, o Comercial tem mais uma oportunidade de mudar sua hist\u00f3ria na competi\u00e7\u00e3o. O Le\u00e3o do Norte encara o Velo Clube, \u00e0s 16h, no est\u00e1dio Benit\u00e3o.\u00a0\u00a0A partida vai marcar a estreia de Wagner Lopes no comando do Comercial. O treinador foi\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-11-scaled.jpeg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-11-scaled.jpeg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-11-scaled.jpeg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Comercial-11-scaled.jpeg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24298,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/04\/em-cravinhos-comercial-e-derrotado-na-estreia-da-copa-sp\/","url_meta":{"origin":40158,"position":5},"title":"Em Cravinhos, Comercial \u00e9 derrotado na estreia da Copa SP","author":"ismaelcolosi.com.br","date":"4 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O Comercial perdeu, por 3 a 1, para o Gr\u00eamio Novorizontino, na abertura no Grupo 6 da Copa S\u00e3o Paulo de Futebol J\u00fanior 2024. O duelo foi na cidade de Cravinhos, no est\u00e1dio Bela Vista, na tarde desta quarta-feira (3). O Novorizontino abriu o placar no primeiro tempo com\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-03-at-16.47.15-scaled.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-03-at-16.47.15-scaled.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-03-at-16.47.15-scaled.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-03-at-16.47.15-scaled.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-03-at-16.47.15-scaled.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-arI","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40158"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/40159"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}