{"id":40056,"date":"2024-02-29T18:11:48","date_gmt":"2024-02-29T21:11:48","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/29\/vagas-de-empregos-na-bild-desenvolvimento-imobiliario-para-trabalhar-em-ribeirao-preto-sp-2\/"},"modified":"2024-02-29T18:11:48","modified_gmt":"2024-02-29T21:11:48","slug":"vagas-de-empregos-na-bild-desenvolvimento-imobiliario-para-trabalhar-em-ribeirao-preto-sp-2","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/29\/vagas-de-empregos-na-bild-desenvolvimento-imobiliario-para-trabalhar-em-ribeirao-preto-sp-2\/","title":{"rendered":"Vagas de empregos na Bild Desenvolvimento Imobili\u00e1rio para trabalhar em Ribeir\u00e3o Preto-SP"},"content":{"rendered":"<div class=\"sc-e9dd4d1-3 fwSjGW\">\n<div class=\"sc-e9dd4d1-4 gUILIM\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"Logo da empresa\" src=\"https:\/\/i0.wp.com\/attachments.gupy.io\/production\/companies\/1669\/career\/2554\/images\/2020-09-30_15-00_logo.png?w=1200&#038;ssl=1\"><\/div>\n<div class=\"sc-e9dd4d1-6 hlIymR\">\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" aria-label=\"Voc\u00ea est\u00e1 na p\u00e1gina de carreira {{pageTitle}}\" class=\"sc-eACynP jLQMmr sc-e9dd4d1-5 cEgRjA\">Bild Desenvolvimento Imobili\u00e1rio<\/h1>\n<\/div>\n<div class=\"sc-e9dd4d1-7 iRZAen\">\n<div aria-label=\"Esta \u00e9 uma empresa com alta taxa de retorno e atividade nas vagas nos \u00faltimos 3 meses\" data-testid=\"friendly-badge\" role=\"figure\" class=\"sc-455cc177-0 jZIoSL\"><svg width=\"34\" height=\"38\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" alt=\"Selo de Feedback\" class=\"sc-455cc177-2 hcesJe\"><path d=\"M15.001 1.153a4 4 0 0 1 4 0l12.455 7.19a4 4 0 0 1 2 3.465v14.381a4 4 0 0 1-2 3.464L19 36.843a4 4 0 0 1-4 0l-12.454-7.19a4 4 0 0 1-2-3.464V11.808a4 4 0 0 1 2-3.464L15 1.154Z\" fill=\"#fff\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M30.956 9.21 18.5 2.02a3 3 0 0 0-3 0L3.047 9.21a3 3 0 0 0-1.5 2.598v14.381a3 3 0 0 0 1.5 2.598l12.454 7.19a3 3 0 0 0 3 0l12.455-7.19a3 3 0 0 0 1.5-2.598V11.808a3 3 0 0 0-1.5-2.598ZM19 1.153a4 4 0 0 0-4 0L2.547 8.343a4 4 0 0 0-2 3.465v14.381a4 4 0 0 0 2 3.464L15 36.843a4 4 0 0 0 4 0l12.455-7.19a4 4 0 0 0 2-3.464V11.808a4 4 0 0 0-2-3.464L19 1.154Z\" fill=\"#1666DB\"><\/path><path d=\"M16.005 3.573a2 2 0 0 1 2 0l11.856 6.845a2 2 0 0 1 1 1.732v13.69a2 2 0 0 1-1 1.733l-11.856 6.845a2 2 0 0 1-2 0L4.148 27.573a2 2 0 0 1-1-1.732V12.15a2 2 0 0 1 1-1.732l11.857-6.845Z\" fill=\"#1666DB\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7 17.93A5.926 5.926 0 0 1 12.921 12h7.895a5.926 5.926 0 0 1 5.922 5.93v.988a5.926 5.926 0 0 1-5.922 5.93L19.33 27.57a.454.454 0 0 1-.162.18.404.404 0 0 1-.447-.007.46.46 0 0 1-.156-.186l-1.317-2.708h-4.325A5.926 5.926 0 0 1 7 18.918v-.988Zm14.618-3.45a.197.197 0 0 1 .37 0l.583 1.578c.02.054.063.097.117.117l1.576.584a.198.198 0 0 1 0 .37l-1.576.585a.197.197 0 0 0-.117.116l-.583 1.578a.197.197 0 0 1-.37 0l-.583-1.578a.198.198 0 0 0-.117-.116l-1.576-.584a.198.198 0 0 1 0-.371l1.576-.584a.196.196 0 0 0 .117-.117l.583-1.577Zm-2.776.982c0 .273-.221.494-.494.494h-7.895a.494.494 0 0 1 0-.988h7.895c.273 0 .494.22.494.494ZM17.36 18.92a.494.494 0 0 0 0-.988H9.466a.494.494 0 0 0 0 .988h7.895Zm6.415 2.47c0 .274-.22.495-.494.495H10.453a.494.494 0 0 1 0-.988h12.83c.272 0 .493.221.493.494Z\" fill=\"#fff\"><\/path><\/svg><\/p>\n<p aria-hidden=\"true\" title=\"Esta \u00e9 uma empresa com alta taxa de retorno e atividade nas vagas nos \u00faltimos 3 meses\" class=\"sc-455cc177-1 yUHes\">Selo de Feedback<\/p>\n<\/div>\n<\/div>\n<\/div>\n<section data-testid=\"company-description\" id=\"about\" class=\"sc-c1003a30-0 bTlhYQ\">\n<h2 data-testid=\"section-Fa\u00e7a parte do nosso Time!-title\" class=\"sc-6fde0c52-0 haCHdH\">Fa\u00e7a parte do nosso Time!<\/h2>\n<div class=\"sc-c1003a30-1 cBNEfU\">\n<p class=\"ql-align-justify\"><strong style=\"color:black\">O momento de olhar para o novo. O novo jeito de morar, novo jeito de nos relacionar, o novo jeito de viver.<\/strong><\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p class=\"ql-align-justify\"><\/p>\n<p class=\"ql-align-justify\"><span style=\"color:black\">N\u00e3o temos medo de tentar, de arriscar e, se erramos, n\u00e3o nos deixamos abalar mas aproveitamos para aprender, assim nos tornamos quem somos.<\/span><\/p>\n<p class=\"ql-align-justify\"><\/p>\n<p class=\"ql-align-justify\"><strong style=\"color:black\">N\u00e3o nos limitamos, a cimento, vidro e a\u00e7o!<\/strong><\/p>\n<p class=\"ql-align-justify\"><\/p>\n<p class=\"ql-align-justify\"><span style=\"color:black\">Temos a honra de acompanhar as transforma\u00e7\u00f5es nas vidas de <\/span><strong style=\"color:black\">nossos clientes<\/strong><span style=\"color:black\">, de v\u00ea-los conquistando, formando fam\u00edlias, realizando sonhos e evoluindo sempre!<\/span><\/p>\n<p class=\"ql-align-justify\"><span style=\"color:black\">\ufeff<\/span><\/p>\n<p class=\"ql-align-justify\"><span style=\"color:black\">Nossos produtos s\u00e3o o cen\u00e1rio, o ch\u00e3o, o teto para todos esses movimentos, para toda esta vida. Somos orgulhosos de todos que vestem a camisa laranja, adoramos ver nossos colaboradores, crescendo, aprendendo, empreendendo e tendo a felicidade como um valor. Assistimos orgulhosos o crescimento e comprometimento de cada um. Todos os dias, os Bilders acordam para fazer melhor que ontem, com uma inquietude t\u00edpica destes cora\u00e7\u00f5es que vibram em laranja, em nosso nome.<\/span><\/p>\n<p class=\"ql-align-justify\"><\/p>\n<p><span style=\"color:rgb(32, 33, 36)\">Somos uma empresa em constante movimento e um deles est\u00e1 direcionado \u00e0 busca de maior <\/span><strong style=\"color:rgb(32, 33, 36)\">diversidade e inclus\u00e3o<\/strong><span style=\"color:rgb(32, 33, 36)\"> em nosso ecossistema.<\/span><\/p>\n<p><\/p>\n<p class=\"ql-align-justify\"><strong style=\"color:rgb(32, 33, 36)\">Nossas vagas tamb\u00e9m s\u00e3o destinadas a Pessoas com Defici\u00eancia (PcD).<\/strong><\/p>\n<\/div>\n<\/section>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA CONTABIL em Ribeir\u00e3o Preto - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6708897?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA CONTABIL<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA CR\u00c9DITO IMOBILI\u00c1RIO em Uberl\u00e2ndia - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6725690?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA CR\u00c9DITO IMOBILI\u00c1RIO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberl\u00e2ndia &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista de Engenharia  em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6809795?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Analista de Engenharia <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" aria-label=\"Voc\u00ea est\u00e1 na p\u00e1gina de carreira {{pageTitle}}\" class=\"sc-eACynP jLQMmr sc-e9dd4d1-5 cEgRjA\">Bild Desenvolvimento Imobili\u00e1rio<\/h1>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA DE PRODUTO em Uberl\u00e2ndia - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6571856?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA DE PRODUTO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberl\u00e2ndia &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista de Suprimentos Jr - S\u00e3o Paulo em S\u00e3o Paulo - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6170282?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Analista de Suprimentos Jr &#8211; S\u00e3o Paulo<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista de Suprimentos Pleno em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6807902?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Analista de Suprimentos Pleno<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA REPASSE em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6740853?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA REPASSE<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA SUPRIMENTOS em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6572610?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA SUPRIMENTOS<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ALMOXARIFE   em Paul\u00ednia - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6699709?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ALMOXARIFE  <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Paul\u00ednia &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA ADMINISTRATIVO em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6792763?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA ADMINISTRATIVO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA SUPRIMENTOS em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6572610?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA SUPRIMENTOS<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA DE PRODUTO em Uberl\u00e2ndia - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6571856?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA DE PRODUTO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberl\u00e2ndia &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA DE PRODUTO em Uberl\u00e2ndia - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6571856?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA DE PRODUTO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberl\u00e2ndia &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<div data-testid=\"secondaryImage2\" role=\"img\" class=\"sc-ee78b7b3-2 oiIKP\"><\/div>\n<section data-testid=\"job-list\" id=\"job-listing\" class=\"sc-f5007364-1 hRVHMy\">\n<h2 data-testid=\"section-Nossas oportunidades-title\" class=\"sc-6fde0c52-0 haCHdH\">Nossas oportunidades<\/h2>\n<div data-testid=\"section-Nossas oportunidades-description\" class=\"sc-6fde0c52-1 iAgJhf\">Conhe\u00e7a um pouco mais sobre os desafios que temos aqui na Bild.<\/div>\n<div data-testid=\"old-job-filters\">\n<form aria-label=\"Busca de Vagas\" data-testid=\"job-search-form\" class=\"sc-d52d7ce9-0 gnWcBe\"><label for=\"job-search\" class=\"sc-d52d7ce9-1 bBVWZj\">Busca de Vagas<\/label><span role=\"searchbox\" aria-label=\"jobSearchFilterLabel\" class=\"sc-bbpGSz dLHSKU\"><input type=\"input\" data-testid=\"job-search\" label=\"jobSearchFilterLabel\" name=\"jobSearch\" placeholder=\"Digite o nome da vaga\" value=\"\" id=\"job-search\" aria-labelledby=\"input-job-search\" aria-describedby=\"react-aria-3 react-aria-4\" class=\"sc-jItqcz sc-UxxwN jsApaO bMvAsC\"><button aria-labelledby=\"job-search\" class=\"sc-irTswW boqOgV sc-jJgynQ jjsrBz\" id=\"job-search-button\"><\/p>\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M15.5 14h-.79l-.28-.27C15.41 12.59 16 11.11 16 9.5 16 5.91 13.09 3 9.5 3S3 5.91 3 9.5 5.91 16 9.5 16c1.61 0 3.09-.59 4.23-1.57l.27.28v.79l5 4.99L20.49 19l-4.99-5zm-6 0C7.01 14 5 11.99 5 9.5S7.01 5 9.5 5 14 7.01 14 9.5 11.99 14 9.5 14z\"><\/path><\/svg><\/div>\n<p><\/button><\/span><\/form>\n<form aria-label=\"Op\u00e7\u00f5es de Filtro de Vaga\" class=\"sc-d52d7ce9-2 fREpEo\">\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todas\" id=\"label-job-types\" for=\"job-types\" class=\"sc-brKeYL dtexMX\">Tipo de Vaga<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-113338-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-113338-placeholder\">Todas<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-types\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-types\" role=\"combobox\" aria-describedby=\"react-select-113338-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"jobTypesFilter\" value=\"\"><\/div>\n<\/div>\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todos\" id=\"label-job-workplaces\" for=\"job-workplaces\" class=\"sc-brKeYL dtexMX\">Locais de Trabalho<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-113339-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-113339-placeholder\">Todos<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-workplaces\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-workplaces\" role=\"combobox\" aria-describedby=\"react-select-113339-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"workplacesFilter\" value=\"\"><\/div>\n<\/div>\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"Todas\" id=\"label-job-departments\" for=\"job-departments\" class=\"sc-brKeYL dtexMX\">\u00c1reas<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-113340-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-113340-placeholder\">Todas<\/div>\n<style data-emotion=\"css 19bb58m\">.css-19bb58m{visibility:visible;-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;display:inline-grid;grid-area:1\/1\/2\/3;grid-template-columns:0 min-content;margin:2px;padding-bottom:2px;padding-top:2px;color:hsl(0, 0%, 20%);box-sizing:border-box;}.css-19bb58m:after{content:attr(data-value) \" \";visibility:hidden;white-space:pre;grid-area:1\/2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0;}<\/style>\n<div class=\" css-19bb58m\" data-value=\"\"><input type=\"text\" class=\"\" style=\"label:input;color:inherit;background:0;opacity:1;width:100%;grid-area:1 \/ 2;font:inherit;min-width:2px;border:0;margin:0;outline:0;padding:0\" autocapitalize=\"none\" autocomplete=\"off\" autocorrect=\"off\" id=\"job-departments\" spellcheck=\"false\" tabindex=\"0\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-job-departments\" role=\"combobox\" aria-describedby=\"react-select-113340-placeholder\"><\/div>\n<\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"departmentsFilter\" value=\"\"><\/div>\n<\/div>\n<\/form>\n<\/div>\n<div class=\"sc-f5007364-7 cYAFjr\">\n<div role=\"status\" class=\"sc-f5007364-0 cDdpev\">48 vagas encontradas para 0 filtros aplicados<\/div>\n<div aria-hidden=\"true\" data-testid=\"job-list-amount\" class=\"sc-f5007364-8 dCDcPy\">48 vagas<\/div>\n<div class=\"sc-f5007364-8 dCDcPy\">\n<div class=\"sc-4284ca6f-3 iPhDzt\">\n<div class=\"sc-jfSnVq hAFaOK\"><span class=\"sc-eKYjST kEFcXj\"><label placeholder=\"10\" id=\"label-items-por-pagina\" for=\"items-por-pagina\" class=\"sc-brKeYL dtexMX\">Itens por p\u00e1gina<\/label><\/span><\/p>\n<style data-emotion=\"css 7960i3-container\">.css-7960i3-container{position:relative;box-sizing:border-box;border-radius:0.75rem;width:100%;}<\/style>\n<div class=\" css-7960i3-container\">\n<style data-emotion=\"css 7pg0cj-a11yText\">.css-7pg0cj-a11yText{z-index:9999;border:0;clip:rect(1px, 1px, 1px, 1px);height:1px;width:1px;position:absolute;overflow:hidden;padding:0;white-space:nowrap;}<\/style>\n<p><span id=\"react-select-113341-live-region\" class=\"css-7pg0cj-a11yText\"><\/span><span aria-live=\"polite\" aria-atomic=\"false\" aria-relevant=\"additions text\" class=\"css-7pg0cj-a11yText\"><\/span><\/p>\n<style data-emotion=\"css 16fgkcs-control\">.css-16fgkcs-control{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;cursor:pointer;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-box-pack:justify;-webkit-justify-content:space-between;justify-content:space-between;min-height:38px;outline:0!important;position:relative;-webkit-transition:all 100ms;transition:all 100ms;background-color:#FFFFFF;border-color:#27262A;border-radius:0.75rem;border-style:solid;border-width:1px;box-shadow:0 0 0 0px transparent;box-sizing:border-box;height:44px;padding:0 0.75rem;}.css-16fgkcs-control:hover{border-color:hsl(0, 0%, 70%);}.css-16fgkcs-control:hover{border:0.0625rem solid #535257;}<\/style>\n<div class=\" css-16fgkcs-control\">\n<style data-emotion=\"css hlgwow\">.css-hlgwow{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;display:grid;-webkit-flex:1;-ms-flex:1;flex:1;-webkit-box-flex-wrap:wrap;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;-webkit-overflow-scrolling:touch;position:relative;overflow:hidden;padding:2px 8px;box-sizing:border-box;}<\/style>\n<div class=\" css-hlgwow\">\n<style data-emotion=\"css 3v4ece-placeholder\">.css-3v4ece-placeholder{grid-area:1\/1\/2\/3;color:#535257;margin-left:2px;margin-right:2px;box-sizing:border-box;font-size:1rem;overflow:hidden;text-overflow:ellipsis;white-space:nowrap;line-height:20px;margin:0;padding:0;}<\/style>\n<div class=\" css-3v4ece-placeholder\" id=\"react-select-113341-placeholder\">10<\/div>\n<style data-emotion=\"css 1hac4vs-dummyInput\">.css-1hac4vs-dummyInput{background:0;border:0;caret-color:transparent;font-size:inherit;grid-area:1\/1\/2\/3;outline:0;padding:0;width:1px;color:transparent;left:-100px;opacity:0;position:relative;-webkit-transform:scale(.01);-moz-transform:scale(.01);-ms-transform:scale(.01);transform:scale(.01);}<\/style>\n<p><input id=\"items-por-pagina\" tabindex=\"0\" inputmode=\"none\" value=\"\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-labelledby=\"label-items-por-pagina\" role=\"combobox\" aria-readonly=\"true\" aria-describedby=\"react-select-113341-placeholder\" class=\"css-1hac4vs-dummyInput\"><\/div>\n<style data-emotion=\"css 1wy0on6\">.css-1wy0on6{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-align-self:stretch;-ms-flex-item-align:stretch;align-self:stretch;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-shrink:0;-ms-flex-negative:0;flex-shrink:0;box-sizing:border-box;}<\/style>\n<div class=\" css-1wy0on6\">\n<style data-emotion=\"css 1hyfx7x\">.css-1hyfx7x{display:none;}<\/style>\n<p><span class=\" css-1hyfx7x\"><\/span><\/p>\n<style data-emotion=\"css npownn-indicatorContainer\">.css-npownn-indicatorContainer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-transition:color 150ms;transition:color 150ms;color:#27262A;padding:8px;box-sizing:border-box;}.css-npownn-indicatorContainer:hover{color:hsl(0, 0%, 60%);}<\/style>\n<div class=\" css-npownn-indicatorContainer\" aria-hidden=\"true\">\n<style data-emotion=\"css 8mmkcg\">.css-8mmkcg{display:inline-block;fill:currentColor;line-height:1;stroke:currentColor;stroke-width:0;}<\/style>\n<p><svg height=\"20\" width=\"20\" viewbox=\"0 0 20 20\" aria-hidden=\"true\" focusable=\"false\" class=\"css-8mmkcg\"><path d=\"M4.516 7.548c0.436-0.446 1.043-0.481 1.576 0l3.908 3.747 3.908-3.747c0.533-0.481 1.141-0.446 1.574 0 0.436 0.445 0.408 1.197 0 1.615-0.406 0.418-4.695 4.502-4.695 4.502-0.217 0.223-0.502 0.335-0.787 0.335s-0.57-0.112-0.789-0.335c0 0-4.287-4.084-4.695-4.502s-0.436-1.17 0-1.615z\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p><input type=\"hidden\" name=\"items-por-pagina\" value=\"\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<ul aria-label=\"Lista de Vagas\" data-testid=\"job-list__list\">\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ALMOXARIFE   em Paul\u00ednia - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6699709?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ALMOXARIFE  <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Paul\u00ednia &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA ADMINISTRATIVO em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6792763?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA ADMINISTRATIVO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA CONTABIL em Ribeir\u00e3o Preto - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6708897?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA CONTABIL<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA CR\u00c9DITO IMOBILI\u00c1RIO em Uberl\u00e2ndia - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6725690?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA CR\u00c9DITO IMOBILI\u00c1RIO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberl\u00e2ndia &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista de Engenharia  em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6809795?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Analista de Engenharia <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA DE PRODUTO em Uberl\u00e2ndia - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6571856?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA DE PRODUTO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberl\u00e2ndia &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista de Suprimentos Jr - S\u00e3o Paulo em S\u00e3o Paulo - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6170282?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Analista de Suprimentos Jr &#8211; S\u00e3o Paulo<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Analista de Suprimentos Pleno em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6807902?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Analista de Suprimentos Pleno<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA REPASSE em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6740853?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA REPASSE<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ANALISTA SUPRIMENTOS em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6572610?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ANALISTA SUPRIMENTOS<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Aprendiz como APRENDIZ em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6822624?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">APRENDIZ<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Aprendiz<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Assistente Administrativo em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6798793?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Assistente Administrativo<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como ASSISTENTE SUPRIMENTOS em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6014520?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ASSISTENTE SUPRIMENTOS<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como  AUXILIAR DE ALMOXARIFE  em Campinas - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/5678122?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\"> AUXILIAR DE ALMOXARIFE <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Campinas &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Banco de Talentos em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/2828212?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Banco de Talentos<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Banco de talentos como Banco de Talentos - Engenharia Bild Sorocaba  em Sorocaba - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/5096586?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Banco de Talentos &#8211; Engenharia Bild Sorocaba <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Sorocaba &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Banco de talentos<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Cientista de Dados em Ribeir\u00e3o Preto - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/5333845?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Cientista de Dados<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como Consultor de Vendas em Campinas - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6681692?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Consultor de Vendas<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Campinas &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como Consultor de Vendas em Piracicaba - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6745499?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Consultor de Vendas<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Piracicaba &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como Consultor de Vendas em S\u00e3o Jos\u00e9 do Rio Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6655619?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Consultor de Vendas<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Jos\u00e9 do Rio Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como Consultor de Vendas  em S\u00e3o Paulo - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6738835?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Consultor de Vendas <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Paulo &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como Consultor de Vendas  em Campinas - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6165416?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Consultor de Vendas <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Campinas &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como CONSULTOR DE VENDAS em Uberl\u00e2ndia - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6756009?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">CONSULTOR DE VENDAS<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberl\u00e2ndia &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como CONSULTOR DE VENDAS em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/4518448?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">CONSULTOR DE VENDAS<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como CONSULTOR DE VENDAS  em Araraquara - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6719589?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">CONSULTOR DE VENDAS <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Araraquara &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Aut\u00f4nomo como CONSULTOR DE VENDAS  em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6754229?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">CONSULTOR DE VENDAS <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Aut\u00f4nomo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como CONSULTOR DE VENDAS  em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6564264?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">CONSULTOR DE VENDAS <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Coordenador de Cr\u00e9dito Imobili\u00e1rio em Ribeir\u00e3o Preto - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6676913?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Coordenador de Cr\u00e9dito Imobili\u00e1rio<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Coordenador de Projetos - GETEC em Bauru - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6696226?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Coordenador de Projetos &#8211; GETEC<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Bauru &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Coordenador de Suprimentos em Bauru - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6193529?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Coordenador de Suprimentos<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Bauru &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como COORDENADOR PRODU\u00c7\u00c3O em Franca - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6706128?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">COORDENADOR PRODU\u00c7\u00c3O<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Franca &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Est\u00e1gio como ESTAGIARIO ADMINISTRATIVO em Bauru - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6673706?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ESTAGIARIO ADMINISTRATIVO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Bauru &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Est\u00e1gio<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Est\u00e1gio como Estagi\u00e1rio (a) - Engenharia Civil \/ Arquitetura em Campinas - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6659268?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Estagi\u00e1rio (a) &#8211; Engenharia Civil \/ Arquitetura<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Campinas &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Est\u00e1gio<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Est\u00e1gio como Estagi\u00e1rio (a) - Engenharia Civil \/ Arquitetura  em Paul\u00ednia - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6789643?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Estagi\u00e1rio (a) &#8211; Engenharia Civil \/ Arquitetura <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Paul\u00ednia &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Est\u00e1gio<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Est\u00e1gio como ESTAGI\u00c1RIO DE SUPRIMENTOS em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6606689?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">ESTAGI\u00c1RIO DE SUPRIMENTOS<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Est\u00e1gio<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Est\u00e1gio como Estagi\u00e1rio - Engenharia Civil em Uberl\u00e2ndia - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6743287?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Estagi\u00e1rio &#8211; Engenharia Civil<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberl\u00e2ndia &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Est\u00e1gio<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Est\u00e1gio como Estagi\u00e1rio - Engenharia Civil em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6809812?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Estagi\u00e1rio &#8211; Engenharia Civil<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Est\u00e1gio<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Est\u00e1gio como Estagi\u00e1rio - Engenharia Civil em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/5666675?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Estagi\u00e1rio &#8211; Engenharia Civil<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Est\u00e1gio<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Est\u00e1gio como Estagi\u00e1rio Engenharia Civil  em Campinas - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6207840?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Estagi\u00e1rio Engenharia Civil <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Campinas &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Est\u00e1gio<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Est\u00e1gio como Estagiario Marketing em S\u00e3o Jos\u00e9 do Rio Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6666658?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Estagiario Marketing<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Jos\u00e9 do Rio Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Est\u00e1gio<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Aut\u00f4nomo como EXECUTIVO DE VENDAS  em Franca - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6762985?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">EXECUTIVO DE VENDAS <\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Franca &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Aut\u00f4nomo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Pessoa jur\u00eddica como GERENTE DE VENDAS em Bauru - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6803869?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">GERENTE DE VENDAS<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Bauru &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Pessoa jur\u00eddica<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Aut\u00f4nomo como Gerente de Vendas (Terceiros) - Pr\u00f3xima Porta em S\u00e3o Jos\u00e9 do Rio Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6583301?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Gerente de Vendas (Terceiros) &#8211; Pr\u00f3xima Porta<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Jos\u00e9 do Rio Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Aut\u00f4nomo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Aut\u00f4nomo como Gestor Trafego em S\u00e3o Jos\u00e9 do Rio Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6666306?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Gestor Trafego<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">S\u00e3o Jos\u00e9 do Rio Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Aut\u00f4nomo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Mestre de Obras em Uberl\u00e2ndia - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6756443?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Mestre de Obras<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberl\u00e2ndia &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Pessoa Desenvolvedora Backend em Trabalho Remoto\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6732406?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Pessoa Desenvolvedora Backend<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Trabalho Remoto<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como Supervisor(a) de Tecnologia da Informa\u00e7\u00e3o em Ribeir\u00e3o Preto - SP e H\u00edbrido\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6071404?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">Supervisor(a) de Tecnologia da Informa\u00e7\u00e3o<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Ribeir\u00e3o Preto &#8211; SP e H\u00edbrido<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 cskvFe\"><a aria-label=\"Vaga para Efetivo como TECNICO SEGURANCA DO TRABALHO em Uberaba - MG\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/bild.gupy.io\/jobs\/6786630?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 iGazNJ\">\n<div class=\"sc-f5007364-4 gUEGnC\">TECNICO SEGURANCA DO TRABALHO<\/div>\n<div class=\"sc-f5007364-5 dejhbi\">Uberaba &#8211; MG<\/div>\n<div class=\"sc-f5007364-6 iWKdVs\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<\/ul>\n<div class=\"sc-f5007364-9 gXOSFh\">\n<nav aria-label=\"Pagina\u00e7\u00e3o do resultado da busca\">\n<ul class=\"sc-llcuoN bHIMne\">\n<li class=\"sc-jnsZEu dVzXoV\"><button data-testid=\"pagination-prev-button\" aria-disabled=\"false\" aria-label=\"V\u00e1 para p\u00e1gina anterior\" class=\"sc-hsiEis fXWJKC\">\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M15.41 7.41L14 6l-6 6 6 6 1.41-1.41L10.83 12z\"><\/path><\/svg><\/div>\n<p><\/button><\/li>\n<li class=\"sc-jnsZEu dVzXoV\"><button data-testid=\"pagination-next-button\" aria-disabled=\"false\" aria-label=\"V\u00e1 para pr\u00f3xima p\u00e1gina\" class=\"sc-hsiEis fXWJKC\">\n<div class=\"sc-gueYoa gQmunR\"><svg class=\"MuiSvgIcon-root\" focusable=\"false\" viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M10 6L8.59 7.41 13.17 12l-4.58 4.59L10 18l6-6z\"><\/path><\/svg><\/div>\n<p><\/button><\/li>\n<\/ul>\n<\/nav>\n<\/div>\n<\/section>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Bild Desenvolvimento Imobili\u00e1rio Selo de Feedback Fa\u00e7a parte do nosso Time! O momento de olhar para o novo. O novo jeito de morar, novo jeito de nos relacionar, o novo jeito de viver. N\u00e3o temos medo de tentar, de arriscar e, se erramos, n\u00e3o nos deixamos abalar mas aproveitamos para aprender, assim nos tornamos quem &#8230; <a title=\"Vagas de empregos na Bild Desenvolvimento Imobili\u00e1rio para trabalhar em Ribeir\u00e3o Preto-SP\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/29\/vagas-de-empregos-na-bild-desenvolvimento-imobiliario-para-trabalhar-em-ribeirao-preto-sp-2\/\" aria-label=\"Read more about Vagas de empregos na Bild Desenvolvimento Imobili\u00e1rio para trabalhar em Ribeir\u00e3o Preto-SP\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":40057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-40056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas-de-empregos-em-ribeirao-preto-regiao-brasil"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1709241112_1-Captura-de-tela-inteira-01032021-181603.jpg?fit=473%2C288&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1709241112_1-Captura-de-tela-inteira-01032021-181603.jpg?fit=473%2C288&ssl=1",473,288,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1709241112_1-Captura-de-tela-inteira-01032021-181603.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1709241112_1-Captura-de-tela-inteira-01032021-181603.jpg?fit=300%2C183&ssl=1",300,183,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1709241112_1-Captura-de-tela-inteira-01032021-181603.jpg?fit=473%2C288&ssl=1",473,288,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1709241112_1-Captura-de-tela-inteira-01032021-181603.jpg?fit=473%2C288&ssl=1",473,288,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1709241112_1-Captura-de-tela-inteira-01032021-181603.jpg?fit=473%2C288&ssl=1",473,288,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1709241112_1-Captura-de-tela-inteira-01032021-181603.jpg?fit=473%2C288&ssl=1",473,288,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"Bild Desenvolvimento Imobili\u00e1rio Selo de Feedback Fa\u00e7a parte do nosso Time! O momento de olhar para o novo. O novo jeito de morar, novo jeito de nos relacionar, o novo jeito de viver. N\u00e3o temos medo de tentar, de arriscar e, se erramos, n\u00e3o nos deixamos abalar mas aproveitamos para aprender, assim nos tornamos quem&hellip;","jetpack-related-posts":[{"id":54909,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/28\/vagas-de-emprego-para-engenheiro-civil-em-ribeirao-preto-sp-9\/","url_meta":{"origin":40056,"position":0},"title":"Vagas de emprego para Engenheiro Civil em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"28 de June de 2024","format":false,"excerpt":"Engenheiro Civil Engenheiro Civil COORDENADOR ASSISTENCIA TECNICA Ribeir\u00e3o Preto - SP Efetivo Estagi\u00e1rio de engenharia civil Est\u00e1gio em Engenharia Civil Get notified about new Engenheiro Civil jobs in Ribeir\u00e3o Preto, SP. Sign in to create job alert 17 Engenheiro Civil Jobs in Ribeir\u00e3o Preto, SP Engenheiro Civil Engenheiro Civil EngenhariaJob\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/1719600153_ENGENHEIRO_00.jpg?fit=550%2C550&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/1719600153_ENGENHEIRO_00.jpg?fit=550%2C550&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/1719600153_ENGENHEIRO_00.jpg?fit=550%2C550&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":63205,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/31\/vagas-de-emprego-para-engenheiro-civil-em-ribeirao-preto-sp-16\/","url_meta":{"origin":40056,"position":1},"title":"Vagas de emprego para Engenheiro Civil em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"31 de August de 2024","format":false,"excerpt":"Engenheiro(a) Civil COORDENADOR ASSISTENCIA TECNICA Ribeir\u00e3o Preto - SP Efetivo COORDENADOR ASSISTENCIA TECNICA COORDENADOR ASSIST\u00caNCIA T\u00c9CNICA Ribeir\u00e3o Preto - SP Efetivo Engenheiro Civil-Projetista Get notified about new Engenheiro Civil jobs in Ribeir\u00e3o Preto. Sign in to create job alert 13 Engenheiro Civil Jobs in Ribeir\u00e3o Preto Engenheiro(a) Civil Engenheiro(a) Civil\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725131686_ENGENHEIRO_00.jpg?fit=550%2C550&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725131686_ENGENHEIRO_00.jpg?fit=550%2C550&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725131686_ENGENHEIRO_00.jpg?fit=550%2C550&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":57063,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/17\/vagas-de-emprego-para-engenheiro-civil-em-ribeirao-preto-sp-12\/","url_meta":{"origin":40056,"position":2},"title":"Vagas de emprego para Engenheiro Civil em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"17 de July de 2024","format":false,"excerpt":"Engenheiro(a) Civil Engenheiro Civil Engenheiro Civil COORDENADOR ASSISTENCIA TECNICA Ribeir\u00e3o Preto - SP Efetivo Engenheiro Civil Parma Consultoria Ribeir\u00e3o Preto e Regi\u00e3o H\u00e1 3 semanas Est\u00e1gio em Engenharia Civil Receba alertas de novas vagas de Engenheiro Civil em: Ribeir\u00e3o Preto e Regi\u00e3o. Entre para criar um alerta de vaga 22\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59048,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/05\/vagas-de-emprego-para-engenheiro-civil-em-ribeirao-preto-sp-14\/","url_meta":{"origin":40056,"position":3},"title":"Vagas de emprego para Engenheiro Civil em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"5 de August de 2024","format":false,"excerpt":"Engenheiro(a) Civil Est\u00e1gio em Engenharia Civil COORDENADOR ASSISTENCIA TECNICA Ribeir\u00e3o Preto - SP Efetivo EST\u00c1GIO EM ENGENHARIA CIVIL S\u00c3O PAULO- RIBEIR\u00c3O PRETO Receba alertas de novas vagas de Engenheiro Civil em: Ribeir\u00e3o Preto e Regi\u00e3o. Entre para criar um alerta de vaga 18 Engenheiro Civil vagas em Ribeir\u00e3o Preto e\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":65536,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/12\/vagas-de-emprego-para-engenheiro-civil-em-ribeirao-preto-sp-17\/","url_meta":{"origin":40056,"position":4},"title":"Vagas de emprego para Engenheiro Civil em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"12 de September de 2024","format":false,"excerpt":"Engenheiro de Seguran\u00e7a do Trabalho Ribeir\u00e3o Preto - SP Efetivo COORDENADOR ASSISTENCIA TECNICA Ribeir\u00e3o Preto - SP Efetivo Engenheiro de Seguran\u00e7a do Trabalho Engenheiro de Seguran\u00e7a do Trabalho Engenheiro Civil-Projetista Or\ufffdamentista Est\u00e1gio em Engenharia Civil e Arquitetura - Ribeir\u00e3o Preto , SP Ribeir\u00e3o Preto - SP Banco de talentos Receba\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":68698,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/01\/vagas-de-emprego-para-engenheiro-civil-em-ribeirao-preto-sp-19\/","url_meta":{"origin":40056,"position":5},"title":"Vagas de emprego para Engenheiro Civil em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"1 de October de 2024","format":false,"excerpt":"Est\u00e1gio Engenheiro Civil COORDENADOR ASSISTENCIA TECNICA Ribeir\u00e3o Preto - SP Efetivo COORDENADOR ASSISTENCIA TECNICA Engenheiro Civil Engenheiro Civil Engenheiro Civil-Projetista Supervisor Pleno Engenharia Civil Pavimenta\u00e7\u00e3o - SP Quality Consultoria Franca, SP Seja um dos primeiros a se candidatar H\u00e1 21 horas Engenheiro Civil-Projetista COORDENADOR ASSIST\u00caNCIA T\u00c9CNICA Ribeir\u00e3o Preto - SP\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/quanto-ganha-engenheiro-civil.png?fit=1200%2C635&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-aq4","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40056"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/40057"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}