{"id":40022,"date":"2024-02-29T15:00:17","date_gmt":"2024-02-29T18:00:17","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/29\/tiago-alves-acerta-saida-do-botafogo\/"},"modified":"2024-02-29T15:00:17","modified_gmt":"2024-02-29T18:00:17","slug":"tiago-alves-acerta-saida-do-botafogo","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/29\/tiago-alves-acerta-saida-do-botafogo\/","title":{"rendered":"Tiago Alves acerta sa\u00edda do Botafogo\u00a0\u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-02-29T14:30:08-03:00\">29 de fevereiro de 2024 | 14:30<\/time><time class=\"updated\" datetime=\"2024-02-29T12:33:19-03:00\">29 de fevereiro de 2024 | 12:33<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"375448\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Tiago%20Alves%20acerta%20sa\u00edda%20do%20Botafogo\u00a0\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/tiago-alves-acerta-saida-do-botafogo\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p><span data-contrast=\"auto\">O atacante portugu\u00eas Tiago Alves n\u00e3o \u00e9 mais jogador do Botafogo. O jogador recebeu uma proposta de um clube japon\u00eas e pediu para deixar o Tricolor. Como seu contrato estava perto do fim, o Pantera acatou a solicita\u00e7\u00e3o e liberou o atleta.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Alves chegou ao Botafogo ap\u00f3s se destacar pelo Montedio Yamagata, tamb\u00e9m do Jap\u00e3o. Entretanto, no Pantera, o atacante n\u00e3o conseguiu emplacar e deixa o Brasil de forma apagada.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Em oito partidas, quatro delas como titular, ele n\u00e3o colaborou com gols e nem assist\u00eancias. A expectativa entorno do atacante era grande, j\u00e1 que ele vinha de boa temporada e teve n\u00fameros superiores ao de Dellatorre, atacante brasileiro que foi seu parceiro no Jap\u00e3o.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Dellatorre tamb\u00e9m retornou ao Brasil para defender o Mirassol e \u00e9 o artilheiro do Paulist\u00e3o, com\u00a0 7 gols em nove partidas. O brilho do ex-companheiro tamb\u00e9m dificultou a passagem do jogador pelo Pantera.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Alves se despediu dos companheiros na ter\u00e7a e j\u00e1 viajou para o Jap\u00e3o na quarta-feira.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A sa\u00edda de Tiago Alves abre caminho para o Botafogo iniciar as modifica\u00e7\u00f5es no plantel visando a sequ\u00eancia da temporada. O clube deve fazer adi\u00e7\u00f5es pontuais no elenco de Paulo Gomes.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Janela de transfer\u00eancias\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Desde o ano passado, o futebol brasileiro possui duas janelas de transfer\u00eancias. Uma entre janeiro e mar\u00e7o e outra entre julho e setembro. A primeira janela fecha no dia 7 de mar\u00e7o, prazo m\u00e1ximo para as equipes regularizarem seus novos jogadores.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Esse per\u00edodo \u00e9 v\u00e1lido somente para atletas que n\u00e3o est\u00e3o disputando os campeonatos estaduais ou atuando fora do pa\u00eds.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Para os jogadores inscritos nos estaduais existe uma exce\u00e7\u00e3o que permite a inscri\u00e7\u00e3o dos mesmos at\u00e9 o dia 19 de abril. Isso se d\u00e1 por conta do per\u00edodo de disputa das competi\u00e7\u00f5es, que terminam depois do fechamento da janela.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p>\u00a0<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/tiago-alves-acerta-saida-do-botafogo\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 29 de fevereiro de 2024 | 14:3029 de fevereiro de 2024 | 12:33 0 O atacante portugu\u00eas Tiago Alves n\u00e3o \u00e9 mais jogador do Botafogo. O jogador recebeu uma proposta de um clube japon\u00eas e pediu para deixar o Tricolor. Como seu contrato estava perto do fim, o Pantera acatou a solicita\u00e7\u00e3o e liberou &#8230; <a title=\"Tiago Alves acerta sa\u00edda do Botafogo\u00a0\u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/29\/tiago-alves-acerta-saida-do-botafogo\/\" aria-label=\"Leia mais sobre Tiago Alves acerta sa\u00edda do Botafogo\u00a0\u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":40023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1763,2268,52,1809,2267],"class_list":["post-40022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-acerta","tag-alves","tag-botafogo","tag-saida","tag-tiago"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-17-scaled.jpg?fit=967%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-17-scaled.jpg?fit=967%2C645&ssl=1",967,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-17-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-17-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-17-scaled.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-17-scaled.jpg?fit=967%2C645&ssl=1",967,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-17-scaled.jpg?fit=967%2C645&ssl=1",967,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-17-scaled.jpg?fit=967%2C645&ssl=1",967,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 29 de fevereiro de 2024 | 14:3029 de fevereiro de 2024 | 12:33 0 O atacante portugu\u00eas Tiago Alves n\u00e3o \u00e9 mais jogador do Botafogo. O jogador recebeu uma proposta de um clube japon\u00eas e pediu para deixar o Tricolor. Como seu contrato estava perto do fim, o Pantera acatou a solicita\u00e7\u00e3o e liberou&hellip;","jetpack-related-posts":[{"id":39732,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/27\/apos-vitoria-botafogo-comeca-pensar-planejamento-para-serie-b\/","url_meta":{"origin":40022,"position":0},"title":"Ap\u00f3s vit\u00f3ria, Botafogo come\u00e7a pensar planejamento para S\u00e9rie B\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"27 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 27 de fevereiro de 2024 | 17:0027 de fevereiro de 2024 | 10:07 0O Botafogo bateu a Portuguesa com o placar de 2 a 1 no \u00faltimo domingo e praticamente confirmou sua perman\u00eancia na elite do futebol paulista. Os gols da partida foram anotados por Douglas Baggio e Patrick\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-16-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-16-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-16-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-2-16-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":16834,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/16\/botafogo-contrata-atacante-portugues-tiago-alves\/","url_meta":{"origin":40022,"position":1},"title":"Botafogo contrata atacante portugu\u00eas Tiago Alves\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"16 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 16 de dezembro de 2023 | 16:0016 de dezembro de 2023 | 12:49 0O Botafogo tem mais um refor\u00e7o para o setor ofensivo. Trata-se do extremo portugu\u00eas Tiago Alves, de 27 anos, revelado nas categorias de base do Sporting (POR) e que atualmente veste a camisa do Montedio Yamagata,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Botafogo-2-1-scaled.jpg?fit=957%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Botafogo-2-1-scaled.jpg?fit=957%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Botafogo-2-1-scaled.jpg?fit=957%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Botafogo-2-1-scaled.jpg?fit=957%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":39357,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/25\/botafogo-recebe-a-lusa-para-espantar-chances-de-rebaixamento\/","url_meta":{"origin":40022,"position":2},"title":"Botafogo recebe a Lusa para espantar chances de rebaixamento\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"25 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O Botafogo come\u00e7ou a temporada com a promessa de mais investimento e a forma\u00e7\u00e3o de um time que teria condi\u00e7\u00f5es de brigar pelo acesso para a S\u00e9rie A do Campeonato Brasileiro.\u00a0\u00a0A folha salarial foi aumentada, chegando na casa dos R$ 2 milh\u00f5es por m\u00eas, bons jogadores chegaram, mas no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-domingo-1-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-domingo-1-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-domingo-1-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Botafogo-domingo-1-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":33040,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/27\/botafogo-visita-o-red-bull-bragantino\/","url_meta":{"origin":40022,"position":3},"title":"Botafogo visita o Red Bull Bragantino\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"27 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Embalado pela vit\u00f3ria fora de casa contra o \u00c1gua Santa, o Botafogo volta a campo neste s\u00e1bado para encarar o Red Bull Bragantino, tamb\u00e9m fora de casa. O jogo acontece \u00e0s 17h15, no est\u00e1dio Nabi Abi Chedid.\u00a0\u00a0Para a partida, o t\u00e9cnico Paulo Gomes n\u00e3o vai poder contar com o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-2-9-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-2-9-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-2-9-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-2-9-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":30147,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/20\/botafogo-recebe-o-santos-na-estreia-do-paulistao\/","url_meta":{"origin":40022,"position":4},"title":"Botafogo recebe o Santos na estreia do Paulist\u00e3o\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"20 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 20 de janeiro de 2024 | 11:0019 de janeiro de 2024 | 22:03 0O Botafogo est\u00e1 pronto para estrear no Campeonato Paulista. Depois de pouco menos de um m\u00eas de prepara\u00e7\u00e3o, o Pantera duela com o Santos no est\u00e1dio Santa Cruz neste s\u00e1bado, \u00e0s 18h.\u00a0\u00a0A partida marca tamb\u00e9m o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-2-7-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-2-7-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-2-7-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-2-7-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":25544,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/07\/com-reforcos-gringos-bota-se-prepara-para-temporada\/","url_meta":{"origin":40022,"position":5},"title":"Com refor\u00e7os gringos, Bota se prepara para temporada\u00a0\u00a0","author":"ismaelcolosi.com.br","date":"7 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Ano novo, vida nova e tudo come\u00e7a outra vez. Assim \u00e9 a vida e assim \u00e9 para os clubes de futebol. No Botafogo n\u00e3o \u00e9 diferente e a prepara\u00e7\u00e3o para a temporada de 2024 est\u00e1 a todo vapor. O clube vai participar do Paulist\u00e3o, Copa do Brasil e S\u00e9rie\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-Leandro-Maciel-1-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-Leandro-Maciel-1-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-Leandro-Maciel-1-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Botafogo-Leandro-Maciel-1-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-apw","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40022"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/40023"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}