{"id":3950,"date":"2023-11-20T14:16:34","date_gmt":"2023-11-20T17:16:34","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/20\/esta-musica-e-capaz-de-reduzir-a-ansiedade-em-ate-65-segundo-a-ciencia\/"},"modified":"2023-11-20T14:16:34","modified_gmt":"2023-11-20T17:16:34","slug":"esta-musica-e-capaz-de-reduzir-a-ansiedade-em-ate-65-segundo-a-ciencia","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/20\/esta-musica-e-capaz-de-reduzir-a-ansiedade-em-ate-65-segundo-a-ciencia\/","title":{"rendered":"Esta m\u00fasica \u00e9 capaz de reduzir a ansiedade em at\u00e9 65%, segundo a ci\u00eancia"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div id=\"attachment_2312409\" class=\"wp-caption alignnone\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2312409\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Getty Images\/iStockphoto\" decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2312409 size-full\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg?resize=1200%2C801&#038;ssl=1\" alt=\"Ansiedade \u00e9 um mecanismo do nosso c\u00e9rebro que serve para nos alertar em situa\u00e7\u00f5es adversas e desconhecidas. M\u00fasica ajuda a reduzir sintomas do transtorno \u2013 iStock\/Getty Images\" width=\"1200\" height=\"801\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg 1253w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421-450x300.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421-768x512.jpg 768w\" sizes=\"(max-width: 1253px) 100vw, 1253px\"\/><\/p>\n<p>Cr\u00e9ditos: Getty Images\/iStockphoto<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Ansiedade \u00e9 um mecanismo do nosso c\u00e9rebro que serve para nos alertar em situa\u00e7\u00f5es adversas e desconhecidas. M\u00fasica ajuda a reduzir sintomas do transtorno \u2013 iStock\/Getty Images<\/span><\/p>\n<\/div>\n<p>Em busca de respostas para o controle da ansiedade, a neuroci\u00eancia constatou que a m\u00fasica pode desempenhar um papel fundamental para o tratamento do transtorno.<\/p>\n<p>O h\u00e1bito, no entanto, \u00e9 praticado durante s\u00e9culos pela<strong><a href=\"https:\/\/catracalivre.com.br\/saude-bem-estar\/cultura-indigena-parto\/\" target=\"_blank\" rel=\"noopener\"> culturas ind\u00edgena<\/a><\/strong>s, que usavam a m\u00fasica para aumentar o bem-estar e melhorar as condi\u00e7\u00f5es de sa\u00fade. A diferen\u00e7a \u00e9 que, agora, os cientistas descobriram uma melodia espec\u00edfica capaz de reduzir a ansiedade.<\/p>\n<p>\u00c9 o que mostra pesquisa feita por cientistas do <strong><a href=\"https:\/\/themindlab.co.uk\/\" target=\"_blank\" rel=\"noopener\">Mindlab International<\/a><\/strong>, que submeteu volunt\u00e1rios \u00e0 audi\u00e7\u00e3o da m\u00fasica \u201cWeightless\u201d, do grupo Marconi Union. A experi\u00eancia apresentou redu\u00e7\u00e3o impressionante de 65% na ansiedade geral.<\/p>\n<h2>Terapia do som<\/h2>\n<p>H\u00e1, contudo, uma raz\u00e3o espec\u00edfica para a m\u00fasica ter surtido tanto efeito. \u00c9 que neste caso ela foi criada justamente para isso, com a ajuda de terapeutas de som. Ou seja, as harmonias e ritmos cuidadosamente organizados ajudam a desacelerar a freq\u00fc\u00eancia card\u00edaca do ouvinte e a reduzir a press\u00e3o arterial e os n\u00edveis do horm\u00f4nio do estresse cortisol.<\/p>\n<p>O estudo foi conduzido em participantes que tentaram resolver quebra-cabe\u00e7as dif\u00edceis o mais r\u00e1pido poss\u00edvel enquanto estavam conectados a sensores. Os quebra-cabe\u00e7as induziram um certo n\u00edvel de estresse, e os participantes ouviram diferentes can\u00e7\u00f5es enquanto os pesquisadores mediam a atividade cerebral, bem como os estados fisiol\u00f3gicos que inclu\u00edam frequ\u00eancia card\u00edaca, press\u00e3o arterial e frequ\u00eancia respirat\u00f3ria.<\/p>\n<p>De acordo com o Dr. David Lewis-Hodgson da Mindlab International , que conduziu a pesquisa, a m\u00fasica produziu um estado de relaxamento maior do que qualquer outra m\u00fasica testada at\u00e9 hoje.<\/p>\n<h2>Conhe\u00e7a a m\u00fasica que ajuda a reduzir a ansiedade no link abaixo:<\/h2>\n<p class=\"embed-responsive embed-responsive-16by9 mb-3 d-block\"><iframe title=\"Marconi Union - Weightless (Official 10 Hour Version)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/qYnA9wWFHLI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/saude-bem-estar\/esta-musica-e-capaz-de-reduzir-a-ansiedade-em-ate-65-segundo-a-ciencia\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Cr\u00e9ditos: Getty Images\/iStockphoto Ansiedade \u00e9 um mecanismo do nosso c\u00e9rebro que serve para nos alertar em situa\u00e7\u00f5es adversas e desconhecidas. M\u00fasica ajuda a reduzir sintomas do transtorno \u2013 iStock\/Getty Images Em busca de respostas para o controle da ansiedade, a neuroci\u00eancia constatou que a m\u00fasica pode desempenhar um papel fundamental para o tratamento do &#8230; <a title=\"Esta m\u00fasica \u00e9 capaz de reduzir a ansiedade em at\u00e9 65%, segundo a ci\u00eancia\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/20\/esta-musica-e-capaz-de-reduzir-a-ansiedade-em-ate-65-segundo-a-ciencia\/\" aria-label=\"Leia mais sobre Esta m\u00fasica \u00e9 capaz de reduzir a ansiedade em at\u00e9 65%, segundo a ci\u00eancia\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":3951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-3950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1444381421.jpg?fit=1200%2C638&ssl=1",1200,638,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Cr\u00e9ditos: Getty Images\/iStockphoto Ansiedade \u00e9 um mecanismo do nosso c\u00e9rebro que serve para nos alertar em situa\u00e7\u00f5es adversas e desconhecidas. M\u00fasica ajuda a reduzir sintomas do transtorno \u2013 iStock\/Getty Images Em busca de respostas para o controle da ansiedade, a neuroci\u00eancia constatou que a m\u00fasica pode desempenhar um papel fundamental para o tratamento do&hellip;","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-11I","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3950"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/3951"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}