{"id":39458,"date":"2024-02-26T12:11:39","date_gmt":"2024-02-26T15:11:39","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/26\/ribeirao-rodeo-music-jorge-e-mateus-lancam-musica-com-lauana-prado\/"},"modified":"2024-02-26T12:11:39","modified_gmt":"2024-02-26T15:11:39","slug":"ribeirao-rodeo-music-jorge-e-mateus-lancam-musica-com-lauana-prado","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/26\/ribeirao-rodeo-music-jorge-e-mateus-lancam-musica-com-lauana-prado\/","title":{"rendered":"Ribeir\u00e3o Rodeo Music: Jorge e Mateus lan\u00e7am m\u00fasica com Lauana Prado"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_107\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Atra\u00e7\u00e3o confirmada no <strong><a href=\"https:\/\/www.ribeiraorodeomusic.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Ribeir\u00e3o Rodeo Music<\/a><\/strong>, a dupla <strong>Jorge e Mateus<\/strong> lan\u00e7ou na \u00faltima semana a m\u00fasica <strong>\u201cHaver\u00e1 Sinais\u201d<\/strong>, que conta com a participa\u00e7\u00e3o da cantora<strong> Lauana Prado<\/strong>, que tamb\u00e9m \u00e9 atra\u00e7\u00e3o no evento.<\/p>\n<p>A parceria entre os artistas \u00e9 o primeiro lan\u00e7amento de <strong>Jorge e Mateus<\/strong> em 2024 e conta com a produ\u00e7\u00e3o de Dudu Borges \u2013 veja o clipe:<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<p><iframe title=\"Jorge &amp; Mateus, Lauana Prado - Haver\u00e1  Sinais (Clipe Oficial)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/Muo3F10dAcw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<\/figure>\n<h4 class=\"wp-block-heading\"><strong>Ribeir\u00e3o Rodeo Music<\/strong><\/h4>\n<p>A dupla<mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\"> Jorge e Mateus vai se apresentar no <strong>Ribeir\u00e3o Rodeo Music <\/strong>no dia 30 de abril. <\/mark>No mesmo dia, sobem no palco do rodeio <strong>\u00cdcaro e Gilmar<\/strong>, <strong>Gustavo Mioto<\/strong> e<strong> Zez\u00e9 di Camargo e Luciano.<\/strong><\/p>\n<p>J\u00e1 <strong>Lauana Prado<\/strong> \u00e9 atra\u00e7\u00e3o do<strong> Ribeir\u00e3o Rodeo Music<\/strong> no dia 26 de abril. No mesmo dia, v\u00e3o se apresentar <strong>Z\u00e9 Neto e Cristiano<\/strong>,<strong> DJ Locos <\/strong>e <strong>Cesar Menotti e Fabiano<\/strong>.<\/p>\n<p>Os ingressos j\u00e1 est\u00e3o dispon\u00edveis pela internet (<a href=\"https:\/\/www.ribeiraorodeomusic.com.br\/ingressos\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">clique aqui<\/a>) e em pontos f\u00edsicos \u2013 saiba mais aqui.<\/p>\n<p>SAIBA MAIS<br \/>Inscri\u00e7\u00f5es para concurso p\u00fablico de Ribeir\u00e3o Preto terminam esta semana<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on<\/strong> no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on <\/strong>no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Que horas come\u00e7a o BBB 24 hoje?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/ribeirao-rodeo-music\/ribeirao-rodeo-music-jorge-e-mateus-lancam-musica-lauana-prado\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Atra\u00e7\u00e3o confirmada no Ribeir\u00e3o Rodeo Music, a dupla Jorge e Mateus lan\u00e7ou na \u00faltima semana a m\u00fasica \u201cHaver\u00e1 Sinais\u201d, que conta com a participa\u00e7\u00e3o da cantora Lauana Prado, que tamb\u00e9m \u00e9 atra\u00e7\u00e3o no evento. A parceria entre os artistas \u00e9 o primeiro lan\u00e7amento de Jorge e Mateus em 2024 e conta com a produ\u00e7\u00e3o &#8230; <a title=\"Ribeir\u00e3o Rodeo Music: Jorge e Mateus lan\u00e7am m\u00fasica com Lauana Prado\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/26\/ribeirao-rodeo-music-jorge-e-mateus-lancam-musica-com-lauana-prado\/\" aria-label=\"Leia mais sobre Ribeir\u00e3o Rodeo Music: Jorge e Mateus lan\u00e7am m\u00fasica com Lauana Prado\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":39459,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-39458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/jorge-e-mateus-lauana-prado.jpg?fit=950%2C731&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/jorge-e-mateus-lauana-prado.jpg?fit=950%2C731&ssl=1",950,731,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/jorge-e-mateus-lauana-prado.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/jorge-e-mateus-lauana-prado.jpg?fit=300%2C231&ssl=1",300,231,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/jorge-e-mateus-lauana-prado.jpg?fit=768%2C591&ssl=1",768,591,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/jorge-e-mateus-lauana-prado.jpg?fit=950%2C731&ssl=1",950,731,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/jorge-e-mateus-lauana-prado.jpg?fit=950%2C731&ssl=1",950,731,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/jorge-e-mateus-lauana-prado.jpg?fit=950%2C731&ssl=1",950,731,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Atra\u00e7\u00e3o confirmada no Ribeir\u00e3o Rodeo Music, a dupla Jorge e Mateus lan\u00e7ou na \u00faltima semana a m\u00fasica \u201cHaver\u00e1 Sinais\u201d, que conta com a participa\u00e7\u00e3o da cantora Lauana Prado, que tamb\u00e9m \u00e9 atra\u00e7\u00e3o no evento. A parceria entre os artistas \u00e9 o primeiro lan\u00e7amento de Jorge e Mateus em 2024 e conta com a produ\u00e7\u00e3o&hellip;","jetpack-related-posts":[{"id":41508,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/08\/saiba-qual-e-a-dupla-que-mais-participou-do-ribeirao-rodeo-music\/","url_meta":{"origin":39458,"position":0},"title":"Saiba qual \u00e9 a dupla que mais participou do Ribeir\u00e3o Rodeo Music","author":"ismaelcolosi.com.br","date":"8 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Para quem acompanha desde o in\u00edcio o Ribeir\u00e3o Rodeo Music \u00e9 f\u00e1cil adivinhar que a dupla sertaneja Jorge e Mateus \u00e9 a que mais participou no evento. Os cantores marcaram presen\u00e7a no RRM por 10 anos e nesta edi\u00e7\u00e3o voltam aos palcos do evento no dia 30 de abril.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/jorge-e-mateus.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/jorge-e-mateus.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/jorge-e-mateus.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/jorge-e-mateus.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/jorge-e-mateus.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41526,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/08\/saiba-qual-e-a-dupla-que-mais-participou-do-ribeirao-rodeo-music-2\/","url_meta":{"origin":39458,"position":1},"title":"Saiba qual \u00e9 a dupla que mais participou do Ribeir\u00e3o Rodeo Music","author":"ismaelcolosi.com.br","date":"8 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Para quem acompanha desde o in\u00edcio o Ribeir\u00e3o Rodeo Music \u00e9 f\u00e1cil adivinhar que a dupla sertaneja Jorge e Mateus \u00e9 a que mais participou no evento. Os cantores marcaram presen\u00e7a no RRM por 10 anos e nesta edi\u00e7\u00e3o voltam aos palcos do evento no dia 30 de abril.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao-rodeo-music-2023.jpg?fit=1200%2C777&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao-rodeo-music-2023.jpg?fit=1200%2C777&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao-rodeo-music-2023.jpg?fit=1200%2C777&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao-rodeo-music-2023.jpg?fit=1200%2C777&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/ribeirao-rodeo-music-2023.jpg?fit=1200%2C777&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45835,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/08\/ana-castela-e-lauana-prado-no-topo-das-paradas-nacionais\/","url_meta":{"origin":39458,"position":2},"title":"Ana Castela e Lauana Prado no topo das paradas nacionais","author":"ismaelcolosi.com.br","date":"8 de Abril de 2024","format":false,"excerpt":"[ad_1] As vozes marcantes de Ana Castela e Lauana Prado est\u00e3o no topo dos hits sertanejos nas paradas nacionais. Segundo os rankings da Billboard Brasil, a boiadeira figura h\u00e1 30 semanas entre os artistas mais ouvidos no Pa\u00eds. J\u00e1 Lauana Prado dominou a lista Hot 100 com o medley de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__Ana_Lauana_REPRODUCAO_INSTAGRAM.webp.webp?fit=701%2C552&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__Ana_Lauana_REPRODUCAO_INSTAGRAM.webp.webp?fit=701%2C552&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__Ana_Lauana_REPRODUCAO_INSTAGRAM.webp.webp?fit=701%2C552&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__Ana_Lauana_REPRODUCAO_INSTAGRAM.webp.webp?fit=701%2C552&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":35827,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/07\/rodeo-music-tera-16-shows\/","url_meta":{"origin":39458,"position":3},"title":"Rodeo Music ter\u00e1 16 shows\u00a0","author":"ismaelcolosi.com.br","date":"7 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 7 de fevereiro de 2024 | 16:007 de fevereiro de 2024 | 16:12 0Junto com a abertura da venda de ingressos, o Ribeir\u00e3o Rodeo Music anunciou nesta ter\u00e7a-feira, 6 de abril, que em 2024 a programa\u00e7\u00e3o art\u00edstica ter\u00e1 16 shows. No dia 20 de abril, s\u00e1bado, a primeira noite\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/RodeioRP-Ana-Divulgacao.jpg?fit=800%2C533&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/RodeioRP-Ana-Divulgacao.jpg?fit=800%2C533&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/RodeioRP-Ana-Divulgacao.jpg?fit=800%2C533&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/RodeioRP-Ana-Divulgacao.jpg?fit=800%2C533&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":38476,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/20\/ribeirao-rodeo-music-comeca-venda-de-ingressos-em-pontos-fisicos-veja-os-locais\/","url_meta":{"origin":39458,"position":4},"title":"Ribeir\u00e3o Rodeo Music come\u00e7a venda de ingressos em pontos f\u00edsicos; Veja os locais","author":"ismaelcolosi.com.br","date":"20 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O Ribeir\u00e3o Rodeo Music liberou nesta ter\u00e7a-feira (20) a venda de ingressos nos pontos f\u00edsicos. Os interessados podem comprar as entradas para o rodeio nas lojas Oscar Cal\u00e7ados do Novo Shopping e no Centro de Ribeir\u00e3o Preto. Nos pontos f\u00edsicos, o p\u00fablico encontra ingressos para os setores: camarote Ballantine\u2019s\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ribeirao-rodeo-music.jpg?fit=1200%2C781&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ribeirao-rodeo-music.jpg?fit=1200%2C781&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ribeirao-rodeo-music.jpg?fit=1200%2C781&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ribeirao-rodeo-music.jpg?fit=1200%2C781&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ribeirao-rodeo-music.jpg?fit=1200%2C781&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44352,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/27\/zeze-di-camargo-luciano-voltam-ao-ribeirao-rodeo-music-depois-de-mais-de-10-anos\/","url_meta":{"origin":39458,"position":5},"title":"Zez\u00e9 di Camargo &#038; Luciano voltam ao Ribeir\u00e3o Rodeo Music depois de mais de 10 anos","author":"ismaelcolosi.com.br","date":"27 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A dupla sertaneja Zez\u00e9 di Camargo & Luciano est\u00e1 de volta ao Ribeir\u00e3o Rodeo Music depois de mais de 10 anos da \u00faltima apresenta\u00e7\u00e3o no evento, que aconteceu em 2013. Os irm\u00e3os conhecidos por cantar m\u00fasicas rom\u00e2nticas como \u201c\u00c9 o amor\u201d, participam da 18\u00aa edi\u00e7\u00e3o do RRM , que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1711554263_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1711554263_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1711554263_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1711554263_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1711554263_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-agq","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39458"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/39459"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}