{"id":39372,"date":"2024-02-25T17:10:18","date_gmt":"2024-02-25T20:10:18","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/25\/jornada-da-leitura-6-0-aborda-a-importancia-da-leitura-para-as-pessoas-idosas\/"},"modified":"2024-02-25T17:10:18","modified_gmt":"2024-02-25T20:10:18","slug":"jornada-da-leitura-6-0-aborda-a-importancia-da-leitura-para-as-pessoas-idosas","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/25\/jornada-da-leitura-6-0-aborda-a-importancia-da-leitura-para-as-pessoas-idosas\/","title":{"rendered":"Jornada da Leitura 6.0 aborda a import\u00e2ncia da leitura para as pessoas idosas"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O Observat\u00f3rio do Livro realiza, a partir da pr\u00f3xima ter\u00e7a-feira (27), uma jornada on-line para discutir e intensificar a divulga\u00e7\u00e3o, entre a popula\u00e7\u00e3o mais velha, sobre os benef\u00edcios da leitura de livros para uma velhice mais saud\u00e1vel e repleta de sonhos poss\u00edveis. A cerim\u00f4nia de abertura conta com a presen\u00e7a da secret\u00e1ria de Assist\u00eancia Social do munic\u00edpio, Glaucia Berenice, e a presidente do Conselho Municipal do Idoso, Gislene Mazzer Ribeiro.<\/p>\n<p>A programa\u00e7\u00e3o do evento de tr\u00eas dias (27, 28 e 29\/2) \u00e9 dividida em tr\u00eas atra\u00e7\u00f5es di\u00e1rias, contando com dois pain\u00e9is e o sarau, apresentadas por Galeno Amorim, presidente da institui\u00e7\u00e3o, e pela assistente social e educadora Luciana Paschoalin, que acaba de assumir a Dire\u00e7\u00e3o de Opera\u00e7\u00f5es do Observat\u00f3rio. A Jornada da Leitura 6.0 traz para esta 4\u00aa edi\u00e7\u00e3o nove lives e \u00e9 transmitida pelo Canal do Galeno no YouTube de 16 \u00e0s 18h.<\/p>\n<p>O elenco de especialistas \u00e9 composto por nomes como Karla Giacomin, geriatra e consultora da Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS); Eg\u00eddio D\u00f3rea, geriatra e coordenador do programa USP 60+; e Sylvia Loeb, psicanalista e escritora, criadora da p\u00e1gina \u201cMinha idade n\u00e3o me define\u201d. Entre os escritores e artistas est\u00e3o Luiz Puntel, um dos principais expoentes da Cole\u00e7\u00e3o Vaga-lume, que se tornou a principal refer\u00eancia liter\u00e1ria de pelo menos tr\u00eas gera\u00e7\u00f5es de crian\u00e7as e jovens; os jornalistas e escritores Luciana Salvaget e Luiz Carlos Ramos; a escritora ind\u00edgena M\u00e1rcia Kambeba; e a artista pl\u00e1stica Maria Helena Oliveira.<\/p>\n<p>Para encerrar a programa\u00e7\u00e3o de cada dia, o j\u00e1 tradicional Sarau, com a apresenta\u00e7\u00e3o de Gerson Ramos, que \u00e9 livreiro e violeiro; do Rapper Vini, que traz textos consagrados em nova linguagem; e a necess\u00e1ria poesia de protesto de Carlos de Assumpc\u0327a\u0303o. A 4\u00aaJornada da Leitura 6.0, vale destacar, conta com a parceria do Conselho Municipal do Idoso de Ribeir\u00e3o Preto, que, como o Observat\u00f3rio acredita que hist\u00f3rias e sonhos n\u00e3o envelhecem.<\/p>\n<p>Galeno Amorim, idealizador do projeto Clube de Leitura 6.0, diz que mais do que o entretenimento cultural, os clubes de leitura para pessoas idosas e atividades como a jornada estimulam maior conv\u00edvio social, cultura, lazer e informa\u00e7\u00f5es para o bem-estar dos participantes. As vagas para participar da jornada continuam abertas e as inscri\u00e7\u00f5es podem ser feitas atrav\u00e9s<br \/>do link https:\/\/observatoriodolivro.org.br\/jornada-leitura-60<\/p>\n<p><strong>Servi\u00e7o:<\/strong><br \/>Evento: 4\u00aa. Jornada de Leitura 6.0<br \/>Quando: 27, 28 e 29 de fevereiro, de 16 \u00e0s 18h<br \/>Onde assistir: YouTube @canaldogaleno<br \/>Inscri\u00e7\u00e3o: https:\/\/observatoriodolivro.org.br\/jornada-leitura-60<\/p>\n<p><strong>Programa\u00e7\u00e3o Completa:<\/strong><\/p>\n<p><strong>Tema central: Hist\u00f3rias e sonhos n\u00e3o envelhecem<\/strong><br \/><strong>Ter\u00e7a-feira, 27 de fevereiro<\/strong><br \/>Eixo tem\u00e1tico do dia 1: \u201cLiteratura e a constru\u00e7\u00e3o dos sonhos na maturidade\u201d<br \/>16:00 \u2013 Abertura<br \/>Galeno Amorim, presidente do Observat\u00f3rio do Livro, jornalista e escritor<br \/>Gl\u00e1ucia Berenice, secret\u00e1ria da Assist\u00eancia Social de Ribeir\u00e3o Preto<\/p>\n<p>Gislene Mazzer Ribeiro, presidente do Conselho Municipal do Idoso de Ribeir\u00e3o Preto<br \/>16:15 \u2013 Painel 1<br \/>Luiz Puntel, escritor<br \/>Media\u00e7\u00e3o: Galeno Amorim<br \/>17:00 \u2013 Painel 2<br \/>Luciana Salvaget, jornalista e escritora<br \/>Luiz Carlos Ramos, escritor e jornalista<br \/>Media\u00e7\u00e3o: Luciana Paschoalin, diretora de Opera\u00e7\u00f5es do Observat\u00f3rio do Livro<br \/>17h45 \u2013 Sarau<br \/>Gerson Ramos, livreiro e violeiro<\/p>\n<p><strong>Quarta-feira, 28 de fevereiro<\/strong><br \/>Eixo tem\u00e1tico do dia 2: \u201cO valor das trocas Intergeracionais\u201d<br \/>16:00 \u2013 Painel 1<br \/>Karla Giacomin, m\u00e9dica geriatra, ex-presidente do Conselho Nacional do Idoso e consultora da OMS<br \/>Media\u00e7\u00e3o: Galeno Amorim<br \/>17:00 \u2013 Painel 2<br \/>Sylvia Loeb, psicanalista e escritora, criadora da p\u00e1gina \u201cMinha idade n\u00e3o me define\u201d<br \/>Luciana Paschoalin, assistente social, educadora e diretora de Opera\u00e7\u00f5es do Observat\u00f3rio do Livro<br \/>Media\u00e7\u00e3o: Galeno Amorim<br \/>17:45 \u2013 Sarau<br \/>Vini, rapper<\/p>\n<p><strong>Quinta-feira, 29 de fevereiro<\/strong><br \/>Eixo tem\u00e1tico do dia 3: \u201cQuem l\u00ea, tamb\u00e9m escreve\u201d<br \/>16:00 \u2013 Painel 1<br \/>Eg\u00eddio D\u00f3rea, m\u00e9dico geriatra e coordenador do programa USP 60+<br \/>Media\u00e7\u00e3o: Galeno Amorim<br \/>17:00 \u2013 Painel 2<br \/>Maria Helena Oliveira, mediadora de leitura do Sarau Preto<br \/>M\u00e1rcia Kambeba, escritora ind\u00edgena<br \/>Media\u00e7\u00e3o: Luciana Paschoalin<br \/>17h45 \u2013 Sarau<br \/>Carlos Assun\u00e7\u00e3o, poeta<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/jornada-da-leitura-6-0-aborda-a-importancia-da-leitura-para-as-pessoas-idosas\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O Observat\u00f3rio do Livro realiza, a partir da pr\u00f3xima ter\u00e7a-feira (27), uma jornada on-line para discutir e intensificar a divulga\u00e7\u00e3o, entre a popula\u00e7\u00e3o mais velha, sobre os benef\u00edcios da leitura de livros para uma velhice mais saud\u00e1vel e repleta de sonhos poss\u00edveis. A cerim\u00f4nia de abertura conta com a presen\u00e7a da secret\u00e1ria de Assist\u00eancia &#8230; <a title=\"Jornada da Leitura 6.0 aborda a import\u00e2ncia da leitura para as pessoas idosas\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/25\/jornada-da-leitura-6-0-aborda-a-importancia-da-leitura-para-as-pessoas-idosas\/\" aria-label=\"Leia mais sobre Jornada da Leitura 6.0 aborda a import\u00e2ncia da leitura para as pessoas idosas\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":39373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[4514,4515,1443,2087,3847,71,581],"class_list":["post-39372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-aborda","tag-idosas","tag-importancia","tag-jornada","tag-leitura","tag-para","tag-pessoas"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/54f1aeee-d7a6-4b8d-aacc-aa69e02e2651-scaled.jpg?fit=860%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/54f1aeee-d7a6-4b8d-aacc-aa69e02e2651-scaled.jpg?fit=860%2C645&ssl=1",860,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/54f1aeee-d7a6-4b8d-aacc-aa69e02e2651-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/54f1aeee-d7a6-4b8d-aacc-aa69e02e2651-scaled.jpg?fit=300%2C225&ssl=1",300,225,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/54f1aeee-d7a6-4b8d-aacc-aa69e02e2651-scaled.jpg?fit=768%2C576&ssl=1",768,576,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/54f1aeee-d7a6-4b8d-aacc-aa69e02e2651-scaled.jpg?fit=860%2C645&ssl=1",860,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/54f1aeee-d7a6-4b8d-aacc-aa69e02e2651-scaled.jpg?fit=860%2C645&ssl=1",860,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/54f1aeee-d7a6-4b8d-aacc-aa69e02e2651-scaled.jpg?fit=860%2C645&ssl=1",860,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O Observat\u00f3rio do Livro realiza, a partir da pr\u00f3xima ter\u00e7a-feira (27), uma jornada on-line para discutir e intensificar a divulga\u00e7\u00e3o, entre a popula\u00e7\u00e3o mais velha, sobre os benef\u00edcios da leitura de livros para uma velhice mais saud\u00e1vel e repleta de sonhos poss\u00edveis. A cerim\u00f4nia de abertura conta com a presen\u00e7a da secret\u00e1ria de Assist\u00eancia&hellip;","jetpack-related-posts":[{"id":40178,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/01\/4a-jornada-da-leitura-6-0-discutiu-o-papel-da-literatura-na-velhice\/","url_meta":{"origin":39372,"position":0},"title":"4\u00aa. Jornada da Leitura 6.0 discutiu o papel da literatura na velhice","author":"ismaelcolosi.com.br","date":"1 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 1 de mar\u00e7o de 2024 | 13:301 de mar\u00e7o de 2024 | 11:27 0Quarta edi\u00e7\u00e3o do evento atraiu 4590 pessoas, durante tr\u00eas dias, para ouvir escritores, especialistas e artistas sobre o papel dos livros, da literatura e da escrita para uma velhice mais ativa e inclusiva. Al\u00e9m disso, contabilizou\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/12540370-e7eb-4fa6-b4a9-7b3f56e4ec1c-scaled.jpg?fit=970%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/12540370-e7eb-4fa6-b4a9-7b3f56e4ec1c-scaled.jpg?fit=970%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/12540370-e7eb-4fa6-b4a9-7b3f56e4ec1c-scaled.jpg?fit=970%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/12540370-e7eb-4fa6-b4a9-7b3f56e4ec1c-scaled.jpg?fit=970%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":74708,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/01\/5a-jornada-da-leitura-no-carcere-aborda-a-importancia-de-ampliar-o-acesso-aos-livros\/","url_meta":{"origin":39372,"position":1},"title":"5\u00aa Jornada da Leitura no C\u00e1rcere aborda a import\u00e2ncia de ampliar o acesso aos livros","author":"ismaelcolosi.com.br","date":"1 de Novembro de 2024","format":false,"excerpt":"[ad_1] Evento que reuniu mais de 29.745 pessoas em 2023, sendo 20.750 privadas de liberdade e servidores p\u00fablicos, a Jornada de Leitura no C\u00e1rcere chega \u00e0 sua quinta edi\u00e7\u00e3o neste ano com o objetivo de fortalecer iniciativas de acesso ao livro e \u00e0 leitura em unidades prisionais. Escritores, especialistas, apenados\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/424aaac6-1061-402c-bb56-c68a158a55fb-scaled.jpeg?fit=667%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/424aaac6-1061-402c-bb56-c68a158a55fb-scaled.jpeg?fit=667%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/424aaac6-1061-402c-bb56-c68a158a55fb-scaled.jpeg?fit=667%2C500&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":42084,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/12\/observatorio-do-livro-leva-leitura-para-pessoas-idosas-em-situacao-de-rua-em-ribeirao\/","url_meta":{"origin":39372,"position":2},"title":"Observat\u00f3rio do Livro leva leitura para pessoas idosas em situa\u00e7\u00e3o de rua em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"12 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 12 de mar\u00e7o de 2024 | 15:3012 de mar\u00e7o de 2024 | 15:02 0Decorrente do aumento da expectativa de vida em geral e das desigualdades sociais, o n\u00famero de pessoas idosas em situa\u00e7\u00e3o de rua aumentou sete vezes nos \u00faltimos dez anos no Brasil, segundo a pesquisa Levantamento do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8235b944-f1b8-416f-9225-9d13477abf45-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8235b944-f1b8-416f-9225-9d13477abf45-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8235b944-f1b8-416f-9225-9d13477abf45-scaled.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8235b944-f1b8-416f-9225-9d13477abf45-scaled.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":74052,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/29\/observatorio-do-livro-realiza-sarau-com-participantes-do-clube-de-leitura-6-0-em-ribeirao\/","url_meta":{"origin":39372,"position":3},"title":"Observat\u00f3rio do Livro realiza sarau com participantes do Clube de Leitura 6.0 em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"29 de Outubro de 2024","format":false,"excerpt":"[ad_1] Al\u00e9m de n\u00e3o deixar a data passar em branco, a proposta do evento \u2013 que reuniu membros 60+ de v\u00e1rios grupos do Clube de Leitura na Biblioteca Sinh\u00e1 Junqueira \u2013 contemplou a apresenta\u00e7\u00e3o de textos autorais dos participantes e trechos de obras que fizeram parte da curadoria do projeto\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/e2667ae3-aa49-4960-b108-6b9fc6fbb2c7-scaled.jpeg?fit=800%2C451&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/e2667ae3-aa49-4960-b108-6b9fc6fbb2c7-scaled.jpeg?fit=800%2C451&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/e2667ae3-aa49-4960-b108-6b9fc6fbb2c7-scaled.jpeg?fit=800%2C451&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/e2667ae3-aa49-4960-b108-6b9fc6fbb2c7-scaled.jpeg?fit=800%2C451&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":13201,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/09\/melhor-ong-de-cultura-e-de-rp\/","url_meta":{"origin":39372,"position":4},"title":"Melhor ONG de cultura \u00e9 de RP","author":"ismaelcolosi.com.br","date":"9 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Com expertise em projetos voltados para leitores improv\u00e1veis, o Observat\u00f3rio do Livro, com sede em Ribeir\u00e3o Preto e atua\u00e7\u00e3o internacional, recebeu, na quinta-feira, 7 de dezembro, o Pr\u00eamio de Melhor ONG de Cultura do Pa\u00eds e o das 100 Melhores ONGs do Brasil em 2023. Vai completar 25 anos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Galeno.jpg?fit=833%2C566&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Galeno.jpg?fit=833%2C566&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Galeno.jpg?fit=833%2C566&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Galeno.jpg?fit=833%2C566&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":76284,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/12\/observatorio-do-livro-e-finalista-do-premio-governador-do-estado-para-as-artes-2024\/","url_meta":{"origin":39372,"position":5},"title":"Observat\u00f3rio do Livro \u00e9 finalista do Pr\u00eamio Governador do Estado para as Artes 2024","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2024","format":false,"excerpt":"[ad_1] 12 de novembro de 202411 de novembro de 202410 Compartilhar0 A entrega do pr\u00eamio ocorrer\u00e1 nesta ter\u00e7a-feira (12), no Pal\u00e1cio dos Bandeirantes. Em dezembro do ano passado, o Observat\u00f3rio recebeu o Pr\u00eamio de Melhor ONG de Cultura do Pa\u00eds. O an\u00fancio foi feito pela Secretaria da Cultura, Economia e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/c75aafcb-c77c-4dbe-944b-702efa94ec19-scaled.jpeg?fit=500%2C500&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-af2","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39372"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/39373"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}